{"id":64885,"date":"2000-09-10T00:00:00","date_gmt":"2000-09-09T22:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2000\/09\/10\/lhomme-du-siecle\/"},"modified":"2026-02-27T15:51:56","modified_gmt":"2026-02-27T13:51:56","slug":"lhomme-du-siecle","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2000\/09\/10\/lhomme-du-siecle\/","title":{"rendered":"L&rsquo;homme du si\u00e8cle"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955;font-size:2em;\">L&rsquo;homme du si\u00e8cle<\/h2>\n<\/p>\n<blockquote>\n<p><p>&#8230; Mais de quel si\u00e8cle? Le XXe ou le XXIe? Le philosophe Fr\u00e9d\u00e9ric Nietzsche est mort le 25 ao&ucirc;t 1900 et nous venons de comm\u00e9morer le centenaire de sa disparition. Plus qu&rsquo;un philosophe, c&rsquo;est un visionnaire, une r\u00e9f\u00e9rence, un symbole et un myst\u00e8re. Son oeuvre, \u00e9crite dans la douleur et la solitude, est assez fulgurante pour \u00e9clairer cr&ucirc;ment notre \u00e9trange d\u00e9cadence. Perspectives \u00e0 l&rsquo;ombre de celui que le po\u00e8te-chanteur Dirk Annegan baptisa &laquo;l&rsquo;homme de l&rsquo;aube&raquo;.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>On a tellement dit sur Nietzsche qu&rsquo;on croirait que tout est dit, &mdash; mais tout n&rsquo;est jamais dit pour autant. Tout cela \u00e9tant fa\u00e7on de parler, nous ne nous en priverons pas \u00e0 notre tour.<\/p>\n<\/p>\n<p><p>Fr\u00e9d\u00e9ric Nietzsche est le philosophe qui a diagnostiqu\u00e9 le nihilisme comme caract\u00e9ristique fondamentale du modernisme qu&rsquo;il a per\u00e7u comme une d\u00e9cadence et une maladie de l&rsquo;esprit, voire de l&rsquo;humeur. Ainsi \u00e9tait-il m\u00e9decin et psychologue plus que philosophe (d&rsquo;ailleurs, en est-il un ? Beaucoup lui d\u00e9nient ce titre &mdash; voir Sartre &mdash; alors que d&rsquo;autres l&rsquo;affirment au contraire avec une vigueur extr\u00eame, pour justifier leur int\u00e9r\u00eat pour Nietzsche ; rien entre ces deux attitudes extr\u00eames). Nietzsche a appel\u00e9 \u00e0 opposer un autre nihilisme \u00e0 ce qu&rsquo;il percevait comme le nihilisme g\u00e9n\u00e9ral de notre soci\u00e9t\u00e9 pour mieux le combattre, comme on arr\u00eate le feu avec un contre-feu. M\u00e9decin, mais \u00e9galement musicien (il interpr\u00e9tait magnifiquement et il a compos\u00e9 assez joliment), Nietzsche se r\u00e9f\u00e9rait \u00e0 l&rsquo;esth\u00e9tique comme \u00e0 une arme individuelle pour combattre cette peste du modernisme qu&rsquo;est l&rsquo;individualisme social. II sous-entendait qu&rsquo;il fallait devenir individualiste <em>per se<\/em>, tactiquement dirait-on, pour prendre les armes contre la peste-individualisme que r\u00e9pand la soci\u00e9t\u00e9 nihiliste et totalitaire. Feu contre feu.<\/p>\n<\/p>\n<p><p>Nietzsche annon\u00e7a le r\u00e8gne du &laquo;<em>dernier homme<\/em>&raquo;, celui qui porte le nihilisme \u00e0 son terme absurde. On pourrait avancer que nous y sommes. Il y a aujourd&rsquo;hui une attitude dans ce sens pas loin d&rsquo;\u00eatre universelle, ou globalis\u00e9e selon le terme \u00e0 la mode ; il y a en g\u00e9n\u00e9ral chez nos hommes politiques et chez nos intellectuels, et chez nos marchands-capitalistes derri\u00e8re eux &mdash; c&rsquo;est-\u00e0-dire ce qui forme notre \u00ab\u00a0\u00e9lite\u00a0\u00bb &mdash; une tension extr\u00eame pour se r\u00e9aliser totalement dans ce dernier homme. Les uns et les autres ne parlent que de la fin des choses qui ont structur\u00e9 la civilisation : la &laquo;<em>fin de l&rsquo;histoire<\/em>&raquo;, la \u00ab\u00a0fin de la politique\u00a0\u00bb, etc. Les critiques de cette \u00e9volution retrouvent le pr\u00e9cepte de Nietzsche (nihilisme contre nihilisme) sans y songer pr\u00e9cis\u00e9ment sinon par d\u00e9marche de nature; ils parlent, eux, de \u00ab\u00a0la fin du progr\u00e8s\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Le dernier homme, c&rsquo;est celui qui a remplac\u00e9 d\u00e9finitivement la substance par la forme, celui qui coupe les ponts avec le pass\u00e9 pour r\u00e9duire l&rsquo;avenir \u00e0 l&rsquo;instant pr\u00e9sent, celui qui installe une r\u00e9alit\u00e9 totalitaire virtualiste \u00e0 la place de la r\u00e9alit\u00e9 ; celui qui saccage toutes les structures qui tiennent la soci\u00e9t\u00e9 ; celui qui dit avoir dompt\u00e9 la nature comme s&rsquo;il s&rsquo;agissait d&rsquo;un ennemi et rompt les liens de l&rsquo;homme avec la nature ; celui qui, enfin, installe la totalit\u00e9 de l&rsquo;intol\u00e9rance sans r\u00e9f\u00e9rence \u00e0 une id\u00e9e ou \u00e0 un projet politique ext\u00e9rieur, en la baptisant \u00ab\u00a0libert\u00e9\u00a0\u00bb, sous-entendant <em>de facto<\/em> et comme par inadvertance une consigne \u00e9trange, g\u00e9nitrice de la terreur ultime, et qu&rsquo;on \u00e9noncerait comme ceci : \u00ab\u00a0pas de tol\u00e9rance pour les ennemis de l&rsquo;intol\u00e9rance\u00a0\u00bb.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Pourquoi cet homme est dangereux<\/h3>\n<\/p>\n<p><p>Nietzsche, dit-on, est \u00e9tonnamment actuel. Ce que ce lieu commun a d&rsquo;\u00e9trange, c&rsquo;est-\u00e0-dire de paradoxalement exceptionnel et in\u00e9dit, est qu&rsquo;il vaut \u00e0 peu pr\u00e8s pour toutes les \u00e9poques depuis sa mort du 25 ao&ucirc;t 1900 (et m\u00eame avant), et \u00e0 peu pr\u00e8s pour toutes les tendances, toutes les id\u00e9ologies, toutes les d\u00e9viances, des plus ang\u00e9liques aux plus monstrueuses, des doux <em>beatniks<\/em> \u00e0 la Kerouac aux id\u00e9ologues du nazisme. Nietzsche est aujourd&rsquo;hui une r\u00e9f\u00e9rence oblig\u00e9e comme il l&rsquo;est depuis un si\u00e8cle.<\/p>\n<\/p>\n<p><p>L&rsquo;explication possible est qu&rsquo;il est profond, visionnaire et universel, et nullement rattach\u00e9 \u00e0 une \u00e9cole de pens\u00e9e m\u00eame s&rsquo;il s&rsquo;attache \u00e0 longuement analyser certaines d&rsquo;entre elles, m\u00eame si son apport \u00e0 permis \u00e0 certaines de progresser tr\u00e8s s\u00e9rieusement. II d\u00e9crit un monde commun \u00e0 tous avec une forme (aphorisme) qui laisse sa libert\u00e9 au lecteur. II pourrait servir de r\u00e9f\u00e9rence \u00e0 un Indien et \u00e0 un Sud-Am\u00e9ricain comme \u00e0 un Europ\u00e9en occidental. II est \u00e9galement \u00ab\u00a0\u00e0 la mode\u00a0\u00bb parce que la mode, dans ces temps d&rsquo;apparence o&ugrave; la libert\u00e9 comme slogan porte beau, est de se r\u00e9f\u00e9rer \u00e0 un homme qui est la libert\u00e9 m\u00eame, avec sa d\u00e9mesure et ses limites. Nietzsche est donc \u00e9galement dangereux, non parce qu&rsquo;il \u00ab\u00a0sent le souffre\u00a0\u00bb comme on le disait parfois aux jeunes gens bourgeois des diverses \u00e9poques du XXe si\u00e8cle qui se d\u00e9couvraient fascin\u00e9s par ce nom myst\u00e9rieux et ce visage extraordinaire, mais parce que les imb\u00e9ciles s&rsquo;y r\u00e9f\u00e8rent \u00e9galement.<\/p>\n<\/p>\n<p><p>Nietzsche est une auberge espagnole o&ugrave; il faut savoir poser les pieds. Dans cette appr\u00e9ciation foisonnante, nous devrions parler de la culpabilit\u00e9 ou de l&rsquo;innocence de ceux qui se disent adeptes de Nietzsche plut\u00f4t que de la culpabilit\u00e9 ou de l&rsquo;innocence de la pens\u00e9e nietzsch\u00e9enne. Nietzsche nous interdit vis-\u00e0-vis de lui-m\u00eame cette sorte de d\u00e9marche qui se r\u00e9f\u00e8re \u00e0 une morale et pr\u00e9tendrait par cons\u00e9quent nous faire croire qu&rsquo;il existe encore un ordre du monde. Nietzsche nous rappelle qu&rsquo;il n&rsquo;y a nulle pens\u00e9e qui soit fondamentalement coupable ou innocente, que toute pens\u00e9e est un peu innocente et coupable \u00e0 la fois, que d&rsquo;ailleurs ce n&rsquo;est pas le probl\u00e8me et que lui-m\u00eame &mdash; cela devrait tout r\u00e9gler pour ce domaine du proc\u00e8s qu&rsquo;on fait parfois \u00e0 Nietzsche &mdash; a \u00e9crit <em>Par-del\u00e0 le Bien et le Ma<\/em> et s&rsquo;est tenu \u00e0 cette maxime. En attaquant la morale, Nietzsche ne fait que nous signaler par avance ce que nous ne cessons de constater de toutes les fa\u00e7ons aux jours d&rsquo;aujourd&rsquo;hui : la morale devenue un faux-semblant, un masque si l&rsquo;on veut. La morale est destin\u00e9e \u00e0 tomber dans l&rsquo;escarcelle des m\u00e9diocres pour remplacer par la vertu le bon sens qu&rsquo;ils n&rsquo;ont pas et pour donner ce caract\u00e8re irresponsable si caract\u00e9ristique \u00e0 leur go&ucirc;t du pouvoir absolu derri\u00e8re les c\u00e9r\u00e9monies de la d\u00e9magogie d\u00e9mocratique.<\/p>\n<\/p>\n<p><p>Nietzsche commente, parfois avec exaltation parfois avec ironie, un monde de d\u00e9sordre qui se pare de l&rsquo;apparence de l&rsquo;organisation, le monde du d\u00e9sordre install\u00e9 par une \u00e9volution subversive de la pens\u00e9e humaine et peinturlur\u00e9 des apparences d&rsquo;un ordre d\u00e9crit comme moralement vertueux. Nietzsche attaque donc une m\u00e9thode, un penchant, une faiblesse g\u00e9n\u00e9rale de la pens\u00e9e, une d\u00e9cadence technique et camoufl\u00e9e, et nullement un parti ou un courant de pens\u00e9e. II refuse d&rsquo;\u00eatre partisan dans ce cas universel qui est le n\u00f4tre, o&ugrave; il y a une autre urgence que celle de faire triompher un parti ou de renforcer une tendance.<\/p>\n<\/p>\n<p><p>Mais tout le monde ne lit pas cela lorsqu&rsquo;on lit Nietzsche. Rien de plus normal, apr\u00e8s ce qu&rsquo;on vient de dire de lui (Nietzsche-auberge espagnole). Nietzsche est \u00e9galement une caution, un parapluie. Nietzsche est un argument pour les partisans de tous bords, et, par cons\u00e9quent, un diable pour ceux qui se situent \u00e0 l&rsquo;autre bord. On s&rsquo;y perd. La complexit\u00e9 de la perception qu&rsquo;on a de Nietzsche r\u00e9pond \u00e0 la complexit\u00e9 de Nietzsche. Cette complexit\u00e9 m\u00e9rite qu&rsquo;on s&rsquo;y arr\u00eate un peu : qui est cet homme qui a passionn\u00e9 tout un si\u00e8cle et qui reste para&icirc;t-il, aujourd&rsquo;hui encore, un myst\u00e8re toujours d\u00e9battu, et qui, demain, le restera pour beaucoup? (&laquo;<em>Derniers masques de Nietzsche <\/em>[&hellip;] <em>l&rsquo;\u00e9nigmatique cr\u00e9ateur de Zarathoustra<\/em>&raquo;, &mdash; titre d&rsquo;un article du <em>Monde<\/em> du 28 mai 1999.)<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">La pens\u00e9e-Nietzsche : un d\u00e9sordre plein de tout<\/h3>\n<\/p>\n<p><p>Nietzsche a ceci de particulier qu&rsquo;il est un des rares philosophes de cette dimension, le seul m\u00eame se permettrait-on d&rsquo;avancer, \u00e0 passionner \u00e0 la fois les philosophes (les \u00ab\u00a0techniciens de la philosophie\u00a0\u00bb), les penseurs, les historiens, les \u00e9crivains et les artistes, les hommes d&rsquo;action, et m\u00eame, dans les cat\u00e9gories inf\u00e9rieures, les journalistes et les \u00e9chotiers du temps pr\u00e9sent. II fait \u00e0 la fois partie de l&rsquo;histoire de la philosophie et de l&rsquo;actualit\u00e9 la plus br&ucirc;lante, de la r\u00e9flexion inspir\u00e9e et de \u00ab\u00a0l&rsquo;\u00e9cume des jours\u00a0\u00bb. II est &laquo;<em>l&rsquo;\u00e9nigmatique cr\u00e9ateur de Zarathoustra<\/em>&raquo; pour cela aussi, et m\u00eame pour cela d&rsquo;abord.<\/p>\n<\/p>\n<p><p>Effectivement, l&rsquo;homme et ses activit\u00e9s sont \u00e9videmment la cause de cette prog\u00e9niture si vari\u00e9e, &mdash; d&rsquo;o&ugrave; la difficult\u00e9 de la d\u00e9finir: Nietzsche est-il un moraliste de combat (l&rsquo;adversaire de Wagner et du <em>kulturkampf<\/em> allemand, l&rsquo;adversaire de &laquo;<em>la morale des esclaves<\/em>&raquo; chr\u00e9tienne), un po\u00e8te philosophique et \u00e9pique (<em>Ainsi Parlait Zarathoustra<\/em>), un philosophe fondateur et\/ou promoteur de diverses th\u00e8ses (l&rsquo;\u00e9ternel retour, le mythe du Surhumain, la &laquo; <em>volont\u00e9 de puissance<\/em> &raquo;), un visionnaire (\u00ab\u00a0Dieu est mort\u00a0\u00bb) ?<\/p>\n<\/p>\n<p><p>Les concepts nietzsch\u00e9ens (l&rsquo;\u00e9ternel retour, le surhumain, la volont\u00e9 de puissance, le d\u00e9passement de soi) sont c\u00e9l\u00e8bres. Ils sont le fond de commerce de Nietzsche-auberge espagnole. Chacun s&rsquo;y r\u00e9f\u00e8re en les jugeant exceptionnels &mdash; c&rsquo;est-\u00e0-dire: en jugeant exceptionnelle sa propre interpr\u00e9tation et en d\u00e9non\u00e7ant les autres interpr\u00e9tations. C&rsquo;est l\u00e0 un grave et persistant probl\u00e8me. Tant d&rsquo;interpr\u00e8tes des concepts nietzsch\u00e9ens ne font, en consid\u00e9rant Nietzsche, que projeter sur lui leur propre image. Il en r\u00e9sulte que les concepts nietzsch\u00e9ens charrient \u00e0 la fois le pire et le meilleur. La cause de ce d\u00e9sordre en est qu&rsquo;il ne s&rsquo;agit pas de concepts \u00e9labor\u00e9s mais de concepts visionnaires (l&rsquo;id\u00e9e d&rsquo;\u00e9ternel retour est venue \u00e0 Nietzsche devant le rocher de Sils-Maria, en Engadine, \u00e0 l&rsquo;\u00e9t\u00e9 1881 et l&rsquo;on peut alors \u00e9crire: &laquo;<em>Le probl\u00e8me, c&rsquo;est que Nietzsche affirme plus qu&rsquo;il ne d\u00e9montre<\/em>&raquo; [Roger Pol Droit]).<\/p>\n<\/p>\n<p><p>Il ne s&rsquo;agit pas de concepts compliqu\u00e9s et pr\u00e9cis\u00e9ment expliqu\u00e9s mais de concepts g\u00e9n\u00e9raux qui empruntent souvent \u00e0 l&rsquo;\u00e9vidence de l&rsquo;\u00e9lan vital et sont d\u00e9crits par une langue lyrique plus que par un langage philosophique abstrait. Chaque chapelle adapte le concept nietzsch\u00e9en \u00e0 son cat\u00e9chisme et sa signification en est fondamentalement brouill\u00e9e. II est difficile de prononcer l&rsquo;expression \u00ab\u00a0volont\u00e9 de puissance\u00a0\u00bb sans provoquer aussit\u00f4t, et avec autant de bonnes raisons parait-il, un froncement de sourcil d&rsquo;horreur et un hochement de t\u00eate approbateur de l&rsquo;\u00e9vidence.<\/p>\n<\/p>\n<p><p>La philosophie de Nietzsche est essentiellement une philosophie de pol\u00e9mique dont il est difficile de retirer des enseignements pr\u00e9cis. Si Nietzsche n&rsquo;\u00e9tait que philosophe, son enseignement ne serait que confusion et pol\u00e9mique et certains seraient fond\u00e9s de le juger comme un semeur de d\u00e9sordre de l&rsquo;esprit plus que comme un philosophe. Mais Nietzsche n&rsquo;est pas que philosophe et c&rsquo;est alors qu&rsquo;il devient passionnant, voire essentiel parce qu&rsquo;il est philosophe et qu&rsquo;en plus il est bien d&rsquo;autres choses.<\/p>\n<\/p>\n<p><p>La vie de Nietzsche, les \u00e9preuves qu&rsquo;il a subies, jouent un r\u00f4le fondamental dans sa d\u00e9marche intellectuelle. Promis \u00e0 une gloire conformiste dans les ann\u00e9es 1860 lorsqu&rsquo;il \u00e9tait \u00e9l\u00e8ve spirituel de Wagner et l&rsquo;une des grandes promesses de l&rsquo;universit\u00e9 allemande, il se d\u00e9tacha insensiblement mais irr\u00e9sistiblement de ce destin. Il abandonna son \u00ab\u00a0plan de carri\u00e8re\u00a0\u00bb. II choisit la solitude, c&rsquo;est-\u00e0-dire la marginalit\u00e9, c&rsquo;est-\u00e0-dire la dissidence <em>de facto<\/em>. En m\u00eame temps, il \u00e9tait de plus en plus touch\u00e9 par ses maux chroniques, notamment des migraines \u00e9pouvantables. Son oeuvre ressemble \u00e0 des \u00e9clairs presque aveuglants \u00e0 force d&rsquo;\u00eatre lumineux, n\u00e9s de rares moments d&rsquo;apaisement et d&rsquo;une disposition intellectuelle totalement retrouv\u00e9e. La vie de Nietzsche est un calvaire. A l&rsquo;heure de sombrer dans la folie, fin 1888, il signait ses lettres \u00ab\u00a0Le Crucifi\u00e9\u00a0\u00bb.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Nietzsche est-il un &laquo;<strong><em>g\u00e9nie de la critique<\/em><\/strong>&raquo;?<\/h3>\n<\/p>\n<p><p>Parmi les destinataires de ses lettres justement, un homme qui nous int\u00e9resse, son ami Franz Overbeck qui fut souvent \u00e0 ses c\u00f4t\u00e9s, qui l&rsquo;aida, le soutint, qui vint \u00e0 son secours lorsqu&rsquo;il s&rsquo;effondra \u00e0 Turin \u00e0 la fin de 1888. Overbeck est l&rsquo;ami fid\u00e8le mais nullement l&rsquo;ami aveugle. C&rsquo;est \u00e0 lui qu&rsquo;on s&rsquo;arr\u00eate, et \u00e0 ses <em>Souvenirs sur Fr\u00e9d\u00e9ric Nietzsche<\/em>. (1) Relus aujourd&rsquo;hui, les <em>Souvenirs<\/em> d&rsquo;Overbeck apparaissent tr\u00e8s actuels, comme s&rsquo;ils permettaient par avance d&rsquo;\u00f4ter les &laquo;<em>derniers masques<\/em>&raquo; de Nietzsche dont se plaignent encore les intellectuels et chroniqueurs pseudo-nietzsch\u00e9ens. &laquo;<em>Si l&rsquo;on regarde en arri\u00e8re ou si l&rsquo;on consid\u00e8re les choses sous un angle historique, aucune des pens\u00e9es qui sont apparues chez Nietzsche n&rsquo;est totalement nouvelle ni in\u00e9dite<\/em>&raquo; nous dit Overbeck assez justement, bouclant si on l&rsquo;en croit toutes les interrogations \u00e0 propos de la philosophie nietzsch\u00e9enne. Quant \u00e0 la solitude de notre philosophe, Overbeck tord le cou \u00e0 sa signification ontologique de fa\u00e7on aussi convaincante, pour lui assigner un r\u00f4le tactique et conscient : &laquo;<em>Nietzsche lui-m\u00eame \u00e9tait loin d&rsquo;\u00eatre aussi seul qu&rsquo;il le pensait <\/em> [NDLR : peut-\u00eatre Overbeck, en \u00e9crivant cela, pense-t-il notamment \u00e0 lui-m\u00eame?] ; <em>il ne fut pas v\u00e9ritablement un solitaire, mais il affectait la solitude ou s&rsquo;y complaisait et voulait \u00eatre un solitaire.<\/em>&raquo; Overbeck semble r\u00e9duire son ami Nietzsche si l&rsquo;on se r\u00e9f\u00e8re \u00e0 la vision conformiste qu&rsquo;on en a. Peut-\u00eatre en r\u00e9alit\u00e9 le grandit-il en d\u00e9finissant sa r\u00e9alit\u00e9.<\/p>\n<\/p>\n<p><p>Dispers\u00e9e, l&rsquo;image du Nietzsche solitaire \u00e9grenant les v\u00e9rit\u00e9s du monde pour un monde hostile. (La r\u00e9alit\u00e9 historique va dans le sens de l&rsquo;interpr\u00e9tation d&rsquo;Overbeck. Dr\u00f4le de solitaire que cet homme qui a d\u00e9lib\u00e9r\u00e9ment choisi la solitude en se plaignant d&rsquo;\u00eatre un incompris, et qui, malgr\u00e9 l&rsquo;\u00e9norme handicap de ses maux terribles trouve toujours dans ses amis de fid\u00e8les secr\u00e9taires pour transcrire ses oeuvres, voire pour les coucher sur papier quand lui-m\u00eame ne peut le faire ; qui, malgr\u00e9 cet \u00e9norme handicap \u00ab\u00a0de communication\u00a0\u00bb, comme on dit aujourd&rsquo;hui, qu&rsquo;est sa solitude, est tenu par nombre de ses contemporains, notamment et surtout \u00e0 Paris \u00e0 partir des ann\u00e9es 1880, comme un des grands esprits du si\u00e8cle, un philosophe fondamental, et dont la gloire ne cessera plus jusqu&rsquo;\u00e0 nous. C&rsquo;est un des grands myst\u00e8res du philosophe, et un des grands miracles de notre culture, que malgr\u00e9 des donn\u00e9es objectives catastrophiques, &mdash; solitude, tirages confidentiels de ses &oelig;uvres, etc, &mdash; Nietzsche est reconnu en Europe, avant m\u00eame qu&rsquo;il ne devienne fou, comme un des grands esprits de l&rsquo;histoire de la pens\u00e9e occidentale.)<\/p>\n<\/p>\n<p><p>Overbeck va plus loin: dispers\u00e9e \u00e9galement, l&rsquo;image de la pens\u00e9e nietzsch\u00e9enne qui bouleverse le monde. (Et, dans ce cas, esprit n&rsquo;est pas pens\u00e9e.) Pour Overbeck, Nietzsche est un g\u00e9nie d&rsquo;une forme tr\u00e8s particuli\u00e8re. &laquo;<em>Nietzsche \u00e9tait un g\u00e9nie mais son g\u00e9nie r\u00e9sidait dans son talent de critique.<\/em>&raquo; Cette interpr\u00e9tation appara&icirc;t \u00e0 la r\u00e9flexion comme extr\u00eamement enrichissante. Surtout, elle devrait nous \u00e9clairer lorsqu&rsquo;elle est prolong\u00e9e d&rsquo;une autre r\u00e9flexion d&rsquo;Overbeck sur ce qu&rsquo;est r\u00e9ellement Fr\u00e9d\u00e9ric Nietzsche, en tous les cas selon son point de vue, Overbeck signale combien Nietzsche n&rsquo;h\u00e9sita pas \u00e0 porter sa vision critique qui fait son g\u00e9nie d&rsquo;abord contre lui-m\u00eame, et ainsi donnant une explication acceptable psychologiquement du d\u00e9s\u00e9quilibre nietzsch\u00e9en qui conduisit, ou acc\u00e9l\u00e9ra la chute vers la folie. &laquo;<em>L&rsquo;usage qu&rsquo;il a fait de ce talent critique, \u00e0 savoir l&rsquo;appliquer \u00e0 lui-m\u00eame, \u00e9tait le plus dangereux qui fut ; c&rsquo;\u00e9tait en r\u00e9alit\u00e9 un usage fatal Celui qui de mani\u00e8re exclusive mit autant d&rsquo;\u00e9nergie \u00e0 se faire lui-m\u00eame objet d&rsquo;un talent critique aussi g\u00e9nial \u00e9tait n\u00e9cessairement vou\u00e9 \u00e0 la folie et \u00e0 l&rsquo;autodestruction.<\/em>&raquo; (Cette id\u00e9e se retrouve chez certains, en plus \u00e9labor\u00e9e. Estimant la folie de Nietzsche comme l&rsquo;ach\u00e8vement logique, et donc voulu, d&rsquo;un parcours de la pens\u00e9e que le philosophe a lui-m\u00eame ordonn\u00e9, Pierre Klossowski sugg\u00e8re que cette folie aura \u00e9t\u00e9 &laquo;<em>une d\u00e9cision ultime, l&rsquo;accomplissement d&rsquo;un projet existentiel, consistant \u00e0 faire exploser l&rsquo;identit\u00e9 du sujet, \u00e0 assumer une pluralit\u00e9, une discontinuit\u00e9 nouvelle<\/em>&raquo;.)<\/p>\n<\/p>\n<p><p>A la lumi\u00e8re de ces appr\u00e9ciations, on pourrait dire que Nietzsche paya comptant, par le traitement qu&rsquo;il s&rsquo;appliqua \u00e0 lui-m\u00eame (et, accessoirement, par l&rsquo;existence qu&rsquo;il se m\u00e9nagea), le droit d&rsquo;observer le monde avec son g\u00e9nie de critique sans restriction, sans retenue. A cet \u00e9gard, sans le moindre doute, Nietzsche est un esprit h\u00e9ro\u00efque.<\/p>\n<\/p>\n<p><p>Nietzsche fut donc le g\u00e9nie-critique, l&rsquo;homme de la &laquo;<em>philosophie au marteau<\/em>&raquo;, c&rsquo;est-\u00e0-dire de la critique ass\u00e9n\u00e9e \u00e0 coups de marteau. On a l&rsquo;explication de sa modernit\u00e9 qui serait ainsi celle d&rsquo;un \u00ab\u00a0anti-moderne\u00a0\u00bb \u00e9vident, et m\u00eame, plus encore, de sa compl\u00e8te actualit\u00e9. Nietzsche s&rsquo;attaque \u00e0 l&rsquo;essentiel et au plus urgent: la critique syst\u00e9matique d&rsquo;une \u00e9poque dont la subversion, amplement d\u00e9montr\u00e9e par les \u00e9v\u00e9nements du XXe si\u00e8cle et par le couronnement subversif qu&rsquo;est cette fin de si\u00e8cle que nous vivons, m\u00e9rite d&rsquo;abord d&rsquo;\u00eatre soumise \u00e0 ce feu. Avant de songer \u00e0 construire une belle architecture, il importe de d\u00e9truire l&rsquo;horrible construction bancale mise en place. Celle-ci d\u00e9truite, on devra tout repenser en fonction du nouveau paysage apparu ; celle-ci d\u00e9truite, peut-\u00eatre le monde nouveau nous sugg\u00e9rera la voie de l&rsquo;h\u00e9ro\u00efsme<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Le paradoxal optimisme de Nietzsche<\/h3>\n<\/p>\n<p><p>Du coup, l&rsquo;image qu&rsquo;on peut avoir de Nietzsche devient tr\u00e8s diff\u00e9rente. Il s&rsquo;agit moins d&rsquo;un philosophe s&rsquo;inscrivant dans la continuit\u00e9 de la pens\u00e9e et de la philosophie elle-m\u00eame que d&rsquo;un destructeur, un homme-rupture. Certes, tout philosophe est un peu une rupture par la nouveaut\u00e9 qu&rsquo;il pr\u00e9tend apporter par sa philosophie, mais Nietzsche l&rsquo;est de fa\u00e7on substantielle et ontologique. II est homme-rupture avant d&rsquo;\u00eatre philosophe et il l&rsquo;est par la forme autant que par le fond. Nietzsche affectionnait de dire qu&rsquo;il philosophait au marteau, entendant par l\u00e0 qu&rsquo;il ass\u00e9nait ses v\u00e9rit\u00e9s simples comme avec un marteau et qu&rsquo;il ne cessait de taper sur le clou pour mieux l&rsquo;enfoncer. Effectivement, sa litt\u00e9rature et sa r\u00e9flexion sont faites \u00e0 coups de marteau, et l&rsquo;on peut aussi bien appr\u00e9cier que l&rsquo;instrument lui sert d&rsquo;abord \u00e0 frapper sur les murs vermoulus de l&rsquo;architecture en place.<\/p>\n<\/p>\n<p><p>Le fond de son attitude est le d\u00e9sespoir. C&rsquo;est un d\u00e9sespoir tr\u00e8s particulier, un d\u00e9sespoir utilis\u00e9 de fa\u00e7on offensive, pour animer le marteau. Le paradoxe est que cet aspect de d\u00e9sespoir qu&rsquo;on trouve chez Nietzsche engendre un optimisme conqu\u00e9rant dans l&rsquo;activit\u00e9 du philosophe, dans son lyrisme, dans la puissance de son verbe, et surtout, enfin, dans la conviction extraordinaire qui anime ses \u00e9crits. Overbeck note effectivement cela: &laquo;<em>L&rsquo;optimisme de Nietzsche est bel et bien celui d&rsquo;un desperado. Il se pr\u00e9vaut des ressources illimit\u00e9es de son imagination pour lutter contre le d\u00e9sespoir et il s&rsquo;appuie sur l&rsquo;infinit\u00e9 du d\u00e9sespoir pour \u00e9touffer l&rsquo;imagination.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>L\u00e0 aussi, comme dans le cas du nihilisme qu&rsquo;on a pr\u00e9sent\u00e9 au d\u00e9but, Nietzsche appara&icirc;t comme un manipulateur des sentiments et des caract\u00e9ristiques psychologiques les plus profonds. Il s&rsquo;en sert comme on se sert d&rsquo;outils pour appuyer une (sa) philosophie qui est d&rsquo;abord une exhortation, et dans laquelle, par cons\u00e9quent (et l&rsquo;on retrouve les remarques d\u00e9j\u00e0 faites sur le contenu), l&rsquo;\u00e9lan compte plus que le contenant. La force de Nietzsche semble \u00eatre effectivement que les sentiments et les \u00e9tats d&rsquo;esprit les plus fondamentaux, ceux dont on juge qu&rsquo;ils peuvent orienter ou d\u00e9s-orienter une soci\u00e9t\u00e9 et une civilisation, ne sont chez lui que des outils dont il use tactiquement. Nietzsche est d\u00e9sesp\u00e9r\u00e9 (on serait tent\u00e9 d&rsquo;ajouter : \u00e9videmment), mais son comportement, son jugement, son analyse ne sont pas fondamentalement affect\u00e9s par cet \u00e9tat d&rsquo;esprit. Il ne joue pas (dans le sens d&rsquo;interpr\u00e9ter) son d\u00e9sespoir qui est bien r\u00e9el mais il en joue sans aucun doute. Nietzsche s&rsquo;est sorti de la dimension humaine o&ugrave; le d\u00e9sespoir semble l&rsquo;ultime sanction du sentiment qu&rsquo;on peut avoir de l&rsquo;existence, pour se placer en-dehors et au-del\u00e0, et en jouer selon les n\u00e9cessit\u00e9s. Le d\u00e9sespoir n&rsquo;est plus, avec Nietzsche, la description d&rsquo;une situation sans issue mais un \u00e9l\u00e9ment du jeu qui permet de faire avancer sa description philosophique de la situation terrestre.<\/p>\n<\/p>\n<p><p>De m\u00eame qu&rsquo;il est par-del\u00e0 le Bien et le Mal, et notamment \u00e0 cause de cela du reste, il est par-del\u00e0 l&rsquo;espoir et le d\u00e9sespoir. Le jugement d&rsquo;Overbeck selon lequel la d\u00e9marche critique de Nietzsche, n\u00e9cessairement une autocritique, \u00e9tait \u00e9videmment &laquo;<em>auto-destructrice<\/em>&raquo;, nous para&icirc;t particuli\u00e8rement justifi\u00e9e, et plus simplement, &mdash; tout simplement juste. L&rsquo;admirable chez Nietzsche, dans cette utilisation de ses traits de caract\u00e8re fondamentaux pour l&rsquo;usage de son sujet d&rsquo;analyse qui n&rsquo;est rien d&rsquo;autre que la destin\u00e9e du genre humain, c&rsquo;est que cette utilisation impliquait son d\u00e9s\u00e9quilibre et sa chute.<\/p>\n<\/p>\n<p><p>L&rsquo;autocritique implicite de Nietzsche \u00e9tait n\u00e9cessairement &laquo;<em>auto-destruction<\/em>&raquo;. C&rsquo;est le sacrifice ultime, accompli en toute conscience de son utilit\u00e9 fondamentale pour la destin\u00e9e du genre humain.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Nietzsche et la France : une rencontre significative<\/h3>\n<\/p>\n<p><p>N\u00e9 en Allemagne (il aimait insister sur ses origines polonaises), pr\u00e9sent\u00e9 aussi bien et contradictoirement comme l&rsquo;arch\u00e9type de l&rsquo;Allemand et comme le contraire du \u00ab\u00a0philosophe allemand\u00a0\u00bb \u00e0-la-Kant, Nietzsche n&rsquo;est pleinement devenu lui-m\u00eame que \u00ab\u00a0francis\u00e9\u00a0\u00bb. Il l&rsquo;est tellement qu&rsquo;on parle aujourd&rsquo;hui d&rsquo;un \u00ab\u00a0Nietzsche fran\u00e7ais\u00a0\u00bb, tandis que le Nietzsche originel, le \u00ab\u00a0Nietzsche allemand\u00a0\u00bb, est plut\u00f4t laiss\u00e9 au purgatoire par des Allemands qui s&rsquo;effraient de toute pens\u00e9e un peu ferme et un peu haute parce qu&rsquo;elle semblerait devoir menacer leur r\u00e9cente vertu d\u00e9mocratique.<\/p>\n<\/p>\n<p><p>La gloire fran\u00e7aise de Nietzsche fut aussit\u00f4t tr\u00e8s haute et ne se d\u00e9mentit jamais, au travers de plusieurs \u00e9poques qui la relanc\u00e8rent (trois pr\u00e9cis\u00e9ment, d\u00e9sign\u00e9s comme les &laquo;<em>Moments fran\u00e7ais de Nietzsche<\/em>&raquo; : 1889-1914, les ann\u00e9es 1930 et \u00e0 partir de 1960). Il n&rsquo;y a aucune gloire litt\u00e9raire (insistons sur le qualificatif) \u00e9trang\u00e8re qui re\u00e7ut un tel accueil en France, sinon, momentan\u00e9ment, les grands \u00e9crivains russes (Tolsto\u00ef et Dosto\u00efevski) au XIXe si\u00e8cle, et, peut-\u00eatre, de fa\u00e7on plus diffuse mais bien \u00e9tablie, les \u00e9crivains am\u00e9ricains en tant que groupe culturel. Surtout, Nietzsche fut parfaitement compris, d\u00e8s l&rsquo;origine, parce qu&rsquo;il toucha encore plus les artistes que les philosophes, et qu&rsquo;il les toucha comme il convient (cette remarque vaut moins pour la p\u00e9riode depuis 1960, o&ugrave; la philosophie et surtout l&rsquo;Universit\u00e9 fran\u00e7aises se sont empar\u00e9es de Nietzsche ; ce n&rsquo;est peut-\u00eatre pas la meilleure chose du monde).<\/p>\n<\/p>\n<p><p>Sa proximit\u00e9 avec Stendhal, avec Flaubert, avec Baudelaire, est connue. Gide \u00e9crivait en 1898 ceci qui correspond si bien \u00e0 l&rsquo;interpr\u00e9tation artistique et litt\u00e9raire de Nietzsche : &laquo;<em>L&rsquo;influence de Nietzsche a pr\u00e9c\u00e9d\u00e9 chez nous l&rsquo;apparition de son oeuvre <\/em>[&#8230;] <em>Je l&rsquo;attendais avant de le conna&icirc;tre &mdash; de le conna&icirc;tre f&ucirc;t-ce de nom<\/em>&#8230; [&#8230;] <em>Et pas \u00e0 pas ensuite, le lisant, il me semblait qu&rsquo;il excitait mes pens\u00e9es.<\/em>&raquo; Cette approche de Nietzsche, intuitive, artistique et litt\u00e9raire tout ensemble, se retrouve chez nombre d&rsquo;\u00e9crivains fran\u00e7ais de cette \u00e9poque. Paul Valery, ami de Gide, \u00e9crivait (mi-captiv\u00e9 mi-inquiet) que &laquo;<em>Nietzsche n&rsquo;est pas une nourriture &mdash; c&rsquo;est un stimulant. <\/em>[&#8230;] <em>Nietzsche ne repr\u00e9sente pas la \u00ab\u00a0philosophie\u00a0\u00bb (heureusement pour lui) &mdash; mais un compositeur, un \u00ab\u00a0po\u00e8te\u00a0\u00bb du syst\u00e8me nerveux<\/em>&raquo; ; pour Charles Du Bos, Nietzsche \u00e9tait &laquo;<em>un climat et un tonique de l&rsquo;\u00e2me<\/em>&raquo; ; pour Romain Rolland, &laquo;<em>la Solitude libre<\/em>&raquo;. Ainsi 1&prime;\u00a0\u00bbesprit de Nietzsche\u00a0\u00bb pr\u00e9c\u00e8de Nietzsche, et m\u00eame, peut-\u00eatre, a-t-il toujours \u00ab\u00a0\u00e9t\u00e9\u00a0\u00bb le v\u00e9ritable Nietzsche \u00e0 la place du Nietzsche-philosophe, ou du Nietzsche-proph\u00e8te, ou du Nietzsche-scandaleux.<\/p>\n<\/p>\n<p><p>On est conduit \u00e0 interpr\u00e9ter cet \u00e9v\u00e9nement d&rsquo;un Nietzsche francis\u00e9 au-del\u00e0 de l&rsquo;histoire de la litt\u00e9rature ou de la philosophie. La francisation de Nietzsche, si durable et si constante et profonde, c&rsquo;est la rencontre d&rsquo;un \u00eatre exceptionnel par sa vision qui le sort du commun de ses confr\u00e8res, avec une nation qui s&rsquo;affirma constamment et qui est aujourd&rsquo;hui plus que jamais, par les caract\u00e8res tragiques et h\u00e9ro\u00efques qui forment sa sp\u00e9cificit\u00e9, une exception (l&rsquo; \u00ab\u00a0exception fran\u00e7aise\u00a0\u00bb, comprise de fa\u00e7on sensible et intelligente) repr\u00e9sentant une des rares possibilit\u00e9s restantes d&rsquo;attaquer la d\u00e9cadence l\u00e0 o&ugrave; il importe de le faire. Nous parlons ici d&rsquo;\u00e9tats d&rsquo;esprit g\u00e9n\u00e9raux plus que de faits pr\u00e9cis, d&rsquo;images et de perceptions plus que d&rsquo;une philosophie pr\u00e9cise ou d&rsquo;une attitude politique sp\u00e9cifique. Nous parlons d'\u00a0\u00bb\u00e9tat d&rsquo;esprit\u00a0\u00bb plus que du contenu d&rsquo;un esprit. Enfin, nous parlons de la perception qu&rsquo;on a de Nietzsche et de la perception qu&rsquo;on a de l&rsquo;exception fran\u00e7aise, et effectivement tout d\u00e9pend de ces perceptions, et si ces perceptions s&rsquo;av\u00e8rent fauss\u00e9es les deux exceptions sombrent dans la radicalisation, dans la p\u00e9danterie ou dans le malentendu.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Nietzsche, ou le devoir de critique<\/h3>\n<\/p>\n<p><p>Ainsi Nietzsche appara&icirc;t-il aujourd&rsquo;hui dans la perception qu&rsquo;on en a bien plus fran\u00e7ais que nombre de Fran\u00e7ais qui rejette le contenu oppositionnel et dissident de l&rsquo;exception fran\u00e7aise. Cette rencontre entre Nietzsche et l&rsquo;exception fran\u00e7aise est des plus actuelles en ce sens quelle s&rsquo;inscrit dans le contexte d&rsquo;une critique radicale de la situation moderniste et dans la perspective d&rsquo;une r\u00e9sistance d\u00e9termin\u00e9e aux courants de d\u00e9sagr\u00e9gation subversive que charrient les th\u00e8ses anti-identitaires de la globalisation. Il s&rsquo;agit d&rsquo;une rencontre totale, avec ses bons et ses mauvais aspects (Nietzsche interpr\u00e9t\u00e9 comme exemple d&rsquo;\u00e9nergie, comme po\u00e8te, comme philosophe, etc). C&rsquo;est une rencontre si puissante qu&rsquo;on est amen\u00e9 \u00e0 constater que c&rsquo;est l&rsquo;analyse fran\u00e7aise de Nietzsche qui, dans les ann\u00e9es 1970, relan\u00e7a l&rsquo;\u00e9tude de Nietzsche aux &Eacute;tats-Unis ; qu&rsquo;on est amen\u00e9 \u00e0 constater \u00e9galement que Nietzsche existe plus aujourd&rsquo;hui en France qu&rsquo;en Allemagne, et que, pour r\u00e9introduire Nietzsche en Allemagne, comme le sugg\u00e8re ironiquement Jacques Le Rider (2), &laquo;[i]<em>l faudrait en somme retraduire Nietzsche en allemand<\/em>&raquo;.<\/p>\n<\/p>\n<p><p>Nietzsche g\u00e9nie critique, Nietzsche francis\u00e9, Nietzsche-philosophe dont on ignore s&rsquo;il n&rsquo;est pas d&rsquo;abord po\u00e8te &#8230; Il y a, dans cette confusion comme dans la persistance de la pr\u00e9sence de Nietzsche sans qu&rsquo;on parvienne \u00e0 d\u00e9terminer ce que cette pr\u00e9sence apporte exactement, un signe de sa n\u00e9cessit\u00e9 autant que de la profondeur de la crise que nous traversons. Ce que nous lisons chez Nietzsche depuis un si\u00e8cle, c&rsquo;est une mise au point permanente sur la m\u00e9fiance n\u00e9cessaire \u00e0 l&rsquo;encontre de l&rsquo;\u00e9tat du monde. Nietzsche est donc actuel. Il le sera de plus en plus au fur et \u00e0 mesure que le monde s&rsquo;ab&icirc;mera dans l&rsquo;\u00e9tat du d\u00e9sordre postmoderne qu&rsquo;on lui conna&icirc;t d\u00e9j\u00e0.<\/p>\n<\/p>\n<p><p>Nietzsche nous oblige et nous rend cr\u00e9diteur, c&rsquo;est-\u00e0-dire responsable. Il est une part de nous-m\u00eame, cette part qui nous emp\u00eache de sombrer compl\u00e8tement dans le monde orwellien d&rsquo;un 1984 postmoderne. Il est celui qui nous impose la n\u00e9cessit\u00e9 d&rsquo;\u00eatre critique, et surtout qui nous impose la n\u00e9cessit\u00e9 de l&rsquo;existence de la critique, dans un monde dont la d\u00e9cadence, si \u00e9vidente qu&rsquo;on n&rsquo;en discute plus que la forme et la vitesse, s&rsquo;ach\u00e8vera le jour o&ugrave; il sera proclam\u00e9 que la critique n&rsquo;y a plus sa place. Nietzsche, c&rsquo;est par cons\u00e9quent la libert\u00e9 bon gr\u00e9 mal gr\u00e9, et la libert\u00e9 non parce qu&rsquo;il en use et en proclame, comme aujourd&rsquo;hui o&ugrave; la libert\u00e9 est partout proclam\u00e9e alors que nous n&rsquo;avons jamais \u00e9t\u00e9 moins libre, mais \u00e0 cause de ce qu&rsquo;il met dans cette libert\u00e9, qui est la critique \u00e0 coups de marteau.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955;font-size:1.25em;\">Notes<\/h3>\n<\/p>\n<p><p>(1) Souvenirs sur Fr\u00e9d\u00e9ric Nietzsche, \u00e9ditions Allia, Paris, 1999.<\/p>\n<\/p>\n<p><p>(2) Nietzsche en France, PUF,1999.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;homme du si\u00e8cle &#8230; Mais de quel si\u00e8cle? Le XXe ou le XXIe? Le philosophe Fr\u00e9d\u00e9ric Nietzsche est mort le 25 ao&ucirc;t 1900 et nous venons de comm\u00e9morer le centenaire de sa disparition. Plus qu&rsquo;un philosophe, c&rsquo;est un visionnaire, une r\u00e9f\u00e9rence, un symbole et un myst\u00e8re. Son oeuvre, \u00e9crite dans la douleur et la solitude,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[3077,3075,2856,2631,3076,2655,3073,3074],"class_list":["post-64885","post","type-post","status-publish","format-standard","hentry","category-de-defensa","tag-anti-moderne","tag-coups","tag-critique","tag-de","tag-marteau","tag-modernite","tag-nietzsche","tag-philosophe"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/64885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=64885"}],"version-history":[{"count":1,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/64885\/revisions"}],"predecessor-version":[{"id":64904,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/64885\/revisions\/64904"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=64885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=64885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=64885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}