{"id":64891,"date":"1997-05-01T00:00:00","date_gmt":"1997-04-30T22:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/1997\/05\/01\/la-destinee-manifeste-par-les-armes\/"},"modified":"2026-03-12T20:57:52","modified_gmt":"2026-03-12T18:57:52","slug":"la-destinee-manifeste-par-les-armes","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/1997\/05\/01\/la-destinee-manifeste-par-les-armes\/","title":{"rendered":"La &lsquo;\u201cdestin\u00e9e manifeste\u201d par les armes"},"content":{"rendered":"<p><h2 class=\"common-article\">La &lsquo;destin\u00e9e manifeste par les armes<\/h2>\n<\/p>\n<p><p>\tY a-t-il une ambition sp\u00e9cifique, un dessein particulier des \u00c9tats-Unis \u00e0 l&rsquo;\u00e9gard des exportations d&rsquo;armement, objet depuis 1989 de leurs efforts et de leurs pressions les plus intenses et les plus agressifs ? Y a-t-il autre chose que la seule dynamique mercantile de la recherche de nouveaux march\u00e9s ? <\/p>\n<\/p>\n<p><p>\tPlus pr\u00e9cis\u00e9ment, y a-t-il une strat\u00e9gie de \u00ab\u00a0domination du monde\u00a0\u00bb, comme certains l&rsquo;ont sugg\u00e9r\u00e9 ? Ces questions m\u00e9ritent une attention particuli\u00e8re qui passe d&rsquo;abord par la r\u00e9f\u00e9rence historique, tr\u00e8s \u00e9clairante pour le cas am\u00e9ricain.<\/p>\n<h3>L&rsquo;\u00e9tablissement du \u00ab\u00a0Complexe militaro-industriel\u00a0\u00bb<\/h3>\n<\/p>\n<p><p>\tL&rsquo;id\u00e9e de domination du monde per\u00e7ue non comme acte de conqu\u00eate \u00e0caract\u00e8re historique mais comme \u00ab\u00a0Destin\u00e9e manifeste\u00a0\u00bb (1) relevant du mythe originel qui transformerait l&rsquo;Histoire en se r\u00e9alisant, est \u00e0 la fois ontologique et r\u00e9curente aux \u00c9tats-Unis. Elle a des racines religieuses et mystiques \u00e9videntes (repr\u00e9sentation de l&rsquo;Am\u00e9rique comme \u00ab\u00a0terre promise\u00a0\u00bb, mod\u00e8le pour le reste du monde et auquel le reste du monde ne peut qu&rsquo;adh\u00e9rer). Elle s&rsquo;exprime explicitement, pour les justifier, dans les entreprises les plus mat\u00e9rialistes de la grande R\u00e9publique, dont la principale est la conqu\u00eate commerciale des march\u00e9s ext\u00e9rieurs. Depuis les origines, elle fut constat\u00e9e dans les faits par les observateurs perspicaces et constamment r\u00e9affirm\u00e9e dans les d\u00e9clarations am\u00e9ricaines les plus officielles. En 1829 un jeune capitaine anglais en visite aux \u00c9tats-Unis, Bedford H. Wilson, \u00e9crivit au lib\u00e9rateur sud-am\u00e9ricain Salazar dont il \u00e9tait un compagnon d&rsquo;armes ce jugement sur l&rsquo;Am\u00e9rique qui devrait appara\u00eetre comme une intuition fulgurante aujourd&rsquo;hui : <em>\u00ab Plus je vois ce pays extraordinaire, plus je suis stup\u00e9fi\u00e9 des grands progr\u00e8s qu&rsquo;il fait et qu&rsquo;il continue \u00e0 faire. Quelque jour, peut-\u00eatre, il se d\u00e9membrera ; je le d\u00e9sire pour le bien de l&rsquo;humanit\u00e9. Sinon, ce colosse sera encore plus terrible que les hordes de la Russie. Son ambition d\u00e9passe ses progr\u00e8s ; elle est plus vaste que son territoire. Il ne sera satisfait que lorsqu&rsquo;il sera le ma\u00eetre des destin\u00e9es du monde. \u00bb<\/em> (2) <\/p>\n<\/p>\n<p><p>\tL&rsquo;id\u00e9e de domination du monde est aussi pr\u00e9sente \u00e0 la fin du XIXe si\u00e8cle, avec les premi\u00e8res exp\u00e9ditions outre-mer (Cuba, les Philippines) sous McKinley et Th\u00e9odore Roosevelt) ; elle est pr\u00e9sente avec Woodrow Wilson, pr\u00e9sident de 1912 \u00e0 1920, avec son r\u00f4le fondamental dans le Trait\u00e9 de Versailles qui redessina la carte de l&rsquo;Europe ; et encore dans la d\u00e9cennie des ann\u00e9es 1920 avec la formidable expansion du commerce am\u00e9ricain, o\u00f9 une \u00ab\u00a0industrie\u00a0\u00bb comme le cin\u00e9ma US \u00e9tait explicitement per\u00e7ue comme un instrument d&rsquo;h\u00e9g\u00e9monie culturelle encore plus fortement qu&rsquo;aujourd&rsquo;hui ; et encore avec la victoire de 1945 et l&rsquo;\u00e9tablissement du \u00ab\u00a0Monde libre\u00a0\u00bb face \u00e0 l&rsquo;URSS &#8230; jusqu&rsquo;\u00e0 aujourd&rsquo;hui, o\u00f9 l&rsquo;id\u00e9e, avec une vigueur renouvel\u00e9e, baigne implicitement toute la dialectique am\u00e9ricaniste.<\/p>\n<\/p>\n<p><p>\tUne seconde r\u00e9f\u00e9rence historique am\u00e9ricaine importante est le penchant de l&rsquo;\u00e9conomie US pour les cycles de guerre, et sa capacit\u00e9 d&rsquo;en tirer profit pour ses structures g\u00e9n\u00e9rales.<\/p>\n<\/p>\n<p><p>\tLe ph\u00e9nom\u00e8ne apparut avec la Guerre de S\u00e9cession, du c\u00f4t\u00e9 du Nord. \u00c9lu pr\u00e9sident en 1860 et aussit\u00f4t tr\u00e8s isol\u00e9 face \u00e0 la r\u00e9bellion du Sud et aux attitudes ambig\u00fces de nombre d&rsquo;\u00c9tats du Nord, Lincoln trouva comme principal appui la puissance financi\u00e8re et industrielle du Nord-Est. Celle-ci jugeait l&rsquo;enjeu du conflit capital pour elle : son but \u00e9tait d&rsquo;instituer une sorte de march\u00e9 unique prot\u00e9g\u00e9 relevant totalement du protectionnisme, en imposant de nouvelles r\u00e8gles \u00e9conomiques au Sud producteur de coton et libre-\u00e9changiste. La guerre de 1861-65 fut la matrice d&rsquo;un prodigieux <em>boom<\/em> \u00e9conomique pour une industrie qui, \u00e0la diff\u00e9rence des traditions europ\u00e9ennes, n&rsquo;accepte pas dans ces circonstances la mobilisation au nom de la nation mais effectue une formidable mont\u00e9e en puissance de la production qui ne modifie rien au fonctionnement capitaliste courant (lois du march\u00e9, d\u00e9veloppement du gain, recherche du monopole, etc.). Suivit, jusqu&rsquo;autour des ann\u00e9es 1890 (le <em>Gilded Age<\/em>), un d\u00e9veloppement capitalistique et industriel sauvage et d&rsquo;une puissance rarement \u00e9gal\u00e9e dans l&rsquo;histoire \u00e9conomique. Le m\u00eame processus, fond\u00e9 sur la capacit\u00e9 de profiter d&rsquo;une fa\u00e7on ou de l&rsquo;autre des ann\u00e9es de guerre, fut r\u00e9p\u00e9t\u00e9 avec les deux Guerres mondiales. Le professeur Frank Kosky, de l&rsquo;universit\u00e9 de Californie du Sud, d\u00e9crit le ph\u00e9nom\u00e8ne : \u00ab<em>Durant les ann\u00e9es de guerre, d&rsquo;importants achats de mat\u00e9riels militaires am\u00e9ricains  d&rsquo;abord par les Alli\u00e9s, ensuite par le gouvernement am\u00e9ricain lui-m\u00eame apr\u00e8s l&rsquo;entr\u00e9e en guerre d&rsquo;avril 1917  amena un quasi-plein emploi.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;essentiel de la production \u00e9tant destin\u00e9e aux champs de bataille, il n&rsquo;y avait gu\u00e8re de produits pour les consommateurs. Ceux-ci r\u00e9alis\u00e8rent ce que les \u00e9conomistes nomment de l&rsquo;\u00e9pargne forc\u00e9e. \u00ab<em>A la fin de la guerre, il y avait des masses de liquidit\u00e9s pr\u00eates \u00e0 alimenter une explosion de la consommation <\/em>[qui eut lieu] <em>durant la premi\u00e8re moiti\u00e9 des ann\u00e9es vingt. Simultan\u00e9ment, le conflit avait amen\u00e9 d\u00e9vastation et pauvret\u00e9 dans le monde, surtout en Europe, march\u00e9 traditionnel pour les exportations am\u00e9ricaines. <\/em>[&#8230;] <em>La Grande D\u00e9pression des ann\u00e9es trente stoppa temporairement la consommation. Mais conduite ensuite \u00e0 une nouvelle phase d&rsquo;\u00e9pargne forc\u00e9e durant la Deuxi\u00e8me Guerre, la consommation repartit avec force d\u00e8s que les combats cess\u00e8rent. Une fois de plus, comme dans les ann\u00e9es 1920, <\/em>[il y eut] <em>une \u00e9norme demande int\u00e9rieure coupl\u00e9e avec les destructions inimaginables outremer &#8230;<\/em> \u00bb (3)<\/p>\n<\/p>\n<p><p>\tUn troisi\u00e8me aspect historique doit \u00eatre relev\u00e9, avec la constitution, entre 1935 et 1947, d&rsquo;un ph\u00e9nom\u00e8ne \u00e9conomique, et m\u00eame g\u00e9o\u00e9conomique avant la lettre, unique au monde, baptis\u00e9 par le pr\u00e9sident Eisenhower dans un discours fameux du 17 janvier 1961 \u00ab\u00a0Complexe Militaro-Industriel\u00a0\u00bb (CMI). Il serait erron\u00e9 de s&rsquo;en tenir aux aspects habituels de l&rsquo;influence des militaires ou des \u00ab\u00a0marchands de canon\u00a0\u00bb. Le CMI porte initialement une ambition de conqu\u00eate du monde, alors que ses liens avec les militaires sont t\u00e9nus, voire inexistants. La v\u00e9ritable fondation du CMI date des ann\u00e9es 1930, \u00e0 partir d&rsquo;un noyau d&rsquo;universitaires, de millionnaires du <em>Big Business<\/em>, de R\u00e9publicains de la tendance Hoover-Taft, et de l&rsquo;industrie a\u00e9ronautique naissante en Californie du Sud. Ce vaste projet techno-industriel regroup\u00e9 autour d&rsquo;un triangle scientifico-industriel (la Huntington Library, l&rsquo;observatoire de Pasadena et surtout le California Institute of Technology, ou CalTech) avait indubitablement des orientations philosophiques et spirituelles, voire des connotations racistes spiritualistes ; on note m\u00eame, d\u00e8s cet \u00e9poque, des contacts avec la scientologie en d\u00e9veloppement. Roger Millikan, Prix Nobel de physique et Pr\u00e9sident de CalTech d\u00e9finissait le projet de cette fa\u00e7on en 1936: \u00ab<em>La Californie du Sud est devenue, comme la Grande-Bretagne il y a deux si\u00e8cles, l&rsquo;avanc\u00e9e occidentale de la civilisation nordique, avec l&rsquo;exceptionnelle opportunit\u00e9 d&rsquo;avoir une population qui est de souche anglo-saxonne dans un rapport double de celui qu&rsquo;on rencontre \u00e0 New York, \u00e0 Chicago et dans les autres grandes villes du pays.<\/em>\u00bb (4) Le sociologue Mike Davis donna ainsi sa propre d\u00e9finition: \u00ab<em>Une entreprise de la science et du business renouvelant la supr\u00e9matie aryenne sur les rives du Pacifique<\/em>\u00bb (5). A partir de cette base dont il faut \u00e9galement retenir qu&rsquo;elle \u00e9tait totalement ind\u00e9pendante du gouvernement, et m\u00eame d\u00e9velopp\u00e9e dans un esprit d&rsquo;hostilit\u00e9 radicale, voire hyst\u00e9rique \u00e0 Roosevelt (qualifi\u00e9 d'\u00a0\u00bbagent du communisme\u00a0\u00bb) et \u00e0 son <em>New Deal<\/em>, le Complexe initial devint le CMI pendant la guerre. Cela se fit en conjonction avec l&rsquo;\u00e9mergence des militaires,  surtout l&rsquo;aviation militaire, force nouvelle d\u00e9velopp\u00e9e comme on l&rsquo;a vu \u00e0 partir de la technologie, de l&rsquo;industrie a\u00e9ronautique localis\u00e9e en Californie du Sud, des contacts avec le <em>business<\/em> et m\u00eame avec le cin\u00e9ma pour ses actions de relations publiques (6). \u00ab<em>Entre-temps, <\/em>r\u00e9suma John Kenneth Galbraith (7), <em>l&rsquo;arm\u00e9e avait fait son apparition. En 1940, sur les questions d&rsquo;\u00e9conomie, d&rsquo;industrie et d&rsquo;approvisionnement, son influence \u00e9tait d\u00e9risoire. A pr\u00e9sent <\/em>[en 1943], <em>elle pesait lourd dans les d\u00e9cisions. <\/em>[&#8230;] <em>A mesure que les militaires gagnaient en influence, bon nombre de lib\u00e9raux, s\u00e9duits par leur style ou convaincus que les soldats ne manifesteraient envers la politique int\u00e9rieure qu&rsquo;indiff\u00e9rence ou neutralit\u00e9 pour se consacrer seulement \u00e0 la guerre, ralli\u00e8rent leur cause. Ce fut le d\u00e9but d&rsquo;une association qui devait rev\u00eatir une si lourde signification pendant la guerre froide et la guerre du Vi\u00eat-nam. Nous devions payer la victoire sur Hitler d&rsquo;une militarisation durable de l&rsquo;Etat.<\/em>\u00bb<\/p>\n<h3>Le probl\u00e8me de l&rsquo;apr\u00e8s-Guerre froide<\/h3>\n<\/p>\n<p><p>\tDepuis 1945, l&rsquo;\u00e9conomie am\u00e9ricaine est qualitativement appuy\u00e9e sur la puissance novatrice du CMI, qui passe par le soutien massif et direct des subventions f\u00e9d\u00e9rales (8). L&rsquo;industrie a\u00e9ronautique militaire a \u00e9t\u00e9 le <em>sponsor<\/em> quasiment exclusif du d\u00e9veloppement des industries \u00e9lectronique et spatiale dans les ann\u00e9es 1945-60, avec lesquelles elle a conserv\u00e9 des liens tr\u00e8s forts. Dans les ann\u00e9es soixante, 46% de l&rsquo;aide f\u00e9d\u00e9rale \u00e0 la recherche universitaire venaient du Pentagone. La p\u00e9n\u00e9tration du CMI dans le r\u00e9seau universitaire \u00e9tait consid\u00e9rable : par exemple, la soci\u00e9t\u00e9 North American Aviation \u00e9tait pr\u00e9sente dans 30 conseils d&rsquo;administration d&rsquo;universit\u00e9s qu&rsquo;elle soutenait de ses dons, avec l&rsquo;influence qu&rsquo;on imagine. <\/p>\n<\/p>\n<p><p>\tDe 1981 \u00e0 1984, la fameuse p\u00e9riode de la reprise Reagan qui fit applaudir \u00e0 un retour d&rsquo;une \u00e9conomie pure de march\u00e9 libre, se d\u00e9veloppa en fait une doctrine in\u00e9dite, pour le temps de paix, que certains d\u00e9sign\u00e8rent ironiquement sous l&rsquo;expression de \u00ab\u00a0keyn\u00e9sianisme militaire\u00a0\u00bb, et qui est \u00e0 la base de l&rsquo;\u00e9norme endettement am\u00e9ricain actuel. <\/p>\n<\/p>\n<p><p>\tJacqueline Grapin le d\u00e9finit ainsi: \u00ab<em>C&rsquo;est au point o\u00f9 il est permis de se dire que les d\u00e9penses militaires cr\u00e9ent certainement plus d&#8217;emplois que les programmes officiels de lutte contre le ch\u00f4mage. <\/em>[&#8230;] <em>Lorsque, \u00e0 la fin de 1983, le gouvernement annonce que la production industrielle a atteint un niveau record, il faut noter les pr\u00e9cisions suivantes: La production des biens de consommation n&rsquo;a augment\u00e9 que l\u00e9g\u00e8rement, et la production automobile a l\u00e9g\u00e8rement diminu\u00e9, mais celle de biens d&rsquo;\u00e9quipement s&rsquo;est nettement accrue. Autrement dit: le syst\u00e8me militaro-industriel fonctionne bien. <\/em>\u00bb (9)<\/p>\n<\/p>\n<p><p>\tDerri\u00e8re l&rsquo;apparence, c&rsquo;est avec une \u00e9conomie militaris\u00e9e, notamment en termes d&rsquo;influence, de leadership qualitatif \u00e0 base de d\u00e9veloppement technologique et de transfusion discr\u00e8te et\/ou indirecte de subventions f\u00e9d\u00e9rales du militaire vers le civil (10), que l&rsquo;Am\u00e9rique a abord\u00e9 l&rsquo;apr\u00e8s-Guerre froide en 1989-91. Croire qu&rsquo;elle se soit adapt\u00e9e en se tournant vers le secteur civil, comme il est en g\u00e9n\u00e9ral proclam\u00e9, est une illusion et une m\u00e9connaissance des m\u00e9canismes industriels et financiers am\u00e9ricains tant il est vrai qu&rsquo;on ne change pas une \u00e9quipe qui gagne, et qui rapporte (11).<\/p>\n<\/p>\n<p><p>\tSur le fond des choses, la fin de la Guerre froide amenait aux \u00c9tats-Unis une question angoissante parce que quasiment ontologique pour le syst\u00e8me industriel : que faire pour conserver, et peut-\u00eatre p\u00e9renniser en temps de paix cet \u00e9norme Complexe ? Au niveau int\u00e9rieur, il n&rsquo;y a pas (encore ?) eu de vraie r\u00e9ponse. On a tent\u00e9 de conserver un budget militaire type Guerre froide, disproportionn\u00e9 par rapport aux risques et menaces subsistants (12). Cela n&rsquo;a fait que repousser le probl\u00e8me, car entre-temps les commandes int\u00e9rieures se sont effondr\u00e9es (13). Lorsqu&rsquo;elles reprendront avec les modernisations pr\u00e9vues et les nouveaux programmes tr\u00e8s on\u00e9reux (\u00e0 partir de 1998), il va manquer plus de $20 milliards au budget annuel actuel alors que la pression pour r\u00e9duire le d\u00e9ficit f\u00e9d\u00e9ral ne fait que s&rsquo;amplifier. Nous avons l\u00e0 les \u00e9l\u00e9ments d&rsquo;une grave crise int\u00e9rieure (parmi d&rsquo;autres).<\/p>\n<\/p>\n<p><p>\tEntre-temps, le Complexe pensa trouver la r\u00e9ponse \u00e0 son dilemme de l&rsquo;apr\u00e8s-Guerre froide : les exportations. Ce que le Pentagone ne pouvait plus commander aux usines du Complexe, le monde ext\u00e9rieur le ferait. Cela supposait une changement fondamental de strat\u00e9gie. Les exportations d&rsquo;armes am\u00e9ricaines, pass\u00e9e la manne du r\u00e9armement initial \u00e0 partir des stocks de la Seconde Guerre et apr\u00e8s le r\u00e9gime interm\u00e9diaire de l&rsquo;assistance militaire aux pays alli\u00e9s, avaient vraiment d\u00e9marr\u00e9 dans les ann\u00e9es 1970 (de $1,4 milliard en 1970 \u00e0 $17 milliards en 1975). Mais le rythme satisfaisant acquis alors se justifiait par la menace sovi\u00e9tique : il fallait armer les alli\u00e9s divers. L&rsquo;argument n&rsquo;existait plus d\u00e8s 1990-91. La guerre du Golfe ne fut qu&rsquo;un incident dans cette chronologie : elle apporta un \u00e9norme suppl\u00e9ment d&rsquo;exportations (mais \u00e0 quel prix? On le verra plus loin), mais ne fournit \u00e9videmment aucune strat\u00e9gie de substitution. A part les d\u00e9lires m\u00e9diatiques de l&rsquo;\u00e9poque, il \u00e9tait grotesque de croire qu&rsquo;un ennemi comme l&rsquo;Irak, ou de sa cat\u00e9gorie (Libye, Iran, Cor\u00e9e du Nord, etc.), justifierait une strat\u00e9gie \u00e0 l&rsquo;exportation capable de faire tourner le CMI. Ainsi naquit une autre conception, une autre strat\u00e9gie,  et nous en (re)venons \u00e0 notre id\u00e9e initiale de domination du monde.<\/p>\n<h3>Une conception manifeste : la destin\u00e9e am\u00e9ricaine par les armes<\/h3>\n<\/p>\n<p><p>\tLorsque nous parlons de \u00ab\u00a0domination du monde\u00a0\u00bb (\u00ab\u00a0<em>World Dominance<\/em>\u00ab\u00a0, l&rsquo;id\u00e9e est aujourd&rsquo;hui reprise sous cette expression employ\u00e9e g\u00e9n\u00e9riquement), il ne s&rsquo;agit pas de la conceptualisation d&rsquo;une situation g\u00e9n\u00e9rale que nous interpr\u00e9terions d&rsquo;une fa\u00e7on approximative et en tout cas pour conforter notre th\u00e8se. Il y a des prises de position explicites et jamais d\u00e9menties, en g\u00e9n\u00e9ral de la part de chefs militaires responsables \u00e9crivant dans des revues de haute tenue ou m\u00eame t\u00e9moignant devant le Congr\u00e8s, pour affirmer l&rsquo;ambition globale, quasi imp\u00e9riale qui accompagne les exportations d&rsquo;armement. Nous pr\u00e9sentons quelques-unes de ces d\u00e9clarations, en m\u00eame temps que des \u00e9v\u00e9nements, ou des commentaires, qui nous semblent bien tracer les grandes lignes du tableau que nous voulons pr\u00e9senter :<\/p>\n<\/p>\n<p><p>\t\u00a0En f\u00e9vrier 1992, le New York <em>Times<\/em> diffusa des extraits copieux, obtenus clandestinement, du document de base de ce qui aurait d\u00fb \u00eatre le <em>Policy Guidance<\/em> quadriannuel du Pentagone (rapport \u00e9tablissant la vision politico-strat\u00e9gique du d\u00e9partement de la D\u00e9fense). Le document, fort comment\u00e9 \u00e0l&rsquo;\u00e9poque, tra\u00e7ait le cadre d&rsquo;une puissance am\u00e9ricaine appuy\u00e9e sur la d\u00e9monstration de la force militaire mettant en place une h\u00e9g\u00e9monie mondiale et veillant \u00e0 ce qu&rsquo;aucune puissance concurrente (y compris chez les alli\u00e9s) puisse la contester. Les r\u00e9actions, surtout dans les pays alli\u00e9s, conduisirent le Pentagone \u00e0 enterrer cette version du <em>Policy Guidance<\/em> avec quelques explications confuses. L&rsquo;esprit, lui, subsista.<\/p>\n<\/p>\n<p><p>\t\u00a0Le 2 mars 1994, l&rsquo;amiral Larson, U.S. Navy, USAPCOM (commandant en chef, Pacifique), vint pr\u00e9senter ses conceptions devant la Commission des Forces Arm\u00e9es du S\u00e9nat. Il \u00e9non\u00e7a pour les s\u00e9nateurs approbateurs une <em>\u00ab strat\u00e9gie d&rsquo;engagement de coop\u00e9ration \u00bb<\/em>. Il s&rsquo;agit d&rsquo;une strat\u00e9gie offensive d&rsquo;influence correspondant \u00e0 une situation,  celle de l&rsquo;apr\u00e8s-Guerre froide,  o\u00f9, selon ses mots, \u00ab<em>les incertitudes que nous affrontons sont largement d\u00e9pass\u00e9es par les opportunit\u00e9s qui s&rsquo;offrent \u00e0 nous<\/em>\u00bb; <MI opportunit\u00e9s<D>, non pas de renforcer la stabilit\u00e9, ou l&rsquo;\u00e9quilibre des relations internationales, mais bien de faire progresser les int\u00e9r\u00eats US. Larson d\u00e9tailla la situation dans le Pacifique et montra l&rsquo;int\u00e9r\u00eat pour les \u00c9tats-Unis de cette strat\u00e9gie d&rsquo;engagement par la coop\u00e9ration. Il cita l&rsquo;ann\u00e9e 1993 en r\u00e9f\u00e9rence : \u00ab<em>Nous avons sponsor\u00e9 plus de 200 exercices interarmes et combin\u00e9s avec d&rsquo;autres nations du Pacifique et d&rsquo;Asie &#8230; <\/em>\u00bb. Avec cette r\u00e8gle d&rsquo;or, \u00e9nonc\u00e9e en termes clairs: \u00ab<em>Si nous ne sommes pas l\u00e0, nous ne pouvons pas participer; si nous ne participons pas, nous n&rsquo;avons pas d&rsquo;influence<\/em>.\u00bb<\/p>\n<\/p>\n<p><p>\t\u00a0En avril 1994, le g\u00e9n\u00e9ral John Loh, alors commandant de l&rsquo;Air Combat Command de l&rsquo;USAF (c&rsquo;est-\u00e0-dire l&rsquo;officier g\u00e9n\u00e9ral le plus important de la hi\u00e9rarchie apr\u00e8s le Chef d&rsquo;\u00e9tat-major), publia un article o\u00f9 l&rsquo;on trouvait ces remarques:  \u00ab<em>Quand les \u00c9tats-Unis vendent des \u00e9quipements militaires aux alli\u00e9s, ils y gagnent un acc\u00e8s et de l&rsquo;influence qu&rsquo;ils ne pourraient avoir d&rsquo;aucune autre fa\u00e7on,  notamment en envoyant des techniciens dans ces pays, pour entra\u00eener leurs techniciens au maniement de ces \u00e9quipements ; en invitant des militaires alli\u00e9s \u00e0 venir aux \u00c9tats-Unis pour un entra\u00eenement technique et op\u00e9rationnel ; en d\u00e9ployant <\/em>[des unit\u00e9s am\u00e9ricaines] <em>dans ces pays alli\u00e9s, &#8230; <\/em>[&#8230;] <em>Quand les USA vendent des \u00e9quipements \u00e0d&rsquo;autres pays, ils gagnent de l&rsquo;influence. <\/em>[&#8230;] <em>Nous devons changer notre fa\u00e7on de penser \u00e0 propos des FMS <\/em>[<em>Foreign Military Sells<\/em>] &#8230; <em>Les ventes par FMS renforcent l&rsquo;int\u00e9gration de notre politique de s\u00e9curit\u00e9 nationale visant \u00e0 aider au renforcement de notre influence dans le monde.<\/em> \u00bb (14)<\/p>\n<\/p>\n<p><p>\t\u00a0En 1996, le contre-amiral Sutton, directeur du Bureau des Programmes internationaux de l&rsquo;U.S. Navy, d\u00e9taillait un plan selon lequel les commandements navals r\u00e9gionaux am\u00e9ricains outre-mer \u00e9taient invit\u00e9s \u00e0 se transformer en office de promotion des exportations d&rsquo;armes: \u00ab<em>Nous travaillons avec les commandements outre-mer sur les pays de leurs zones, <\/em>[pour d\u00e9terminer] <em>quels pays ont besoin de notre assistance, de quelle assistance ils ont besoin, et de quelle fa\u00e7on la marine peut les aider \u00e0 l&rsquo;obtenir.<\/em>\u00bb (15)<\/p>\n<\/p>\n<p><p>\t\u00a0L&rsquo;Europe elle-m\u00eame constitue dans cette offensive un territoire de choix, mais cette fois par le biais de l&rsquo;investissement de son industrie. Il y a, \u00e0 cet \u00e9gard, bien des indications \u00e0 m\u00e9diter, telle cette remarque de John Deutch, alors n<198>2 du Pentagone, disant \u00e0 l&rsquo;ancien PDG de GIAT Industrie \u00e0Washington le 16 janvier 1995 que les USA sont partisans d&rsquo;une coop\u00e9ration transatlantique \u00ab<em>mais <\/em>[sont ouvertement oppos\u00e9s] <em>\u00e0 des rapprochements entre les industries de d\u00e9fense europ\u00e9enne sans <\/em>[qu&rsquo;ils] <em>aient leur mot \u00e0 dire<\/em>\u00bb (c&rsquo;est-\u00e0-dire, renseignement pris, un droit de participer \u00e0 ces rapprochements comme partie \u00e9ventuellement prenante). Dix-huit mois plus tard, l&rsquo;amiral Norman Ray, dynamique adjoint du Secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;OTAN pour les armements, demandait (semble-t-il, en tant qu&rsquo;officier am\u00e9ricain plut\u00f4t que fonctionnaire international) que \u00ab<em>les Europ\u00e9ens ne mettent pas en oeuvre des politiques qui excluent syst\u00e9matiquement les Am\u00e9ricains de leur march\u00e9 via une pr\u00e9f\u00e9rence europ\u00e9enne<\/em>\u00bb. (16)<\/p>\n<h3>Une offensive massive et globale: pour quels r\u00e9sultats qualitatifs?<\/h3>\n<\/p>\n<p><p>\tLes intentions am\u00e9ricaines ne font pas le moindre doute. Rarement m\u00eame, les esprits avertis auront dispos\u00e9 d&rsquo;autant d&rsquo;\u00e9l\u00e9ments clairs et irr\u00e9futables pour identifier un mouvement de cette importance. On en vient donc naturellement au constat de l&rsquo;importance des effets de cette offensive \u00e0 ce jour.<\/p>\n<\/p>\n<p><p>\tPour cela, on dispose de chiffres pr\u00e9cis. Si les chiffres ne disent en g\u00e9n\u00e9ral pas tout, avec les USA ils disent presque tout. Les Am\u00e9ricains eux-m\u00eames le veulent ainsi : pour eux, l&rsquo;influence va avec le <em>business<\/em>, et la strat\u00e9gie est d&rsquo;abord une question de \u00ab\u00a0poids\u00a0\u00bb d&rsquo;armement et son \u00e9quivalent en dollars. De plus, l&rsquo;importance consid\u00e9rable des disparit\u00e9s constat\u00e9es permet de tirer ais\u00e9ment des conclusions d&rsquo;ordre politique et conceptuel.<\/p>\n<\/p>\n<p><p>\tUne compilation tr\u00e8s pr\u00e9cise des exportations d&rsquo;armes am\u00e9ricaines, telles que notifi\u00e9es au Congr\u00e8s (toute transaction de plus de $14 millions doit effectivement l&rsquo;\u00eatre), sur la p\u00e9riode entre le 1er janvier 1990 et d\u00e9cembre 1996, donne un chiffre g\u00e9n\u00e9ral des exportations d&rsquo;armement de $120,3 milliards. L&rsquo;int\u00e9r\u00eat est d&rsquo;en signaler plusieurs d\u00e9comptes s\u00e9lectifs, pour d\u00e9gager la tendance g\u00e9n\u00e9rale qui nous permettra de r\u00e9pondre \u00e0 la question pos\u00e9e.<\/p>\n<\/p>\n<p><p>\t\u00a0Un seul pays, le premier importateur, compte pour $47,27 milliards, soit pratiquement 40% du total: l&rsquo;Arabie Saoudite. C&rsquo;est l\u00e0 o\u00f9 l&rsquo;on peut parler d&rsquo;un effet pervers de la guerre du Golfe, \u00e0 laquelle est du l&rsquo;essentiel de ces commandes gigantesques. Le cas saoudien \u00e9tablit une fausse perspective quant \u00e0 la capacit\u00e9 d&rsquo;influence des exportations d&rsquo;armement, en m\u00eame temps qu&rsquo;il am\u00e8ne une mise en difficult\u00e9, d&rsquo;abord financi\u00e8re et peut-\u00eatre sociale et politique, du r\u00e9gime pro-am\u00e9ricain.<\/p>\n<\/p>\n<p><p>\t\u00a0Les trois premiers pays repr\u00e9sentent $66,83 milliards, soit 60% du total des exportations: l&rsquo;Arabie ($47,27 milliards), Ta\u00efwan ($10,83 milliards) et le Koweit ($8,73 milliards).<\/p>\n<\/p>\n<p><p>\t\u00a0Si l&rsquo;on ajoute aux trois premiers, les trois suivants importateurs d&rsquo;armes US (Cor\u00e9e du Sud avec $6,45 milliards, Turquie avec $6,06 milliards et Egypte avec $5,81 milliards), on arrive au chiffre de $85,15 milliards, soit un peu plus de 70% de toutes les exportations d&rsquo;armes am\u00e9ricaines.<\/p>\n<\/p>\n<p><p>\tAinsi l&rsquo;effort d&rsquo;exportation d&rsquo;armement des \u00c9tats-Unis dans les six derni\u00e8res ann\u00e9es (consid\u00e9rable si on l&rsquo;\u00e9value par rapport \u00e0la situation g\u00e9n\u00e9rale beaucoup moins favorable aux d\u00e9penses d&rsquo;armement que la Guerre froide) appara\u00eet marqu\u00e9 par des d\u00e9s\u00e9quilibres tr\u00e8s profonds, et de ce fait pr\u00e9occupants par rapport au but recherch\u00e9, l&rsquo;influence g\u00e9n\u00e9rale dans le monde.<\/p>\n<\/p>\n<p><p>\t\u00a0Autour de 60% des exportations am\u00e9ricaines dans le monde de 1990 \u00e0 1996 ont \u00e9t\u00e9 destin\u00e9s \u00e0 trois pays qui regroupent environ 29 millions d&rsquo;habitants, soit approximativement 0,5% de la population mondiale. Le d\u00e9s\u00e9quilibre est \u00e0 peine modifi\u00e9 si l&rsquo;on \u00e9tend la r\u00e9f\u00e9rence aux six pays qui re\u00e7oivent 70% des exportations.<\/p>\n<\/p>\n<p><p>\t\u00a0 Les pays constitutifs de ce groupe de t\u00eate ne forment en aucune fa\u00e7on des avanc\u00e9es strat\u00e9giques nouvelles pour les \u00c9tats-Unis. Ce sont tous des pays quasiment sous tutelle am\u00e9ricaine depuis les premi\u00e8res ann\u00e9es de la Guerre froide, et o\u00f9 l&rsquo;influence am\u00e9ricaine n&rsquo;a plus cess\u00e9 de grandir, notamment par le biais d&rsquo;un flot constant d&rsquo;exportations d&rsquo;armes.<\/p>\n<\/p>\n<p><p>\t\u00a0 Le reste des exportations se fait dans 43 pays, parmi lesquels une part importante sont acquis aux \u00c9tats-Unis ou tr\u00e8s proches d&rsquo;eux (par exemple Isra\u00ebl et Japon). Finalement et pour ce qui concerne la masse de ces 43 pays, il s&rsquo;agit d&rsquo;exportations assez faibles, impliquant une coop\u00e9ration assez r\u00e9duite et ayant peu de chances de donner des gains d&rsquo;influence consid\u00e9rables par rapport \u00e0 la client\u00e8le traditionnelle des USA. Ainsi d\u00e9gage-t-on la conclusion que, par contraste avec la masse financi\u00e8re consid\u00e9rable des importations am\u00e9ricaines, les effets g\u00e9ostrat\u00e9giques diversifi\u00e9s de cette activit\u00e9 sont r\u00e9duits. Bien plus que d&rsquo;une op\u00e9ration g\u00e9ostrat\u00e9gique, il s&rsquo;agit d&rsquo;une op\u00e9ration g\u00e9o\u00e9conomique dans un sens plut\u00f4t restreint, qui place les r\u00e9alit\u00e9s en contradiction avec le discours imp\u00e9rial tel que nous l&rsquo;avons analys\u00e9 ci-dessus. Au contraire, on constate aujourd&rsquo;hui l&rsquo;extr\u00eame difficult\u00e9 des ventes des grands syst\u00e8mes d&rsquo;armes, type avions de combat, co\u00fbteux et porteurs d&rsquo;influence \u00e0long terme pour les Am\u00e9ricains. M\u00eame dans un march\u00e9 comme celui des nouveaux avions de combat pour la Cor\u00e9e du Sud (pr\u00e9vu pour 2001-2002), la traditionnelle position de domination des \u00c9tats-Unis est loin, tr\u00e8s loin, d&rsquo;assurer \u00e0 ce pays la certitude d&#8217;emporter le march\u00e9. C&rsquo;est un changement, plut\u00f4t n\u00e9gatif, par rapport aux ann\u00e9es de Guerre froide.<\/p>\n<\/p>\n<p><p>\tCe qu&rsquo;a, sans aucun doute, \u00e9tabli la pouss\u00e9e am\u00e9ricaine \u00e0l&rsquo;exportation des ann\u00e9es 1990, c&rsquo;est une valeur politique et de souverainet\u00e9 nationale, et une force d&rsquo;influence consid\u00e9rable que n&rsquo;avaient pas auparavant les grands syst\u00e8mes d&rsquo;armes. Les Fran\u00e7ais, qui ont dans ce domaine une position privil\u00e9gi\u00e9e par rapport \u00e0 leur taille d\u00e9mographique dans le monde contemporain, feraient bien de pleinement prendre en compte ce ph\u00e9nom\u00e8ne nouveau, en accordant \u00e0 ces syst\u00e8mes l&rsquo;importance universelle qu&rsquo;ils ont acquis, plut\u00f4t que de se r\u00e9signer un peu trop facilement aux \u00ab\u00a0victoires\u00a0\u00bb am\u00e9ricaines.<\/p>\n<\/p>\n<p><p>\tLes ambitions de l&rsquo;Am\u00e9rique sont bien \u00e9tablies et demeurent mais des obstacles persistent pour les mener \u00e0 bien. Les vis\u00e9es am\u00e9ricaines sp\u00e9cifiques d&rsquo;h\u00e9g\u00e9monie mondiale par l&rsquo;exportation des armes sont loin d&rsquo;\u00eatre assur\u00e9es, bien qu&rsquo;elles n&rsquo;aient jamais \u00e9t\u00e9 affirm\u00e9es aussi cat\u00e9goriquement. Du coup, le probl\u00e8me que conna\u00eet le CMI am\u00e9ricain, et par cons\u00e9quent la structure industrielle am\u00e9ricaine de d\u00e9veloppement des technologies, n&rsquo;est toujours pas r\u00e9solu. On devrait s&rsquo;en apercevoir dans les ann\u00e9es 1998-2002, o\u00f9 les pressions budg\u00e9taires int\u00e9rieures font se faire de plus en plus pesantes.<\/p>\n<\/p>\n<p><p>\t<strong>Philippe GRASSET<\/strong><\/p>\n<\/p>\n<p><p>\tPubli\u00e9 dans <em>La Revue de G\u00e9o\u00e9conomie<\/em>, n\u00b01, mai 1997<\/p>\n<\/p>\n<p><p>\t(1) L&rsquo;expression \u00ab\u00a0Destin\u00e9e manifeste\u00a0\u00bb (\u00ab\u00a0Manifest Destiny\u00a0\u00bb), interpr\u00e9t\u00e9e par le dictionnaire Collins comme \u00ab<em>l&rsquo;expansion territoriale in\u00e9vitable des \u00c9tats-Unis<\/em>\u00bb, fut officiellement utilis\u00e9e pour la premi\u00e8re fois en 1845, pour qualifier la politique du pr\u00e9sident Polk. Celui-ci soutint avec enthousiasme le rattachement du Texas \u00e0l&rsquo;Union (vot\u00e9e par le Congr\u00e8s de cet \u00c9tat cette m\u00eame ann\u00e9e). Dans le conflit qui opposait les \u00c9tats-Unis et le Royaume-Uni \u00e0 propos de l&rsquo;Oregon (les Britanniques y avaient des int\u00e9r\u00eats et les Am\u00e9ricains s&rsquo;y \u00e9tablissaient), Polk choisit de r\u00e9affirmer la doctrine de Monro\u00eb pour r\u00e9clamer la fin de l&rsquo;occupation conjointe de cet \u00c9tat au profit des \u00c9tats-Unis seuls.<\/p>\n<\/p>\n<p><p>\t(2) Lettre cit\u00e9e par M. Andr\u00e9, en note dans son livre <em>\u00ab\u00a0Entretiens avec le g\u00e9n\u00e9ral Mangin sur l&rsquo;Am\u00e9rique\u00a0\u00bb<\/em>, librairie Pierre Roger, Paris 1929.<\/p>\n<\/p>\n<p><p>\t(3) Article paru dans le San Francisco <em>Examiner<\/em>, le 3 mai 1996.<\/p>\n<\/p>\n<p><p>\t(4) Cit\u00e9 par Mike Davis, \u00e0 partir des documents personnels de Millikan, <em>City of Quartz<\/em>, Vintage, Londres 1992.<\/p>\n<\/p>\n<p><p>\t(5) Mike Davis, op. cit\u00e9.<\/p>\n<\/p>\n<p><p>\t(6) Il ne s&rsquo;agit pas d&rsquo;une notation accessoire mais d&rsquo;un point fondamental. L&rsquo;aviation militaire (USAAF puis USAF) s&rsquo;est d\u00e9velopp\u00e9e avec des liens tr\u00e8s forts avec diff\u00e9rents cercles du <em>business<\/em>, alors qu&rsquo;elle \u00e9tait assez peu populaire \u00e0 Washington (Roosevelt \u00e9tait un chaud partisan de la marine). Elle constitua la part essentielle de l&rsquo;effort de guerre (304000 avions produits entre 1941 et 1945), son industrie fut soutenue par les grandes banques (la Chase Manhattan surtout) et elle s&rsquo;appuya sur Hollywood pour un effort de promotion sans pr\u00e9c\u00e9cent (les liens personnels du chef de l&rsquo;USAAF, le g\u00e9n\u00e9ral Arnold, et de Jack Warner, PDG de Warner Brothers [nomm\u00e9 major de l&rsquo;USAAF en 1942], furent d\u00e9terminants).<\/p>\n<\/p>\n<p><p>\t(7) Galbraith, <em>Une Vie dans son Si\u00e8cle<\/em>, Gallimard, Paris, 1983.<\/p>\n<\/p>\n<p><p>\t(8) Un rapport de la Harvard Business School a calcul\u00e9 qu&rsquo;entre 1945 et 1985, 85% des d\u00e9penses de recherche et d\u00e9veloppement (R&#038;D) pour l&rsquo;industrie a\u00e9ronautique (civile et militaire) ont \u00e9t\u00e9 constitu\u00e9s de subventions f\u00e9d\u00e9rales (c&rsquo;est parfois plus que la situation europ\u00e9enne : pour les programmes militaires command\u00e9s par l&rsquo;\u00c9tat en France, le constructueur doit participer \u00e0 hauteur de 25% aux d\u00e9penses R&#038;D). Cit\u00e9 dans \u00ab<em>Mideast Oil Forever<\/em>\u00bb de Joseph J. Romm et Charles B. Curtis, <em>Atlantic Monthly<\/em>, avril 1996.<\/p>\n<\/p>\n<p><p>\t(9) Dans <em>\u00ab\u00a0Forteresse Am\u00e9rique\u00a0\u00bb<\/em>, Grasset, 1984. <\/p>\n<\/p>\n<p><p>\t(10) Boeing n&rsquo;aurait jamais pu prendre la t\u00eate de l&rsquo;industrie civile comme il fit \u00e0 partir de 1956-60 (Boeing 707), sans l&rsquo;acquis technologique et les fonds en R&#038;D du Pentagone (le 707 fut d\u00e9velopp\u00e9 dans une version militaire, C-135 et KC-135).<\/p>\n<\/p>\n<p><p>\t(11) Un rapport du Congressional Budget Office de 1986 indique que la marge b\u00e9n\u00e9ficiaire des industries de d\u00e9fense en 1981-85 atteignait 23% contre 10% aux entreprises civiles. Depuis la fin de la Guerre froide, il y a eu d&rsquo;autres formes d'\u00a0\u00bbadaptation\u00a0\u00bb et les \u00e9normes conglom\u00e9rats militaires constitu\u00e9s dans les ann\u00e9es 90 n&rsquo;ont pas manqu\u00e9 de phagocyter des secteurs civils tr\u00e8s rentables. Lockheed-Martin est le premier acteur dans la gestion des d\u00e9penses de s\u00e9curit\u00e9 sociale transf\u00e9r\u00e9es du gouvernement au priv\u00e9 par une loi Clinton de l&rsquo;\u00e9t\u00e9 1996, avec la gestion de 1,5 milliard USD (sur lequel il fait 19% de b\u00e9n\u00e9fices) de subventions sociales du gouvernement f\u00e9d\u00e9ral. <\/p>\n<\/p>\n<p><p>\t(12) Le budget actuel (autour de $250 milliards) correspond \u00e0 17 fois les budgets combin\u00e9s des six pays les plus souvent identifi\u00e9s comme de \u00ab\u00a0probables adversaires\u00a0\u00bb (Cor\u00e9e du Nord, Iran, Libye, Syrie, Cuba).<\/p>\n<\/p>\n<p><p>\t(13) En g\u00e9n\u00e9ral, les structures des forces am\u00e9ricaines ont \u00e9t\u00e9 r\u00e9duites dans des proportions allant de 40 \u00e0 50% en dix ans. Par exemple, l&rsquo;USAF est pass\u00e9 de 38 \u00e0 20 escadres de combat entre 1987 et 1995. Cette tendance implique une chute vertigineuse des commandes int\u00e9rieures : en 1994 et en 1995, pour la premi\u00e8re depuis sa constitution (en 1947), l&rsquo;USAF n&rsquo;a pas achet\u00e9 un seul avion de combat tactique (chasseur\/chasseur-bombardier).<\/p>\n<\/p>\n<p><p>\t(14) <em>Strategic Review<\/em>, Spring 1994. <\/p>\n<\/p>\n<p><p>\t(15) <em>Defense News<\/em>, interview, 12 mai 1996.<\/p>\n<\/p>\n<p><p>\t\u00a0(16) <em>Defense News<\/em>, interview, 19 mai 1996.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sur le fond d&rsquo;une analyse historique du d\u00e9veloppement du complexe militaro-industriel am\u00e9ricain, une question actuelle: les USA veulent-ils assurer leur h\u00e9g\u00e9monie par les ventes d&rsquo;armes?<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[3124,3126,3127,3012,3125,3123],"class_list":["post-64891","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-armement","tag-black","tag-budget","tag-complexe","tag-grasset","tag-militaro-industriel"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/64891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=64891"}],"version-history":[{"count":2,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/64891\/revisions"}],"predecessor-version":[{"id":81912,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/64891\/revisions\/81912"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=64891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=64891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=64891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}