{"id":64918,"date":"2001-03-25T00:00:00","date_gmt":"2001-03-24T22:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2001\/03\/25\/de-defensa-volume-16-n13-du-25-mars-2001-bouvard-and-pecuchet-at-war\/"},"modified":"2001-03-25T00:00:00","modified_gmt":"2001-03-24T22:00:00","slug":"de-defensa-volume-16-n13-du-25-mars-2001-bouvard-and-pecuchet-at-war","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2001\/03\/25\/de-defensa-volume-16-n13-du-25-mars-2001-bouvard-and-pecuchet-at-war\/","title":{"rendered":"de defensa Volume 16, n\u00b013 du 25 mars 2001 &#8211; <strong><em>Bouvard and Pecuchet at war<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Bouvard and Pecuchet at war<\/h2>\n<\/p>\n<p><p>\tAutre anniversaire, apr\u00e8s celui de la guerre du Golfe : celui de la guerre du Kosovo, deux ans apr\u00e8s (d\u00e9marrage des frappes le 24 mars 1999). Comm\u00e9moration d&rsquo;autant plus n\u00e9cessaire \u00e0 c\u00e9l\u00e9brer qu&rsquo;au Kosovo, et autour du Kosovo (c&rsquo;est la nouveaut\u00e9), dans cette fameuse r\u00e9gion qui est une partie de l&rsquo;Europe (combien de fois l&rsquo;argument fut r\u00e9p\u00e9t\u00e9 pour nous convaincre de soutenir l&rsquo;intervention), la crise se poursuit et continue \u00e0 s&rsquo;aggraver, et m\u00eame \u00ab\u00a0recommence\u00a0\u00bb \u00e0 s&rsquo;aggraver en s&rsquo;\u00e9tendant \u00e0 l&rsquo;extr\u00e9mit\u00e9 de la Serbie et \u00e0 la Mac\u00e9doine. Bien qu&rsquo;indirectement, ce que nous allons exposer ci-apr\u00e8s participe sans aucun doute de cette aggravation de la situation.<\/p>\n<\/p>\n<p><p>\tLa fa\u00e7on dont la repr\u00e9sentation de la r\u00e9alit\u00e9 de la guerre a \u00e9t\u00e9 construite, il y a deux ans, comme quelque chose d&rsquo;absolument \u00e9tranger \u00e0 la r\u00e9alit\u00e9, conduisit \u00e9videmment aux erreurs dans la r\u00e9alit\u00e9 qui suivirent et s&rsquo;encha\u00een\u00e8rent jusqu&rsquo;\u00e0 la situation d&rsquo;aujourd&rsquo;hui o\u00f9 la KFOR semble \u00eatre devenue une force de figuration l\u00e0 o\u00f9 elle pr\u00e9tendait \u00eatre une force d&rsquo;intervention et de stabilisation. La KFOR ne s&rsquo;est absolument pas int\u00e9gr\u00e9e \u00e0 la crise. La KFOR figure, impuissante, dans une zone g\u00e9opolitique totalement soumise au processus d&rsquo;aggravation de la crise qui la secoue, et \u00e0 la limite elle appara\u00eet m\u00eame comme une force de protection des conditions qui font que la situation s&rsquo;aggrave dans la r\u00e9gion (on pense \u00e9videmment au soutien constant, pratique, compl\u00e8tement d\u00e9stabilisateur, fourni par les USA [la CIA, jamais en retard d&rsquo;une action hasardeuse depuis la baie des Cochons] aux gu\u00e9rillas de l&rsquo;UCK et compagnie). La KFOR est devenue un acteur virtuel dont le r\u00f4le involontaire est de verser, m\u00e9thodiquement, avec toute l&rsquo;arrogance des certitudes de l&rsquo;\u00ab <em>hyperpuissance<\/em> \u00bb, avec toute l&rsquo;efficacit\u00e9 de la bureaucratie otano-pentagonienne au travail, de l&rsquo;huile sur le feu.<\/p>\n<\/p>\n<p><p>\tDeux ans apr\u00e8s, nous voulons analyser le d\u00e9roulement de la technique de pr\u00e9sentation de la guerre. Pour cela, nous nous appuyons sur l&rsquo;analyse d&rsquo;un document t\u00e9l\u00e9visuel suffisamment complet et r\u00e9v\u00e9lateur \u00e0 cet \u00e9gard, un magazine de l&rsquo;\u00e9mission <em>90 minutes<\/em>, diffus\u00e9 en d\u00e9cembre 2000 et janvier 2001 sur Canal +. Cette \u00e9mission pr\u00e9sente les circonstances du ph\u00e9nom\u00e8ne, r\u00e9sum\u00e9 de fa\u00e7on satisfaisante et assez juste par le commentateur, par ces mots : \u00ab <em>Comment ils nous ont vendu la guerre<\/em> \u00bb.<\/p>\n<\/p>\n<p><p>\tLe document est int\u00e9ressant, juge-t-on \u00e0 la premi\u00e8re vision. Il ne semble pas vraiment de parti-pris ; mais on d\u00e9couvre assez rapidement que cette objectivit\u00e9 se satisfait de l&rsquo;apparence. L&rsquo;absence de parti-pris se fait dans un sens un peu paradoxal, ou bien, disons autrement, d&rsquo;une fa\u00e7on totalement incompl\u00e8te parce qu&rsquo;elle s&rsquo;appuie sur des consid\u00e9rations qui vont de soi, pos\u00e9es si l&rsquo;on veut comme axiome de tout le r\u00eacit. La cause est entendue par avance et ce que nous allons voir expos\u00e9 et diss\u00e9qu\u00e9 n&rsquo;a strictement aucun pouvoir de changer ce verdict, et certes c&rsquo;est le verdict de la version\/de l&rsquo;histoire officielle : les horreurs (serbes) d\u00e9nonc\u00e9es, la responsabilit\u00e9 quasi-exclusive (serbe), etc. Curieux cas, somme toute, bien dans l&rsquo;esprit du temps, d\u00e9nu\u00e9 du sens de la logique, de la fermet\u00e9 du raisonnement, de la responsabilit\u00e9 du jugement : on diss\u00e8que les m\u00e9canismes fallacieux et trompeurs d&rsquo;une action de communication, sans vraiment dissimuler la nature de la salade vendue par cette action, en acceptant pourtant toute cette m\u00eame salade comme argent comptant. \u00ab <em>Comment ils nous ont vendu la guerre<\/em> \u00bb, certes, et nulle part on n&rsquo;entend la cons\u00e9quence qu&rsquo;il faudrait en tirer,  \u00e0 savoir que, dans ces conditions, la marchandise est un peu suspecte.<\/p>\n<\/p>\n<p><p>\tPassons. Pour ce cas ici choisi, cet aspect-l\u00e0 ne nous int\u00e9resse pas. Nous le notons pourtant, parce que cette fa\u00e7on de \u00ab\u00a0sembler ne pas prendre parti\u00a0\u00bb en tenant pour acquise, pour v\u00e9rit\u00e9 indiscutable, la th\u00e8se officielle, est une attitude qui rejoint l&rsquo;un des aspects du comportement g\u00e9n\u00e9ral que nous analysons, qui est celui des m\u00e9dias. Par cons\u00e9quent, et c&rsquo;est l&rsquo;explication de l&rsquo;int\u00e9r\u00eat que nous lui accordons, l&rsquo;aspect formel de cette pr\u00e9sentation est, lui, prodigieusement r\u00e9v\u00e9lateur.<\/p>\n<\/p>\n<p><p>\tNous nous attachons \u00e0 l&rsquo;aspect technique, professionnel si l&rsquo;on veut, tel qu&rsquo;il appara\u00eet dans le document ; c&rsquo;est-\u00e0-dire, le fonctionnement de la machine humaine qui nous a \u00ab <em>vendu la guerre<\/em> \u00bb. Cette analyse doit nous permettre de mieux d\u00e9finir un ph\u00e9nom\u00e8ne unique, propre \u00e0 notre temps, qui est cette re-pr\u00e9sentation de la r\u00e9alit\u00e9 du monde par re-fondation (re-formatage dirait-on en language informatique), dont le commentateur dit lui-m\u00eame que \u00ab <em>ce n&rsquo;est pas du tout de la propagande, c&rsquo;est bien plus subtil que de la propagande<\/em> \u00bb. (1)<\/p>\n<\/p>\n<p><p>\tLe document de cette \u00e9mission <em>90 minutes<\/em> comprend les \u00e9l\u00e9ments suivants :<\/p>\n<\/p>\n<p><p>\t Des sc\u00e8nes de conf\u00e9rences de presse et divers \u00e0-c\u00f4t\u00e9s, \u00e0 Ev\u00e8re (pr\u00e8s de Bruxelles), au si\u00e8ge de l&rsquo;OTAN, pendant la guerre du Kosovo.<\/p>\n<\/p>\n<p><p>\t\u00a0Des documents d&rsquo;illustration : sc\u00e8nes sp\u00e9cifiques de la guerre, extraits d&rsquo;\u00e9missions d&rsquo;information de l&rsquo;\u00e9poque, tout cela illustrant les sc\u00e8nes \u00e0 l&rsquo;OTAN, o\u00f9 sont d\u00e9battus certains aspects des interventions de communication.<\/p>\n<\/p>\n<p><p>\t\u00a0Des <em>interviews<\/em> de certains acteurs, directs ou indirects, de la guerre de la communication ainsi d\u00e9crite,  en fait, trois porte-paroles : Jamie Shea (OTAN), Jim Lockhardt (Maison-Blanche), Jamie Rubin (State department) ; et deux journalistes fran\u00e7ais : Luc Rozensweig, du <em>Monde<\/em>, Claude Julien, de RTL.<\/p>\n<h3>Un service de communication pris de cours devant des centaines de journalistes<\/h3>\n<\/p>\n<p><p>\tCette \u00ab\u00a0guerre\u00a0\u00bb du Kosovo m\u00e9rite tous les guillemets du monde. Il s&rsquo;agit de la guerre de la communication, mais pas du tout dans le sens classique (propagande amie contre propagande ennemie). Elle \u00ab\u00a0oppose\u00a0\u00bb les autorit\u00e9s officielles dispensatrices d&rsquo;information aux journalistes de leurs pays, ou, dans tous les cas, semble les \u00ab\u00a0opposer\u00a0\u00bb. Le qualificatif d'\u00a0\u00bbopposition\u00a0\u00bb qui vient d&rsquo;abord sous la plume s&rsquo;av\u00e8re \u00eatre une interpr\u00e9tation tr\u00e8s fallacieuse, et nous pr\u00e9tendons montrer au contraire que cette opposition est en fait une complicit\u00e9. La complicit\u00e9 commence par le fait que les journalistes acceptent compl\u00e8tement, sans restriction, sans la moindre g\u00eane, sans aucun frein, que les autorit\u00e9s officielles de leurs pays soient effectivement la source quasi-exclusive de l&rsquo;information sur le monde r\u00e9el, \u00e0 la place du constat du monde r\u00e9el par le journaliste, ses yeux, sa t\u00eate, son coeur.<\/p>\n<\/p>\n<p><p>\tLa \u00ab\u00a0guerre d&rsquo;Ev\u00e8re\u00a0\u00bb men\u00e9e par les <em>spin doctors<\/em> (expression en langue anglo-am\u00e9ricaine d\u00e9signant les sp\u00e9cialistes de publicit\u00e9 et des relations publiques ; litt\u00e9ralement : \u00ab\u00a0professeurs en apparence\u00a0\u00bb) est divis\u00e9e en trois phases dans le document. Ces phases ne suivent que lointainement la guerre proprement dite, sur le terrain, au Kosovo. Ces phases sont les suivantes :<\/p>\n<\/p>\n<p><p>\t\u00a0Les 2-3 premiers jours. Albright avait dit que les frappes dureraient 2-3 jours (ce que femme dit&#8230;) : la guerre devait donc durer deux ou trois jours. C&rsquo;\u00e9tait l&rsquo;analyse de l&rsquo;OTAN et de toutes les chancelleries, puisqu&rsquo;Albright&#8230; L&rsquo;OTAN (son service de communication, avec le porte-parole Jamie Shea) n&rsquo;est pr\u00e9par\u00e9e \u00e0 rien de plus et n&rsquo;a pris aucune disposition particuli\u00e8re. Elle se trouve tr\u00e8s vite d\u00e9munie.<\/p>\n<\/p>\n<p><p>\t\u00a0La guerre continue apr\u00e8s les 2-3 jours fatidiques. Les journalistes affluent. Ils sont bient\u00f4t 400, 500. Chaque jour, ils veulent leur point de presse, pour apprendre des nouvelles et faire leurs \u00e9missions, ou leurs articles, bref revendre la salade qu&rsquo;on leur a fournie une premi\u00e8re fois. Jamie Shea doit tenir ce point de presse, chaque apr\u00e8s-midi. \u00ab <em>Le probl\u00e8me est qu&rsquo;il y avait cette heure d&rsquo;antenne, chaque jour, qu&rsquo;il fallait remplir, <\/em>explique Shea. <em>Si nous ne l&rsquo;avions pas fait, d&rsquo;autres l&rsquo;auraient fait. Milosecic, bien s\u00fbr!<\/em> \u00bb Certains moments sont path\u00e9tiques, au-del\u00e0 de l&rsquo;ironie, de l&rsquo;ennui et de la confusion de se d\u00e9couvrir dans un lieu qui est un des coeurs de l&rsquo;alliance occidentale, en pr\u00e9sence d&rsquo;une telle mati\u00e8re intellectuelle. C&rsquo;est, par exemple, ce moment o\u00f9 Jamie Shea lit soigneusement, article par article, les articles de la Constitution yougoslave que Milosevic serait en train de violer par son comportement. Aux 21e et 23e jours de la guerre, deux grosses \u00ab\u00a0bavures\u00a0\u00bb sur le terrain (attaque d&rsquo;un train et attaque d&rsquo;un convoi de r\u00e9fugi\u00e9s kossovars par l&rsquo;OTAN) mettent le service de l&rsquo;information de l&rsquo;OTAN (Shea) en grandes difficult\u00e9s devant les centaines de journalistes pr\u00e9sents.<\/p>\n<\/p>\n<p><p>\t\u00a0La troisi\u00e8me phase, c&rsquo;est l&rsquo;intervention des <em>spin doctors<\/em> de l&rsquo;ext\u00e9rieur, les grosses pointures, les \u00ab\u00a0mecs\u00a0\u00bb rouleurs de m\u00e9canique, les durs de dur, ceux de Washington et ceux du 10, Downing Street (un peu, \u00e0 peine, ceux de l&rsquo;Elys\u00e9e), parlant anglo-am\u00e9ricain et m\u00e2chant du chewing-gum dans leur t\u00eate. L\u00e0, c&rsquo;est le triomphe de l&rsquo;offensive de communication, l\u00e0 o\u00f9, effectivement, \u00ab <em>on nous a vendu la guerre<\/em> \u00bb.<\/p>\n<\/p>\n<p><p>\tA partir de ce canevas, nous allons faire quelques remarques sur ces \u00ab\u00a0sc\u00e8nes de la vie ordinaire\u00a0\u00bb, \u00e0 Ev\u00e8re, au printremps 1999, pendant la guerre.<\/p>\n<h3>Les \u00ab<strong><em>Top Guns de la communication<\/em><\/strong>\u00bb \u00e0 Bruxelles pour sauver la campagne<\/h3>\n<\/p>\n<p><p>\tCertes, l&rsquo;OTAN\/Shea n&rsquo;\u00e9tait pas pr\u00eate. La raison est tr\u00e8s simple : l&rsquo;OTAN tant vant\u00e9e, qu&rsquo;on embrasse constamment pour mieux la tenir enferm\u00e9e, est un fameux bouc-\u00e9missaire. Quand les choses vont mal, comme \u00e0 Ev\u00e8re-Kosovo au printemps 1999, tout le monde dira en finale que c&rsquo;est de la faute de l&rsquo;OTAN. La malheureuse OTAN n&rsquo;a rien d&rsquo;autre \u00e0 faire qu&rsquo;\u00e0 subir, car elle n&rsquo;a pas les moyens de faire autre chose. Dans la logique de cette situation, tous les membres qui ne cessent de lui tresser des lauriers lui mesurent chichement ses moyens. Il faut voir l&rsquo;\u00e9bahissement du poids lourd (au moins un quintal) Joe Lockhardt, porte-parole de Clinton, lorsqu&rsquo;il rapporte : \u00ab <em>J&rsquo;ai 30 personnes qui travaille dans mon groupe <\/em>[services du porte-parole], <em>ici, \u00e0 la Maison-Blanche. Alors, j&rsquo;ai \u00e9t\u00e9 choqu\u00e9 d&rsquo;apprendre que Jamie Shea n&rsquo;avait que 4 ou 5 personnes&#8230;<\/em> \u00bb <\/p>\n<\/p>\n<p><p>\t[Cette position initiale de Shea est d&rsquo;une importance fondamentale. C&rsquo;est \u00e0 cause de ces difficult\u00e9s initiales que le porte-parole de l&rsquo;OTAN s&#8217;empara du th\u00e8me du \u00ab\u00a0g\u00e9nocide\u00a0\u00bb d\u00e8s que les premiers r\u00e9fugi\u00e9s se pr\u00e9cipit\u00e8rent sur les routes du Kosovo. Cette id\u00e9e de g\u00e9nocide, totalement outranci\u00e8re, absolument d\u00e9mentie par les constats que l&rsquo;on fit ensuite, allait influencer la strat\u00e9gie, la politique, obliger \u00e0 certaines d\u00e9cisions, amener \u00e0 accro\u00eetre d\u00e9cisivement certains soutiens (\u00e0 l&rsquo;UCK notamment) et finalement installer la situation si dommageable qui a suivi la guerre et dont on subit les cons\u00e9quences aujourd&rsquo;hui.], <\/p>\n<\/p>\n<p><p>\tVis-\u00e0-vis des militaires du quartier-g\u00e9n\u00e9ral SHAPE  c&rsquo;est-\u00e0-dire vis-\u00e0-vis des Am\u00e9ricains  Shea et l&rsquo;OTAN ne sont pas mieux lotis. Ainsi le porte-parole de l&rsquo;OTAN apprend-il en regardant la t\u00e9l\u00e9vision de Milosevic, au 21e jour de l&rsquo;offensive, qu&rsquo;il y a eu une \u00ab\u00a0bavure\u00a0\u00bb majeure de l&rsquo;OTAN (le train attaqu\u00e9 sur un pont). Il s&rsquo;informe aupr\u00e8s de SHAPE, pour obtenir, apr\u00e8s beaucoup de r\u00e9ticences, une confirmation partielle ; puis, un peu plus tard, un document pr\u00e9tend\u00fbment d\u00e9cisif (un film dans un cockpit d&rsquo;avion am\u00e9ricain) qui s&rsquo;av\u00e9rera \u00eatre un faux. M\u00eame d\u00e9sordre, m\u00eames r\u00e9ticences des militaires pour la deuxi\u00e8me bavure majeure (un convoi de Kosovars attaqu\u00e9 par erreur).<\/p>\n<\/p>\n<p><p>\tShea est en grande difficult\u00e9. Il l&rsquo;est \u00e0 cause du syst\u00e8me lui-m\u00eame, qui se sert de l&rsquo;OTAN mais ne m\u00e9nage pas les chausse-trappes \u00e0 l&rsquo;Organisation. C&rsquo;est alors qu&rsquo;on d\u00e9cide de renforcer Shea. Les termes employ\u00e9s sont martiaux, comme si nous \u00e9tions sur le th\u00e9\u00e2tre des op\u00e9rations : \u00ab <em>Tony Blair et Bill Clinton d\u00e9cident d&rsquo;envoyer des renforts \u00e0 Bruxelles<\/em> \u00bb Et le commentateur de Canal +, suivant le chemin trac\u00e9, commente : \u00ab <em>En 48 heures, trente Top Guns de la communication d\u00e9barquent \u00e0 Bruxelles<\/em> \u00bb.<\/p>\n<\/p>\n<p><p>\tBref, Ev\u00e8re, c&rsquo;est l\u00e0 que tout se passe, c&rsquo;est l\u00e0 qu&rsquo;on fait la guerre. Mais, certes, c&rsquo;est une guerre tr\u00e8s particuli\u00e8re. Le commentateur de Canal + observe que, \u00ab <em>pour Alastair Campbell, une bonne image vaut mieux que toute action politique<\/em> \u00bb. Alastair Campbell, conseiller en communication de Tony Blair, est en effet d\u00e9plac\u00e9 \u00e0 la t\u00eate des \u00ab <em>Top Guns de la Communication<\/em> \u00bb. Plus tard, en juillet, Campbell expliquera, r\u00e9sumant parfaitement l&rsquo;enjeu d&rsquo;Ev\u00e8re contre l&rsquo;enjeu du Kosovo, que la bataille pour le Kosovo \u00e9tait gagn\u00e9e d&rsquo;avance, et que la vraie bataille, la plus ind\u00e9cise, c&rsquo;\u00e9tait celle qui se livrait pour les esprits et les coeurs des citoyens des pays occidentaux engag\u00e9s dans la guerre, pour ou contre la guerre.<\/p>\n<\/p>\n<p><p>\tLe document nous montre aussit\u00f4t les <em>spin doctors<\/em>. Il faut faire court,  des phrases courtes, des phrases-chocs, que Shea est pri\u00e9 de l\u00e2cher durant sa conf\u00e9rence de presse ; un th\u00e8me chaque jour, si possible simple, frappant, bouleversant, avec un peu de folie sadique (des viols collectifs, des Kosovars forc\u00e9s de donner leur sang). Un conseiller de Clinton, Jonathan Price, exp\u00e9di\u00e9 sur place (\u00e0 Bruxelles) : \u00ab <em>Trouver le mot juste, qualifier ces exactions, constamment diriger les journalistes vers ces sujets, exposer ces faits du mieux que nous pouvions alors que nous n&rsquo;\u00e9tions pas sur le terrain.<\/em> \u00bb Et la r\u00e9alit\u00e9 ? Le commentateur de Canal : \u00ab <em>Ces affirmations sont bas\u00e9es sur des t\u00e9moignages de r\u00e9fugi\u00e9s, inv\u00e9rifiables, elles ne seront jamais confirm\u00e9es.<\/em> \u00bb Aujourd&rsquo;hui, bien entendu, la r\u00e9alit\u00e9 est \u00e0 peu pr\u00e8s connue. On sait que ces r\u00eacits relev\u00e8rent pour l&rsquo;essentiel du phantasme, de la rumeur, de l&rsquo;erreur humaine et ainsi de suite. Mais seul compte l&rsquo;instant et ce qui est dit dans l&rsquo;instant, et l&rsquo;effet obtenu dans l&rsquo;instant. \u00ab <em>Les vendeurs de guerre ont r\u00e9ussi leur coup<\/em> \u00bb, explique le commentateur.<\/p>\n<\/p>\n<p><p>\tLe mot de la fin, sur ces activit\u00e9s et sur les techniques employ\u00e9es, on le tient de Jamie Rubin, porte-parole d&rsquo;Albright. Il est interrog\u00e9 sur le r\u00e9sultat des frappes au Kosovo : 14 chars d\u00e9truits confirm\u00e9s, alors qu&rsquo;on en avait annonc\u00e9 plus de 100, peut-\u00eatre 150. Constat int\u00e9ressant : Rubin ne nie pas (au contraire du Pentagone, par exemple) que le v\u00e9ritable \u00ab\u00a0score\u00a0\u00bb soit de 14 chars d\u00e9truits. Et alors? Semble-t-il dire. Il conclut : \u00ab <em>But it works!<\/em> \u00bb Autrement dit : les gens ont march\u00e9, ils y ont cru, l&rsquo;affaire est boucl\u00e9e. Le ma\u00eetre-mot de Rubin, c&rsquo;est \u00ab <em>cr\u00e9ativit\u00e9<\/em> \u00bb : les <em>spin doctors<\/em> doivent en montrer, tout comme les journalistes eux-m\u00eames.<\/p>\n<\/p>\n<p><p>\tNous ne sommes plus dans le monde de l&rsquo;information (journalistes), nous sommes dans le monde des \u00ab\u00a0cr\u00e9ateurs d&rsquo;\u00e9v\u00e9nements\u00a0\u00bb (publicitaires). Dans son livre <em>Dans les griffes des humanistes<\/em>, Stanko Cerovic, dissident serbe et journaliste \u00e0 Radio France International, remarque : \u00ab <em>Les m\u00e9dias occidentaux savent d\u00e9sormais si habilement occulter la r\u00e9alit\u00e9 qu&rsquo;ils cr\u00e9ent l&rsquo;illusion qu&rsquo;on peut mener une politique tout en la niant.<\/em> \u00bb Cerovic nous rappelle opportun\u00e9ment que les <em>spin doctors<\/em> ne sont pas seuls. La situation n&rsquo;est pas si simple qu&rsquo;elle le serait s&rsquo;il s&rsquo;agissait simplement de propagande, avec le rapport du fort (l&rsquo;\u00c9tat autoritaire) au faible (la presse aux ordres). \u00ab <em>C&rsquo;est bien plus subtil que de la propagande<\/em> \u00bb, disait-on plus haut ; nous nuancerions : c&rsquo;est bien plus compliqu\u00e9 que de la propagande.<\/p>\n<h3>Tentative de dissection et d&rsquo;anatomie de la campagne strat\u00e9gique de la \u00ab\u00a0guerre d&rsquo;Ev\u00e8re\u00a0\u00bb<\/h3>\n<\/p>\n<p><p>\tComment peut-on synth\u00e9tiser et classifier l&rsquo;analyse de cette p\u00e9riode de la \u00ab\u00a0guerre d&rsquo;Ev\u00e8re\u00a0\u00bb, au travers du documentaire que nous avons d\u00e9taill\u00e9? Nous avons d\u00e9termin\u00e9 trois tendances, trois attitudes diff\u00e9rentes et compl\u00e9mentaires, et l&rsquo;ensemble devrait effectivement tracer le tableau dans lequel les \u00e9v\u00e9nements d&rsquo;Ev\u00e8re ont \u00e9volu\u00e9. Ces trois attitudes sont les suivantes :<\/p>\n<\/p>\n<p><p>\t\u00a0Le front et l&rsquo;arri\u00e8re.<\/p>\n<\/p>\n<p><p>\t\u00a0L&rsquo;indiff\u00e9rence pour la r\u00e9alit\u00e9 : cloisonnement et professionnalisme.<\/p>\n<\/p>\n<p><p>\t\u00a0L&rsquo;esprit critique dans les bornes du conformisme.<\/p>\n<\/p>\n<p><p>\tLe premier point est la question du front et de l&rsquo;arri\u00e8re. Lors de la Grande Guerre, \u00e0 cause de la strat\u00e9gie d&rsquo;un front quasiment immobile avec ses tranch\u00e9es, la distinction et l&rsquo;identification entre le front et l&rsquo;arri\u00e8re pouvait ais\u00e9ment \u00eatre faite et c&rsquo;est de ce temps-l\u00e0 que date la distinction. Dans le cas de la guerre du Kosovo, on reprend cette distinction, mais en l&rsquo;inversant. Alastair Campbell nous le laisse clairement entendre lorsqu&rsquo;il dit, en juillet 1999, que la guerre que menait l&rsquo;OTAN au Kosovo ne pouvait \u00eatre perdue, qu&rsquo;en un sens elle \u00e9tait jou\u00e9e d&rsquo;avance, presque comme s&rsquo;il e\u00fbt \u00e9t\u00e9 inutile de la faire, parce que la puissance de l&rsquo;OTAN ne pouvait \u00e9videmment souffrir le moindre soup\u00e7on de d\u00e9faite face \u00e0 la Serbie ; que la vraie guerre, finalement, c&rsquo;est bien la \u00ab\u00a0guerre d&rsquo;Ev\u00e8re\u00a0\u00bb. Ainsi le front s&rsquo;est-il d\u00e9plac\u00e9 \u00e0 Ev\u00e8re, et l'\u00a0\u00bbarri\u00e8re\u00a0\u00bb de la guerre, c&rsquo;est le Kosovo. Il y a une transformation psychologique remarquable qui a certainement contribu\u00e9 \u00e0 donner \u00e0 ce conflit cette impression d&rsquo;irr\u00e9alit\u00e9 si remarquable. La d\u00e9cision extraordinaire pour les alli\u00e9s de tout faire pour \u00e9viter la moindre victime du c\u00f4t\u00e9 alli\u00e9, la tactique du z\u00e9ro-mort, participe \u00e9galement \u00e0 cette d\u00e9marche : cette d\u00e9cision a \u00e9videmment pour but de renforcer, dans la \u00ab\u00a0guerre d&rsquo;Ev\u00e8re\u00a0\u00bb, le parti des <em>spin doctors<\/em>.<\/p>\n<\/p>\n<p><p>\tCe ph\u00e9nom\u00e8ne est marqu\u00e9 dans le documentaire de Canal +, notamment dans les commentaires qui l&rsquo;accompagnent. Il est \u00e9clatant dans le tournant de cette \u00ab\u00a0guerre d&rsquo;Ev\u00e8re\u00a0\u00bb, lorsque le commentateur d\u00e9crit comme path\u00e9tique l&rsquo;\u00e9tat de la communication de l&rsquo;OTAN et annonce la d\u00e9cision du \u00ab\u00a0haut commandement\u00a0\u00bb de la guerre de la communication : \u00ab <em>Tony Blair et Bill Clinton d\u00e9cident d&rsquo;envoyer des renforts \u00e0 Bruxelles.<\/em> \u00bb Les termes sont compl\u00e8tement militaires, dans ce cas comme dans nombre d&rsquo;occasions (les \u00ab <em>Top Guns de la communication<\/em> \u00bb), et c&rsquo;est d&rsquo;ailleurs dans la logique de la d\u00e9marche constante des milieux de la communication, qui raisonnent effectivement en termes militaires (la \u00ab\u00a0strat\u00e9gie\u00a0\u00bb d&rsquo;une \u00ab\u00a0campagne\u00a0\u00bb publicitaire). La guerre au Kosovo devient secondaire. Elle tend \u00e0 prendre une place annexe, une place compl\u00e9mentaire. On en vient \u00e0 se demander s&rsquo;il s&rsquo;agit vraiment de la guerre. On en vient \u00e0 s&rsquo;interroger, comme le poilu de 1914 dans sa tranch\u00e9e, qui s&rsquo;interrogeait plut\u00f4t sarcastiquement : \u00ab <em>tiendront-ils ?<\/em> \u00bb C&rsquo;est-\u00e0-dire, transcrit en termes militaires : effectueront-ils leurs missions selon ce qu&rsquo;on en attend, z\u00e9ro-mort du c\u00f4t\u00e9 alli\u00e9, pas de \u00ab\u00a0bavures\u00a0\u00bb m\u00e9diatiquement d\u00e9sastreuses (c&rsquo;est-\u00e0-dire, pas d&rsquo;incidents collat\u00e9raux avec pr\u00e9sence de la TV pour en faire la publicit\u00e9 ; on ne parle pas ici en termes humanitaires, pour \u00e9viter trop de pertes \u00e0 l&rsquo;adversaires ; on parle en termes d&rsquo;efficacit\u00e9 et d&rsquo;image : il ne faut pas d&rsquo;incidents m\u00e9diatis\u00e9s allant contre le plan pr\u00e9vu).<\/p>\n<\/p>\n<p><p>\tCe ph\u00e9nom\u00e8ne qui transporte le front \u00e0 l&rsquo;arri\u00e8re et fait du front l&rsquo;arri\u00e8re, entra\u00eene sur le nouveau \u00ab\u00a0front\u00a0\u00bb, \u00e0 Ev\u00e8re, l&rsquo;esprit m\u00eame de la guerre en train d&rsquo;\u00eatre men\u00e9e, et c&rsquo;est l&rsquo;esprit absolument, totalement partisan, on dirait m\u00eame : l&rsquo;esprit vitalement partisan (quand on doit gagner une guerre, on se trouve devant une fonction vitale). Il s&rsquo;ensuit le deuxi\u00e8me point, qui est l&rsquo;indiff\u00e9rence totale pour la r\u00e9alit\u00e9, ce qui fait en g\u00e9n\u00e9ral le principal mat\u00e9riel pour d\u00e9terminer la v\u00e9rit\u00e9 : la recherche de la v\u00e9rit\u00e9, d\u00e9marche n\u00e9cessairement objective, n&rsquo;a pas sa place puisqu&rsquo;on est par nature partisan. Il n&rsquo;y a pas l\u00e0, en aucune fa\u00e7on, la moindre d\u00e9termination, le moindre plan, encore moins, le moindre machiav\u00e9lisme (on n&rsquo;est pas contre la r\u00e9alit\u00e9\/la v\u00e9rit\u00e9, on y est induff\u00e9rent). Il n&rsquo;est d&rsquo;ailleurs plus question du fond (qui a raison ? Que nous enseignent les informations venues de la guerre ? Pourquoi cette guerre ? Est-ce la bonne fa\u00e7on de faire cette guerre ? Et ainsi de suite). Il n&rsquo;est plus question que des moyens, de la m\u00e9thode, du \u00ab\u00a0comment\u00a0\u00bb : comment faire passer ce message, comment illustrer le plus favorablement ce que fait l&rsquo;OTAN (pour les <em>spin doctors<\/em>) ; comment d\u00e9busquer l&rsquo;erreur de la communication, comment prendre le porte-parole en flagrant d\u00e9lit d&rsquo;approximation (pour les journalistes). L&rsquo;enqu\u00eate habituelle, le constat et le rapport de la r\u00e9alit\u00e9, le commentaire qu&rsquo;on en fait, qui sont les activit\u00e9s habituelles du journaliste, sont remplac\u00e9s par le professionnalisme et le cloisonnement du travail : il s&rsquo;agit, pour les journalistes, de surveiller le travail des <em>spin doctors<\/em> et \u00e9ventuellement de les prendre en flagrant d\u00e9lit de faiblesse professionnelle (comment ils ne sont pas assez convaincants, comment il ne nous vendent pas assez bien leur salade, etc) ; il s&rsquo;agit de s&rsquo;attacher \u00e0 chaque d\u00e9tail du jour, celui que nous servent les <em>spin doctors<\/em>, et de jauger leur professionnalisme dans ce cadre. Il y a longtemps que la r\u00e9alit\u00e9 du monde (de la guerre) n&rsquo;est plus le probl\u00e8me central, naturellement, et si on la rencontre, c&rsquo;est accidentellement, \u00ab\u00a0professionnellement\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>\tAinsi distingue-t-on d\u00e9j\u00e0 le troisi\u00e8me point parce qu&rsquo;il est in\u00e9vitable, et il est essentiel,  car, finalement, c&rsquo;est ce qui distingue la guerre du Golfe de la guerre du Kosovo : la complicit\u00e9 des journalistes. En s&rsquo;installant \u00e0 Ev\u00e8re, les journalistes ont accept\u00e9 les r\u00e8gles des <em>spin doctors<\/em>, c&rsquo;est-\u00e0-dire les r\u00e8gles du conformisme, nullement en t\u00e9moins tromp\u00e9s mais en acteurs complices. Ils suivent la performance de Shea avec le coup d&rsquo;oeil professionnel, plut\u00f4t critique (\u00ab <em>Jamie est un universitaire<\/em> \u00bb, s&rsquo;exclame Rozensweig, et cela dit tout, notamment le manque de souplesse et de vigueur de Shea) ; ils appr\u00e9cient les performances des nouveaux-venus, les <em>spin doctors<\/em> de la bande \u00e0 Campbell, qui leur vendent enfin la salade qu&rsquo;ils attendent, et ils la vendent, comme on dit, et le terme est bienvenu,  sans bavures.<\/p>\n<\/p>\n<p><p>\tLorsqu&rsquo;un journaliste (anglais, sans aucun doute, pour avoir ce ton p\u00e9remptoire) s&rsquo;adresse \u00e0 Jamie Shea pour lui dire (c&rsquo;est au moment de la deuxi\u00e8me bavure, celle du 23e jour de l&rsquo;offensive, celle du convoi kosovar attaqu\u00e9 par erreur) : \u00ab <em>D\u00e9sol\u00e9 Jamie, mais, cette fois, vous ne vous en tirerez pas comme \u00e7a. Nous comprenons que vous vouliez laisser cela, cet \u00e9chec, derri\u00e8re vous, mais il n&rsquo;y a qu&rsquo;un moyen : nous dire tout ce que vous savez.<\/em> \u00bb (Le paradoxe tragi-comique est que Shea ne sait rien, les militaires de SHAPE jouant le jeu de leur c\u00f4t\u00e9.) En fait, on a moins l&rsquo;impression d&rsquo;un enqu\u00eateur \u00e0 la recherche de la r\u00e9alit\u00e9 d&rsquo;un point particulier pour parvenir \u00e0 la v\u00e9rit\u00e9 g\u00e9n\u00e9rale, que d&rsquo;un censeur (de lyc\u00e9e) r\u00e9primandant l&rsquo;acteur (l&rsquo;\u00e9l\u00e8ve) qui a laiss\u00e9 la pi\u00e8ce transgresser ses r\u00e8gles (c&rsquo;est la bavure), et ainsi d\u00e9ranger l&rsquo;agencement g\u00e9n\u00e9ral. La d\u00e9nonciation de la bavure ne sert en aucun cas \u00e0 \u00e9tablir (r\u00e9tablir) une r\u00e9alit\u00e9 au service de la v\u00e9rit\u00e9, elle sert \u00e0 rappeler les r\u00e8gles qui r\u00e9gissent l&rsquo;appr\u00e9ciation conformiste du monde \u00e0 laquelle les journalistes sont totalement, professionnellement, et, l&rsquo;on dirait encore plus, moralement partie prenante. Les journalistes sont, encore plus que les <em>spin doctors<\/em>, les principaux combattants de cette \u00ab\u00a0guerre d&rsquo;Ev\u00e8re\u00a0\u00bb. Au contraire de la guerre du Golfe o\u00f9 ils avaient \u00e9t\u00e9 manipul\u00e9s, ils ont \u00e9t\u00e9, en cette occurence, du c\u00f4t\u00e9 des tireurs de ficelle.<\/p>\n<h3>Il s&rsquo;agit des m\u00eames Bouvard et P\u00e9cuchet <strong><em>at war<\/em><\/strong><\/h3>\n<\/p>\n<p><p>\tMaintenant (en guise de conclusion disons), il s&rsquo;agit d&rsquo;\u00eatre s\u00e9rieux. Lorsque le commentateur tr\u00e8s style-Canal, voix m\u00e9tallique, banalit\u00e9s p\u00e9remptoires, commente l&rsquo;arriv\u00e9e de Tony Blair \u00e0 l&rsquo;OTAN, Tony venu \u00ab <em>remettre de l&rsquo;ordre dans la communication de l&rsquo;OTAN<\/em> \u00bb, il faut finalement en arriver \u00e0 se pincer. Ainsi, on devrait r\u00e9aliser o\u00f9 l&rsquo;on est et de quoi l&rsquo;on parle, et ce qui est dit. Le pr\u00e9sentateur-Canal nous parle et nous pr\u00e9sente les choses en termes pompeux, enthousiastes et sourcilleux, c&rsquo;est selon, comme s&rsquo;il d\u00e9crivait le comportement de Napoleon \u00e0 Austerlitz,  c&rsquo;est-\u00e0-dire, que l&rsquo;on aime ou pas Napol\u00e9on, le comportement du g\u00e9nie strat\u00e9gique. Dans le cas de Blair et compagnie, c&rsquo;est au niveau de la parole qu&rsquo;on nous invite \u00e0 reconna\u00eetre ce qui semble un comportement assimilable au g\u00e9nie strat\u00e9gique de Napol\u00e9on \u00e0 Austerlitz. Justement, il y a les paroles, c&rsquo;est-\u00e0-dire le contenu.<\/p>\n<\/p>\n<p><p>\tCe que nous dit Blair, finalement, c&rsquo;est le mensonge plus court, plus p\u00e9remptoire en un sens (voil\u00e0 ce que nous montre le documentaire, tous comptes faits). Du coup, le regard plus clair, l&rsquo;on comprend \u00e0 qui l&rsquo;on a \u00e0 faire. (L&rsquo;on se prend \u00e0 noter que Campbell pourrait aussi conseiller \u00e0 Blair, pendant qu&rsquo;il y est, de changer, et de tailleur, et de chemisier et de coiffeur). Alors, quel est le g\u00eanie de Blair ? Le mentir-court, le mentir-Fleet Street ? Il ment plus court que les autres, donc il distance les autres ? (Et le plus fort, et cela situe l&rsquo;esprit de nos dirigeants et la confusion o\u00f9 ils \u00e9voluent, notre certitude est que, lorsqu&rsquo;il parle et qu&rsquo;il est emport\u00e9 par l&rsquo;atmosph\u00e8re, Blair ne doit pas se voir mentir, il a l&rsquo;impression de parler vrai. \u00ab <em>Our cause is just<\/em> \u00bb : effectivement, une phrase si courte ne laisse gu\u00e8re de place au mensonge.)<\/p>\n<\/p>\n<p><p>\tPour autant, le lieu commun reste le lieu commun. Nous dire que \u00ab <em>our cause is just<\/em> \u00bb et que \u00ab <em>nous faisons cette guerre et nous allons la gagner<\/em> \u00bb (Blair <em>dixit<\/em>), cela n&rsquo;a pas vraiment de quoi bouleverser, et cela ne distingue pas de fa\u00e7on d\u00e9cisive notre \u00e9poque de celles qui ont pr\u00e9c\u00e9d\u00e9 ; un truc comme \u00ab <em>la route du fer est coup\u00e9<\/em> \u00bb, ou bien \u00ab <em>nous gagnerons parce que nous sommes les plus forts<\/em> \u00bb, ou bien encore \u00ab <em>la mobilisation n&rsquo;est pas la guerre<\/em> \u00bb, aurait eu certainement sa place \u00e0 Ev\u00e8re. Non, ce qui nous inqui\u00e8te, c&rsquo;est que ces 400, 500 journalistes \u00e9coutent cela, presque religieusement, et semblent y croire, et y croient finalement, et, un an ou deux ans plus tard, vous font des \u00e9missions qu&rsquo;ils ponctuent d&rsquo;un \u00ab <em>chapeau<\/em> \u00bb, ou d&rsquo;un \u00ab <em>Bien jou\u00e9<\/em> \u00bb. Nous allons devoir vivre avec ce doute formidable concernant cette profession si importante des journalistes.<\/p>\n<\/p>\n<p><p>\tNous devons aussi nous rassurer. Finalement, la guerre d&rsquo;Ev\u00e8re n&rsquo;a pas \u00e9t\u00e9 une intense machination, une formidable machine de d\u00e9sinformation, une incroyable campagne de propagande subtile, \u00ab <em>quelque chose de bien plus subtil que la propagande<\/em> \u00bb, non. Ces explications sont plus accessoires qu&rsquo;on croit, m\u00eame si elles ont leur place et si l&rsquo;on doit en tenir compte. C&rsquo;\u00e9tait simplement la traditionnelle, l&rsquo;habituelle, la lourde et l\u00e9g\u00e8re \u00e0 la fois, la sottise bien-connue, multipli\u00e9e par les moyens fantastiques de la technologie et de la communication. C&rsquo;\u00e9tait \u00ab <em>Bouvard and P\u00e9cuchet at war<\/em> \u00bb, mais en moins bourgeois, en moins flaub\u00e9rien, en plus <em>high tech<\/em>, plus <em>hip hop<\/em>,  bref, en plus con. Rassurez-vous, c&rsquo;est toujours Bouvard et P\u00e9cuchet. Il y a quelque chose comme la constance et la continuit\u00e9 de la tradition.<\/p>\n<\/p>\n<p><p>\t(1) Nous avons donn\u00e9 un nom \u00e0 ce ph\u00e9nom\u00e8ne, que nous tendons \u00e0 consid\u00e9rer comme une sorte de doctrine, d&rsquo;id\u00e9ologie : le virtualisme. (Voir Analyse, Volume 15, n<198>01, du 10 septembre 1999.)<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bouvard and Pecuchet at war Autre anniversaire, apr\u00e8s celui de la guerre du Golfe : celui de la guerre du Kosovo, deux ans apr\u00e8s (d\u00e9marrage des frappes le 24 mars 1999). Comm\u00e9moration d&rsquo;autant plus n\u00e9cessaire \u00e0 c\u00e9l\u00e9brer qu&rsquo;au Kosovo, et autour du Kosovo (c&rsquo;est la nouveaut\u00e9), dans cette fameuse r\u00e9gion qui est une partie de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[],"class_list":["post-64918","post","type-post","status-publish","format-standard","hentry","category-de-defensa"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/64918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=64918"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/64918\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=64918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=64918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=64918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}