{"id":64921,"date":"2000-05-25T00:00:00","date_gmt":"2000-05-24T22:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2000\/05\/25\/etrange-france\/"},"modified":"2000-05-25T00:00:00","modified_gmt":"2000-05-24T22:00:00","slug":"etrange-france","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2000\/05\/25\/etrange-france\/","title":{"rendered":"Etrange France ..<strong><em>.<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955;font-size:2em;\">Etrange France&#8230;<\/h2>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955;font-size:1.25em;\">Extrait de <em>de defensa<\/em> Volume 15, n&deg;17 du 25 mai 2000<\/h3>\n<\/p>\n<p><p>Ces deux derni\u00e8res ann\u00e9es, si l&rsquo;on veut consid\u00e9rer la situation des relations internationales comme un match o&ugrave; l&rsquo;on marque des points, la France en a marqu\u00e9 quelques-uns d&rsquo;importance dans l&rsquo;ar\u00e8ne des rapports entre alli\u00e9s qui ressemblent souvent \u00e0 des affrontements syst\u00e9matiques. Nous d\u00e9taillons quelques-uns de ces points. Il ne s&rsquo;agit pas de ces victoires m\u00e9diatiques, de ces sommets ou rencontres spectaculaires, etc ; ces points marqu\u00e9s ne font l&rsquo;objet d&rsquo;aucun communi- qu\u00e9 et ne constituent pas des \u00ab\u00a0nouvelles\u00a0\u00bb en soi. Ils sont rarement repris aux Journaux t\u00e9l\u00e9vis\u00e9s. Ils n&rsquo;appartiennent pas \u00e0 l&rsquo;apparence m\u00e9diatique du monde. Par contre, ils font na&icirc;tre les courants profonds qui d\u00e9terminent les positions politiques, alimentent les positions de force, suscitent les rapports de puissance. Ils sont ce qui, au bout du compte, importe compl\u00e8tement.<\/p>\n<\/p>\n<p><p>&bull; Le lancement d&rsquo;une initiative de d\u00e9fense europ\u00e9enne (PESD). Le Royaume-Uni a \u00e9t\u00e9 en t\u00eate de cette dynamique initialement, et la France l&rsquo;a rejoint naturellement (apr\u00e8s les soup\u00e7ons d&rsquo;usage), dans sa position naturelle dans cette sorte d&rsquo;exercice, \u00e0 la fois incontournable et indispensable. La PESD repr\u00e9sente un triomphe des th\u00e8ses europ\u00e9ennes de la France depuis un demi-si\u00e8cle. Peu importe la fa\u00e7on qu&rsquo;on la pr\u00e9sente et peu importe ce qu&rsquo;il en r\u00e9sultera, peu importe les h\u00e9sitations des uns et des autres, ce qui est devenu la PESD impose une dynamique qui est essentiellement conforme aux conceptions strat\u00e9giques de la France pour l&rsquo;Europe. C&rsquo;est une \u00e9norme surprise par rapport \u00e0 la situation europ\u00e9enne et euroatlantiste.<\/p>\n<\/p>\n<p><p>&bull; L&rsquo;\u00e9conomie fran\u00e7aise constitue aujourd&rsquo;hui la r\u00e9f\u00e9rence europ\u00e9enne. Elle montre une capacit\u00e9 d&rsquo;adaptation qui n&rsquo;est pas n\u00e9cessairement une approbation des m\u00e9thodes qu&rsquo;elle \u00e9pouse, mais certainement l&rsquo;acceptation d&rsquo;une situation qui la d\u00e9passe et qu&rsquo;il lui faut pour l&rsquo;instant songer \u00e0 ma&icirc;triser plut\u00f4t qu&rsquo;\u00e0 combattre. Cette adaptation \u00e9conomique fran\u00e7aise est soutenue par une base technologique dont les produits font de la France le deuxi\u00e8me pays du monde dans ce domaine, derri\u00e8re les Am\u00e9ricains bien s&ucirc;r.<\/p>\n<\/p>\n<p><p>&bull; La guerre du Kosovo, \u00e0 c\u00f4t\u00e9 des pol\u00e9miques et des critiques qu&rsquo;elle soul\u00e8ve du point de vue politique, a mis en \u00e9vidence dans les rangs des alli\u00e9s europ\u00e9ens les exceptionnelles capacit\u00e9s fran\u00e7aises. C&rsquo;est surtout au niveau de l&rsquo;organisation, de l&rsquo;autonomie, de la suffisance strat\u00e9gique que la France a brill\u00e9. Elle a ainsi montr\u00e9 l&rsquo;effet au niveau de la puissance d&rsquo;une politique d&rsquo;ind\u00e9pendance et de souverainet\u00e9 d\u00e9velopp\u00e9e et suivie avec constance depuis le d\u00e9but des ann\u00e9es 1960.<\/p>\n<\/p>\n<p><p>A c\u00f4t\u00e9 de cela, la France continue \u00e0 affirmer une r\u00e9elle influence culturelle qualitative. Ce n&rsquo;est pas n\u00e9cessairement l&rsquo;avis des Fran\u00e7ais, mais dans ce cas les Fran\u00e7ais ne sont pas les meilleurs juges. Il suffit, pour mesurer la p\u00e9rennit\u00e9 de cette influence qui peut sembler paradoxale \u00e0 certains, de mentionner l&rsquo;exemple de la position qu&rsquo;occupe le fran\u00e7ais aux &Eacute;tats-Unis, comme deuxi\u00e8me \u00ab\u00a0langue \u00e9trang\u00e8re\u00a0\u00bb, c&rsquo;est-\u00e0-dire la premi\u00e8re en r\u00e9alit\u00e9 (l&rsquo;espagnol, la premi\u00e8re class\u00e9e, \u00e9tant avec l&rsquo;anglo-am\u00e9ricain l&rsquo;autre \u00ab\u00a0langue nationale\u00a0\u00bb des &Eacute;tats-Unis). Rapportant le fait, le journaliste am\u00e9ricain Jacques Strinberg note (1): &laquo;<em>Pr\u00e8s d&rsquo;un \u00e9tudiant am\u00e9ricain sur 4 du secondaire et du sup\u00e9rieur choisit toujours le fran\u00e7ais alors que cette langue n&rsquo;est parl\u00e9e que par un habitant sur 50 dans le monde. Par contraste, un \u00e9tudiant am\u00e9ricain sur 100 apprend le chinois ou le japonais, qui sont parl\u00e9s par 20% de la population mondiale.<\/em> &raquo; Le m\u00eame journaliste cite Richard Brecht, qui fait la promotion de l&rsquo;apprentissage des langages d\u00e9favoris\u00e9s aux USA, et qui remarque en se pla\u00e7ant du point de vue pratique que le succ\u00e8s de la langue fran\u00e7aise r\u00e9pond \u00e0 &laquo; <em>un argument culturel, pas \u00e0 un argument logique &#8230;<\/em> &raquo;.<\/p>\n<\/p>\n<p><p>L&rsquo;influence fran\u00e7aise d\u00e9fie la logique, notamment la logique de son rapport \u00e0 la puissance comptabilis\u00e9e, et c&rsquo;est la v\u00e9ritable puissance de la France : l&rsquo;influence fran\u00e7aise d\u00e9passe tr\u00e8s largement l&rsquo;influence qu&rsquo;on pourrait attendre de son degr\u00e9 de puissance. En un mot qu&rsquo;on se permettra d&#8217;emprunter ironiquement \u00e0 Madeleine Albright et consort, la France est une autre &laquo; <em>nation indispensable<\/em> &raquo;, bien diff\u00e9rente de l&rsquo;am\u00e9ricaine, affirm\u00e9e en qualit\u00e9 plus qu&rsquo;en quantit\u00e9, \u00e9chappant \u00e0 la raison pour s&rsquo;affirmer d&rsquo;une fa\u00e7on incontr\u00f4lable, plac\u00e9e en observateur critique des flux grossiers qui dominent plus qu&rsquo;en acteur inconscient et enjou\u00e9 de la globalisation courante et de la domination qui va avec.<\/p>\n<\/p>\n<p><p>Ce ne sont pas des mots en l&rsquo;air. Au contraire, ils dessinent une appr\u00e9ciation g\u00e9n\u00e9rale coh\u00e9rente. Aujourd&rsquo;hui, la France n&rsquo;est incomparable qu&rsquo;en ce qu&rsquo;elle affirme sa diff\u00e9rence (c&rsquo;est une lapalissade au fond mais il faut la r\u00e9p\u00e9ter en ces temps de confusion, et finalement elle devrait satisfaire le c\u00f4t\u00e9 cart\u00e9sien de l&rsquo;esprit fran\u00e7ais) ; &laquo; <em>affirmer sa diff\u00e9rence<\/em> &raquo; pas tant pour se diff\u00e9rencier que pour illustrer le principe dont elle devrait \u00eatre la d\u00e9fenderesse intraitable qu&rsquo;il est n\u00e9cessaire que les diff\u00e9rences et les identit\u00e9s s&rsquo;affirment pour sauvegarder la civilisation et refuser la servilit\u00e9 de l&rsquo;homo- g\u00e9n\u00e9isation du monde ; &laquo; <em>affirmer sa diff\u00e9rence<\/em> &raquo; pas du tout pour la gloriole futile de se comparer \u00e0 la puissance am\u00e9ricaine que pour la gloire de se proposer comme r\u00e9f\u00e9rence de ralliement \u00e0 ceux qui n&rsquo;acceptent pas d&rsquo;abdiquer leur identit\u00e9 et leur libert\u00e9 devant la puissance du syst\u00e8me am\u00e9ricaniste. Bien peu de Fran\u00e7ais sont conscients de ces opportunit\u00e9s qui tracent sa \u00ab\u00a0mission\u00a0\u00bb \u00e0 la France. Ils ne sont pas tellement plus conscients que, sans cette \u00ab\u00a0mission\u00a0\u00bb, la France n&rsquo;a plus aujourd&rsquo;hui aucun int\u00e9r\u00eat, qu&rsquo;elle devient alors insupportable avec ses pr\u00e9tentions \u00e0l&rsquo;exception, et qu&rsquo;elle m\u00e9rite alors mille fois les sarcasmes et les rebuffades dont les Anglo-Saxons sont coutumiers \u00e0 son encontre. D&rsquo;autres Anglo-Saxons sont bien plus conscients que les Fran\u00e7ais, avec plus d&rsquo;entendement et de profondeur, de ce caract\u00e8re exceptionnel de la France au nom duquel on peut affirmer que la France a une \u00ab\u00a0mission\u00a0\u00bb; ainsi, l&rsquo;historien am\u00e9ricain Eugen Weber (2) : &laquo;La culture fran\u00e7aise conforte mes pr\u00e9dilections. Avec une fr\u00e9quence qui m&rsquo;enchante, l&rsquo;exception, chez les Fran\u00e7ais, ne se borne pas \u00e0confirmer la r\u00e8gle ; c&rsquo;est <em>la r\u00e8gle.<\/em> &raquo; R\u00e9sumons pour notre cas : la France est et sera diff\u00e9rente ou elle ne m\u00e9rite plus d&rsquo;\u00eatre du tout.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Le parti m\u00e9diatique jusqu&rsquo;\u00e0 la guerre du Kosovo<\/h3>\n<\/p>\n<p><p>Au contraire, dans l&rsquo;expression, la formulation et l&rsquo;utilisation avantageuse de cette diff\u00e9rence fran\u00e7aise, la France est aujourd&rsquo;hui extraordinairement handicap\u00e9e. La France est enti\u00e8rement sous la coupe de ce qu&rsquo;on a coutume de nommer \u00ab\u00a0le parti intellectuel\u00a0\u00bb. Comme lorsque nous appr\u00e9cions d&rsquo;une fa\u00e7on critique l&rsquo;am\u00e9ricanisme en pr\u00e9cisant express\u00e9ment que ce n&rsquo;est pas attaquer les Am\u00e9ricains, notre critique du parti intellectuel concerne un syst\u00e8me avec son \u00e9tat d&rsquo;esprit, ses conventions, son conformisme, et pas du tout, en tous les cas pas du tout de fa\u00e7on n\u00e9cessaire, les hommes qui en d\u00e9pendent \u00e0 cause de ce qu&rsquo;ils sont ; comme dans le cas des Am\u00e9ricains, le syst\u00e8me du parti intellectuel est, pour nombre d&rsquo;intellectuels, une pesanteur in\u00e9vitable qu&rsquo;ils sont les premiers \u00e0 critiquer, et pour certains c&rsquo;est m\u00eame une mal\u00e9diction et\/ou un calvaire.<\/p>\n<\/p>\n<p><p>Inutile de s&rsquo;\u00e9tendre sur la d\u00e9finition du parti intellectuel, qui constitue un ph\u00e9nom\u00e8ne tr\u00e8s fran\u00e7ais par sa diversit\u00e9, sa p\u00e9rennit\u00e9, son influence et sa puissance ; inutile de rappeler son histoire, tr\u00e8s connue, entre l&rsquo;affirmation d&rsquo;une opinion publique fran\u00e7aise suscit\u00e9e par et appuy\u00e9e sur les intellectuels au XVIIIe si\u00e8cle, et son orientation d\u00e9finitive depuis l&rsquo;affaire Dreyfus de la fin du XIXe si\u00e8cle. Dans la deuxi\u00e8me partie du XXe si\u00e8cle, un \u00e9v\u00e9nement important a pris place, qui a profond\u00e9ment modifi\u00e9 le parti intellectuel : l&rsquo;arriv\u00e9e \u00e0 maturit\u00e9 du ph\u00e9nom\u00e8ne du m\u00e9diatisme, avec notamment l&rsquo;apparition de la t\u00e9l\u00e9vision, la prolif\u00e9ration de l&rsquo;image, la proclamation de la \u00ab\u00a0soci\u00e9t\u00e9 de l&rsquo;information\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Cette modification du parti intellectuel est \u00e0 la fois sociologique et intellectuelle (sic). Son recrutement s&rsquo;est \u00e9largi et sa pens\u00e9e dominante s&rsquo;est simplifi\u00e9e. Aux intellectuels eux-m\u00eames s&rsquo;est ajout\u00e9e une cohorte de nouveaux-venus qui forment aujourd&rsquo;hui une classe indistincte, renvoyant \u00e0 la fois aux grands m\u00e9dias d&rsquo;image, au <em>show-business<\/em>, voire \u00e0 d&rsquo;autres activit\u00e9s fortement m\u00e9diatis\u00e9es comme les sports. Cette transformation a con-duit le parti intellectuel \u00e0 une enflure d\u00e9mesur\u00e9e, dans une sorte de \u00ab\u00a0parti m\u00e9diatique\u00a0\u00bb dont le parti intellectuel lui-m\u00eame serait le coeur. La pens\u00e9e g\u00e9n\u00e9rale s&rsquo;est formidablement simplifi\u00e9e et est pass\u00e9e du politique souvent complexe au moral le plus souvent sommaire. Les r\u00e9f\u00e9rences sont devenues \u00ab\u00a0humanitaires\u00a0\u00bb et l&rsquo;expression s&rsquo;est transform\u00e9e en un discours convenu, extr\u00eamement sommaire lui aussi et surtout g\u00e9n\u00e9rant un conformisme tr\u00e8s puissant. Ce ph\u00e9nom\u00e8ne est connu, il est identifi\u00e9 par diverses expressions qui le d\u00e9finissent aussi sommairement qu&rsquo;est son contenu : langue de bois, pens\u00e9e unique, etc.<\/p>\n<\/p>\n<p><p>M\u00eame si ce ph\u00e9nom\u00e8ne du conformisme est g\u00e9n\u00e9ral, certainement en Occident et m\u00eame ailleurs, il n&rsquo;est certainement nulle part plus puissant qu&rsquo;en France. Il semble m\u00eame avoir, en France, une substance diff\u00e9rente, o&ugrave; l&rsquo;application syst\u00e9- matique de l&rsquo;intelligence fran\u00e7aise sur une ligne intellectuelle si sommaire a fini par produire une sorte d&#8217;embrigadement de forme religieuse, extr\u00eamement puissant, extr\u00eamement influent au niveau politique, et bien entendu plus par la terreur qu&rsquo;il inspire \u00e0ceux qui s&rsquo;\u00e9carteraient de la ligne conformiste que par l&rsquo;enrichissement intellectuel qu&rsquo;on souhaiterait lui voir apporter. L&rsquo;exercice pratique le plus impressionnant de cette dictature du parti m\u00e9diatique fran\u00e7ais a \u00e9t\u00e9 bien entendu la guerre du Kosovo.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">La France morale mais fort provinciale<\/h3>\n<\/p>\n<p><p>Nul n&rsquo;a mieux d\u00e9crit ce ph\u00e9nom\u00e8ne et la circonstance de la guerre du Kosovo que Regis Debray, dans son r\u00e9cent essai <em>L&rsquo;&Eacute;treinte<\/em> (3). Lui-m\u00eame intellectuel, Debray a \u00e9t\u00e9 une des victimes fameuses du parti m\u00e9diatique, qu&rsquo;il nomme pour son compte et avec les meilleures raisons du monde &laquo;<em>le clerg\u00e9 m\u00e9diatique<\/em>&raquo;. Nous sommes dans le domaine pur de la foi religieuse.<\/p>\n<\/p>\n<p><p>On conna&icirc;t l&rsquo;incident. Revenu d&rsquo;un reportage au Kosovo en pleine guerre, Debray avait sugg\u00e9r\u00e9 que la situation n&rsquo;\u00e9tait peut-\u00eatre pas aussi tranch\u00e9e, aussi manich\u00e9enne que le sugg\u00e9rait le cat\u00e9chisme m\u00e9diatique (le diable \u00e9vocateur du nazisme du c\u00f4t\u00e9 serbe, la vertu fille des Lumi\u00e8res du c\u00f4t\u00e9 kosovar). La riposte fut formidable de puissance. Debray fut clou\u00e9 au pilori avec une hargne terroriste qui passe l&rsquo;entendement. On ne lui passa rien, de \u00ab\u00a0Tintin au Kosovo\u00a0\u00bb aux r\u00e9f\u00e9rences \u00e0 Drieu La Rochelle, de l&rsquo;affirmation sarcastique de na\u00efvet\u00e9 \u00e0 la d\u00e9non- ciation haineuse de perversit\u00e9 collaborationniste avec le nouvel Hitler des Balkans, jusqu&rsquo;\u00e0 l&rsquo;indiff\u00e9rence coupable et culinaire de s&rsquo;int\u00e9resser aux <em>pizzerias<\/em> du Kosovo alors que se poursuivait l&rsquo;abomination qu&rsquo;on sait. Depuis, les faits se sont charg\u00e9s, avec leur ent\u00eatement coutumier (mis en \u00e9vidence beaucoup plus vite qu&rsquo;\u00e0 l&rsquo;habitude par les r\u00e9seaux dissidents d&rsquo;Internet), de montrer que la mesure et la distance conseill\u00e9es par Debray n&rsquo;\u00e9taient pas vraiment d\u00e9plac\u00e9es. Reste l&rsquo;extraordinaire souvenir de ce d\u00e9cha&icirc;nement hyst\u00e9rique, ce rench\u00e9rissement de clameur, cette \u00e9trange et sombre jouissance \u00e0 se trouver unis et compl\u00e8tement conformes dans des attitudes (d\u00e9nonciation, insultes, insinuations calomnieuses) qu&rsquo;un esprit haut consid\u00e8re habituellement comme indignes.<\/p>\n<\/p>\n<p><p>Effectivement, le territoire est celui de la foi, de la religion, de l&rsquo;Inquisition, en un mot de la Croisade. Debray se r\u00e9f\u00e8re, lorsqu&rsquo;il est question du Kosovo et du parti m\u00e9diatique fran\u00e7ais, \u00e0 &laquo; <em>notre devoir de Croisade<\/em> &raquo;. Il d\u00e9taille les \u00e9v\u00e9nements parisiens li\u00e9s \u00e0 la mobilisation pour le Kosovo et les fait correspondre sans gu\u00e8re forcer \u00e0 la Croisade d&rsquo;il y a pr\u00e8s d&rsquo;un mill\u00e9naire avant. Tout y est, tout s&rsquo;y r\u00e9f\u00e8re, sauf peut-\u00eatre que la Croisade est devenue fort confortable, que c&rsquo;est aujourd&rsquo;hui la croisade \u00ab\u00a0z\u00e9ro-mort\u00a0\u00bb o&ugrave; l&rsquo;infid\u00e8le cr\u00e8ve mais o&ugrave; le Crois\u00e9 s&rsquo;en sort sain et sauf. On ne risque pas sa peau \u00e0 Saint-Jean-D&rsquo;Acre-Belgrade.<\/p>\n<\/p>\n<p><p>On l&rsquo;a compris, l&rsquo;enjeu n&rsquo;\u00e9tait pas de savoir ce que vaut Milosevic ni \u00e0 quoi servit cette guerre, o&ugrave; elle allait conduire et ainsi de suite. L&rsquo;enjeu fut le respect de la foi, rien de moins ; l&rsquo;enjeu fut essentiellement parisien, et il n&rsquo;est pas s&ucirc;r que le sort des innocents, l\u00e0-bas, au Kosovo, en Serbie, ait vraiment et continuellement conduit la r\u00e9flexion.<\/p>\n<\/p>\n<p><p>L&rsquo;exp\u00e9rience fran\u00e7aise du Kosovo fut un exercice pratique en terreur appliqu\u00e9e, avec la consigne principale d&rsquo;aveuglement de toutes les sources de lumi\u00e8re pouvant alimenter l&rsquo;esprit critique, et le confinement de l&rsquo;esprit critique \u00e0 la recherche des nuances du discours de chacun o&ugrave; l&rsquo;on aurait pu trouver le signe du sacril\u00e8ge (le terme est : \u00ab\u00a0d\u00e9rapage\u00a0\u00bb). Cela conduit \u00e0 troubler l&rsquo;image du pays pr\u00e9sent\u00e9 comme celui de l&rsquo;intelligence et de la libert\u00e9. Ce n&rsquo;est pas tout.<\/p>\n<\/p>\n<p><p>Un autre effet des consignes du &laquo; <em>clerg\u00e9 m\u00e9diatique<\/em> &raquo;, c&rsquo;est la courte vue ou pas de vue du tout (on craint de sortir des voies et r\u00e9f\u00e9rences autoris\u00e9es), la r\u00e9f\u00e9rence r\u00e9duite effectivement aux organes d&rsquo;information autoris\u00e9s (le premier d&rsquo;entre eux, <em>Le Monde<\/em>, dit &laquo; <em>journal de r\u00e9f\u00e9rences<\/em> &raquo;). Le r\u00e9sultat est la sous- information, une appr\u00e9ciation quasi-provinciale (la province lorsque le journal du jour mettait trois semaines \u00e0 vous atteindre) des \u00e9v\u00e9nements du monde. Ainsi Paris montre-t-elle un impressionnant retard sur l&rsquo;\u00e9volution des \u00e9v\u00e9nements. Le Kosovo fut \u00e0 nouveau exemplaire.<\/p>\n<\/p>\n<p><p>Paris a p\u00e9niblement d\u00e9couvert, \u00e0 peu pr\u00e8s au d\u00e9but du printemps apr\u00e8s quelques tentatives vite avort\u00e9es \u00e0 la fin de 1999, qu&rsquo;il existait un mouvement de r\u00e9vision des \u00e9v\u00e9nements du Kosovo (le &laquo;<em>clerg\u00e9 m\u00e9diatique<\/em>&raquo; dit aussit\u00f4t &laquo;<em>r\u00e9visionnisme<\/em>&raquo;, le mot vaut mieux qu&rsquo;un long discours). C&rsquo;est pour le premier anniversaire de la guerre du Kosovo que la chose est apparue nettement. La r\u00e9alisation que les r\u00e9f\u00e9rences ext\u00e9rieures du parti m\u00e9diatique, surtout anglo-saxonnes, \u00e9taient d\u00e9j\u00e0 fort avanc\u00e9es sur la voie de la r\u00e9vision, a sem\u00e9 d\u00e9sarroi puis discorde dans le camp m\u00e9diatique. On a pu constater que l&rsquo;affaire du Kosovo n&rsquo;\u00e9tait pas class\u00e9e. (Les r\u00e9actions au livre de Debray ont montr\u00e9 cela : le livre a \u00e9t\u00e9 comment\u00e9 de fa\u00e7on tr\u00e8s ouverte et plut\u00f4t lou\u00e9 que condamn\u00e9 finalement, alors qu&rsquo;il y a un an il e&ucirc;t \u00e9t\u00e9 unanimement appr\u00e9ci\u00e9, c&rsquo;est-\u00e0-dire jug\u00e9, condamn\u00e9 et ex\u00e9cut\u00e9.) Les articles publi\u00e9s dans la presse parisienne \u00e0 cette \u00e9poque, autour du 25 mars 2000, ont ressembl\u00e9 comme autant de fr\u00e8res \u00e0 ceux qu&rsquo;avaient publi\u00e9s, courant novembre 1999, le <em>Financial Times<\/em>, ou le New York <em>Times<\/em> (s&rsquo;ils n&rsquo;\u00e9pousaient pas le parti des adversaires de la guerre, ces journaux reconnaissaient qu&rsquo;il y avait un probl\u00e8me dans l&rsquo;appr\u00e9ciation des circonstances de cette guerre) ; et ces articles de la grande presse anglo-saxonne n&rsquo;\u00e9taient d\u00e9j\u00e0, eux-m\u00eames, que la prise en compte d&rsquo;un courant d&rsquo;analyse apparu sur Internet d\u00e8s la fin septembre 1999 (site <em>Emperor Clothes<\/em> de Jared Isra\u00ebl, site Antiwar.org de Justin Raimundo, site Stratfor.com, etc). Six mois de retard dans l&rsquo;interpr\u00e9tation d&rsquo;un \u00e9v\u00e9nement comme le Kosovo o&ugrave; les choses vont vraiment tr\u00e8s vite, c&rsquo;est un lourd tribut pay\u00e9 \u00e0 l&rsquo;orthodoxie qu&rsquo;exige le &laquo; <em>clerg\u00e9 m\u00e9diatique<\/em> &raquo;. A cet \u00e9gard, la France du parti m\u00e9diatique est sous-inform\u00e9e, enferm\u00e9e par la vigilance de son &laquo; <em>clerg\u00e9<\/em> &raquo; dans une sorte de donjon o&ugrave; l&rsquo;on passe le temps \u00e0 \u00e9changer arguments et invectives sur le sexe des anges kosovars.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Le soutien du parti m\u00e9diatique<\/h3>\n<\/p>\n<p><p>Les d\u00e9g\u00e2ts de l&rsquo;influence du parti m\u00e9diatique apparaissent encore plus grands lorsqu&rsquo;on observe quelques cas de politique \u00e9trang\u00e8re, et l&rsquo;on peut m\u00eame avancer l&rsquo;hypoth\u00e8se que cette influence est devenue structurelle. L&rsquo;interf\u00e9rence de ces remous int\u00e9rieurs qui repr\u00e9sentent une activit\u00e9 m\u00e9diatique sans r\u00e9el fondement et ne correspond \u00e0 aucun d\u00e9bat national y est consid\u00e9rable et par con- s\u00e9quent disproportionn\u00e9e. Deux cas r\u00e9cents sont celui de l&rsquo;Autriche et celui de la Russie.<\/p>\n<\/p>\n<p><p>&bull;  Dans le cas autrichien, la France a pris la t\u00eate de la croisade anti-autrichienne avec la Belgique. Les causes de cet engagement sont assez \u00e9videntes : on veut bien conc\u00e9der une vague conviction id\u00e9ologique qui n&rsquo;est certainement pas propre aux seuls Fran\u00e7ais, mais l&rsquo;essentiel de la dynamique anti-autrichienne est fourni par la pr\u00e9occupation de la direction politique des r\u00e9actions du parti m\u00e9diatique sur laquelle sont venues se greffer des pr\u00e9occupations politiciennes type-cohabitation. Certains commentateurs cherchant \u00e0 rationaliser cette politique parlent de la crainte des dirigeants fran\u00e7ais et belges confront\u00e9s \u00e0 l&rsquo;\u00e9mergence d&rsquo;une extr\u00eame-droite puissante dans leurs pays ; l&rsquo;argument est bancal d\u00e8s lors que l&rsquo;extr\u00eame-droite fran\u00e7aise est en pleine d\u00e9bacle et que l&rsquo;extr\u00eame-droite belge est flamande alors que le ministre belge qui a manipul\u00e9 cette affaire (Louis Michel) et contraint ses coll\u00e8gues \u00e0 le suivre est Wallon et que son attaque anti-Haider a surtout pour but int\u00e9rieur de paralyser la d\u00e9mocratie-chr\u00e9tienne flamande face \u00e0 son extr\u00eame-droite (le Vlaamse Block) avant les \u00e9lections communales de septembre prochain. Le r\u00e9sultat pour la France, dans cette affaire, est plus que mitig\u00e9. La France se retrouve relativement isol\u00e9e vis-\u00e0-vis de nombre de pays europ\u00e9ens ; elle compromet \u00e9ventuellement sa pr\u00e9sidence (juillet 2000-janvier 2001) de l&rsquo;UE o&ugrave; plane la menace d&rsquo;actions radicales d&rsquo;une Autriche exasp\u00e9r\u00e9e ; elle renforce de fa\u00e7on appr\u00e9ciable le parti anti-europ\u00e9en dans plusieurs pays europ\u00e9ens parce que l&rsquo;action europ\u00e9enne instrument\u00e9e essentiellement par la France repr\u00e9sente dans ce cas une interf\u00e9rence flagrante dans la souverainet\u00e9 d&rsquo;un &Eacute;tat-membre ; elle renforce les sentiments anti-fran\u00e7ais dans plusieurs pays de l&rsquo;UE, en Autriche d&rsquo;une fa\u00e7on formidable, mais aussi dans d&rsquo;autres tels que le Danemark.<\/p>\n<\/p>\n<p><p>&bull; Dans le cas russe, on a bien devin\u00e9 que la diplomatie fran\u00e7aise ne tenait pas \u00e0 s&rsquo;engager dans une action de condamnation type-autrichienne, au nom d&rsquo;un r\u00e9alisme qui manque aussi bien \u00e0 l&rsquo;action de la France vis-\u00e0-vis de l&rsquo;Autriche. Cette attitude a aussit\u00f4t aliment\u00e9 l&rsquo;accusation du \u00ab\u00a0deux poids-deux mesures\u00a0\u00bb (la r\u00e9f\u00e9rence \u00e9galement pr\u00e9sent\u00e9e \u00e9tant que la France refusait de prendre \u00e0 l&rsquo;encontre de la Russie engag\u00e9e en Tch\u00e9tch\u00e9nie l&rsquo;attitude qu&rsquo;elle avait suivie contre la Serbie engag\u00e9e au Kosovo). La diplomatie fran\u00e7aise s&rsquo;est donc gard\u00e9e, face \u00e0 la vigilance du parti m\u00e9diatique, d&rsquo;aller au bout de sa logique et elle est rest\u00e9e relativement neutre, ou paralys\u00e9e c&rsquo;est selon, devant la situation russe de ces derniers mois. Le r\u00e9sultat est qu&rsquo;en cette mati\u00e8re vitale des relations avec la Russie au moment essentiel o&ugrave; un nouveau pr\u00e9sident russe entre en fonction, c&rsquo;est le Royaume-Uni qui a suivi une politique offensive (visite Blair \u00e0 moscou, visite Poutine \u00e0 Londres), montrant la \u00ab\u00a0souplesse\u00a0\u00bb proverbiale des Britanniques \u00e0cet \u00e9gard (le Blair de &laquo; <em>la premi\u00e8re guerre progressiste<\/em> &raquo;[Kosovo] embrassant l&rsquo;homme de la 2e guerre de Tch\u00e9tch\u00e9nie). Le r\u00e9sultat est que les Fran\u00e7ais se voient priv\u00e9s, pour l&rsquo;instant, d&rsquo;une de leurs cartes europ\u00e9ennes traditionnelles (la possibilit\u00e9 de relations resserr\u00e9es avec la Russie).<\/p>\n<\/p>\n<p><p>De nombreux autres domaines de la politique ext\u00e9rieure sont affect\u00e9s par cette interf\u00e9rence du parti m\u00e9diatique. Plus qu&rsquo;une interf\u00e9rence <em>ad hoc<\/em>, sur telle ou telle question \u00e0laquelle le parti m\u00e9diatique sera sensible, on parlerait d&rsquo;une interf\u00e9rence qui devient structurelle et affecte l&rsquo;\u00e9tat d&rsquo;esprit et le jugement plus que l&rsquo;objet de la politique. La classe politique r\u00e9siste de moins en moins \u00e0 cette influence parce qu&rsquo;elle est faible ; mais on doit aller plus loin et avancer l&rsquo;hypoth\u00e8se qu&rsquo;elle n&rsquo;y r\u00e9siste plus du tout parce qu&rsquo;elle ne voit plus fondamentalement de raison d&rsquo;y r\u00e9sister et qu&rsquo;elle trouve le plus d\u00e9licieux confort \u00e0 jouir du soutien de la classe m\u00e9diatique.<\/p>\n<\/p>\n<p><p>Les hommes politiques fran\u00e7ais sont devenus eux-m\u00eames adh\u00e9rents de ce parti m\u00e9diatique qu&rsquo;ils comprennent si bien dans la mesure o&ugrave; ce parti est le ma&icirc;tre de l&rsquo;apparence, de l&rsquo;influence, de la pression psychologique et du conformisme du jugement politique. La situation de la cohabitation accentue cette \u00e9volution parce qu&rsquo;elle place les deux partenaires-adversaires dans un \u00e9tat de permanente concurrence \u00e9lectoraliste o&ugrave; le soutien du parti m\u00e9diatique est essentiel. Cet opportunisme de situation finit par cr\u00e9er ce qui para&icirc;t \u00eatre une conviction politique et habille du manteau de la rationalit\u00e9 morale les vagues convictions g\u00e9n\u00e9rales du monde politique. Aujourd&rsquo;hui, les hommes politiques fran\u00e7ais pr\u00e9c\u00e8dent les <em>diktat<\/em> du parti m\u00e9diatique (Jacques Chirac avertit qu&rsquo;un gouvernement italien de droite qu&rsquo;on peut soup\u00e7onner d&rsquo;accointances n\u00e9o-fascisantes, ou ex-n\u00e9o-fascisantes, pourrait valoir \u00e0 l&rsquo;Italie le m\u00eame sort qu&rsquo;\u00e0 l&rsquo;Autriche). La situation \u00e9volue dans le sens, \u00e0 la fois d&rsquo;une rh\u00e9torique de plus en plus pr\u00e9sente dans la formulation de la politique \u00e9trang\u00e8re et d&rsquo;une paralysie de plus en plus effective de cette politique \u00e9trang\u00e8re.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">La France puissante contre son gr\u00e9<\/h3>\n<\/p>\n<p><p>Certains aspects de cette description de la situation fran\u00e7aise vaudraient aussi bien pour n&rsquo;importe quel autre pays. On trouverait alors une France o&ugrave; le parti m\u00e9diatique est encore plus puissant qu&rsquo;ailleurs, parce qu&rsquo;il a exploit\u00e9 la position de puissance initiale du parti intellectuel. La France serait \u00e0l&rsquo;avanc\u00e9e extr\u00eame d&rsquo;une tendance g\u00e9n\u00e9rale d&rsquo;un monde politique gouvern\u00e9 par le parti m\u00e9diatique, c&rsquo;est-\u00e0-dire la manipulation de l&rsquo;apparence, l&rsquo;instrumentation de l&rsquo;influence et de la pression, le rangement g\u00e9n\u00e9ral selon une ligne absolument et totalement conformiste. La France serait parfaitement int\u00e9gr\u00e9e. La France serait l&rsquo;antith\u00e8se de ce qu&rsquo;on a vu qu&rsquo;elle \u00e9tait traditionnellement, ce pays o&ugrave;, selon Weber, l&rsquo;exception est la r\u00e8gle. Mais il y a un paradoxe. Si ce constat est vrai, il ne l&rsquo;est qu&rsquo;\u00e0 moiti\u00e9. Les effets de l&rsquo;extraordinaire puissance du parti m\u00e9diatique et de son acceptation d\u00e9sormais totale par la classe politique ne portent pas sur tous les domaines de la politique, et pr\u00e9cis\u00e9ment de la politique ext\u00e9rieure, l\u00e0 o&ugrave; nous concentrons notre attention parce qu&rsquo;\u00e0 l&rsquo;\u00e9poque de la globalisation \u00e9videmment la politique ext\u00e9rieure importe plus que jamais.<\/p>\n<\/p>\n<p><p>L&rsquo;int\u00e9r\u00eat fi\u00e9vreux et parfois hyst\u00e9rique de cette alliance politico-m\u00e9diatique exige quelques caract\u00e8res fondamentaux des sujets choisis, et prestement transform\u00e9s en autant de causes morales : il faut justement leur trouver une dimension morale, il faut pouvoir les opposer sommairement en deux partis arrang\u00e9s selon une vision manich\u00e9enne, il faut pouvoir r\u00e9duire leur complexit\u00e9 au rudiment d&rsquo;un jugement absolu m\u00eame s&rsquo;il est temporaire, il faut pouvoir les appr\u00e9cier tr\u00e8s vite de cette fa\u00e7on sommaire pour obtenir un \u00ab\u00a0effet\u00a0\u00bb instantan\u00e9 qui puisse \u00eatre exploit\u00e9 par la machine m\u00e9diatique, et qui pourra \u00eatre abandonn\u00e9 aussi vite quand une autre cause morale aura \u00e9t\u00e9 d\u00e9busqu\u00e9e. Un vaste domaine o&ugrave; s&rsquo;expriment des politiques nuanc\u00e9es et complexes \u00e9chappe \u00e0 cette investigation de la machine, investigation si permanente qu&rsquo;elle ressemble \u00e0 une inquisition. Il porte sur des questions essentielles, d\u00e9laiss\u00e9es parce qu&rsquo;inclassables selon les normes m\u00e9diatiques dont on a compris que la principale caract\u00e9ristique est d&rsquo;\u00eatre n\u00e9cessairement sommaire.<\/p>\n<\/p>\n<p><p>Qui peut trouver une dimension morale claire et tranch\u00e9e \u00e0 la politique europ\u00e9enne de s\u00e9curit\u00e9 et de d\u00e9fense (PESD) ? Dans le parti m\u00e9diatique on la juge n\u00e9cessaire en passant parce que tout ce qui rel\u00e8ve du qualificatif \u00ab\u00a0europ\u00e9en\u00a0\u00bb renvoie \u00e0 une cause sacr\u00e9e et stimule un r\u00e9flexe pavlovien. Aller plus loin n\u00e9cessiterait d&rsquo;examiner une probl\u00e9matique o&ugrave; l&rsquo;on trouve l&rsquo;inconfortable situation de devoir consid\u00e9rer des r\u00e9alit\u00e9s complexes o&ugrave; l&rsquo;indispensable mesure morale peine \u00e0 retrouver ses r\u00e9f\u00e9rences (dans le cas de la PESD : l&rsquo;OTAN, c&rsquo;est-\u00e0-dire les Am\u00e9ricains qui sont une autre r\u00e9f\u00e9rence indiscutable du parti m\u00e9diatique, &mdash; l&rsquo;OTAN est-elle une amie ou une redoutable concurrente attach\u00e9e \u00e0 contrecarrer la PESD ? Gravissime question : si l&rsquo;on peut commencer \u00e0 douter de la bienveillance otanienne, la r\u00e9f\u00e9rence morale se trouve tout soudain mise en cause). Cette complexit\u00e9 d\u00e9courage. On ne s&rsquo;int\u00e9resse pas \u00e0 la PESD.<\/p>\n<\/p>\n<p><p>Avec la PESD, nous citons un exemple qui est aussi une de nos pr\u00e9occupations favorites, mais son importance justifie de la voir comme la manifestation caract\u00e9ristique de l&rsquo;autre extr\u00eame de la politique fran\u00e7aise. Sur cette question, la France conduit avec constance et d&rsquo;ailleurs sans vraiment en d\u00e9lib\u00e9rer une politique d&rsquo;affirmation d&rsquo;une diff\u00e9rence, et m\u00eame d&rsquo;une exception dans le concert europ\u00e9en depuis un demi-si\u00e8cle, jusqu&rsquo;\u00e0 une force de permanence o&ugrave; le contexte psychologique et strat\u00e9gique conduit les partenaires europ\u00e9ens de la France \u00e0 accepter d&rsquo;explorer la voie fran\u00e7aise. La politique fran\u00e7aise retrouve \u00e0 la fois les traditions de la diplomatie fran\u00e7aise et les impulsions fondamentales donn\u00e9es par le gaullisme pour adapter ces traditions \u00e0 la modernit\u00e9 (souverainet\u00e9 identitaire, ind\u00e9pendance nationale par le moyen de capacit\u00e9s telles que l&rsquo;arme nucl\u00e9aire ou la suffisance technologique). C&rsquo;est-\u00e0-dire qu&rsquo;elle se conforme naturellement \u00e0 une structure fondamentale de la vision fran\u00e7aise du monde et des relations entre les composants du monde. Une m\u00eame appr\u00e9ciation peut \u00eatre faite sur la politique fran\u00e7aise vis-\u00e0-vis de la pol\u00e9mique actuelle sur le contr\u00f4le des armements et le projet am\u00e9ricain de d\u00e9ploiement d&rsquo;un syst\u00e8me anti-missile (NMD). On voit bien combien tous ces dossiers internationaux correspondent peu aux crit\u00e8res qui stimulent les r\u00e9actions extr\u00eames du syst\u00e8me politico-m\u00e9diatique et du parti m\u00e9diatique.<\/p>\n<\/p>\n<p><p>&Eacute;trange constat, curieuse conclusion : la France est puissante pour tout ce que ses \u00e9lites ignorent et repoussent. La France puissante contre son gr\u00e9 d&rsquo;aujourd&rsquo;hui, comme par inadvertance de ses \u00e9lites occup\u00e9es \u00e0 d&rsquo;autres t\u00e2ches. En un sens, la France d\u00e9passe les Fran\u00e7ais, en tous les cas ceux d&rsquo;aujourd&rsquo;hui. Constat tr\u00e8s gaullien.<\/p>\n<\/p>\n<p><h4><em>de defensa<\/em> Volume 15, n&deg;17 du 25 mai 2000<\/h4>\n<\/p>\n<p><p>(1). International Herald Tribune, 28 d\u00e9cembre 1998<\/p>\n<\/p>\n<p><p> (2) Ma France, Fayard, Paris 1991.<\/p>\n<\/p>\n<p><p>(3) L&rsquo;Etreinte, Gallimard, collection D\u00e9bats, Paris avril 2000.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Etrange France&#8230; Extrait de de defensa Volume 15, n&deg;17 du 25 mai 2000 Ces deux derni\u00e8res ann\u00e9es, si l&rsquo;on veut consid\u00e9rer la situation des relations internationales comme un match o&ugrave; l&rsquo;on marque des points, la France en a marqu\u00e9 quelques-uns d&rsquo;importance dans l&rsquo;ar\u00e8ne des rapports entre alli\u00e9s qui ressemblent souvent \u00e0 des affrontements syst\u00e9matiques. Nous&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[3093,3097,3095,643,3086,2651,398,2687,3090,3085,3096,3094,3091,3092],"class_list":["post-64921","post","type-post","status-publish","format-standard","hentry","category-de-defensa","tag-3093","tag-3097","tag-3095","tag-debray","tag-dedefensa","tag-du","tag-europe","tag-france","tag-influence","tag-kosovo","tag-mai","tag-n17","tag-pesd","tag-volume"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/64921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=64921"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/64921\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=64921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=64921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=64921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}