{"id":64937,"date":"2001-05-06T00:00:00","date_gmt":"2001-05-05T22:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2001\/05\/06\/semaine-du-30-avril-au-6-mai-2001\/"},"modified":"2001-05-06T00:00:00","modified_gmt":"2001-05-05T22:00:00","slug":"semaine-du-30-avril-au-6-mai-2001","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2001\/05\/06\/semaine-du-30-avril-au-6-mai-2001\/","title":{"rendered":"Semaine du 30 avril au 6 mai 2001"},"content":{"rendered":"<p><h3>Le r\u00f4le des militaires US dans la crise de l&rsquo;EP-3E: une hypoth\u00e8se particuli\u00e8rement int\u00e9ressante<\/h3>\n<\/p>\n<p><\/p>\n<p><p>\tIl faut lire <a href=\"http:\/\/www.g2mil.com\/May2001.htm\" class=\"gen\">l&rsquo;\u00e9ditorial<\/a> de Carlton Meyer, \u00e9diteur du site G2mil, dans son \u00e9dition de mai 2001. L&rsquo;hypoth\u00e8se principale qu&rsquo;il soul\u00e8ve pour expliquer l&rsquo;incident qui aboutit \u00e0 l&rsquo;aterrissage en catastrophe du EP-3E de l&rsquo;US Navy sur l&rsquo;\u00eele de Hainan, le 1er avril, est particuli\u00e8rement int\u00e9ressante: provoquer une crise qui mettrait en \u00e9vidence l&rsquo;importance des porte-avions de l&rsquo;US Navy, \u00e0 l&rsquo;heure o\u00f9 l&rsquo;avenir de ces navires semblent menac\u00e9 par l&rsquo;\u00e9tude pour la r\u00e9forme strat\u00e9gique (<em>Strategic Review<\/em>) encours au Pentagone. Sans pour voir trouver mati\u00e8re \u00e0 confirmation de quoi que ce soit, il faut garder ces r\u00e9flexions \u00e0 l&rsquo;esprit; il faut surtout noter combien elles ne semblent nullement fantaisistes ou exag\u00e9r\u00e9es. Il y a l\u00e0 le r\u00e9sultat de l&rsquo;extraordinaire changement de statut et de puissance des chefs militaires am\u00e9ricains sous l&rsquo;administration Clinton. C&rsquo;est surtout le cas des <em>CinCs<\/em> (<em>Commander in Chief<\/em>, ou commandants en chef de th\u00e9\u00e2tres ext\u00e9rieurs, comme le Pacifique, l&rsquo;Atlantique, l&rsquo;Europe, etc). La faiblesse de l&rsquo;administration Clinton a permis \u00e0 ces chefs r\u00e9gionaux de s&rsquo;approprier un r\u00f4le de v\u00e9ritable vice-roi, s&rsquo;abstenant en g\u00e9n\u00e9ral de rendre compte de leurs initiatives au pouvoir civil, et parfois aussi, au pouvoir militaire central au Pentagone. (Outre l&rsquo;\u00e9ditorial de Meyer, \u00e9galement pr\u00e9sent dans notre rubrique <em>Nos Choix<\/em>, on trouve dans cette rubrique le lien d&rsquo;un article d&rsquo;Edward Luttwak donnant des indications, recoup\u00e9es par Meyer, sur la situation et l&rsquo;action de l&rsquo;amiral Blair, CinCPAC, c&rsquo;est-\u00e0-dire \u00ab\u00a0vice-roi\u00a0\u00bb du Pacifique depuis plus d&rsquo;un an. Cette situation de l&rsquo;autonomie des <em>CinCs<\/em> nous a \u00e9t\u00e9 confirm\u00e9e par une source diplomatique fran\u00e7aise travaillant dans le domaine diplomatico-militaire europ\u00e9en: \u00ab<em>L&rsquo;autonomie des commandants en chef de th\u00e9\u00e2tre a pris des proportions stup\u00e9fiantes sous Clinton. Litt\u00e9ralement, plus personne ne contr\u00f4le directement ces chefs.<\/em>\u00bb) C&rsquo;est un facteur extr\u00eamement grave de d\u00e9stabilisation potentielle, dans une situation internationale de plus en plus tendue, avec une pression m\u00e9diatique constante et un <em>establishment<\/em> washingtonien tr\u00e8s prompt \u00e0 demander l&rsquo;utilisation de la force. L&rsquo;une des t\u00e2ches principales de Rumsfeld, aujourd&rsquo;hui, est de restaurer le contr\u00f4le civil au Pentagone, comme il l&rsquo;a express\u00e9ment d\u00e9clar\u00e9 <a href=\"http:\/\/www.washtimes.com\/national\/20010424-13721652.htm\" class=\"gen\">tr\u00e8s r\u00e9cemment.<\/a> Cela inclut la question des acquisitions, des nouveaux programmes, de la gestion, etc, autant que cette question encore plus d\u00e9licate parce qu&rsquo;extr\u00eamement politique des pouvoirs de d\u00e9cision que s&rsquo;arrogent les commandants de th\u00e9\u00e2tre dans des affaires engageant la s\u00e9curit\u00e9 des \u00c9tats-Unis.<\/p>\n<\/p>\n<p><\/p>\n<h3>La d\u00e9fense anti-missiles tr\u00e8s vite, pour \u00eatre verrouill\u00e9e avant l&rsquo;\u00e9lection de 2004?<\/h3>\n<\/p>\n<p><\/p>\n<p><p>\tLe 2 mai, GW Bush annonce le lancement du syst\u00e9me anti-missile (MDS), dont on sait depuis plus d&rsquo;un an qu&rsquo;il sera la priorit\u00e9 d&rsquo;une \u00e9ventuelle administration GW Bush. Cette priorit\u00e9 avait \u00e9t\u00e9 confirm\u00e9e peu apr\u00e8s l&rsquo;installation de l&rsquo;administration. Le d\u00e9ploiement m\u00e9diatique est consid\u00e9rable pour annoncer la nouvelle, qui n&rsquo;en est pas vraiment une, qui reste dans le vague sur les modalit\u00e9s et les d\u00e9tails du projet. Il y a ainsi une certaine impression d&rsquo;urgence de r\u00e9aliser ce programme, y compris avec des dimensions (et des investissements) consid\u00e9rables, contrastant avec une impr\u00e9paration et une impr\u00e9cision consid\u00e9rables sur les modalit\u00e9s de d\u00e9veloppement, les syst\u00e8mes constitutifs de l&rsquo;ensemble, etc. Dans ces conditions, la th\u00e8se notamment d\u00e9velopp\u00e9e par <a href=\"http:\/\/www.latimes.com\/news\/nation\/updates2\/lat_missile0105-01.htm\" class=\"gen\">le Los Angeles Times<\/a> est int\u00e9ressante: il s&rsquo;agirait, pour l&rsquo;administration GW Bush, de mettre en place des \u00e9l\u00e9ments fondamentaux du syst\u00e8me avant les \u00e9lections de 2004, pour verrouiller ce qui deviendrait le legs de cette administration et ce qui est consid\u00e9r\u00e9 comme le projet fondamental du parti r\u00e9publicain. Cette th\u00e8se ne laisse gu\u00eare de place aux alli\u00e9s, qui sont pourtant concern\u00e9s au premier chef dans cette affaire puisque le MDS doit \u00eatre un r\u00e9seau global, assurant leur protection au m\u00eame titre que celle des USA. GW Bush promet beaucoup de consultations avec ses alli\u00e9s dans cette perspective. Les r\u00e9actions sont \u00e0 la fois prudentes et retenues. Les alli\u00e9s sont plac\u00e9s devant un fait accompli gracieusement pr\u00e9sent\u00e9, dont ils ne savent rien puisque les auteurs eux-m\u00eames en ignorent \u00e0 peu pr\u00e8s tout, et qui va jouer un r\u00f4le majeur sur la sc\u00e8ne strat\u00e9gique internationale alors qu&rsquo;il s&rsquo;agit d&rsquo;abord d&rsquo;une affaire de politique int\u00e9rieure, et de politique politicienne.<\/p>\n<\/p>\n<p><\/p>\n<h3>La litt\u00e9rature comme instrument privil\u00e9gi\u00e9 pour mettre \u00e0 jour la v\u00e9rit\u00e9 du monde<\/h3>\n<\/p>\n<p><\/p>\n<p><p>\tInt\u00e9ressante page dans <a href=\"http:\/\/www.lemonde.fr\/article.0,5987,3260--1796678-,00.html\" class=\"gen\">le suppl\u00e9ment \u00ab\u00a0Livres\u00a0\u00bb<\/a> du <em>Monde<\/em> du 3 mai. Un titre: \u00ab<em>Les enfants de la guerre froide<\/em>\u00bb, une chronique consacr\u00e9e \u00e0 un Russe (Viktor Pelevine pour <em>Homo Zapiens<\/em>) et un Am\u00e9ricain (Michael Collins pour <em>Les Gardiens de la v\u00e9rit\u00e9<\/em>). L&rsquo;int\u00e9r\u00eat de cette chronique sur deux romans parus parall\u00e8lement, et qui expriment un \u00e9tat d&rsquo;esprit d\u00e9sesp\u00e9r\u00e9 assez semblable, est justement de les rassembler dans une appr\u00e9ciation politique commune. Comme l&rsquo;\u00e9crit l&rsquo;auteur Raphaelle r\u00e9rolle, et c&rsquo;est une phrase mise en exergue, \u00ab[d]<em>ans des styles radicalement distincts, le Russe Viktor Pelevine et l&rsquo;Am\u00e9ricain Michael Collins dressent le tableau lugubre de deux empires au bord du chaos<\/em>\u00bb. Par rapport \u00e0 l&rsquo;appr\u00e9ciation conformiste, \u00e0 l&rsquo;interpr\u00e9tation officielle, cette remarque est bien \u00e9tonnante; si l&rsquo;on comprend bien, issus de la guerre froide (\u00ab<em>enfants de la guerre froide<\/em>\u00bb), voici les \u00ab<em>deux empires au bord du chaos<\/em>\u00bb, c&rsquo;est-\u00e0-dire l&rsquo;URSS et les USA; pour la premi\u00e8re, ce n&rsquo;est pas une nouvelle; pour les seconds, c&rsquo;est beaucoup plus inattendu tant on est habitu\u00e9 \u00e0 entendre louer la puissance, la prosp\u00e9rit\u00e9, l&rsquo;exceptionnalit\u00e9, l&rsquo;unicit\u00e9 sans exemple ni pr\u00e9c\u00e9dent du cas am\u00e9ricain. Une fois notre \u00e9tonnement, tout de convention, d\u00e9pass\u00e9, il faut convenir que l&rsquo;id\u00e9e n&rsquo;est pas mauvaise; que, derri\u00e8re les propagandes \u00e9tourdissantes, cette interpr\u00e9tation-l\u00e0, des deux \u00e9crivains, rend le son de la v\u00e9rit\u00e9. L&rsquo;absence de sens et l&rsquo;individualisme nihiliste, la folie hyst\u00e9rique du gain, l&rsquo;\u00e9go\u00efsme, l&rsquo;ignorance compl\u00e8te du monde ext\u00e9rieur alors qu&rsquo;on s&rsquo;en affirme le <em>leader<\/em> et l&rsquo;inspirateur, le refus des responsabilit\u00e9s, tous ces traits politiques qui caract\u00e9risent les USA aujourd&rsquo;hui, peuvent effectivement annoncer, voire simplement illustrer une forme de chaos qui, en perspective, et, dans tous les cas, dans ses cons\u00e9quences \u00e0 long terme, vaudra bien celle qui a frapp\u00e9 l&rsquo;URSS en 1989-91. Du coup, la capacit\u00e9 de l&rsquo;artiste \u00e0 sentir, qui caract\u00e9rise ces oeuvres litt\u00e9raires, devient une vertu politique rare dans des temps obscurcis par la propagande. L&rsquo;analyse politique devrait avoir l&rsquo;esprit de s&rsquo;informer plus souvent qu&rsquo;elle ne fait, aupr\u00e8s de telles sources. Elle s&rsquo;y retrouverait un peu plus.<\/p>\n<\/p>\n<p><\/p>\n<h3>\u00ab<strong><em>We Are the World<\/em><\/strong>\u00bb, &mdash; et Washington perdit son si\u00e8ge \u00e0 la Commission des droits de l&rsquo;homme<\/h3>\n<\/p>\n<p><\/p>\n<p><p>\tLes USA battus \u00e0 l&rsquo;ONU, et encore, dans la prestigieuse Commission des droits de l&rsquo;homme, celle dont la grande dame de la pr\u00e9sidence, Eleanor Roosevelt, fut la v\u00e9ritable \u00ab\u00a0marraine\u00a0\u00bb en y \u00e9tant la premi\u00e8re repr\u00e9sentante am\u00e9ricaine: c&rsquo;est une grave d\u00e9faite de prestige et de symbole, dans une \u00e9poque o\u00f9 ces valeurs de repr\u00e9sentation (prestige et symbole) sont un attribut essentiel de la manifestation de la puissance. L&rsquo;\u00e9v\u00e9nement a d&rsquo;ailleurs \u00e9t\u00e9 ressenti de cette fa\u00e7on <a href=\"http:\/\/ww.iht.com\/articles\/18997.html\" class=\"gen\">\u00e0 Washington,<\/a> personne ne s&rsquo;y est tromp\u00e9. Il est aussit\u00f4t interpr\u00e9t\u00e9 symboliquement, comme une marque symbolique et solennelle de la d\u00e9fiance et de l&rsquo;irritation du reste du monde devant la politique am\u00e9ricaine, parfois brutale, souvent irresponsable, toujours unilat\u00e9rale. Il y a beaucoup d&rsquo;\u00e9motions, d&rsquo;exclamations, de vocif\u00e9rations dans les r\u00e9actions am\u00e9ricaines; on ne peut pour autant \u00e9carter ce constat, qu&rsquo;on doit faire avec sang-froid pour mieux en mesurer l&rsquo;importance: les USA vont devoir choisir, et, cela, tr\u00e8s rapidement; entre assurer avec responsabilit\u00e9 un <em>leadership<\/em> qu&rsquo;ils r\u00e9clament \u00e0 corps et \u00e0 cri comme \u00e9tant un d\u00fb \u00e9vident, et poursuivre une attitude marqu\u00e9e par l&rsquo;irresponsabilit\u00e9 et bient\u00f4t promise \u00e0 susciter contre eux des rassemblements tels qu&rsquo;ils devront s\u00e9rieusement consid\u00e9rer le repli sur la dimension continentale.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le r\u00f4le des militaires US dans la crise de l&rsquo;EP-3E: une hypoth\u00e8se particuli\u00e8rement int\u00e9ressante Il faut lire l&rsquo;\u00e9ditorial de Carlton Meyer, \u00e9diteur du site G2mil, dans son \u00e9dition de mai 2001. L&rsquo;hypoth\u00e8se principale qu&rsquo;il soul\u00e8ve pour expliquer l&rsquo;incident qui aboutit \u00e0 l&rsquo;aterrissage en catastrophe du EP-3E de l&rsquo;US Navy sur l&rsquo;\u00eele de Hainan, le 1er&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[7],"tags":[],"class_list":["post-64937","post","type-post","status-publish","format-standard","hentry","category-journal"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/64937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=64937"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/64937\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=64937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=64937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=64937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}