{"id":64939,"date":"2001-05-20T00:00:00","date_gmt":"2001-05-19T22:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2001\/05\/20\/semaine-du-14-au-20-mai-2001\/"},"modified":"2001-05-20T00:00:00","modified_gmt":"2001-05-19T22:00:00","slug":"semaine-du-14-au-20-mai-2001","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2001\/05\/20\/semaine-du-14-au-20-mai-2001\/","title":{"rendered":"Semaine du 14 au 20 mai 2001"},"content":{"rendered":"<p><h3>L&rsquo;extraordinaire (et fausse) image de puissance qu&rsquo;est en train d&rsquo;acqu\u00e9rir l&rsquo;Europe<\/h3>\n<\/p>\n<p><\/p>\n<p><p>\tIl nous est d\u00e9j\u00e0 arriv\u00e9 de citer le chroniqueur Justin Raimundo, qui dirige le site <em>Antiwar.com<\/em> et qui publie sur ce site une chronique r\u00e9guli\u00e8re. Raimundo est de l&rsquo;extr\u00eame-droite libertarienne am\u00e9ricaine: isolationiste, anti-interventioniste dans les deux sens du mot (adversaire des interventions arm\u00e9es ext\u00e9rieures et des interventions de l&rsquo;\u00c9tat dans l&rsquo;\u00e9conomie), plut\u00f4t proche des tendances de la d\u00e9mocratie localiste, souvent regroup\u00e9es sous le nom de jeffersoniens par r\u00e9f\u00e9rence \u00e0 Thomas Jefferson. Dans nombre de cas, ses prises de position rencontrent celles des Europ\u00e9ens qui s&rsquo;opposent \u00e0 l&rsquo;h\u00e9g\u00e9monie et l&rsquo;interventionnisme am\u00e9ricains, et \u00e0 la globalisation \u00e9conomique. Cette fois, nous voudrions mettre en \u00e9vidence une autre position de Raimundo, largement r\u00e9pandue dans la droite isolationniste am\u00e9ricaine, mais \u00e9galement dans l&rsquo;<em>establishment<\/em> washingtonien en g\u00e9n\u00e9ral (un des rares sujets, finalement, o\u00f9 se retrouvent ces deux tendances farouchement adversaires par ailleurs). On trouve cette position d\u00e9taill\u00e9e dans sa <a href=\"http:\/\/www.antiwar.com\/justin\/pf\/p-jO51401.html\" class=\"gen\">chronique du 14 mai.<\/a> Cette chronique est un commentaire du vote hostile \u00e0 l&rsquo;Am\u00e9rique \u00e0 la Commission des droits de l&rsquo;homme (le 3 mai), et c&rsquo;est une attaque en r\u00e8gle contre l&rsquo;Europe, et, plus particuli\u00e8rement, contre l&rsquo;Union europ\u00e9enne en tant que \u00a0\u00bb<em>European socialist super-state<\/em>\u00a0\u00bb. Ce texte est \u00e9difiant dans la mesure o\u00f9 il montre \u00e0quel point la m\u00e9connaissance de la r\u00e9alit\u00e9 peut conduire le jugement d&rsquo;un esprit qu&rsquo;on peut estimer par ailleurs lucide et sans v\u00e9ritable conformisme; m\u00e9connaissance dans le sens d&rsquo;une fausse repr\u00e9sentation, d&rsquo;une appr\u00e9ciation compl\u00e8tement d\u00e9form\u00e9e, d&rsquo;une mesure absolument tronqu\u00e9e, par rapport \u00e0 la r\u00e9alit\u00e9 europ\u00e9enne aujourd&rsquo;hui. (M\u00e9connaissance compl\u00e8te de l&rsquo;\u00e9tat r\u00e9el des institutions europ\u00e9ennes, d\u00e9nonc\u00e9es comme ce super-\u00c9tat: ces institutions sont plut\u00f4t marqu\u00e9es par la vell\u00e9it\u00e9, la faiblesse, la pusillanimit\u00e9, et l&rsquo;impuissance dans l&rsquo;action, particuli\u00e8rement depuis l&rsquo;entr\u00e9e en activit\u00e9 de l&rsquo;actuelle Commission europ\u00e9enne.) On peut noter que cette m\u00e9connaissance se retrouve chez certains opposants nationaux europ\u00e9ens, chez les conservateurs eurosceptiques britanniques, chez les souverainistes fran\u00e7ais.<\/p>\n<\/p>\n<p><\/p>\n<h3>L&rsquo;Inde a effectu\u00e9 un tournant de 180\u00b0 vis-\u00e0-vis des \u00c9tats-Unis: une \u00e9volution aventuriste?<\/h3>\n<\/p>\n<p><\/p>\n<p><p>\tUn pays s&rsquo;est compl\u00e8tement singularis\u00e9 dans sa r\u00e9action vis-\u00e0-vis de l&rsquo;initiative US d&rsquo;un syst\u00e8me anti-missile (MDS): l&rsquo;Inde a soutenu avec enthousiasme le projet am\u00e9ricain, g\u00e9n\u00e9ralement accueilli au mieux avec r\u00e9serve, au pire avec hostilit\u00e9. Cette position indienne donne lieu \u00e0<a href=\"http:\/\/www.wsws.org\/articles\/2001\/may2000\/indm16_prn.shtml\" class=\"gen\">de longues analyses,<\/a>, parce qu&rsquo;il s&rsquo;agit d&rsquo;un \u00e9v\u00e9nement g\u00e9opolitique important. L&rsquo;Inde esp\u00e8re recueillir de ce ralliement des avantages importants pour sa position r\u00e9gionale, notamment vis-\u00e0-vis des positions respectives de la Chine et du Pakistan, en obtenant le soutien am\u00e9ricain. Du c\u00f4t\u00e9 am\u00e9ricain, d&rsquo;o\u00f9 est venue l&rsquo;impulsion initiale pour ce rapprochement, l&rsquo;appr\u00e9ciation est enthousiaste (il faut dire que les Am\u00e9ricains ont aujourd&rsquo;hui si peu de soutiens ext\u00e9rieurs, sur le MDS et le reste, qu&rsquo;un rapprochement avec l&rsquo;Inde est une aubaine). Les plus enthousiastes parmi les membres de l&rsquo;administration GW Bush, en g\u00e9n\u00e9ral \u00e0 la droite de cette administration, jugent que l&rsquo;Inde pourrait devenir un alli\u00e9 strat\u00e9gique fondamental face \u00e0 la Chine. Cette id\u00e9e pourrait prendre encore plus de corps, selon l&rsquo;\u00e9volution japonaise, notamment si le Japon choisissait de prendre une certaine distance par rapport aux positions hostiles des Am\u00e9ricains face \u00e0 la Chine. En Inde m\u00eame, cette \u00e9volution du gouvernement nationaliste a provoqu\u00e9 une forte opposition du parti du Congr\u00e8s, actuellement dans l&rsquo;opposition, au nom de la politique traditionnelle de non-alignement de l&rsquo;Inde. Une analyse europ\u00e9enne de l&rsquo;\u00e9v\u00e9nement note, comme dans d&rsquo;autres cas et d&rsquo;autres situations, les perspectives d\u00e9stabilisantes de cette nouvelle pouss\u00e9e am\u00e9ricaine: \u00a0\u00bb<em>un rapprochement aussi affirm\u00e9e entre l&rsquo;Inde et les \u00c9tats-Unis risque de donner \u00e0 l&rsquo;Inde un poids particulier dans la r\u00e9gion, et d&rsquo;activer l&rsquo;antagonisme entre l&rsquo;Inde et le Pakistan d&rsquo;une part, l&rsquo;Inde et la Chine de l&rsquo;autre, et m\u00eame entre l&rsquo;Inde et la Russie. Le paradoxe de cette perspective tr\u00e8s d\u00e9stabilisante est, d&rsquo;autre part, qu&rsquo;elle rapprocherait indirectement des pays actuellement s\u00e9par\u00e9s par des tensions indirectes: le Pakistan, proche des fondamentalistes musulmans, et la Russie qui leur est hostile. Quoiqu&rsquo;il en soit, on voit \u00e0 nouveau Washington soutenir une \u00e9quipe nationaliste dont le comportement pourrait devenir aventuriste.<\/em>\u00a0\u00bb <\/p>\n<\/p>\n<p><\/p>\n<h3>Le Royaume-Uni dans l&rsquo;euro? Le probl\u00e8me est que Dieu n&rsquo;est pas d&rsquo;accord<\/h3>\n<\/p>\n<p><\/p>\n<p><p>\tVoici qui montre l&rsquo;intensit\u00e9 paradoxale du d\u00e9bat \u00e9lectoral britannique, par rapport aux questions europ\u00e9ennes. Les arguments font d\u00e9sormais entrer les appr\u00e9ciations th\u00e9ologiques. Ici, il s&rsquo;agit des affirmations d&rsquo;un \u00e9conomiste d\u00e9vot, le chief economist of the Institute of Directors, Greame Leach, qui fait entrer <a href=\"http:\/\/www.telegraph.co.uk\/et?ac=001669821461706&#038;rtmo=fwrfa-3Ds&#038;atmo=..\" class=\"gen\">Dieu dans la bataille de l&rsquo;euro,<\/a> en affirmant qu&rsquo;Il (Dieu) est d\u00e9favorable \u00e0 l&rsquo;entr\u00e9e du Royaume-Uni dans la monnaie europ\u00e9enne. Leach cite beaucoup la Bible dans ses attendus. Cette incursion du religieux est inattendu mais pas v\u00e9ritablement surprenant, surtout (paradoxe encore) venant d&rsquo;un \u00e9conomiste. Il s&rsquo;agit d&rsquo;un d\u00e9bat, dans lequel sont l&rsquo;euro et la question de l&rsquo;int\u00e9gration europ\u00e9enne pour nombre de Britanniques, qui s&rsquo;alimente \u00e0 la question du libre-\u00e9change et du march\u00e9 libre. Ces th\u00e8ses \u00e9conomiques ont des racines religieuses, le capitalisme et le libre-\u00e9changisme faisant partie de l&rsquo;h\u00e9ritage religieux protestant dans la mesure o\u00f9 ces conceptions \u00e9conomiques s&rsquo;alimentent aux conceptions m\u00eame de ces tendances religieuses (refus d&rsquo;une autorit\u00e9 terrestre, assurance que l&rsquo;enrichissement constitue une marque de la vertu religieuse, etc). Dans le vocabulaire \u00e9conomique des libre-\u00e9changistes et des partisans du march\u00e9 libre, il y a l&rsquo;id\u00e9e que le march\u00e9, s&rsquo;il doit ne r\u00e9pondre \u00e0 aucune autorit\u00e9 terrestre autre que ses propres lois, r\u00e9pond en fait \u00e0 une \u00a0\u00bb<em>main divine<\/em>\u00a0\u00bb. Il n&rsquo;est pas \u00e9tonnant que cette r\u00e9f\u00e9rence apparaisse dans la campagne \u00e9lectorale britannique, qui est marqu\u00e9e autant par la vigueur et le radicalisme des positions politiques que par l&rsquo;indiff\u00e9rence de l&rsquo;\u00e9lectorat, interpr\u00e9t\u00e9e par certains comme une sourde hostilit\u00e9 \u00e0 la classe politique.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;extraordinaire (et fausse) image de puissance qu&rsquo;est en train d&rsquo;acqu\u00e9rir l&rsquo;Europe Il nous est d\u00e9j\u00e0 arriv\u00e9 de citer le chroniqueur Justin Raimundo, qui dirige le site Antiwar.com et qui publie sur ce site une chronique r\u00e9guli\u00e8re. Raimundo est de l&rsquo;extr\u00eame-droite libertarienne am\u00e9ricaine: isolationiste, anti-interventioniste dans les deux sens du mot (adversaire des interventions arm\u00e9es ext\u00e9rieures&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[7],"tags":[],"class_list":["post-64939","post","type-post","status-publish","format-standard","hentry","category-journal"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/64939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=64939"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/64939\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=64939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=64939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=64939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}