{"id":64956,"date":"2001-06-17T00:00:00","date_gmt":"2001-06-17T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2001\/06\/17\/semaine-du-11-au-17-juin-2001\/"},"modified":"2001-06-17T00:00:00","modified_gmt":"2001-06-17T00:00:00","slug":"semaine-du-11-au-17-juin-2001","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2001\/06\/17\/semaine-du-11-au-17-juin-2001\/","title":{"rendered":"Semaine du 11 au 17 juin 2001"},"content":{"rendered":"<p><h3>La r\u00e9volte des vieux g\u00e9n\u00e9raux, &mdash; britanniques et fran\u00e7ais<\/h3>\n<\/p>\n<p><\/p>\n<p><p>\tL&rsquo;improbable est arriv\u00e9: une union d&rsquo;officiers g\u00e9n\u00e9raux (g\u00e9n\u00e9raux et amiraux) britanniques et fran\u00e7ais, prenant position, signant un texte commun contre la PESD, et la constitution d&rsquo;une Force de R\u00e9action Rapide europ\u00e9enne. Ravi de l&rsquo;aubaine, <a href=\"http:\/\/www.telegraph.co.uk\/et?ac=005231703745325&#038;rtmo=oKNKsxb-q&#038;atmc..\" class=\"gen\">The Telegraph<\/a> publie la lettre commune de ces dix anciens officiers g\u00e9n\u00e9raux et la pr\u00e9sente comme une attaque significative contre l&rsquo;<em>Euro Army<\/em>. Tous les officiers qui ont sign\u00e9 cette lettre sont \u00e0 la retraite, parfois depuis longtemps. Ils repr\u00e9sentent la g\u00e9n\u00e9ration pr\u00e9c\u00e9dente, voire pour certains celle d&rsquo;avant, des officiers g\u00e9n\u00e9raux des deux pays, &mdash; c&rsquo;est-\u00e0-dire des g\u00e9n\u00e9rations d&rsquo;avant la fin de la guerre froide. Ainsi leur prise de position appara\u00eet-elle comme extr\u00eamement logique, puisqu&rsquo;elle refl\u00e8te effectivement l&rsquo;analyse courante \u00e0 l&rsquo;\u00e9poque de leur commandement. Le paradoxe de cette prise de position est qu&rsquo;elle tend \u00e0 confirmer le caract\u00e8re r\u00e9volutionnaire de la PESD, et le fait que la PESD est vraiment une initiative d&rsquo;une \u00e9poque nouvelle, c&rsquo;est-\u00e0-dire une initiative radicalement en rupture avec la psychologie \u00ab\u00a0de blocs\u00a0\u00bb de la guerre froide (psychologie qui ne d\u00e9bouchait que sur cette alternative: l&rsquo;isolement [des USA] \u00e0 la fran\u00e7aise ou l&rsquo;alignement [sur les USA] \u00e0 l&rsquo;anglaise). La logique de ces g\u00e9n\u00e9raux et de ces amiraux est purement nationale et s&rsquo;appuie sur une hypoth\u00e8se de conflit (ou de menace de conflit) relevant des situations classiques ayant exist\u00e9 jusqu&rsquo;\u00e0 la fin de la guerre froide, et n&rsquo;existant plus aujourd&rsquo;hui. Si l&rsquo;on accepte au contraire ces donn\u00e9es comme donn\u00e9es de d\u00e9part de l&rsquo;analyse, celle-ci se r\u00e9v\u00e8le \u00e9videmment juste et imparable. On comprend \u00e9videmment que c&rsquo;est l&rsquo;essentiel: une analyse juste datant d&rsquo;une autre \u00e9poque. Cette lettre doit plut\u00f4t nous faire mesurer l&rsquo;extraordinaire bouleversement survenue en une g\u00e9n\u00e9ration d&rsquo;officiers g\u00e9n\u00e9raux, dans les relations internationales (encore bien plus que le bouleversement en Europe, car la PESD est bien plus un ph\u00e9nom\u00e8ne concernant la situation des relations internationales que la situation europ\u00e9enne; c&rsquo;est-\u00e0-dire la situation de l&rsquo;Europe par rapport aux autres forces des relations internationales plut\u00f4t que la situation intra-europ\u00e9enne).<\/p>\n<\/p>\n<p><\/p>\n<h3>Derri\u00e8re l&rsquo;apparence des sommets absolument vierges de toute substance, la rivalit\u00e9 transatlantique qui ne cesse de monter<\/h3>\n<\/p>\n<p><\/p>\n<p><p>\tLa visite de GW Bush en Europe a \u00e9t\u00e9 d\u00e9sign\u00e9 comme le <em>Grand Tour<\/em>, selon les commentateurs am\u00e9ricains [ironiquement ou pas? On l&rsquo;ignore]: sans passer par Londres, ni Paris, ni Berlin. Elle a marqu\u00e9 la r\u00e9alit\u00e9 d&rsquo;une situation d\u00e9sormais ais\u00e9ment identifiable sur deux niveaux: le premier, public, t\u00e9l\u00e9vis\u00e9, celui des sommets, sans substance, sans cons\u00e9quence, sans rien du tout; le second, qui est l&rsquo;occasion de commentaires, de r\u00e9flexion, de jugements, et qui marque aussi bien, pour le cas qui nous occupe, un accroissement g\u00e9n\u00e9ral et r\u00e9gulier des tensions transatlantiques. Les Am\u00e9ricains, comme l&rsquo;\u00e9crit avec agressivit\u00e9 <LIENS=http:\/\/www.nytimes.com\/2001\/06\/14\/opinion\/14SAFI.html>William Safire<D>, ont d\u00e9sormais la sensation d&rsquo;avoir en face d&rsquo;eux (contre eux?) une seule Europe, et une Europe critique, agressive. (La chose, dans tous les cas pour ce qui est de l&rsquo;unit\u00e9 europ\u00e9enne, est confirm\u00e9e par les \u00e9valuations courantes du State department, souvent \u00e9tonnantes tant elles grandissent la perception de l&rsquo;Europe: voir notre rubrique <em>de defensa<\/em>, dans <em>dd&#038;e<\/em>, Vol16, n<198>19 du 25 juin 2001.) Cette humeur des relations transatlantiques se retrouve au <LIENS=http:\/\/biz.yahoo.com\/rf\/010614\/l010614\/l14310511_2.html>Salon a\u00e9ronautique du Bourget<D>, ouvert le 16 juin. L&rsquo;humeur y est \u00e0l&rsquo;affrontement transatlantique, comme d&rsquo;habitude mais un peu plus qu&rsquo;\u00e0 l&rsquo;habitude. Pour expliquer cette tension, les sujets ne manquent pas, qu&rsquo;on aille du commerce \u00e0 l&rsquo;environnement, de l&rsquo;organisation de la s\u00e9curit\u00e9 europ\u00e9enne \u00e0 la question de la d\u00e9fense anti-missile. D\u00e9sormais, cette tension transatlantique, c&rsquo;est du <em>business as usual<\/em> des relations internationales.<\/p>\n<\/p>\n<p><\/p>\n<h3>Il n&#8217;emp\u00eache, le Wall Street <strong><em>Journal<\/em><\/strong> est rassur\u00e9: l&rsquo;Europe ne hait pas Bush<\/h3>\n<\/p>\n<p><\/p>\n<p><p>\tNous d\u00e9couvrons que les Am\u00e9ricains attendaient le voyage de GW Bush en Europe vraiment avec des anxi\u00e9t\u00e9s diverses. Apr\u00e8s avoir lu la chronique de William Safire (voir ci-dessus), qui refl\u00e8te un \u00e9tat d&rsquo;esprit g\u00e9n\u00e9ral des commentateurs am\u00e9ricains, voici un texte finalement assez surprenant du <a href=\"http:\/\/www.opinionjournal.com\/editorial\/feature.html?id=95000-628\" class=\"gen\">Wall Street Journal(WSJ)<\/a>, au titre aussi rassurant qu&rsquo;un soupir de soulagement: \u00ab<em>Europe Doesn&rsquo;t Hate Bush<\/em>\u00bb. Le WSJ est certainement l&rsquo;un des journaux les plus agressifs vis-\u00e0-vis de l&rsquo;Europe par les temps qui courent; il repr\u00e9sente les tendances agressives combin\u00e9es des r\u00e9publicains <em>neocons<\/em> h\u00e9g\u00e9monistes et des r\u00e9publicains hyper-conservateurs de type religieux, tout cela \u00e0la sauce du sarcasme anti-europ\u00e9en des milieux d&rsquo;affaires et de Wall Street. Pourtant, le WSJ est soulag\u00e9, parce que la foule n&rsquo;a pas lapid\u00e9 GW \u00e0 Bruxelles (au contraire de ce qu&rsquo;elle a fait \u00e0G\u00f6teborg, pr\u00e9tendument contre l&rsquo;UE, contre les dirigeants europ\u00e9ens). <\/p>\n<\/p>\n<p><p>\tLaissons le fait de savoir si l&rsquo;Europ\u00e9en moyen hait ou ne hait pas GW, et si l&rsquo;homme politique europ\u00e9en moyen a \u00e9t\u00e9, comme l&rsquo;\u00e9crit <a href=\"http:\/\/news.ft.com\/ft\/gx.cgi\/ftc?pagename=View&#038;c=Article&#038;cid=-FT3SESDAo(..\" class=\"gen\">The Financial Times (FT)<\/a>, rassur\u00e9 de savoir que l&rsquo;image de GW est d\u00e9sormais \u00ab<em>No More Unilateralist<\/em>\u00bb (cela vaut le \u00ab<em>Don&rsquo;t call Me unilateralist<\/em>\u00bb de Safire). Tout cela, la r\u00e9action du WSJ comme le commentaire du FT, nous donne une indication extr\u00eamement int\u00e9ressante, la seule pour l&rsquo;instant qui soit vraiment instructive (quant aux sourires des Europ\u00e9ens devant un pr\u00e9sident am\u00e9ricain, rien que du <em>business as usual<\/em>): la crainte vertigineuse de l&rsquo;<em>establishment<\/em> transatlantique, de part et d&rsquo;autre de l&rsquo;Atlantique, devant une tendance, qui n&rsquo;est pourtant pour l&rsquo;instant qu&rsquo;une brise innocente, qui pourrait ressembler \u00e0 un d\u00e9sengagement am\u00e9ricain d&rsquo;Europe dans la logique de cette mont\u00e9e des tensions signal\u00e9e plus haut. Nous sommes bien, avec les relations transatlantiques, au coeur de la grande rupture du monde occidental, celle qui fait peur \u00e0 tout le monde.<\/p>\n<\/p>\n<p><\/p>\n<h3>Le sommet de G\u00f6teborg, ou l&rsquo;affirmation solennelle de l&rsquo;Europe sans casse ni castagne: les chefs d&rsquo;\u00c9tat et de gouvernement ne se rendront pas<\/h3>\n<\/p>\n<p><\/p>\n<p><p>\tD&rsquo;abord, ce commentaire compl\u00e8tement \u00e9poustouflant d&rsquo;un journaliste en plein travail, samedi 16 juin \u00e0 20H15, sur TF1, en direct de G\u00f6teborg (il s&rsquo;agit de Fran\u00e7ois Bachy, mais tous, apr\u00e8s tout, auraient pu dire la m\u00eame chose): \u00ab<em>Les casseurs ont gagn\u00e9 s&rsquo;ils voulaient perturber le d\u00e9roulement du sommet, mais ils ont perdu s&rsquo;ils croient pouvoir emp\u00eacher la construction de l&rsquo;Europe et les chefs d&rsquo;\u00c9tat de se rencontrer.<\/em>\u00bb On est rassur\u00e9: les chefs d&rsquo;\u00c9tat et de gouvernement tiendront et l&rsquo;Europe (tout de m\u00eame: pr\u00e8s de 400 millions d&rsquo;habitants) r\u00e9sistera aux quelques milliers de manifestants-cogneurs de G\u00f6teborg; et les commentaires des journalistes parleront d\u00e9sormais du sommet de G\u00f6teborg comme d&rsquo;une bataille o\u00f9 l&rsquo;Europe n&rsquo;a pas capitul\u00e9, o\u00f9 une victoire de plus fut brillamment (quoique bruyamment) remport\u00e9e. Apr\u00e8s G\u00f6teborg, les commentaires ont \u00e9t\u00e9 bon train, et les d\u00e9bats <em>itou<\/em>, \u00e0Bruxelles, au gouvernement, \u00e0 l&rsquo;ex\u00e9cutif bruxellois, au gouvernement flamant et au gouvernement wallon, et tout cela portant sur le fait de savoir si l&rsquo;on r\u00e9unirait les chefs d&rsquo;\u00c9tat et de gouvernement dans le quartier de l&rsquo;Europe, en centre-ville, ou au Heysel, en-dehors de l&rsquo;agglom\u00e9ration, s&rsquo;il y aurait de quoi les \u00e9vacuer \u00e0 temps, si les routes seraient assez larges pour abriter les auto-pompes. Des commissaires en chef bruxellois parlaient avec un certain m\u00e9pris de leurs coll\u00e8gues exp\u00e9riment\u00e9s de G\u00f6teborg et Stockholm r\u00e9unis (on voit bien que les Su\u00e9dois sont tout neufs dans l&rsquo;UE) et mettaient en avant l&rsquo;une des plus belles victoires de la capitale de l&rsquo;Europe: la phase finale du championnat du monde de football, dit <em>Euro-2000<\/em>, sans casse ni castagne. D\u00e9sormais, un sommet r\u00e9ussi au sein de l&rsquo;UE, c&rsquo;est un sommet o\u00f9 les chefs de l&rsquo;\u00c9tat et de gouvernement peuvent se rencontrer, &mdash; sans casse ni castagne, ou \u00e0 peine. Bien, passons aux choses s\u00e9rieuses: c&rsquo;est-\u00e0-dire, ni les propos des chefs d&rsquo;\u00c9tat et de gouvernement, ni les d\u00e9cisions du sommet. <\/p>\n<\/p>\n<p><p>\tCe qui s&rsquo;est pass\u00e9 <a href=\"http:\/\/www.liberation.com\/quotidien\/semaine\/200106same.html\" class=\"gen\">\u00e0 G\u00f6teborg<\/a> ne fait que confirmer ce qui s&rsquo;est pass\u00e9 au Royaume-Uni le 7 juin (abstentions massives, d\u00e9sint\u00e9r\u00eat du public), en Irlande (non au sommet de Nice), voire autour du voyage de GW Bush (\u00ab<em>Europe Doesn&rsquo;t Hate Bush<\/em>\u00bb, sans doute parce qu&rsquo;elle s&rsquo;en fout): la confirmation r\u00e9guli\u00e8re, r\u00e9p\u00e9t\u00e9e, bruyante ou discr\u00e8te, brutale et \u00e9vidente, dans les rues, face aux policiers, dans les isoloirs, que ces gens (les chefs d&rsquo;\u00c9tat et de gouvernement, de l&rsquo;UE et du \u00ab<em>rest of the world<\/em>\u00bb comme on dit au State department) vivent sur une plan\u00e8te diff\u00e9rente de celle o\u00f9 l&rsquo;on peut rencontrer les gens en g\u00e9n\u00e9ral (les \u00e9lecteurs, les casseurs, les bourgeois, les agriculteurs, les \u00e9lecteurs et ainsi de suite). Par cons\u00e9quent, les d\u00e9cisions de l&rsquo;UE ne nous concernent pas vraiment, ni les promesses, ni les manoeuvres; elles exposent, par l&rsquo;indiff\u00e9rence ou la col\u00e8re \u00e0premi\u00e8re vue inexplicable qu&rsquo;elles suscitent, la crise g\u00e9n\u00e9rale o\u00f9 se d\u00e9bat notre monde, avec ses politiciens coinc\u00e9s entre les casseurs-castagneurs et leurs images dans les m\u00e9dias, et totalement absents du monde r\u00e9el. Dans cette sorte de sommet, aucun enseignement politique ne peut \u00eatre tir\u00e9, mais des enseignements sociologiques, psychologiques, historiques \u00e0 la pelle, sur nos institutions, notre civilisation, notre mode de vie, notre syst\u00e8me de valeurs et ainsi de suite. G\u00f6teborg gagnera donc \u00e0 \u00eatre examin\u00e9 par les psychologues, les sociologues et, \u00e9ventuellement, par les historiens, plus que par les politologues.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La r\u00e9volte des vieux g\u00e9n\u00e9raux, &mdash; britanniques et fran\u00e7ais L&rsquo;improbable est arriv\u00e9: une union d&rsquo;officiers g\u00e9n\u00e9raux (g\u00e9n\u00e9raux et amiraux) britanniques et fran\u00e7ais, prenant position, signant un texte commun contre la PESD, et la constitution d&rsquo;une Force de R\u00e9action Rapide europ\u00e9enne. Ravi de l&rsquo;aubaine, The Telegraph publie la lettre commune de ces dix anciens officiers g\u00e9n\u00e9raux&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[7],"tags":[3188,3091,1205],"class_list":["post-64956","post","type-post","status-publish","format-standard","hentry","category-journal","tag-goteborg","tag-pesd","tag-transatlantique"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/64956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=64956"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/64956\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=64956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=64956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=64956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}