{"id":64977,"date":"2002-02-09T00:00:00","date_gmt":"2002-02-09T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2002\/02\/09\/levaluation-de-la-puissance-us-est-beyond-history-et-out-of-control\/"},"modified":"2002-02-09T00:00:00","modified_gmt":"2002-02-09T00:00:00","slug":"levaluation-de-la-puissance-us-est-beyond-history-et-out-of-control","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2002\/02\/09\/levaluation-de-la-puissance-us-est-beyond-history-et-out-of-control\/","title":{"rendered":"<strong><em>L&rsquo;\u00e9valuation de la puissance US est \u00a0\u00bbbeyond history\u00a0\u00bb et \u00a0\u00bbout of control\u00a0\u00bb<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">L&rsquo;\u00e9valuation de la puissance US est <strong><em>beyond history<\/em><\/strong> et <strong><em>out of control<\/em><\/strong><\/h2>\n<\/p>\n<p><p>\tOn s&rsquo;arr\u00eate \u00e0 deux textes qui nous restituent l&rsquo;atmosph\u00e8re, &mdash; point bien plus int\u00e9ressant que les interventions qui n&rsquo;ont fait que confirmer les diverses tendances &mdash; du colloque annuel de la <em>Wehrkunde<\/em> de Munich, les 2-3 f\u00e9vrier. Ce rendez-vous chic et r\u00e9put\u00e9 r\u00e9unit chaque ann\u00e9e ministres et experts du monde transatlantique, Europe et USA, pour minimiser leurs diff\u00e9rences grandissantes. Extraits de la m\u00eame \u00e9dition (4 f\u00e9vrier) de l&rsquo;International <em>Herald Tribune<\/em>, il y a d&rsquo;abord un <a href=\"http:\/\/www.iht.com\/articles\/46913.html\" class=\"gen\">texte de Thomas Friedman<\/a>, qui y fait implicitement r\u00e9f\u00e9rence, comme on le comprend bien \u00e0 la lumi\u00e8re du <a href=\"http:\/\/www.iht.com\/articles\/46887.html\" class=\"gen\">deuxi\u00e8me texte, de Joseph Fitchett<\/a>, rapportant un compte-rendu de cette rencontre.<\/p>\n<\/p>\n<p><p>\tR\u00e9sumons le th\u00e8me qu&rsquo;on veut mettre ici en \u00e9vidence : la puissance militaire am\u00e9ricaine est telle qu&rsquo;elle tend \u00e0 isoler compl\u00e8tement les USA du reste du monde (pour l&rsquo;occasion, ressortons l&rsquo;acronyme bienvenu : ROW, pour <em>Rest Of the World<\/em>, qui, effectivement, ne semble gu\u00e8re valoir plus que le poids de l&rsquo;acronyme). Cela est bien exprim\u00e9, ou, disons, exprim\u00e9 d&rsquo;une fa\u00e7on imag\u00e9 par cette citation du texte de Fitchett :<\/p>\n<\/p>\n<p><p>\t\u00ab <em>Assessing the impact of the U.S. campaign in Afghanistan, Pentagon officials said that the armed forces&rsquo; success<\/em> &mdash; essentially using sophisticated electronics and sensors to deliver high-precision bombs and missiles &mdash; <em>had already spurred nearly $50 billion in new, extra spending on high-tech weapons in the new U.S. defense budget. \u00a0\u00bbAt this rate, we won&rsquo;t even be able to communicate with you, much less fight alongside you,\u00a0\u00bb a former German defense official said.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The prospect of a split alliance, with U.S. forces fighting wars aided by local allies and the Europeans confined to peacekeeping and other infantry roles, dismayed George Robertson, secretary-general of the North Atlantic Treaty Organization. He warned that trans-Atlantic solidarity was bound to shatter if \u00a0\u00bbthe Americans do the cutting edge while the Europeans are stuck at the bleeding edge, if the Americans fight from the sky and the Europeans fight in the mud.\u00a0\u00bb<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tFriedman, lui, explique comment les USA deviennent unilat\u00e9ralistes, par la gr\u00e2ce \u00e9trange d&rsquo;un ph\u00e9nom\u00e8ne qu&rsquo;il d\u00e9signe comme un \u00ab <em>military apartheid<\/em> \u00bb, o\u00f9 la puissance am\u00e9ricaine enferme les USA par rapport \u00e0 leurs alli\u00e9s. Mais qui enferme l&rsquo;autre ? \u00c9trange combien le texte de Friedman semble montrer les USA \u00ab\u00a0victimes\u00a0\u00bb d&rsquo;une puissance contre laquelle ils semblent ne rien pouvoir faire, comme par exemple la d\u00e9cision d&rsquo;augmenter de $48 milliards leur budget du DoD. La logique de l&rsquo;analyse conduit \u00e0 sugg\u00e9rer qu&rsquo;on pourrait croire que la responsabilit\u00e9 de cet \u00e9tat de chose incomberait \u00e0 ces pauvres Europ\u00e9ens, accus\u00e9s de ne pas faire la m\u00eame chose, de ne pas augmenter leurs budgets de la d\u00e9fense de 14%. Bref, sugg\u00e8re Friedmann, les Europ\u00e9ens feraient bien d&rsquo;acheter de nouveaux \u00e9quipements \u00ab <em>that can take off with America<\/em> \u00bb (c&rsquo;est-\u00e0-dire, en g\u00e9n\u00e9ral, des \u00e9quipements am\u00e9ricains), sans quoi l&rsquo;Am\u00e9rique va dispara\u00eetre vers les confins de cet autre monde o\u00f9 elle se trouve d\u00e9j\u00e0. Friedman :<\/p>\n<\/p>\n<p><p>\t\u00ab <em>As a result, we are increasingly headed for military apartheid within NATO. America will be the chef who decides on the menu and cooks all the great meals, and the NATO allies will be the busboys who stay around and clean up the mess and keep the peace &#8211; indefinitely. As a French diplomat put it to me bluntly, \u00a0\u00bbThat is not going to be sustainable.\u00a0\u00bb He&rsquo;s right.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>If the Europeans truly want to be in on the takeoff of military operations, they had better invest in the planes and equipment that can take off with America. Otherwise they will have no credibility when they complain about U.S. unilateralism.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>At the same time, though, the Bush team would do well to restrain some of its unilateralist instincts, from NATO to Kyoto. Frankly, I&rsquo;m glad America can fight everywhere in the dark, but I wouldn&rsquo;t want it to have to fight everywhere alone.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCes affirmations diverses sont d\u00e9velopp\u00e9es \u00e0 partir d&rsquo;affirmations th\u00e9oriques, assorties d&rsquo;images brutales et d\u00e9finitives dont on retrouve le mod\u00e8le dialectique dans toutes les d\u00e9clarations officielles am\u00e9ricaines. Par contre, les faits eux-m\u00eames semblent souvent moins sollicit\u00e9es. On en citera quelques-uns, ci-dessous, en pr\u00e9cisant de fa\u00e7on tr\u00e8s insistante que la liste n&rsquo;est en aucune fa\u00e7on limitative :<\/p>\n<\/p>\n<p><p>\t&bull; L&rsquo;U.S. Navy a pouss\u00e9 un ouf de soulagement \u00e0 l&rsquo;arriv\u00e9e du <em>Charles-de-Gaulle<\/em>, en d\u00e9cembre, dans la zone de crise de l&rsquo;Oc\u00e9an Indien, parce que cela permettait au USS <em>Carl-Vinson<\/em> de pouvoir rentrer \u00e0 son port d&rsquo;attache, aux USA. Le <em>Carl-Vinson<\/em> \u00e9tait maintenu sur place bien qu&rsquo;il f\u00fbt au terme de ses capacit\u00e9s de fonctionnement parce que l&rsquo;U.S. Navy n&rsquo;a plus de porte-avions disponible.<\/p>\n<\/p>\n<p><p>\t&bull; Dans les op\u00e9rations en Afghanistan, les communications \u00e9tablies entre la CIA en Afghanistan et l&rsquo;Alliance du Nord, bien que primitives au regard des normes actuelles, ont \u00e9t\u00e9 meilleures que les communications entre la CIA et Central Command, simplement parce que les diff\u00e9rents services US fonctionnent avec des \u00e9quipements et des proc\u00e9dures incompatibles. Dans certains cas, pour s&rsquo;adresser \u00e0 Central Command, la CIA a du passer par l&rsquo;Alliance du Nord.<\/p>\n<\/p>\n<p><p>\t&bull; Le meilleur chasseur embarqu\u00e9 du monde aujourd&rsquo;hui est le <em>Rafale<\/em> Marine, dont quatre exemplaires sont embarqu\u00e9s \u00e0 bord du <em>Charles-de-Gaulle<\/em>. Les pilotes am\u00e9ricains de F-18 ont \u00e9t\u00e9 stup\u00e9faits des performances du <em>Rafale<\/em>, et de la domination du <em>Rafale<\/em> dans les combats simul\u00e9s avec leurs propres avions, lors d&rsquo;exercices conjoints dans l&rsquo;Oc\u00e9an Indien.<\/p>\n<\/p>\n<p><p>\t&bull; Durant leur op\u00e9ration sur l&rsquo;Afghanistan, l&rsquo;U.S. Navy, qui a assur\u00e9 l&rsquo;essentiel des attaques tactiques, ne pouvait rien faire sans les ravitailleurs en vol de la Royal Air Force britannique. (M\u00eame le secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;OTAN Robertson, qui est Britannique et ceci explique tout de m\u00eame cela, a pr\u00e9cis\u00e9 ce d\u00e9tail le 31 janvier, lors d&rsquo;une conf\u00e9rence \u00e0 Washington : \u00ab <em>It is a striking fact that because of NATO&rsquo;s emphasis on multinational interoperability, British tanker aircraft over Afghanistan can refuel US Navy fighters, but US Air Force tankers cannot.<\/em> \u00bb)<\/p>\n<\/p>\n<p><p>\tLa r\u00e9alit\u00e9 est que l&rsquo;expertise et la communication (m\u00e9dias compris) dans l&rsquo;\u00e9valuation de la puissance US sont d\u00e9sormais <em>out of control<\/em> et <em>beyond history<\/em> (au-del\u00e0 de la r\u00e9f\u00e9rence factuelle dont est faite d&rsquo;habitude l&rsquo;enqu\u00eate historique). Quelles que soient les r\u00e9alit\u00e9s, plus rien \u00e0 cet \u00e9gard n&rsquo;est int\u00e9gr\u00e9 dans l&rsquo;\u00e9valuation de la puissance US. Celle-ci est d\u00e9crite en termes absolus, qui se r\u00e9f\u00e8rent d&rsquo;abord \u00e0 des masses, des chiffres d&rsquo;une part, et, d&rsquo;autre part, \u00e0 une figuration virtualiste qui ne souffre aucune restriction et qui dit que l&rsquo;Am\u00e9rique est dans un monde \u00e0 part d&rsquo;une sup\u00e9riorit\u00e9 absolue.<\/p>\n<\/p>\n<p><p>\tCette attitude, qui se voudrait n&rsquo;\u00eatre pas politique, qui se voudrait m\u00eame \u00eatre \u00ab\u00a0objective\u00a0\u00bb, comme on constate un fait de la vie, a en r\u00e9alit\u00e9 des effets politiques d\u00e9vastateurs. D&rsquo;une part, les questions commencent \u00e0 appara\u00eetre sur l&rsquo;int\u00e9r\u00eat m\u00eame du d\u00e9veloppement exponentiel de toutes les technologies militaires dans le sens que les Am\u00e9ricains affirment indiquer ; d&rsquo;autre part, nombre d&rsquo;Europ\u00e9ens commencent \u00e0 apercevoir les limites de l&rsquo;argumentation am\u00e9ricaine, qui tend de plus en plus \u00e0 se discr\u00e9diter par ses exc\u00e8s m\u00eame, qui alimente puissamment le m\u00e9contentement g\u00e9n\u00e9ral \u00e0 l&rsquo;encontre de la rh\u00e9torique h\u00e9g\u00e9moniste, mena\u00e7ante, etc, de l&rsquo;administration Bush (\u00ab <em>the devil&rsquo;s axis<\/em> \u00bb et le reste). Il y a un d\u00e9veloppement <em>de facto<\/em> vers la perception d&rsquo;une politique unilat\u00e9raliste, qui ne serait rien d&rsquo;autre qu&rsquo;une attitude isolationniste et indiff\u00e9rente des \u00c9tats-Unis, en m\u00eame temps que le constat que la politique am\u00e9ricaine ne cesse d&rsquo;accentuer le d\u00e9sordre et d&rsquo;aggraver des menaces l\u00e0 o\u00f9 elle pr\u00e9tend les r\u00e9duire. Le militarisme de la pens\u00e9e am\u00e9ricaine p\u00e8se lourd dans ces d\u00e9veloppements ; et de m\u00eame, par cons\u00e9quent, les convictions quasi-religieuses des experts am\u00e9ricaines. <\/p>\n<\/p>\n<p><p>\tRestent sur le carreau les amis de l&rsquo;Am\u00e9rique, qui ne comprennent plus vraiment ce qu&rsquo;il y a dans l&rsquo;esprit des Am\u00e9ricains. Il serait peut-\u00eatre surpris s&rsquo;ils savaient, &mdash; ou bien, peut-\u00eatre commencent-ils \u00e0 s&rsquo;en douter. Friedman rapporte ce propos si r\u00e9v\u00e9lateur : \u00ab <em>\u00a0\u00bbIn the 1960s it was France under Charles de Gaulle that threatened NATO&rsquo;s cohesion; in 2001, it is Don Rumsfeld&rsquo;s America that is doing so,\u00a0\u00bb argues Dominique Mo\u00efsi, a French expert on international relations. \u00a0\u00bbBasically the question before us is this: What happens to a creature when its creator no longer trusts it? What is the meaning of an alliance if the immediate reaction of its leader is, &lsquo;Don&rsquo;t call us, we&rsquo;ll call you, because we basically don&rsquo;t trust you&rsquo;? Look, I am all for NATO, but if the Americans are not, what am I to do?\u00a0\u00bb<\/em> \u00bb La question de Mo\u00efsi sonne avec la nostalgie d&rsquo;un autre temps.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00e9valuation de la puissance US est beyond history et out of control On s&rsquo;arr\u00eate \u00e0 deux textes qui nous restituent l&rsquo;atmosph\u00e8re, &mdash; point bien plus int\u00e9ressant que les interventions qui n&rsquo;ont fait que confirmer les diverses tendances &mdash; du colloque annuel de la Wehrkunde de Munich, les 2-3 f\u00e9vrier. Ce rendez-vous chic et r\u00e9put\u00e9 r\u00e9unit&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[1268,3230,584,2804,3229],"class_list":["post-64977","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-friedman","tag-moisi","tag-otan","tag-usa","tag-wehrkunde"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/64977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=64977"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/64977\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=64977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=64977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=64977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}