{"id":64991,"date":"2001-09-09T00:00:00","date_gmt":"2001-09-09T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2001\/09\/09\/semaine-du-3-septembre-au-9-septembre-2001\/"},"modified":"2001-09-09T00:00:00","modified_gmt":"2001-09-09T00:00:00","slug":"semaine-du-3-septembre-au-9-septembre-2001","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2001\/09\/09\/semaine-du-3-septembre-au-9-septembre-2001\/","title":{"rendered":"Semaine du 3 septembre au 9 septembre 2001"},"content":{"rendered":"<p><h3>Les USA face au Mexique et le Mexique dans les USA<\/h3>\n<\/p>\n<p><p>\tLa visite de Vicente Fox aux USA, \u00e0 Washington la semaine derni\u00e8re, a \u00e9t\u00e9 un \u00e9v\u00e9nement. Le pr\u00e9sident mexicain n&rsquo;a pas cach\u00e9 ses intentions alors qu&rsquo;on attendait qu&rsquo;il se montre beaucoup plus r\u00e9serv\u00e9 : Fox a demand\u00e9 un accord \u00ab <em>d&rsquo;ici No\u00ebl<\/em> \u00bb sur la l\u00e9galisation de la pr\u00e9sence de pr\u00e8s de 4 millions d&rsquo;immigrants mexicains ill\u00e9gaux aux USA. Pourtant, les r\u00e9ticences du Congr\u00e8s (alors que GW Bush est favorable \u00e0un tel accord) avaient fait penser que Fox \u00e9carterait des pressions trop fortes pour un tel accord. A Washington, Vicente Fox a montr\u00e9 qu&rsquo;il ne craignait rien face aux Am\u00e9ricains. L&rsquo;immigration mexicaine aux USA, l\u00e9gale et ill\u00e9gale, voire la pr\u00e9sence d&rsquo;une minorit\u00e9 hispanique d&rsquo;un poids consid\u00e9rable et sans cesse en augmentation aux USA, constituent pour lui une arme politique d&rsquo;une tr\u00e8s grande force. Sans doute jamais aucun homme politique non-am\u00e9ricain n&rsquo;aura tenu une place aussi importante dans la politique int\u00e9rieure am\u00e9ricaine que Vicente Fox depuis son installation comme pr\u00e9sident mexicains (en d\u00e9cembre dernier). Les commentateurs am\u00e9ricains ne s&rsquo;en cachent plus d\u00e9sormais : pour eux, c&rsquo;est sans aucun doute <a href=\"http:\/\/www.time.com\/time\/pow\/article\/0,8599,174018,00.html\" class=\"gen\">une nouvelle \u00e9poque qui commence<\/a>, &mdash; pour les relations am\u00e9ricano-mexicaines, pour le Mexique \u00e9videmment mais aussi, et surtout, de mani\u00e8re bien plus fondamentale, pour les \u00c9tats-Unis. Aujourd&rsquo;hui, sous nos yeux, commence le processus de d\u00e9sint\u00e9gration de la pr\u00e9pond\u00e9rance absolue des WASP (<em>White, Anglo-Saxon, Protestant<\/em>) sur la plus grande puissance du monde. Face \u00e0 cette pouss\u00e9e, GW Bush est le &quot;partenaire&quot; id\u00e9al pour Fox. Certes, il h\u00e9site \u00e0accepter certaines demandes du Mexicain mais on sent qu&rsquo;il est d&rsquo;ores et d\u00e9j\u00e0 acquis aux principes qui justifient ces demandes ; bien que cela puisse para\u00eetre paradoxal pour un pr\u00e9sident r\u00e9publicain qu&rsquo;on pourrait croire partisan d&rsquo;une politique d&rsquo;affirmation am\u00e9ricaine, on retrouve le r\u00e9flexe r\u00e9gional de l&rsquo;ex-gouverneur du Texas dont la premi\u00e8re visite, apr\u00e8s son \u00e9lection de 1996 fut pour le pr\u00e9sident mexicain, \u00e0 Mexico. Mais il faut aller plus loin encore : c&rsquo;est le cadre institutionnel et <a href=\"http:\/\/www.newsmax.com\/archives\/articles\/2001\/9\/7\/204503.shtml\" class=\"gen\">le concept m\u00eame de souverainet\u00e9 des USA<\/a> qui est mis en question au travers de la nouvelle orientation des relations avec le Mexique. Selon ses interventions publiques, Fox se dit pr\u00e9sident des 100 millions de Mexicains du Mexique, ou bien des 117 millions ou des 123 millions de Mexicains du continent nord-am\u00e9ricain (selon qu&rsquo;il prend en compte les 17 millions de Mexicains non-citoyens US vivant aux USA, ou qu&rsquo;il ajoute \u00e0 ces 17 millions les 7 millions de Mexicains n\u00e9s au Mexique et devenus citoyens US). Dans le cas de Fox-pr\u00e9sident de 123 millions de Mexicains du continent nord-am\u00e9ricain, effectivement, que devient la nationalit\u00e9 \u00e9tats-unienne, celle des 7 millions de Mexicains n\u00e9s au Mexique et naturalis\u00e9s citoyens US ? La question est d&rsquo;autant plus int\u00e9ressante que cette affirmation de Vicente Fox va devenir une quasi-r\u00e9alit\u00e9 institutionnelle, lorsque, selon sa promesse, les Mexicains n\u00e9s au Mexique et vivant aux USA, rest\u00e9s citoyens mexicains ou naturalis\u00e9s citoyens US, auront le droit de vote au Mexique pour \u00e9lire leurs s\u00e9nateurs au Parlement de Mexico City. Le cas mexicain, qui est de loin le probl\u00e8me de politique ext\u00e9rieure le plus fondamental pour les \u00c9tats-Unis, met en \u00e9vidence la fondamentale fragilit\u00e9 des \u00c9tats-Unis, pays tr\u00e8s largement conf\u00e9d\u00e9ral et d\u00e9centralis\u00e9 dans sa premi\u00e8re phase d&rsquo;existence, devenu une f\u00e9d\u00e9ration tr\u00e8s centralis\u00e9e dans certains domaines apr\u00e8s la Guerre de S\u00e9cession de 1861-65, mais qui a gard\u00e9 certaines de ses caract\u00e9ristiques initiales. La fatalit\u00e9 d\u00e9mographique (la tr\u00e8s forte pouss\u00e9e de la minorit\u00e9 hispanique, par l&rsquo;immigration, la f\u00e9condit\u00e9, le dynamisme social et religieux, l&rsquo;unit\u00e9 culturelle sp\u00e9cifique et la conservation de la langue) fait de la minorit\u00e9 hispanique l&rsquo;acteur central des \u00c9tats-Unis durant le XXIe si\u00e8cle ; et vus les liens maintenus et constamment renforc\u00e9s de cette minorit\u00e9 avec son pays d&rsquo;origine, c&rsquo;est en fait le Mexique qui va devenir l&rsquo;acteur central de la politique int\u00e9rieure US au XXIe si\u00e8cle. Ainsi peut-on comprendre la raison de l&rsquo;assurance de Vicente Fox lors de sa visite \u00e0Washington.<\/p>\n<h3>Un livre qui pourrait desserrer l&rsquo;\u00e9tau de l&rsquo;inquisition intellectuelle en France <\/h3>\n<\/p>\n<p><p>\tUn livre \u00e0 para\u00eetre le 20 septembre doit constituer un apport important, voire d\u00e9cisif, dans un d\u00e9bat qui d\u00e9chire la France depuis plusieurs ann\u00e9es et paralyse sa propre perception d&rsquo;elle-m\u00eame. Il s&rsquo;agit de <em>La R\u00e9publique x\u00e9nophobe<\/em>, de Pierre-Jean Deschodt et de Fran\u00e7ois Hughenin (J.C. Latt\u00e8s), livre dont <em>Le Figaro<\/em> du 5 septembre donne une <a href=\"http:\/\/www.lefigaro.fr\/cgi-bin\/gx.cgi\/AppLogic+FTContentServer?pa gename=FutureTense\/Apps\/Xcelerate\/View&#038;c=figArticle&#038;cid=FIG5RKUN9RC&#038;liv e=true&#038;Site=true&#038;gCurChannel=ZZZJTGN6J7C&#038;gCurRubrique=&#038;gCurSubRubrique= \" class=\"gen\">longue analyse.<\/a> L&rsquo;importance de ce livre est qu&rsquo;il tend \u00e0 d\u00e9truire compl\u00e8tement un mythe qui avait \u00e9t\u00e9 \u00e9difi\u00e9 ces derni\u00e8res ann\u00e9es, parce qu&rsquo;il constituait un contre-point n\u00e9cessaire \u00e0 l&rsquo;image de diabolisation de la p\u00e9riode vichyssoise qui a \u00e9t\u00e9 donn\u00e9e aux Fran\u00e7ais durant la m\u00eame p\u00e9riode. La condamnation radicale de Vichy, quasiment class\u00e9 comme une \u00e9quivalence de l&rsquo;Allemagne nazie en marge des affaires Bousquet, Papon, etc, impliquait de fa\u00e7on imp\u00e9rative que la IIIe R\u00e9publique qui l&rsquo;avait pr\u00e9c\u00e9d\u00e9, la <em>\u00ab R\u00e9publique des professeurs<\/em> \u00bb ch\u00e8re \u00e0 la gauche lib\u00e9rale et intellectuelle fran\u00e7aise, appar\u00fbt en contre-point comme une r\u00e9f\u00e9rence de vertu r\u00e9publicaine. Si cette R\u00e9publique pouvait \u00eatre accus\u00e9e d&rsquo;avoir \u00e9t\u00e9 impr\u00e9voyante face \u00e0 la mont\u00e9e de l&rsquo;Allemagne nazie (c&rsquo;est d&rsquo;elle que d\u00e9pendit l&rsquo;impr\u00e9paration fran\u00e7aise \u00e0 la guerre), il importait qu&rsquo;elle f\u00fbt id\u00e9ologiquement vertueuse, sans la moindre compromission possible, pour que se marqu\u00e2t de fa\u00e7on d\u00e9cisive la diff\u00e9rence avec Vichy. Ce d\u00e9bat est loin d&rsquo;\u00eatre acad\u00e9mique : il avait et il a son importance au moment o\u00f9 la gauche fran\u00e7aise n&rsquo;a plus que l&rsquo;argument intellectuel de la vertu r\u00e9publicaine virtuelle, contre une droite fran\u00e7aise d&rsquo;ailleurs pareillement d\u00e9munie, avec une vertu patriotique \u00e9galement virtuelle. Nous qualifions ces arguments de \u00ab\u00a0virtuels\u00a0\u00bb, justement parce qu&rsquo;ils s&rsquo;appuient sur des r\u00e9f\u00e9rences historiques pol\u00e9miques, en g\u00e9n\u00e9ral manipul\u00e9s pour intervenir dans le d\u00e9bat politique actuel. L&rsquo;effroyable r\u00e9putation faite \u00e0 Vichy r\u00e9duisait \u00e0 peu de choses, non pas l&rsquo;argument de la vertu patriotique, mais la pr\u00e9tention de la droite classique fran\u00e7aise \u00e0 pouvoir l&rsquo;avancer ; de m\u00eame, cette effroyable r\u00e9putation constitue pour certains un handicap dans le d\u00e9veloppement de th\u00e8ses s&rsquo;appuyant sur le patriotisme (par exemple, certaines th\u00e8ses souverainistes anti-europ\u00e9ennes), parce que la r\u00e9f\u00e9rence vichyssoise est souvent assimil\u00e9e \u00e0 l&rsquo;attitude patriotique. (Toutes ces attitudes et positions peuvent \u00eatre jug\u00e9es excessives mais nous sommes dans le domaine de la pol\u00e9mique et seul compte l&rsquo;effet politique imm\u00e9diat.) <em>La R\u00e9publique des fiches<\/em> r\u00e9duit \u00e0 n\u00e9ant l&rsquo;argument de la vertu r\u00e9publicaine virtuelle de la gauche fran\u00e7aise contre le p\u00e9ch\u00e9 de la droite fran\u00e7aise avec Vichy. D&rsquo;apr\u00e8s les nombreux d\u00e9tails dont on comprend que <em>Le Figaro<\/em> ne soit pas avare, on voit que la IIIe R\u00e9publique \u00e9tablit, notamment \u00e0 partir de 1917, un impitoyable service de fichage des citoyens, particuli\u00e8rement des ci-devant marginaux et autres (la fiche de Cocteau vaut son pesant de dogmatisme anti-<em>gay<\/em>), et pr\u00e9cis\u00e9ment contre les immigrants de tout poil, mais particuli\u00e8rement ceux qui se disaient \u00ab <em>r\u00e9fugi\u00e9s politiques<\/em> \u00bb, et particuli\u00e8rement les juifs fuyant des r\u00e9gimes antis\u00e9mites des ann\u00e9es 1930, avec lesquels il \u00e9tait recommand\u00e9 d&rsquo;\u00eatre particuli\u00e8rement s\u00e9v\u00e8res. On trouve des textes de circulaires sign\u00e9s de ministres de gauche tels que Marx-Dormoy ou Chautemps, que pas un ministre fran\u00e7ais d&rsquo;aujourd&rsquo;hui, fut-il d&rsquo;une hypoth\u00e9tique extr\u00eame-droite, n&rsquo;oserait signer. La publication de ce livre est un \u00e9v\u00e9nement politique important dont on pourrait constater les effets sur l&rsquo;\u00e9volution g\u00e9n\u00e9rale des opinions, mais, surtout, sur le desserrement de l&rsquo;inquisition intellectuelle entretenue en France autour des positions dites nationales. <\/p>\n<h3>Une candidature int\u00e9rieure fran\u00e7aise qui est d&rsquo;abord un \u00e9v\u00e9nement international<\/h3>\n<\/p>\n<p><p>\tLa candidature de Jean-Pierre Chev\u00e9nement \u00e0 la pr\u00e9sidence de la R\u00e9publique, annonc\u00e9e le 5 septembre \u00e0 Belfort, ouvre une p\u00e9riode nouvelle et certainement tr\u00e8s int\u00e9ressante dans la vie politique fran\u00e7aise. <a href=\"http:\/\/www.lemonde.fr\/rech_art\/0,5987,219178,00.html\" class=\"gen\">Cette candidature a \u00e9t\u00e9 pr\u00e9sent\u00e9e<\/a> comme un \u00e9v\u00e9nement politique de premi\u00e8re importance, de fa\u00e7on tr\u00e8s g\u00e9n\u00e9rale, toutes opinions confondues. Elle l&rsquo;est effectivement, et dans une dimension nouvelle et int\u00e9ressante pour une \u00e9lection pr\u00e9sidentielle fran\u00e7aise, qui n&rsquo;a rien \u00e0 voir avec les chiffres de sondages des intentions de vote (tant il est implicitement admis que ces chiffres pourraient varier de fa\u00e7on radicale selon l&rsquo;\u00e9volution de la campagne). Autant les candidatures Chirac et Jospin sont des \u00e9v\u00e9nements int\u00e9rieurs, sans r\u00e9elle importance ext\u00e9rieure et g\u00e9n\u00e9rale, autant les candidatures contestatrices comme celles de l&rsquo;extr\u00eame-droite (Le Pen) \u00e9taient \u00e9galement des \u00e9v\u00e9nements int\u00e9rieurs puisqu&rsquo;elles se contentaient de contester le monopole de la politique int\u00e9rieure par les deux grands partis (droite et gauche), &mdash; autant la candidature Chev\u00e9nement a, au contraire, une importance ext\u00e9rieure et g\u00e9n\u00e9rale \u00e9vidente. Il s&rsquo;agit d&rsquo;un \u00e9v\u00e9nement qui d\u00e9passe le seul cadre restreint, et d&rsquo;une m\u00e9diocrit\u00e9 sans \u00e9gale ces derni\u00e8res ann\u00e9es, du d\u00e9bat politique int\u00e9rieur fran\u00e7ais. Toute la question est de savoir si la campagne du candidat Chev\u00e9nement r\u00e9ussira \u00e0 faire comprendre cette nouveaut\u00e9 dans la politique fran\u00e7aise, si d&rsquo;ailleurs elle en est elle-m\u00eame convaincue. Si elle parvient effectivement \u00e0 d\u00e9passer le cadre qu&rsquo;on tentera de lui imposer et qu&rsquo;elle pourrait \u00eatre tent\u00e9e d&rsquo;accepter, le caract\u00e8re m\u00e9diocre et st\u00e9rile des candidatures Chirac et Jospin sera mis en pleine lumi\u00e8re. D&rsquo;importantes surprises deviennent possibles car il devient alors acceptable de dire que la candidature Chev\u00e9nement est effectivement un \u00e9v\u00e9nement qui n&rsquo;a pas de pr\u00e9c\u00e9dent dans les deux ou trois derni\u00e8res d\u00e9cennies en France, et qui n&rsquo;a pas (encore ?) d&rsquo;\u00e9quivalent aujourd&rsquo;hui dans le monde. Chev\u00e9nement est en effet le premier homme politique d&rsquo;envergure et \u00e0 l\u00e9gitimit\u00e9 nationale (d\u00e9put\u00e9, maire, plusieurs fois ministres, chef d&rsquo;un parti participant au gouvernement) \u00e0 vouloir porter sur la sc\u00e8ne nationale le seul vrai d\u00e9bat qui compte aujourd&rsquo;hui, et qui est soigneusement \u00e9cart\u00e9 par des candidats tout entier acquis aux archa\u00efsmes droite-gauche. Ce d\u00e9bat est celui de le globalisation, de la forme que doit prendre l&rsquo;Europe, de la politique vis-\u00e0-vis de l&rsquo;h\u00e9g\u00e9monie am\u00e9ricaine, de la politique vis-\u00e0-vis des questions sociales d\u00e9structurantes (immigration, s\u00e9curit\u00e9, etc), de la mont\u00e9e de l&rsquo;individualisme ; c&rsquo;est-\u00e0-dire, d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, le d\u00e9bat sur l&rsquo;affrontement g\u00e9n\u00e9ral entre les forces structurantes et les forces d\u00e9structurantes, qui est le point central de la crise de civilisation dans laquelle nous sommes plong\u00e9s. La t\u00e2che prioritaire de Chev\u00e9nement devrait \u00eatre d&rsquo;\u00e9lever un d\u00e9bat qui en reste aux assauts d\u00e9magogiques port\u00e9s par des candidats qui sont comptables d&rsquo;une m\u00eame politique, qui est la politique d&rsquo;un syst\u00e8me \u00e9touffant et sans la moindre perspective, et qui se bat quasi-exclusivement sur le refus absolu d&rsquo;aborder les v\u00e9ritables probl\u00e8mes. Tactiquement, Chev\u00e9nement devrait chercher \u00e0 \u00e9viter les attaques personnelles et s&rsquo;attacher plut\u00f4t \u00e0 montrer combien le d\u00e9bat politique int\u00e9rieur et le syst\u00e8me qui le favorise sont d\u00e9pass\u00e9s, inadapt\u00e9s, totalement r\u00e9duits \u00e0 la simple survivance des aspects les plus d\u00e9testables de la pratique politique moderne.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les USA face au Mexique et le Mexique dans les USA La visite de Vicente Fox aux USA, \u00e0 Washington la semaine derni\u00e8re, a \u00e9t\u00e9 un \u00e9v\u00e9nement. Le pr\u00e9sident mexicain n&rsquo;a pas cach\u00e9 ses intentions alors qu&rsquo;on attendait qu&rsquo;il se montre beaucoup plus r\u00e9serv\u00e9 : Fox a demand\u00e9 un accord \u00ab d&rsquo;ici No\u00ebl \u00bb sur&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[7],"tags":[],"class_list":["post-64991","post","type-post","status-publish","format-standard","hentry","category-journal"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/64991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=64991"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/64991\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=64991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=64991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=64991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}