{"id":65006,"date":"2001-12-16T00:00:00","date_gmt":"2001-12-16T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2001\/12\/16\/semaine-du-10-decembre-au-16-decembre-2001\/"},"modified":"2001-12-16T00:00:00","modified_gmt":"2001-12-16T00:00:00","slug":"semaine-du-10-decembre-au-16-decembre-2001","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2001\/12\/16\/semaine-du-10-decembre-au-16-decembre-2001\/","title":{"rendered":"Semaine du 10 d\u00e9cembre au 16 d\u00e9cembre 2001"},"content":{"rendered":"<p><h3>\u00ab <strong><em>T&rsquo;was a famous victory<\/em><\/strong> \u00bb, d&rsquo;accord, mais qui, r\u00e9ellement, est le vainqueur ?<\/h3>\n<\/p>\n<p><p>\tLe bastion d&rsquo;Al Qa\u00efda est tomb\u00e9, le massif de Tora Bora o\u00f9 devait se trouver le fameux Ben Laden dont le secr\u00e9taire \u00e0 la d\u00e9fense Rumsfeld annon\u00e7ait il y a peu la capture imminente ou la liquidation (avec une pr\u00e9f\u00e9rence pour la deuxi\u00e8me formule). Pour l&rsquo;instant, Rumsfeld philosophe sur la difficult\u00e9 des temps et de la topographie afghane. (O\u00f9 est Ben Laden ? Mort dans la bataille de Tora Bora, disent les Pakistanais qui n&rsquo;ont qu&rsquo;un d\u00e9sir, que personne, et surtout pas les Am\u00e9ricains, n&rsquo;aille conclure que Ben Laden se trouve au Pakistan. D&rsquo;autres sources disent : Ben Laden est vivant dans la r\u00e9gion de Tora Bora et on ne l&rsquo;a pas encore retrouv\u00e9 ; d&rsquo;autres encore : il a fui Tora Bora mais il est toujours en Afghanistan ; et encore : il a quitt\u00e9 l&rsquo;Afghanistan, il est au Pakistan, ou en Iran, etc &#8230; Du point de vue des relations publiques qui est essentiel, l&rsquo;affaire du sort de Ben Laden est un probl\u00e8me pour Washington. Le public am\u00e9ricain ne l&rsquo;entend pas de cette oreille. Il veut Ben Laden ou, \u00e0 d\u00e9faut, une preuve de sa mort. Le sort de Ben Laden, c&rsquo;est un s\u00e9rieux probl\u00e8me, non pour la guerre contre le terrorisme qui est importante mais qui n&rsquo;est pas vraiment l&rsquo;essentiel comme chacun sait, mais pour le montage virtualiste de Washington, qui est l&rsquo;essentiel.)<\/p>\n<\/p>\n<p><p>\tCe qu&rsquo;il faut avoir \u00e0 l&rsquo;esprit par ailleurs, c&rsquo;est l&rsquo;\u00e9tonnante description des restes de la bataille de Tora Bora, une fois la victoire acquise, &mdash; mais on ne sait pas exactement par qui, en fait, et c&rsquo;est l\u00e0 tout le sel de l&rsquo;affaire. Ainsi, cet article bien significatif de <a href=\"http:\/\/www.thetimes.co.uk\/article\/0,,2001570014-2001592711,00 .html\" class=\"gen\">Janine Di Giovanni, dans The Times du 22 d\u00e9cembre<\/a>. Rarement texte aura si bien rendu la confusion, l&rsquo;incertitude, l&rsquo;impr\u00e9cision, le sens du pi\u00e8ge, du th\u00e9\u00e2tre, du montage, de la dissimulation, qui ont caract\u00e9ris\u00e9 de bout en bout cette guerre d&rsquo;Afghanistan. Les Afghans ne s&rsquo;y sont pas montr\u00e9s moins bons que les Am\u00e9ricains, pourtant fortiches en la mati\u00e8re ; ces farouches guerriers au maintien altier, les meilleurs cavaliers du monde comme l&rsquo;\u00e9crivait Kessel, les Afghans, sont aussi des ma\u00eetres de l&rsquo;intrigue orientale, du double discours, des manoeuvres de palais et de la relativit\u00e9 des alliances de guerre. La \u00ab\u00a0bataille de Tora Bora\u00a0\u00bb a \u00e9t\u00e9 un impressionnant exercice en d\u00e9sinformation, notamment de la part des d\u00e9tachements afghans de l&rsquo;Alliance et des divers tribus patchounes.<\/p>\n<\/p>\n<p><p>\tPar ailleurs, attaquer la veille de l&rsquo;inauguration du nouveau gouvernement, celui de la transition d\u00e9mocratique et de la communaut\u00e9 internationale, un convoi de pr\u00e9tendus dirigeants talibans en fuite qui s&rsquo;av\u00e8rent \u00eatre des dignitaires afghans tr\u00e8s comme il faut qui se rendaient \u00e0 Kaboul pour la c\u00e9r\u00e9monie, en laisser autour de 65 au tapis apr\u00e8s des \u00e9tapes a\u00e9riennes r\u00e9p\u00e9t\u00e9es et d&rsquo;une cruaut\u00e9 rare, voil\u00e0 qui serait un acte marquant et une bavure significative de la machine de guerre am\u00e9ricaine. En effet, et selon toutes les indications rassembl\u00e9es en quelques jours, il semble bien que <a href=\" http:\/\/asia.cnn.com\/2001\/WORLD\/asiapcf\/central\/12\/22\/ret.afghan.str ikes.convoy\/index.html\" class=\"gen\">l&rsquo;attaque du 21 d\u00e9cembre soit une s\u00e9rieuse bavure<\/a> des Am\u00e9ricains. Les r\u00e9actions am\u00e9ricaines face \u00e0l&rsquo;\u00e9vidence qui semble de plus en plus affirm\u00e9e sont parfois inattendues. Le Los Angeles <em>Times<\/em> du 23 d\u00e9cembre 2001 \u00e9crit : \u00ab <em>Gen. Tommy Franks, commander of U.S. forces in Afghanistan, who was [in Kabul] for the inauguration, insisted that the airstrike was directed at \u00a0\u00bba good target.\u00a0\u00bb But Franks said an investigation will be conducted to determine whether the attack might have been an unfortunate incident of \u00a0\u00bbfriendly fire\u00a0\u00bb.<\/em> \u00bb En d&rsquo;autres termes, c&rsquo;est-\u00e0-dire en termes tr\u00e8s bureaucratiques : le g\u00e9n\u00e9ral Franks confirme que le convoi \u00e9tait un \u00ab <em>bon objectif<\/em> \u00bb, cela reste s\u00fbr et assur\u00e9, mais qu&rsquo;on va faire une enqu\u00eate pour voir si, dans ce \u00ab <em>bon objectif<\/em> \u00bb ne se trouvaient pas des gens qui ne devaient pas s&rsquo;y trouver.<\/p>\n<h3>Le <strong><em>Boeing deal<\/em><\/strong>, ou l&rsquo;art de subventionner vertueusement, &mdash; mais, cette fois, de fa\u00e7on peut-\u00eatre un peu grossi\u00e8re &#8230;<\/h3>\n<\/p>\n<p><p>\tUne initiative du Congr\u00e8s US de rajouter au budget de la d\u00e9fense 2002 un \u00e9norme plan de leasing de 100 Boeing 767 transform\u00e9s en ravitailleurs en vol pour l&rsquo;US Air Force, et lou\u00e9s pour 10 ans \u00e0 un prix extraordinairement \u00e9lev\u00e9, soul\u00e8ve quelque \u00e9motion. Aux \u00c9tats-Unis, ce plan a suscit\u00e9 un rassemblement d&rsquo;associations de d\u00e9fense des consommateurs <a href=\"http:\/\/commondreams.org\/news2001\/1220-02.htm\" class=\"gen\">de droite et de gauche, men\u00e9 par Ralph Nader<\/a>. Il semble, d&rsquo;apr\u00e8s ce que rapporte l&rsquo;hebdomadaire <em>Defense News<\/em>, que m\u00eame des parlementaires sont assez mal \u00e0 l&rsquo;aise avec le plan, qui a \u00e9t\u00e9 rajout\u00e9 au budget de la d\u00e9fense par la commission inter-parlementaire S\u00e9nat-Chambre charg\u00e9e de finaliser le budget et de le pr\u00e9senter au vote en s\u00e9ance pl\u00e9ni\u00e8re. Les d\u00e9tails de ce plan sont compl\u00e8tement inhabituels et dissimulent difficilement son but \u00e9vident, qui est de subventionner Boeing qui n&rsquo;est pas au mieux de sa forme avec la crise du transport a\u00e9rien.<\/p>\n<\/p>\n<p><p>\tLes d\u00e9tails sont les suivants, selon l&rsquo;appr\u00e9ciation de cette coalition d&rsquo;associations am\u00e9ricaines de gauche et de droite : \u00ab <em>Under the Boeing lease provision, the Air Force will lease 100 Boeing 767s for use as tankers, at a pricetag of $20 million per plane per year, over a 10-year period. This $20 billion expenditure is far higher than the cost of direct purchase. The government will accrue extra expenses because it will be obligated not only to convert the commercial aircraft to military configurations; when the 10-year lease is over, it will be required to convert them back to commercial format, at an estimated cost of $30 million apiece. The cost of the lease plan may be as much as five times higher than an outright purchase would be. A last-minute amendment would also have the Air Force lease four 737s to shuttle Defense Department officials and potentially congressional leaders.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;\u00e9normit\u00e9 du march\u00e9, et surtout son caract\u00e8re affirm\u00e9 de subvention d\u00e9guis\u00e9e, rend possible qu&rsquo;une s\u00e9rieuse contestation se d\u00e9veloppe. Cela est d&rsquo;autant plus possible que cette d\u00e9cision de fournir des ravitailleurs en vol \u00e0 l&rsquo;USAF ne r\u00e9pond \u00e0 aucun besoin imm\u00e9diat, aucune sp\u00e9cification, et que l&rsquo;USAF, tout comme les autres services, n&rsquo;aime gu\u00e8re qu&rsquo;on lui impose des programmes. (Le d\u00e9partement du Budget de l&rsquo;administration a d&rsquo;ores et d\u00e9j\u00e0 signifi\u00e9 son d\u00e9saccord pour cette mesure d\u00e9cid\u00e9e par la commission S\u00e9nat-Chambre.) Quoiqu&rsquo;il en soit, l&rsquo;\u00e9limination de ce plan, ou son amendement, reste hypoth\u00e9tique dans la mesure o\u00f9 le budget 2002 se trouve \u00e0 un stade tr\u00e8s avanc\u00e9, presque finalis\u00e9 ; il faudrait par exemple qu&rsquo;un amendement le supprimant dans le budget DoD soit pr\u00e9sent\u00e9 par des parlementaires et vot\u00e9 (outre l&rsquo;hypoth\u00e8se du refus global du budget DoD lors du vote en s\u00e9ance pl\u00e9ni\u00e8re). Dans tous les cas, et quoiqu&rsquo;il en soit de son issue, l&rsquo;\u00e9pisode montre surtout l&rsquo;\u00e9tat d&rsquo;esprit r\u00e9gnant aujourd&rsquo;hui \u00e0 Washington pour ce qui concerne les r\u00e8gles des subventions \u00e0 l&rsquo;industrie, qui font l&rsquo;objet d&rsquo;accords internationaux. D&rsquo;ores et d\u00e9j\u00e0, les Europ\u00e9ens, et particuli\u00e8rement la Commission europ\u00e9enne, suivent cette affaire avec attention. Si la mesure \u00e9tait finalement adopt\u00e9e, il y aurait sans aucun doute une forte r\u00e9action de la Commission, dans la mesure o\u00f9 celle-ci consid\u00e9rerait probablement qu&rsquo;il y a l\u00e0 une violation de l&rsquo;accord sur les subventions des compagnies a\u00e9rospatiales. (Boeing \u00e9tant \u00e9videmment le concurrent direct d&rsquo;Airbus.)   <\/p>\n<h3>Jean-Marie Messier (J6M) ou le sens bien fran\u00e7ais du \u00ab\u00a0parti de l&rsquo;\u00e9tranger\u00a0\u00bb<\/h3>\n<\/p>\n<p><p>\tCette semaine, Jean-Marie Messier, dit J6M (pour \u00ab <em>Jean-Marie Messier Moi-M\u00eame Ma\u00eetre du Monde<\/em> \u00bb), a beaucoup fait parler de lui \u00e0 Paris, &mdash; alors qu&rsquo;on ne l&rsquo;y voit plus gu\u00e8re puisqu&rsquo;il habite d\u00e9sormais New York. Ce fut d&rsquo;abord une d\u00e9claration, le 17 d\u00e9cembre, selon laquelle \u00ab <em>l&rsquo;exception culturelle fran\u00e7aise est morte<\/em> \u00bb, ce qui s&rsquo;adresse bien entendu \u00e0 la France, mais encore plus \u00e0 l&rsquo;Am\u00e9rique et aux actionnaires de Vivendi. La presse fran\u00e7aise rapporta la d\u00e9claration, suivies des textes d&rsquo;analyse <a href=\"http:\/\/www.lemonde.fr\/article\/0,5987,3230--255564-,00.html\" class=\"gen\">av ec les commentaires grin\u00e7ants, ronchonnants ou \u00e0 l&rsquo;ironie sceptique qui sont d&rsquo;usage.<\/a> Cela signifie qu&rsquo;en g\u00e9n\u00e9ral, dans une presse qui semble tr\u00e8s souvent acquise \u00e0 l&rsquo;am\u00e9ricanisation mais qui passe aussit\u00f4t dans le commentaire inverse d\u00e8s que cette am\u00e9ricanisation se concr\u00e9tise, Messier n&rsquo;a pas eu bonne presse. D&rsquo;o\u00f9, dans les jours suivants, <a href=\"http:\/\/www.liberation.com\/quotidien\/semaine\/011220-080001001L IVR.html\" class=\"gen\">sa r\u00e9plique \u00e9videmment poussive<\/a> ax\u00e9e sur la d\u00e9nonciation, dans le plus pur style relation publique, d&rsquo;un \u00ab <em>faux-proc\u00e8s id\u00e9al<\/em> \u00bb.<\/p>\n<\/p>\n<p><p>\tTout cela est marginal. L&rsquo;essentiel est que, parti \u00e0 la conqu\u00eate du monde \u00e0 partir d&rsquo;une position \u00e0 100% favorable \u00e0\u00ab <em>l&rsquo;exception culturelle fran\u00e7aise<\/em> \u00bb (Canal +, quand Canal+ existait encore, c&rsquo;est-\u00e0-dire existant comme syst\u00e8me dynamique enti\u00e8rement en expansion pour soutenir la production cin\u00e9matographique fran\u00e7aise contre les pressions am\u00e9ricaines, dans le cadre des accords GATT de 1993), Messier-Vivendi aboutit dans son d\u00e9veloppement \u00e0 une philosophie inverse. C&rsquo;est dans la nature des choses. Ayant absorb\u00e9 l&rsquo;un ou l&rsquo;autre g\u00e9ant US (Seagrams, avec les studios Universal), Messier-Vivendi a choisi la voie qu&rsquo;il n&rsquo;a jamais abandonn\u00e9e vraiment tel qu&rsquo;on le conna\u00eet et telle qu&rsquo;on conna\u00eet sa carri\u00e8re, qui est celle de l&rsquo;appr\u00e9ciation prioritairement financi\u00e8re de ses affaires, de ses ambitions et de sa conception du monde. (On ne parle plus de comptabilit\u00e9, de profits, etc, mais bien d&rsquo;un point de vue conceptuel, philosophique.) Ayant choisi cette voie et recherchant \u00e0 atteindre la taille de g\u00e9ant mondial qui correspondait \u00e0 ses ambitions, Messier-Vivendi ne pouvait que s&rsquo;am\u00e9ricaniser car seul un cadre am\u00e9ricain permet cela dans cette vision du monde financi\u00e8re. C&rsquo;est ce qu&rsquo;il fait. Cela ne tuera pas le cin\u00e9ma fran\u00e7ais, qui continuera \u00e0 \u00eatre ce qu&rsquo;il est, c&rsquo;est-\u00e0-dire un ph\u00e9nom\u00e8ne culturel identitaire et non un ph\u00e9nom\u00e8ne financier globalis\u00e9 ; Canal+ s&rsquo;en d\u00e9sengagera peu \u00e0 peu (cela a \u00e9t\u00e9 annonc\u00e9 dans la foul\u00e9e des d\u00e9clarations de Messie) et le cin\u00e9ma fran\u00e7ais trouvera d&rsquo;autres syst\u00e8mes de financement.<\/p>\n<\/p>\n<p><p>\tMessier-Vivendi a suivi le cheminement typique de la globalisation. Il nous a apport\u00e9 une preuve de plus, si besoin en est, que la globalisation ne peut \u00eatre que l&rsquo;am\u00e9ricanisation. Messier-Vivendi ne s&rsquo;est pas conduit en mauvais Fran\u00e7ais, il s&rsquo;est conduit comme ces Fran\u00e7ais qui, de tous les temps, pr\u00e9f\u00e8rent le \u00ab\u00a0parti de l&rsquo;\u00e9tranger\u00a0\u00bb (toujours tr\u00e8s actif en France) \u00e0 celui de la France parce qu&rsquo;ils consid\u00e8rent, outre l&rsquo;appr\u00e9ciation personnelle de leurs int\u00e9r\u00eats, que la France ne peut vraiment \u00eatre elle-m\u00eame qu&rsquo;en ne l&rsquo;\u00e9tant plus tout \u00e0 fait, en choisissant la voie de l&rsquo;universalisation contre la voie de l&rsquo;identit\u00e9 nationale. Il faut malheureusement constater qu&rsquo;en d&rsquo;autres temps, dans tous les cas dans certaines \u00e9poques bien particuli\u00e8res, ce comportement fut condamn\u00e9, peut-\u00eatre injustement, comme une \u00ab\u00a0collaboration\u00a0\u00bb. Comme on le constate, tous ces termes sont relatifs aux situations.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab T&rsquo;was a famous victory \u00bb, d&rsquo;accord, mais qui, r\u00e9ellement, est le vainqueur ? Le bastion d&rsquo;Al Qa\u00efda est tomb\u00e9, le massif de Tora Bora o\u00f9 devait se trouver le fameux Ben Laden dont le secr\u00e9taire \u00e0 la d\u00e9fense Rumsfeld annon\u00e7ait il y a peu la capture imminente ou la liquidation (avec une pr\u00e9f\u00e9rence pour&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[7],"tags":[],"class_list":["post-65006","post","type-post","status-publish","format-standard","hentry","category-journal"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65006"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65006\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}