{"id":65016,"date":"2002-03-03T00:00:00","date_gmt":"2002-03-03T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2002\/03\/03\/semaine-du-25-fevrier-au-3-mars-2002\/"},"modified":"2002-03-03T00:00:00","modified_gmt":"2002-03-03T00:00:00","slug":"semaine-du-25-fevrier-au-3-mars-2002","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2002\/03\/03\/semaine-du-25-fevrier-au-3-mars-2002\/","title":{"rendered":"Semaine du 25 f\u00e9vrier au 3 mars 2002"},"content":{"rendered":"<p><h3>La subtile politique de Blair n&rsquo;est-elle pas en train de se transformer en calvaire de Tony Blair ? <\/h3>\n<\/p>\n<p><p>\tTony Blair va-t-il soutenir l&rsquo;attaque am\u00e9ricaine probable contre l&rsquo;Irak ? Cela se dit, cela se r\u00e9p\u00e8te, cela s&rsquo;annonce m\u00eame, avant la visite \u00e0 Washington de Blair, en avril prochain. Surtout, cela s&rsquo;\u00e9value et se p\u00e8se, avec principalement <a href=\"http:\/\/www.guardian.co.uk\/Archive\/Article\/0,4273,43639 36,00.html\" class=\"gen\">les cons\u00e9quences sur le parti travaillistes<\/a>, pr\u00e9vues comme apocalyptiques et pouvant mener \u00e0 une grave crise int\u00e9rieure. Certes, les pr\u00e9visions \u00e0 cet \u00e9gard ont la plupart du temps \u00e9t\u00e9 d\u00e9menties, soit compl\u00e8tement, soit en partie, mais elles sont dans ce cas assez impressionnantes, lorsqu&rsquo;on d\u00e9taille le r\u00e9sultats d&rsquo;interviews faits avec les parlementaires travaillistes, tels que les rapporte Jackie Ashley, du <em>Guardian<\/em> :<\/p>\n<\/p>\n<p><p>\t\u00ab <em>I have been talking to middle-of-the-road, loyalist MPs; to ministers; and to leading Liberal Democrats. All are speculating that for Mr Blair to back President Bush in this, he may end up having to rely on the payroll vote and the Tories against a large proportion of his own backbenches. How large a proportion? Well, a BBC poll for On the Record of a hundred Labour backbenchers found just eight in favour of attacking Iraq, and 86 firmly against.<\/em> \u00bb <\/p>\n<\/p>\n<p><p>\tEncore une fois, de telles indications n&rsquo;ont rien de ferme ni de d\u00e9finitif. L&rsquo;influence de Tony Blair sur les parlementaires, et sur le parti lui-m\u00eame, est puissante, et les opinions changent ais\u00e9ment. Le probl\u00e8me principal est, non seulement que l&rsquo;opposition est tr\u00e8s puissante mais, surtout, que la cause est tr\u00e8s difficile \u00e0 d\u00e9fendre (\u00e0 \u00ab\u00a0vendre\u00a0\u00bb). A la limite de l&rsquo;argumentation, on dirait qu&rsquo;il appara\u00eet  certain que beaucoup, \u00e0 l&rsquo;int\u00e9rieur du gouvernement britannique, s&rsquo;interrogent tr\u00e8s s\u00e9rieusement sur l&rsquo;int\u00e9r\u00eat de \u00ab\u00a0vendre\u00a0\u00bb cette cause, c&rsquo;est-\u00e0-dire que le probl\u00e8me de la politique britannique actuelle est pos\u00e9e au sein du gouvernement britannique lui-m\u00eame.<\/p>\n<\/p>\n<p><p>\tIl est compl\u00e8tement \u00e9vident que le gouvernement britannique, particuli\u00e8rement bien inform\u00e9 en la mati\u00e8re par une bureaucratie de s\u00e9curit\u00e9 nationale qui a une longue exp\u00e9rience des \u00c9tats-Unis, est aujourd&rsquo;hui extr\u00eamement inquiet du d\u00e9veloppement de la situation dans ce pays. Au-del\u00e0 m\u00eame de la politique am\u00e9ricaine, c&rsquo;est la transformation des structures et des comportements qui constitue la cause de ces inqui\u00e9tudes. Deux \u00e9v\u00e9nements r\u00e9cents ont fait avancer l&rsquo;appr\u00e9ciation \u00e0 cet \u00e9gard, dans un sens tr\u00e8s pessimiste : les p\u00e9rip\u00e9ties autour de <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=171\" class=\"gen\">la cr\u00e9ation de l&rsquo;Office of Strategic Influence,<\/a>, puis de son abandon, qui montrent dans tous les cas la d\u00e9termination du gouvernement am\u00e9ricain de d\u00e9velopper et de pratiquer structurellement une politique de d\u00e9sinformation ; les p\u00e9rip\u00e9ties, \u00e9galement, autour du mode de fonctionnement du gouvernement am\u00e9ricain, qui fonctionne d\u00e9sormais, par roulement, dans une structure de guerre, ce qu&rsquo;on nomme le <em>shadow government<\/em>, et qui a \u00e9t\u00e9 mis en place sans le moindre contr\u00f4le parlementaire. Le s\u00e9nateur Daschle, leader de la majorit\u00e9 d\u00e9mocrate au S\u00e9nat, a effectivement confirm\u00e9 cette situation le 3 mars (Selon l&rsquo;agence AP : \u00ab <em>Senate Majority Leader Tom Daschle, a Democrat, said Sunday he wants Bush to keep congressional leaders better informed about the war on terrorism and the shadow government. He said no lawmakers knew about the continuity of government plan.<\/em> \u00bb) Le probl\u00e8me qui appara\u00eet avec ces diverses p\u00e9rip\u00e9ties pose la question de savoir quelle est l&rsquo;intention des dirigeants am\u00e9ricains en mati\u00e8re de structure de gouvernement, notamment autour de la question de savoir si un gouvernement doit rester compl\u00e8tement d\u00e9mocratique ou pas. Et, certes, cette question domine toutes les autres, notamment celle de la politique ext\u00e9rieure et de s\u00e9curit\u00e9 nationale d&rsquo;un tel gouvernement.<\/p>\n<\/p>\n<p><p>\tOn conna\u00eet la politique de Tony Blair, surnomm\u00e9e la politique \u00ab\u00a0du grand \u00e9cart\u00a0\u00bb, entre l&rsquo;Europe et les \u00c9tats-Unis, \u00e0 la fois engag\u00e9 en Europe, et tr\u00e8s activement, et conservant des liens privil\u00e9gi\u00e9s avec les USA. Cette politique a l&rsquo;apparence de l&rsquo;habilet\u00e9 m\u00eame s&rsquo;il est \u00e9vident qu&rsquo;elle doive devenir de plus en plus difficile \u00e0 conduire entre des politiques qui peuvent\/semblent diff\u00e9rer de plus en plus, voire, qui sont susceptibles de s&rsquo;opposer. La question devient encore plus grave lorsque l&rsquo;\u00e9volution int\u00e9rieure d&rsquo;un des deux piliers de cette politique, en l&rsquo;occurrence les \u00c9tats-Unis, prend l&rsquo;orientation qu&rsquo;on lui va prendre. Le probl\u00e8me ponctuel de l&rsquo;Irak est alors d\u00e9pass\u00e9, ainsi, m\u00eame, que le probl\u00e8me du soutien du parti travailliste, l&rsquo;un et l&rsquo;autre ne servant qu&rsquo;\u00e0 mettre en \u00e9vidence quelque chose de bien plus s\u00e9rieux. On arrive au coeur d&rsquo;un probl\u00e8me strat\u00e9gique fondamental. Il se pose \u00e0 tous les pays occidentaux, particuli\u00e8rement les pays europ\u00e9ens, mais il ne se pose pas en des termes plus graves et plus pressants que dans le cas du Royaume Uni. <\/p>\n<h3>Avec V\u00e9drine et Patten, la critique de la politique am\u00e9ricaine n&rsquo;est pas seulement circonstancielle, elle est fondamentale<\/h3>\n<\/p>\n<p><p>\tLe ministre fran\u00e7ais des affaires \u00e9trang\u00e8res Hubert V\u00e9drine a donn\u00e9 une interview \u00e0 <em>Lib\u00e9ration<\/em>, publi\u00e9e le 1er mars. <a href=\"http:\/\/www.liberation.fr\/quotidien\/semaine\/020301-01 001 0126MOND.html\" class=\"gen\">Le ministre fran\u00e7ais confirme de bout en bout sa d\u00e9claration du d\u00e9but f\u00e9vrier,<\/a> o\u00f9 il faisait une premi\u00e8re et s\u00e9v\u00e8re critique de la politique am\u00e9ricaine. Il explicite cette d\u00e9claration en la portant sur le terrain de la substance, sur la question m\u00eame de la forme de la politique am\u00e9ricaine. Le m\u00eame sujet est r\u00e9guli\u00e8rement abord\u00e9 par le Commissaire europ\u00e9en Chris Patten (comme par exemple dans un discours de Patten, le 21 f\u00e9vrier \u00e0 Dublin, sur la question <a href=\"http:\/\/europa.eu.int\/comm\/external_relations\/news\/patten\/s p02_76.htm\" class=\"gen\">de la souverainet\u00e9 nationale et du multilat\u00e9ralisme<\/a>), \u00e9galement sur le fond, c&rsquo;est-\u00e0-dire sur la fa\u00e7on dont doivent fonctionner les relations internationales, &mdash; et l&rsquo;on comprend aussit\u00f4t que la fa\u00e7on plaid\u00e9e par Patten n&rsquo;est \u00e9videmment pas celle que suivent les \u00c9tats-Unis. Les deux hommes, V\u00e9drine et Patten, plaident pour une approche d&rsquo;une forme multipolaire de conduite des relations internationales, avec une collaboration active (multilat\u00e9ralisme), c&rsquo;est-\u00e0-dire la collaboration entre plusieurs centres de puissance (multipolarisme).<\/p>\n<\/p>\n<p><p>\tIl y a l\u00e0 une diff\u00e9rence de conceptions entre Europ\u00e9ens et Am\u00e9ricains, qui est plus que th\u00e9orique, qui est fondamentale et v\u00e9rifi\u00e9e jour apr\u00e8s jour, au gr\u00e9 des questions trait\u00e9es dans les relations internationales. Cette diff\u00e9rence de conceptions est quasiment existentielle pour les Europ\u00e9ens. L&rsquo;unilat\u00e9ralisme actuel des \u00c9tats-Unis, qui a comme corollaire la puissance consid\u00e9rable des \u00c9tats-Unis, donc l&rsquo;intervention arbitraire et incontestable des \u00c9tats-Unis dans toutes les affaires internationales qui comptent, implique la disparition des autres p\u00f4les de puissance en tant qu&rsquo;acteur disposant d&rsquo;une influence et du droit de participation \u00e0 la gestion de ces m\u00eames affaires. Il s&rsquo;agit de bien plus qu&rsquo;une simple consid\u00e9ration tactique, qu&rsquo;un simple choix de politique par rapport \u00e0 une circonstance ou l&rsquo;autre, par rapport \u00e0 une crise ou l&rsquo;autre. L&rsquo;unilat\u00e9ralisme am\u00e9ricain implique de facto la n\u00e9gation de l&rsquo;existence majeure de tous les autres acteurs internationaux. Jusqu&rsquo;ici, les Am\u00e9ricains ont affirm\u00e9 cette forme de \u00ab\u00a0politique\u00a0\u00bb principalement avec les moyens de leur puissance, essentiellement militaire, leur diplomatie suivant la m\u00eame voie en exploitant les situations cr\u00e9\u00e9es par cette puissance militaire. On comprend alors combien le probl\u00e8me pos\u00e9 aux Europ\u00e9ens est fondamental, et qu&rsquo;il s&rsquo;agit bien d&rsquo;un probl\u00e8me existentiel.<\/p>\n<\/p>\n<p><p>\tQue les deux hommes qui se montrent les plus critiques de la politique am\u00e9ricaine, et les plus critiques sur le fond et non pas selon les circonstances politiques, soient un Fran\u00e7ais et un Britannique (m\u00eame s&rsquo;il est Commissaire europ\u00e9en, Patten est d&rsquo;abord un Britannique), c&rsquo;est un fait qui r\u00e9sume bien la gravit\u00e9 du d\u00e9bat. Les Fran\u00e7ais, de fa\u00e7on ouverte, et les Britanniques, de fa\u00e7on plus indirecte, comprennent de plus en plus que leur existence en tant que puissance nationale est menac\u00e9e par la politique am\u00e9ricaine. Leur critique implique, de fa\u00e7on indirecte, qu&rsquo;il est n\u00e9cessaire que se d\u00e9veloppe une politique europ\u00e9enne ou, disons, des politiques nationales parall\u00e8les de pays europ\u00e9ens qui cr\u00e9ent de facto une politique europ\u00e9enne, pour mettre en question par le fait de son existence l&rsquo;orientation choisie par les Am\u00e9ricains. C&rsquo;est une fa\u00e7on de bien mettre en \u00e9vidence la r\u00e9alit\u00e9 des enjeux de la crise actuelle. Il n&rsquo;est pas n\u00e9cessaire de s&rsquo;appesantir sur ceci qu&rsquo;il semble bien s&rsquo;agir, sur le point pr\u00e9cis qu&rsquo;on envisage ici, d&rsquo;une crise transatlantique. Il s&rsquo;agit effectivement d&rsquo;une crise transatlantique, mais d&rsquo;un type in\u00e9dit. Jusqu&rsquo;ici, les crises transatlantiques portaient sur des mati\u00e8res sp\u00e9cifiques. Cette fois, la crise transatlantique actuelle porte sur la structure m\u00eame, la conception du fonctionnement des relations internationales.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La subtile politique de Blair n&rsquo;est-elle pas en train de se transformer en calvaire de Tony Blair ? Tony Blair va-t-il soutenir l&rsquo;attaque am\u00e9ricaine probable contre l&rsquo;Irak ? Cela se dit, cela se r\u00e9p\u00e8te, cela s&rsquo;annonce m\u00eame, avant la visite \u00e0 Washington de Blair, en avril prochain. Surtout, cela s&rsquo;\u00e9value et se p\u00e8se, avec principalement&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[7],"tags":[705,3232,3231],"class_list":["post-65016","post","type-post","status-publish","format-standard","hentry","category-journal","tag-blair","tag-patten","tag-vedrine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65016"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65016\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}