{"id":65056,"date":"2002-04-05T00:00:00","date_gmt":"2002-04-05T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2002\/04\/05\/les-labyrinthes-du-pentagone\/"},"modified":"2002-04-05T00:00:00","modified_gmt":"2002-04-05T00:00:00","slug":"les-labyrinthes-du-pentagone","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2002\/04\/05\/les-labyrinthes-du-pentagone\/","title":{"rendered":"<strong><em>Les labyrinthes du Pentagone<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Le Pentagone met en place ses labyrinthes pour s&rsquo;isoler toujours plus du reste du monde<\/h2>\n<\/p>\n<p><p>\tLe 5 Avril 2002. &mdash; Le <em>Financial Times<\/em> (FT) signale que le Pentagone (DoD) met en place un processus pour surveiller les acquisitions de soci\u00e9t\u00e9s US connect\u00e9es avec les questions de s\u00e9curit\u00e9 nationale. Le FT d\u00e9signe la structure qui sera charg\u00e9e de cette t\u00e2che de cette fa\u00e7on : \u00ab <em> the Committee on Foreign Investment in the US <\/em>[CFIUS], <em>an obscure interagency panel chaired by the Treasury Department and charged with ensuring foreign acquisitions do not violate US national security<\/em> \u00bb.<\/p>\n<\/p>\n<p><p>\tLe langage employ\u00e9 par le FT dans cette information traduit l&rsquo;agacement du journal, pourtant toujours bienveillant lorsqu&rsquo;il s&rsquo;agit d&rsquo;une nouvelle en provenance des USA. <\/p>\n<\/p>\n<p><p>\t&bull; La CFIUS examinera toute transaction portant sur une soci\u00e9t\u00e9 de plus de $100 millions de CA. Dans le domaine de la d\u00e9fense et des hautes technologies, cela signifie qu&rsquo;\u00e0 peu pr\u00e8s toutes les transactions seront soumises \u00e0 cette censure.<\/p>\n<\/p>\n<p><p>\t&bull; Le processus CFIUS, d\u00e9j\u00e0 discut\u00e9 l&rsquo;ann\u00e9e derni\u00e8re, a provoqu\u00e9 des remous dans les minist\u00e8res int\u00e9ress\u00e9s mais non consult\u00e9s par le DoD, qui m\u00e8ne cette affaire. Le FT cite un officiel US : \u00ab <em>This is incredibly ironic, when this is the type of overly broad merger review that the US has criticised the EU for,<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull; Le FT encore : \u00ab [b]<em>ut in addition to requiring reviews of all deals of more than $100m, the legislation would mandate CFIUS approval on deals where the US company has had any Defense Department contracts valued at more than $1m over the past three years. It would also force reviews of any deals involving foreign firms owned or controlled by a national government.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull; Cette l\u00e9gislation a toutes les chances d&rsquo;\u00eatre adopt\u00e9e et mise en place d\u00e8s cette ann\u00e9e. On a d\u00e9j\u00e0 eu un avant-go\u00fbt de la sorte d&rsquo;intervention qu&rsquo;elle pratiquera avec un incident, l&rsquo;ann\u00e9e derni\u00e8re. (Le FT : Le CFIUS \u00ab <em>held up Dutch group ASM Lithography&rsquo;s $1.2bn takeover of American technology company Silicon Valley Group. It led the Dutch foreign minister to warn of a \u00a0\u00bbblemish\u00a0\u00bb on US-Dutch relations, and ASM was forced to sell off SVG&rsquo;s highly prized optics division before completing the deal.<\/em> \u00bb)<\/p>\n<\/p>\n<p><p>\tLa nouvelle l\u00e9gislation compliquera de fa\u00e7on draconienne, et quasiment dissuasive, un processus d&rsquo;ores et d\u00e9j\u00e0 tr\u00e8s complexe. Elle fait partie de l&rsquo;effort g\u00e9n\u00e9ral des USA de repli sur soi et de contr\u00f4le de tous les flux \u00e9trangers, sp\u00e9cialement en mati\u00e8re de s\u00e9curit\u00e9 nationale, entrepris depuis le 11 septembre 2001. Dans le champ des technologies et de toutes les mati\u00e8res associ\u00e9es au domaine, extr\u00eamement large, de la s\u00e9curit\u00e9 nationale, il s&rsquo;agit de la poursuite de la mise en place d&rsquo;un v\u00e9ritable isolationnisme juridique, qui double et verrouille le protectionnisme naturel des USA. Tout effort de coop\u00e9ration avec l&rsquo;Europe, d\u00e9j\u00e0 extr\u00eamement limit\u00e9, se trouve compl\u00e8tement compromis.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Pentagone met en place ses labyrinthes pour s&rsquo;isoler toujours plus du reste du monde Le 5 Avril 2002. &mdash; Le Financial Times (FT) signale que le Pentagone (DoD) met en place un processus pour surveiller les acquisitions de soci\u00e9t\u00e9s US connect\u00e9es avec les questions de s\u00e9curit\u00e9 nationale. Le FT d\u00e9signe la structure qui sera&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3194,1097],"class_list":["post-65056","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-pentagone","tag-protectionnisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65056"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65056\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}