{"id":65061,"date":"2002-04-15T00:00:00","date_gmt":"2002-04-15T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2002\/04\/15\/chavez-nous-surprend\/"},"modified":"2002-04-15T00:00:00","modified_gmt":"2002-04-15T00:00:00","slug":"chavez-nous-surprend","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2002\/04\/15\/chavez-nous-surprend\/","title":{"rendered":"Chavez nous surprend"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955;font-size:2em;\">Chavez nous surprend<\/h2>\n<\/p>\n<p><p>15 avril 2002 &mdash; Le retour en fanfare du pr\u00e9sident Hugo Chavez du Venezuela, le 14 avril, montre que nous sommes dans une \u00e9poque compl\u00e8tement impr\u00e9visible, o&ugrave; la CIA n&rsquo;a plus la ma&icirc;trise d&rsquo;antan dans ses manipulations favorites, en Am\u00e9rique latine. Les divers soi-disant putschistes avaient mal mesur\u00e9 les difficult\u00e9s de l&rsquo;entreprise et la vigueur des r\u00e9actions populaires et des cadres moyens de l&rsquo;arm\u00e9e, autant que leurs propres dissensions. La m\u00e9canique populiste a fonctionn\u00e9 d&rsquo;une fa\u00e7on inattendue pour organiser une riposte pr\u00e9occupante pour les strat\u00e8ges US.<\/p>\n<\/p>\n<p><p>Les \u00e9v\u00e9nements au Venezuela du 12 au 15 avril ont largement montr\u00e9 le sentiment officiel am\u00e9ricain (satisfaction \u00e0 la chute de Chavez, d\u00e9pit avec son retour), que ce soit indirectement, par la presse qui relaie ce sentiment, ou directement par des d\u00e9clarations officielles.<\/p>\n<\/p>\n<p><p>&bull; Le 13 avril, le New York <em>Times<\/em> publiait un \u00e9ditorial o&ugrave; il \u00e9crivait notamment, \u00e0 propos du renversement de Chavez  : &laquo; <em>Venezuelan democracy is no longer threatened by a would-be dictator <\/em>[&hellip; because] <em>the military intervened and handed power to a respected business leader.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>&bull; Le 14 avril, Condoleeza Rice commentait ainsi le retour au pouvoir de Chavez, \u00e0 l&rsquo;\u00e9mission <em>Cross Fire<\/em>, sur la NBC  : &laquo; <em>We do hope that Chavez recognizes that the whole world is watching and that he takes advantage of this opportunity to right his own ship, which has been moving, frankly, in the wrong direction for quite a long time. <\/em>&lt;[&#8230;] <em>I hope that Hugo Chavez takes the message that his people sent him, that his own policies are not working for the Venezuela people, that he&rsquo;s dealt with him in a high-handed fashion.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Quoiqu&rsquo;il en soit des \u00e9v\u00e9nements \u00e0 venir, le retour du Chavez est un s\u00e9rieux revers pour les services divers US, qui \u00e9taient \u00e9videmment favorables aux putschistes, c&rsquo;est-\u00e0-dire les dirigeants de l&rsquo;arm\u00e9e et une partie du patronat. Les \u00e9v\u00e9nements indiquent que l&rsquo;op\u00e9ration \u00e9tait mal pr\u00e9par\u00e9e, que la pr\u00e9paration s&rsquo;\u00e9tait appuy\u00e9e sur des rapports erron\u00e9es quant aux r\u00e9actions populaires et militaires.<\/p>\n<\/p>\n<p><p>Cette zone du Venezuela, extr\u00eamement strat\u00e9gique \u00e0 cause du poids p\u00e9trolier de ce pays (quatri\u00e8me exportateur de p\u00e9trole du monde, troisi\u00e8me fournisseur des USA), devenue tr\u00e8s sensible avec la pr\u00e9sidence Chavez, populiste et anti-am\u00e9ricaine, devient une zone de crise grave. La proximit\u00e9 avec la Colombie, o&ugrave; une gu\u00e9rilla extr\u00eamement active et un engagement am\u00e9ricain anti-gu\u00e9rilla sont en cours, vont rapidement renforcer les pressions pour susciter une crise r\u00e9gionale grave. Les Am\u00e9ricains pr\u00e9voyaient que la chute de Chavez et son remplacement par un pouvoir sous contr\u00f4le permettraient de prendre la gu\u00e9rilla colombienne \u00e0 revers par une pression ext\u00e9rieure d\u00e9favorable. Ce plan est en \u00e9chec. Les Am\u00e9ricains pr\u00e9voyaient un engagement progressif en Colombie. Les \u00e9v\u00e9nements au Venezuela vont sans doute acc\u00e9l\u00e9rer ce mouvement, d&rsquo;une fa\u00e7on plus inconfortable et plus large que ce que pr\u00e9voyait le Pentagone<\/p>\n<\/p>\n<p><p>C&rsquo;est un nouveau front qui s&rsquo;ouvre, d&rsquo;une fa\u00e7on plus dramatique qu&rsquo;il n&rsquo;\u00e9tait pr\u00e9vu, et c&rsquo;est ainsi que vont le prendre les divers tendances du pouvoir washingtonien, surtout la droite r\u00e9publicaine, tr\u00e8s attentive \u00e0 distinguer dans les activit\u00e9s des chefs d&rsquo;&Eacute;tat sud-am\u00e9ricains des relents de communisme ou de castrisme des \u00e9poques pass\u00e9es (annon\u00e7ant la chute de Chavez le 13 avril, le site <em>Newsmax.com<\/em>, tr\u00e8s \u00e0 droite, le qualifiait de &laquo; <em>The Communist Chavez<\/em> &raquo;). Les r\u00e9actions \u00e0 Washington vont \u00eatre de deux ordres, qui sont les deux domaines qui comptent au niveau politique aujourd&rsquo;hui  :<\/p>\n<\/p>\n<p><p>&bull; La r\u00e9action psychologique. Il y a une exacerbation de la psychologie am\u00e9ricaine depuis le 11 septembre, avec une r\u00e9action obsessionnelle de s\u00e9curit\u00e9 et une affirmation de l&rsquo;<em>hubris<\/em> imp\u00e9rial. Le retour de Chavez va exacerber la perception d&rsquo;une menace et la perception d&rsquo;un d\u00e9fi \u00e0 la puissance am\u00e9ricaine. M\u00eame si Chavez veut suivre une politique de conciliation, comme il semble en avoir l&rsquo;intention ou y \u00eatre forc\u00e9, il semble logique d&rsquo;envisager qu&rsquo;il va \u00eatre soumis \u00e0 des actions de d\u00e9stabilisation et \u00e0 des pressions ext\u00e9rieures qui aggraveront encore une situation v\u00e9n\u00e9zuelienne int\u00e9rieure d\u00e9j\u00e0 tendue.<\/p>\n<\/p>\n<p><p>&bull; La r\u00e9action des groupes de pression, ceux qui pr\u00f4nent un engagement plus dur en Am\u00e9rique centrale (Colombie). Ces groupes vont d\u00e9sormais b\u00e9n\u00e9ficier de l&rsquo;impulsion de l&rsquo;atmosph\u00e8re de mobilisation g\u00e9n\u00e9rale \u00e0 Washington et vont \u00eatre beaucoup plus \u00e9cout\u00e9s.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chavez nous surprend 15 avril 2002 &mdash; Le retour en fanfare du pr\u00e9sident Hugo Chavez du Venezuela, le 14 avril, montre que nous sommes dans une \u00e9poque compl\u00e8tement impr\u00e9visible, o&ugrave; la CIA n&rsquo;a plus la ma&icirc;trise d&rsquo;antan dans ses manipulations favorites, en Am\u00e9rique latine. Les divers soi-disant putschistes avaient mal mesur\u00e9 les difficult\u00e9s de l&rsquo;entreprise&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3304,3306,3305],"class_list":["post-65061","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-chavez","tag-rice","tag-venezuela"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65061"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65061\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}