{"id":65062,"date":"2002-04-16T00:00:00","date_gmt":"2002-04-16T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2002\/04\/16\/expliquons-nous\/"},"modified":"2002-04-16T00:00:00","modified_gmt":"2002-04-16T00:00:00","slug":"expliquons-nous","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2002\/04\/16\/expliquons-nous\/","title":{"rendered":"<strong><em>Expliquons-nous<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Expliquons-nous<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t16 avril 2002 &mdash; Il est courant de constater la m\u00e9sentente grandissante, tr\u00e8s vite, aujourd&rsquo;hui et depuis le 11 septembre, entre l&rsquo;Europe et les USA. Il est rare de tenter de l&rsquo;expliquer ; tr\u00e8s rare en Europe, par crainte de panique de d\u00e9couvrir que le roi est nu (m\u00e9sentente irr\u00e9versible ou pas  ?)  ; disons, rare aux USA, souvent par ignorance, souvent par indiff\u00e9rence, parce que les USA sont plus que jamais repli\u00e9s sur eux-m\u00eames. Saluons donc Jim Hoagland qui a essay\u00e9 dans <a href=\" http:\/\/www.iht.com\/articles\/54685.html\" class=\"gen\">son dernier article du 15 avril.<\/a> Saluons et voyons rapidement ce qu&rsquo;il en est.<\/p>\n<\/p>\n<p><p>\t\u00ab <em>Atlantic Can Become a Chasm<\/em> \u00bb, nous avertit Hoagland. Il constate ce que nous observons, &mdash; cette m\u00e9sentente qui est la cons\u00e9quence d&rsquo;une diff\u00e9rence de plus en plus visible, qui est en fait une diff\u00e9rence qui appara\u00eet au grand jour. Hoagland s&rsquo;en tient au 11 septembre pour s&rsquo;en expliquer. (Nous pourrions, nous devrions pour notre part aller beaucoup plus loin dans l&rsquo;explication. Ici, dans ce commentaire tr\u00e8s court, nous nous en tenons l\u00e0.) <\/p>\n<\/p>\n<p><p>\tD&rsquo;abord, Hoagland fait le constat de cette diff\u00e9rence d&rsquo;attitude entre Europ\u00e9ens et Am\u00e9ricains, qui conduit \u00e0 la perception d&rsquo;une m\u00e9sentente grandissante, en m\u00eame temps que cette m\u00e9sentente s&rsquo;installe effectivement. Ce que Hoagland met en \u00e9vidence, c&rsquo;est l&rsquo;importance du changement intervenu aux USA avec le 11 septembre, et que les Europ\u00e9ens ne semblent pas avoir mesur\u00e9e.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em> Despite the outpouring of deep, genuine sympathy and help from Europe in the wake of Sept. 11, many Europeans do not seem to understand the profound changes that the day of terror brought to American lives. Above all, they do not appreciate that open threats of harm and revenge voiced by Saddam Hussein, Palestinian mobs or Iranian mullahs sound different in the ears of Americans today than they did on the day before the attacks. Woven into the texture of French, German and other commentary is the belief that Saddam Hussein, Islamic Jihad and the rest are the same unpleasant or murderous entities that they were on Sept. 10. That prompts questioning of the Bush administration&rsquo;s decision to assign urgent priority to combating those who openly and repeatedly threaten American lives while working to acquire weapons of mass destruction.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tLe (court) paragraphe que nous citons ci-apr\u00e8s est le plus int\u00e9ressant. Apr\u00e8s avoir fait l&rsquo;observation de la m\u00e9sentente, Hoagland avance une explication. Celle-ci est int\u00e9ressante par sa dimension et ses perspectives, et c&rsquo;est bien \u00e0 ce propos que nous parlerions, avec cet article de Hoagland, d&rsquo;un effort r\u00e9el fait pour tenter d&rsquo;\u00e9clairer la situation transatlantique actuelle.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>Europeans are accustomed to the insecurity of their geography and history. A decade after the Cold War ended, they feel more secure from the direct threat of war and annihilation than they have in centuries. At the same moment, Americans have had the security blanket of oceans and distance yanked away in particularly brutal fashion.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tIl s&rsquo;agit du rappel d&rsquo;une r\u00e9alit\u00e9 finalement peu complexe, qui s&rsquo;appuie sur des \u00e9vidences g\u00e9ographiques et historiques, qui devrait \u00eatre constamment \u00e0 nos esprits \u00e0 cause de son importance et qui ne l&rsquo;est pas. Souvent, dans notre \u00e9poque marqu\u00e9e par un conformisme de la pens\u00e9e sans pr\u00e9c\u00e9dent, les r\u00e9alit\u00e9s appuy\u00e9es sur des \u00e9vidences sont \u00e9cart\u00e9es comme des \u00e9l\u00e9ments de r\u00e9flexion dangereux et r\u00e9volutionnaires. Celle-ci a effectivement des prolongements qui ressemblent \u00e0 des bouleversements, si l&rsquo;on explore la voie ainsi ouverte par Hoagland.<\/p>\n<\/p>\n<p><p>\tLui-m\u00eame, l&rsquo;Am\u00e9ricain, ne cherche pas \u00e0 voir plus loin. Une autre explication qu&rsquo;il donne \u00e0 la s\u00e9paration transatlantique grandissante est conjoncturelle, et moins int\u00e9ressante. La voie qu&rsquo;il propose pour parvenir \u00e0 une solution est pour l&rsquo;essentiel conventionnelle et sans int\u00e9r\u00eat, mais aussi, pour une faible part qui n&rsquo;est pas sans int\u00e9r\u00eat, pleine de territoires nouveaux \u00e0 explorer. Certains de ces territoires nouveaux pourraient s&rsquo;av\u00e9rer r\u00e9volutionnaires et d\u00e9stabilisants.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>In the Cold War, Americans and Europeans actively needed each other. They quarreled knowing that the limits of discord would soon have them working together again. Now the limits of accord dominate this vital relationship. New balances of understanding and mutual help must be developed.<\/em> \u00bb<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Expliquons-nous 16 avril 2002 &mdash; Il est courant de constater la m\u00e9sentente grandissante, tr\u00e8s vite, aujourd&rsquo;hui et depuis le 11 septembre, entre l&rsquo;Europe et les USA. Il est rare de tenter de l&rsquo;expliquer ; tr\u00e8s rare en Europe, par crainte de panique de d\u00e9couvrir que le roi est nu (m\u00e9sentente irr\u00e9versible ou pas ?) ;&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[398,3307,1205,2804],"class_list":["post-65062","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-europe","tag-hoagland","tag-transatlantique","tag-usa"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65062"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65062\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}