{"id":65093,"date":"2002-05-13T00:00:00","date_gmt":"2002-05-13T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2002\/05\/13\/sus-a-la-cour\/"},"modified":"2002-05-13T00:00:00","modified_gmt":"2002-05-13T00:00:00","slug":"sus-a-la-cour","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2002\/05\/13\/sus-a-la-cour\/","title":{"rendered":"<strong><em>Sus \u00e0 la Cour!<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Sus \u00e0 la Cour!<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t13 mai 2002 &mdash; Nous ne cessons nous-m\u00eames d&rsquo;\u00eatre surpris par le cours des choses, la fa\u00e7on dont la caricature, \u00e0 peine imagin\u00e9e avec un haussement d&rsquo;\u00e9paules car on n&rsquo;imagine pas qu&rsquo;elle devienne r\u00e9alit\u00e9, aussit\u00f4t devient r\u00e9alit\u00e9. C&rsquo;est le cas de l&rsquo;attitude am\u00e9ricaine vis-\u00e0-vis de la Cour Internationale, dont les Am\u00e9ricains viennent d&rsquo;annoncer qu&rsquo;ils retirent leur signature du trait\u00e9 qui l&rsquo;institue. Nous venions de <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=217\" class=\"gen\">publier une analyse sur cette question,<\/a> o\u00f9 nous reconnaissons qu&rsquo;il y a dans la position am\u00e9ricaine des arguments qui m\u00e9ritent d&rsquo;\u00eatre pris en consid\u00e9ration, si d&rsquo;autres sont nettement critiquables. Aussit\u00f4t vient la nouvelle que la Chambre des Repr\u00e9sentants est sur la voie de voter une loi qui <a href=\"http:\/\/www.iht.com\/articles\/57496.html\" class=\"gen\">pousse cette d\u00e9marche jusqu&rsquo;\u00e0 la plus compl\u00e8te caricature<\/a>. Curieusement adopt\u00e9e par la Commission des Appropriations de la Chambre, cette loi avait \u00e9t\u00e9 concoct\u00e9e <em>in illo tempore<\/em> par le sulfureux s\u00e9nateur Jesse Helms, puis elle a \u00e9t\u00e9 tr\u00e8s r\u00e9cemment reprise par le <em>leader<\/em> r\u00e9publicain de la Chambre Thomas DeLay. Elle pr\u00e9voit notamment, et de fa\u00e7on tr\u00e8s spectaculaire, que les \u00c9tats-Unis se r\u00e9servent le droit d&rsquo;intervenir par la force pour \u00ab\u00a0lib\u00e9rer\u00a0\u00bb des citoyens am\u00e9ricains qui seraient d\u00e9tenus et conduits devant la Cour. Celle-ci se situe, comme chacun sait (sauf nombre de parlementaires US), \u00e0 &#8230; La Haye.<\/p>\n<\/p>\n<p><p>\tCitation cocasse de l&rsquo;article auquel nous renvoyons nos lecteurs :<\/p>\n<\/p>\n<p><p>\t\u00ab <em>Before the committee voted, 38 to 18, to adopt DeLay&rsquo;s plan, it was bitterly attacked by several Democrats. Representative Patrick Kennedy of Rhode Island said that the DeLay measure sent a message of unilateralism to the world.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Representative David Obey, a Wisconsin Democrat, said the Appropriations Committee should not even consider the measure but leave it to the International Relations Committee. After demonstrating that some committee members did not know the court would be in The Hague, Obey asked if DeLay understood that under the rescue provision, \u00a0\u00bbWe would be sending our troops to invade the Netherlands.\u00a0\u00bb DeLay said he did not consider that a serious question.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tUn autre aspect \u00e9tonnant de cet \u00e9pisode est que la loi DeLay est pr\u00e9sent\u00e9e dans l&rsquo;article comme b\u00e9n\u00e9ficiant d&rsquo;un \u00ab <em>strong administration support<\/em> \u00bb. Cela repr\u00e9sente un changement par rapport \u00e0 d\u00e9cembre dernier, o\u00f9 une version \u00e9dulcor\u00e9e de la loi DeLay avait \u00e9t\u00e9 abandonn\u00e9e lors d&rsquo;une rencontre entre la Chambre et le S\u00e9nat, avec l&rsquo;appui de l&rsquo;administration. Cette fois, DeLay annonce qu&rsquo;il a le soutien sans r\u00e9serve de Rumsfeld (DoD) et de Powell (State). Comme l&rsquo;article le pr\u00e9cise, il ne devrait pas y avoir de probl\u00e8me pour que la Chambre adopte la loi. Cette fois, le S\u00e9nat devrait suivre ; le climat y pousse, ainsi que l&rsquo;attitude de l&rsquo;administration et, d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, la tendance actuelle \u00e0 Washington o\u00f9 tout ce qui est le plus extr\u00eame a le plus de chance de s&rsquo;imposer.<\/p>\n<\/p>\n<p><p>\tL&rsquo;int\u00e9r\u00eat de cet \u00e9pisode est en effet dans le m\u00e9canisme incontr\u00f4lable qui semble d\u00e9sormais pr\u00e9valoir \u00e0 Washington, sans intention ni plan pr\u00e9con\u00e7u d&rsquo;ailleurs. Syst\u00e9matiquement, les options les plus extr\u00eames sont celles qui \u00e9mergent dans les d\u00e9bats, par la force des choses dirait-on. Il s&rsquo;agit d\u00e9sormais d&rsquo;une tendance g\u00e9n\u00e9rale de toutes les forces de pouvoir. Cette tendance existait en bonne partie au Congr\u00e8s (par exemple dans la critique \u00e0 l&rsquo;encontre de l&rsquo;Europe) depuis les derni\u00e8res ann\u00e9es Clinton et avant le 11 septembre mais l&rsquo;ex\u00e9cutif restait une force apaisante. Aujourd&rsquo;hui, il n&rsquo;existe plus de force apaisante. Toutes les forces de pouvoir poussent vers l&rsquo;extr\u00e9misme, sans m\u00eame le souci du vraisemblable et\/ou du ridicule. Le cas de la menace contre la Cour, contre La Haye et contre les Pays-Bas est un bon cas, et d&rsquo;autant meilleur que nombre de ces d\u00e9put\u00e9s ignorent que la menace qu&rsquo;ils viennent de voter s&rsquo;exerce contre les Pays-Bas puisqu&rsquo;ils ignorent que la Cour se trouvera \u00e0 La Haye.<\/p>\n<\/p>\n<p><p>\tTout cela n&rsquo;a rien \u00e0 voir, ni avec la force ni avec la puissance, bien qu&rsquo;il y ait ceci et cela du c\u00f4t\u00e9 am\u00e9ricain. Aujourd&rsquo;hui, ce qui domine \u00e0 Washington, avant toute autre caract\u00e9ristique, c&rsquo;est le d\u00e9sordre. Le syst\u00e8me am\u00e9ricain est, \u00e0 cet \u00e9gard, hors de tout contr\u00f4le s\u00e9rieux et ses tendances s&rsquo;expriment naturellement dans une voie sans cesse en cours de radicalisation.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sus \u00e0 la Cour! 13 mai 2002 &mdash; Nous ne cessons nous-m\u00eames d&rsquo;\u00eatre surpris par le cours des choses, la fa\u00e7on dont la caricature, \u00e0 peine imagin\u00e9e avec un haussement d&rsquo;\u00e9paules car on n&rsquo;imagine pas qu&rsquo;elle devienne r\u00e9alit\u00e9, aussit\u00f4t devient r\u00e9alit\u00e9. C&rsquo;est le cas de l&rsquo;attitude am\u00e9ricaine vis-\u00e0-vis de la Cour Internationale, dont les Am\u00e9ricains&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3359,3055,3360,3358,2622],"class_list":["post-65093","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-chambre","tag-cour","tag-delay","tag-haye","tag-la"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65093"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65093\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}