{"id":65104,"date":"2002-05-24T00:00:00","date_gmt":"2002-05-24T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2002\/05\/24\/semaine-du-13-au-19-mai-2002\/"},"modified":"2002-05-24T00:00:00","modified_gmt":"2002-05-24T00:00:00","slug":"semaine-du-13-au-19-mai-2002","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2002\/05\/24\/semaine-du-13-au-19-mai-2002\/","title":{"rendered":"<strong><em>Semaine du 13 au 19 mai 2002<\/em><\/strong>"},"content":{"rendered":"<p><h3>La Russie, comme si elle \u00e9tait dans l&rsquo;OTAN : quelle signification, quelles perspectives ?<\/h3>\n<\/p>\n<p><p>\tPersonne ne doit s&rsquo;y tromper : les nouvelles relations \u00e9tablies entre l&rsquo;OTAN et la Russie <a href=\"http:\/\/www.timesonline.co.uk\/article\/0,,3-295977,00.html\" class=\"gen\">signifient que la Russie a d\u00e9sormais un droit de veto \u00e0 l&rsquo;OTAN<\/a>, qu&rsquo;elle se trouve dans une position o\u00f9 \u00ab\u00a0tout se passe comme si\u00a0\u00bb la Russie se trouvait dans l&rsquo;OTAN. C&rsquo;est un acte important, mais plus dans son aspect de symbolique politique que dans la r\u00e9alit\u00e9, parce que l&rsquo;Acte Fondamental donne d\u00e9j\u00e0 \u00e0 la Russie une place tr\u00e8s importante dans l&rsquo;OTAN. Mais c&rsquo;est un acte important, et m\u00eame essentiel, \u00e0 cause du contexte, c&rsquo;est-\u00e0-dire de l&rsquo;importance quasi-exclusive et absolue donn\u00e9e d\u00e9sormais par les USA au terrorisme et de l&rsquo;importance que ces m\u00eames USA attribuent \u00e0 la Russie dans la lutte contre le terrorisme. Cette place donn\u00e9e \u00e0 la Russie par cette d\u00e9cision signifie que l&rsquo;OTAN est plus que jamais consid\u00e9r\u00e9e par les Am\u00e9ricains comme une machine au service des Am\u00e9ricains, qu&rsquo;elle est transform\u00e9e dans cette logique, ou qu&rsquo;on (les Am\u00e9ricains en premier) essaie de la transformer en machine \u00e0 lutter contre le terrorisme. C&rsquo;est effectivement dans cette logique que la Russie y aurait une place essentielle, plus importante que celle attribu\u00e9e aux alli\u00e9s europ\u00e9ens traditionnels.<\/p>\n<\/p>\n<p><p>\tIl faut \u00eatre pr\u00e9cis. Cette interpr\u00e9tation ne signifie pas que l&rsquo;OTAN est transform\u00e9e (au b\u00e9n\u00e9fice de tous). Cela signifie que les Am\u00e9ricains veulent transformer l&rsquo;OTAN (au b\u00e9n\u00e9fice d&rsquo;eux-m\u00eames) et qu&rsquo;avec cet acte d&rsquo;en rapprocher d\u00e9cisivement la Russie, ils croient y \u00eatre parvenues. On comprend la nuance fondamentale entre les deux phrases pour ce qui est du statut de l&rsquo;alliance. Pour l&rsquo;instant, avec l&rsquo;arriv\u00e9e de la Russie et tout ce que cela signifie pour l&rsquo;OTAN, et, surtout, tout ce que cela signifie autour de l&rsquo;OTAN en mati\u00e8re de politique et de symbolique politique, notre appr\u00e9ciation est qu&rsquo;il n&rsquo;y a qu&rsquo;une seule certitude qu&rsquo;on puisse avancer, et que c&rsquo;est celle selon laquelle les Am\u00e9ricains ont donn\u00e9 le coup de gr\u00e2ce \u00e0 l&rsquo;OTAN originelle. Quant au nouvel arrangement, qui implique une autre OTAN, sp\u00e9cialis\u00e9e dans la chasse au terrorisme (vaste programme pour la bureaucratie de l&rsquo;OTAN), tourn\u00e9e vers l&rsquo;est et les confins euro-asiatiques et du sous-continent indien (ce qui justifie d&rsquo;autant plus l&rsquo;\u00e9largissement en cours), c&rsquo;est une autre histoire. C&rsquo;est bien l&rsquo;orientation de la \u00ab\u00a0nouvelle OTAN\u00a0\u00bb, mais il est loin d&rsquo;\u00eatre assur\u00e9 qu&rsquo;elle m\u00e8nera \u00e0 une situation satisfaisante.<\/p>\n<\/p>\n<p><p>\tL&rsquo;appr\u00e9ciation compl\u00e9mentaire de cette analyse est que le rapprochement d\u00e9cisif de la Russie avec l&rsquo;OTAN ressuscite d&rsquo;une certaine fa\u00e7on, mais d&rsquo;une fa\u00e7on plus positive et plus active en th\u00e9orie du point de vue des deux acteurs, le condominium USA-URSS de la Guerre froide, cette fois au coeur de l&rsquo;OTAN. <a href=\"http:\/\/www.iht.com\/articles\/58100.html\" class=\"gen\">William Pfaff note qu&rsquo;il s&rsquo;agit a contrario<\/a> d&rsquo;un puissant appel aux Europ\u00e9ens de l&rsquo;Ouest pour \u00e9tablir une d\u00e9fense autonome de l&rsquo;OTAN et des \u00c9tats-Unis, au coeur de l&rsquo;UE.<\/p>\n<\/p>\n<p><p>\t\u00ab <em>When the Europeans decided to establish a common foreign and security policy they expected to cede a serious measure of sovereignty in those matters to Brussels, in the interest of greater European autonomy (vis-\u00e0-vis Russia, for example). The United States, through NATO, is today making a separate and competitive claim on their defense and security resources, which would have the effect of reducing European autonomy.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>That is the issue of the unspoken debate between the Europeans and Americans at NATO, and between Europeans and other Europeans.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tLe dernier point qui doit \u00eatre mentionn\u00e9 pour cet \u00e9v\u00e9nement si important est dans la logique du pr\u00e9c\u00e9dent et concerne la Russie. Jusqu&rsquo;o\u00f9 la Russie est-elle pr\u00eate \u00e0 jouer le jeu am\u00e9ricain qui la place indirectement, et peut-\u00eatre m\u00eame directement, contre les int\u00e9r\u00eats des Europ\u00e9ens de l&rsquo;Ouest partisans d&rsquo;une d\u00e9fense autonome ? La question est pos\u00e9e et les arguments en faveur d&rsquo;un jeu pouss\u00e9 avec les USA (pr\u00e9occupations russes pour le terrorisme avec la Tch\u00e9tch\u00e9nie, illusions de restauration d&rsquo;un statut de super-puissance) existent autant que les arguments pour une \u00e9volution diff\u00e9rente (excellents rapports des Russes avec l&rsquo;Europe de l&rsquo;Ouest, tendance de Poutine \u00e0 \u00eatre plus proche de l&rsquo;Europe de l&rsquo;Ouest, notamment des Allemands). <\/p>\n<h3>Woody Allen au Festival de Cannes, et avec lui un rappel des constantes de la querelle culturelle entre l&rsquo;Europe et le syst\u00e8me am\u00e9ricain<\/h3>\n<\/p>\n<p><p>\tL&rsquo;acteur et r\u00e9alisateur am\u00e9ricain Woody Allen est, cette ann\u00e9e, la vedette du Festival de Cannes (il re\u00e7oit une Palme sp\u00e9ciale, en m\u00eame temps qu&rsquo;il pr\u00e9sente son film <em>Hollywood Ending<\/em>). Sa venue \u00e0 Cannes s&rsquo;est faite sur fond de brouhaha pol\u00e9mique, puisque les organisations juives am\u00e9ricaines demandaient aux Am\u00e9ricains d&rsquo;Hollywood, particuli\u00e8rement aux juifs, de boycotter la France et le Festival. (Les organisations juives entendaient protester contre la soi-disant renaissance de l&rsquo;antis\u00e9mitisme en France, \u00e9vidente selon elles depuis les derniers \u00e9v\u00e9nements jusqu&rsquo;aux \u00e9lections pr\u00e9sidentielles.) Aucun Am\u00e9ricain, et par cons\u00e9quent aucun Am\u00e9ricain juif, n&rsquo;a boycott\u00e9 la France et le Festival. Woody Allen, Am\u00e9ricain et juif, a repouss\u00e9 d&rsquo;un commentaire furieux cette suggestion d&rsquo;un boycott (\u00ab <em>Je trouve \u00e7a <\/em>[le mot d&rsquo;ordre de boycott] <em>absolument d\u00e9bile et ridicule. Ce qui s&rsquo;est pass\u00e9 en France apr\u00e8s le premier tour est tout \u00e0 l&rsquo;honneur de ce pays, ceux qui comme moi aiment la France ont de quoi en \u00eatre fiers.<\/em> \u00bb)<\/p>\n<\/p>\n<p><p>\tA Cannes, Woody Allen a \u00ab\u00a0pr\u00e9sid\u00e9\u00a0\u00bb \u00e0 la c\u00e9l\u00e9bration d&rsquo;un autre cin\u00e9ma am\u00e9ricain, c&rsquo;est-\u00e0-dire d&rsquo;un cin\u00e9ma diff\u00e9rent de celui que l&rsquo;on a coutume d&rsquo;\u00e9voquer. Ainsi <em>Le Monde<\/em> \u00e9voque-t-il cet \u00e9v\u00e9nement (la pr\u00e9sence de Allen, Cannes cette ann\u00e9e, la pr\u00e9sidence de David Lynch) dans ses \u00e9ditions du 15 mai : \u00ab <em>De Lynch, chantant les louanges du \u00a0\u00bbmeilleur festival du monde\u00a0\u00bb \u00e0 Allen (et en attendant Scorsese, pr\u00e9sident du jury des courts m\u00e9trages), c&rsquo;\u00e9tait bien une autre id\u00e9e du cin\u00e9ma am\u00e9ricain qui \u00e9tait c\u00e9l\u00e9br\u00e9e, en opposition implicite avec celle qui domine les \u00e9crans des Etats-Unis et du monde.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tBeaucoup nous est dit par Woody Allen lui-m\u00eame, dans ses d\u00e9clarations, <a href=\"http:\/\/www.guardian.co.uk\/international\/story\/0,3604,716235,00.html\" class=\"gen\">telle que les rapporte le Guardian<\/a>. Woody Allen brosse en quelques phrases une appr\u00e9ciation des conceptions culturelles fran\u00e7aises (et europ\u00e9ennes) par rapport, ou contre les m\u00eames conceptions soi-disant culturelles du syst\u00e8me hollywoodien. Il dit notamment ceci, &mdash; qui nous en dit beaucoup sur les diff\u00e9rences culturelles fondamentales entre le syst\u00e8me am\u00e9ricaniste et les Europ\u00e9ens (Fran\u00e7ais en t\u00eate) :<\/p>\n<\/p>\n<p><p>\t\u00ab <em>The French people have been so supportive of my films for so many years, and so affectionate to Cannes that I thought I ought to make a gesture of reciprocity,\u00a0\u00bb he said. \u00a0\u00bbI always find it very, very amusing and very endearing about the French that they discover our artists before we do. For some reason it takes the validation of the French to recognise our most important artists. When you think of Edgar Allan Poe, William Faulkner, any number of film directors, any number of important jazz musicians, they were all appreciated in France first. European culture takes the arts more seriously than we do.\u00a0\u00bb<\/em> \u00bb<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Russie, comme si elle \u00e9tait dans l&rsquo;OTAN : quelle signification, quelles perspectives ? Personne ne doit s&rsquo;y tromper : les nouvelles relations \u00e9tablies entre l&rsquo;OTAN et la Russie signifient que la Russie a d\u00e9sormais un droit de veto \u00e0 l&rsquo;OTAN, qu&rsquo;elle se trouve dans une position o\u00f9 \u00ab\u00a0tout se passe comme si\u00a0\u00bb la Russie&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[7],"tags":[3365,3366,3163,2687,3371,584,2730,2804,3370],"class_list":["post-65104","post","type-post","status-publish","format-standard","hentry","category-journal","tag-allen","tag-cannes","tag-culture","tag-france","tag-hollywood","tag-otan","tag-russie","tag-usa","tag-woody"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65104"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65104\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}