{"id":65107,"date":"2002-05-26T00:00:00","date_gmt":"2002-05-26T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2002\/05\/26\/le-jsf-et-wall-street\/"},"modified":"2002-05-26T00:00:00","modified_gmt":"2002-05-26T00:00:00","slug":"le-jsf-et-wall-street","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2002\/05\/26\/le-jsf-et-wall-street\/","title":{"rendered":"<strong><em>Le JSF et Wall Street<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Le JSF et Wall Street<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t25 mai 2002 &mdash; La Lettre d&rsquo;Information <em>Inside the Navy<\/em> du 20 mai rapporte la rencontre, datant du 15 mai, entre Vance Coffman, CEO de Lockheed-Martin (LM) et des repr\u00e9sentants de divers gros investisseurs de Wall Street. Le but de la rencontre, organis\u00e9e par Coffman, \u00e9tait de rassurer ces investisseurs sur le sort du programme JSF, <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=232\" class=\"gen\">dont on sait qu&rsquo;il est menac\u00e9 de r\u00e9ductions importantes<\/a> par rapport aux commandes initiales envisag\u00e9es de l&rsquo;USAF et de la Navy. (Cette initiative de Coffman au b\u00e9n\u00e9fice de Wall Street est une puissante confirmation de la r\u00e9alit\u00e9 des difficult\u00e9s auxquelles est confront\u00e9 le programme JSF. Peut-\u00eatre cela int\u00e9ressera-t-il les Europ\u00e9ens qui sont ou vont entrer dans le programme ?)<\/p>\n<\/p>\n<p><p>\tCoffman a \u00e9t\u00e9 net : ces probl\u00e8mes auxquels se heurte le JSF n&rsquo;ont pas beaucoup d&rsquo;importance. Certes, ces probl\u00e8mes existent. Mais le march\u00e9 aussi existe et il existe sur le tr\u00e8s long terme (30-40 ans). Par cons\u00e9quent, puisque le march\u00e9 existe le JSF est assur\u00e9 d&rsquo;un avenir brillant. (Il est implicite dans cet argument que le JSF, puisqu&rsquo;il existe, et puisque le march\u00e9 existe, finira par emporter l&rsquo;essentiel du march\u00e9. C&rsquo;est une argumentation qui \u00e9volue par v\u00e9rit\u00e9s ass\u00e9n\u00e9es au marteau, dont l&rsquo;essentielle est bien que le JSF, \u00e0 cause de ce qu&rsquo;il est, ne peut pas \u00eatre un \u00e9chec.) Coffman dit notamment :<\/p>\n<\/p>\n<p><p>\t\u00ab <em>The size of the marketplace the Joint Strike Fighter will play into is going to be over 30 or 40 years. One administration will not determine how many Joint Strike Fighters there are, because it runs over that many years.<\/em> \u00bb   <\/p>\n<\/p>\n<p><p>\tPuis Coffman abandonne cette dialectique de relations publiques. Lorsqu&rsquo;il est press\u00e9 de questions sur le fond du probl\u00e8me, il se fait encore plus net. Il parle alors le langage qui pla\u00eet aux investisseurs de Wall Street, le langage du profit \u00e0 tr\u00e8s court terme. Dans ce cas, les perspectives de commande et de production du JSF, sur les 30-40 ans, deviennent moins int\u00e9ressantes, l&rsquo;essentiel \u00e9tant les revenus de LM et, par cons\u00e9quent, les dividendes que touchent et toucheront les actionnaires. Voici ce que dit Coffman sur ce point :<\/p>\n<\/p>\n<p><p>\t\u00ab <em>Coffman said the current DOD production projections for the JSF fleet for the year 2020 or 2015 or 2012 is not of particular concern to me. He is much more interested in the $19 billion system design and development contract his company won last October. If we do that job well, I believe that the future of the airplane will be extremely bright and that whatever the numbers are, it&rsquo;s going to be a huge win for Lockheed Martin, he said.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tOn a rarement \u00e9t\u00e9 aussi clair dans l&rsquo;expos\u00e9 d&rsquo;une philosophie industrielle qui consiste \u00e0 d\u00e9solidariser la soci\u00e9t\u00e9 productrice du produit qu&rsquo;elle fabrique, au profit de sa solidarit\u00e9 avec ses investisseurs :<\/p>\n<\/p>\n<p><p>\t&bull; L&rsquo;important pour LM (et Wall Street) se trouve dans les rentr\u00e9es r\u00e9alis\u00e9es imm\u00e9diatement.<\/p>\n<\/p>\n<p><p>\t&bull; Le sort du programme \u00ab <em>is not of particular concern to me<\/em> \u00bb.<\/p>\n<\/p>\n<p><p>\t&bull; L&rsquo;essentiel reste dans les r\u00e9sultats financiers obtenus par LM, quelles que soient les circonstances qui affecteront le programme.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le JSF et Wall Street 25 mai 2002 &mdash; La Lettre d&rsquo;Information Inside the Navy du 20 mai rapporte la rencontre, datant du 15 mai, entre Vance Coffman, CEO de Lockheed-Martin (LM) et des repr\u00e9sentants de divers gros investisseurs de Wall Street. Le but de la rencontre, organis\u00e9e par Coffman, \u00e9tait de rassurer ces investisseurs&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[396,250,394,3372,3132],"class_list":["post-65107","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-coffman","tag-jsf","tag-lockheed-martin","tag-street","tag-wall"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65107"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65107\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}