{"id":65207,"date":"2002-08-07T00:00:00","date_gmt":"2002-08-07T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2002\/08\/07\/drole-de-guerre\/"},"modified":"2002-08-07T00:00:00","modified_gmt":"2002-08-07T00:00:00","slug":"drole-de-guerre","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2002\/08\/07\/drole-de-guerre\/","title":{"rendered":"<strong><em>Dr\u00f4le de guerre<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Dr\u00f4le de guerre<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t7 ao\u00fbt 2002  Parfois, l&rsquo;esprit vient o\u00f9 on ne l&rsquo;attend pas. C&rsquo;est le cas de cet \u00e9ditorial du New York <em>Times<\/em> du 5 ao\u00fbt, o\u00f9 l&rsquo;on distingue une certaine impatience, du type : Il est temps d&rsquo;\u00eatre s\u00e9rieux, non ?<\/p>\n<\/p>\n<p><p>\tVoici l&rsquo;extrait qui nous importe :<\/p>\n<\/p>\n<p><p>\t\u00ab <em>With all their talk about forcing a regime change in Iraq, President George W. Bush and his aides are creating the 2002 equivalent of the 1939 phony war in Europe  the period following the German invasion of Poland when everyone knew war was coming but the shooting hadn&rsquo;t commenced.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>The anticipation of war stirs uncertainty and puts people on edge, which is the way America, already shaken by Sept. 11, is feeling these days. It is time for Bush to level with the nation about his intentions. There may be a compelling case to be made for war with Iraq. The administration has not yet made it.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tLa machine PR (Public Relations) de l&rsquo;administration GW est si impressionnante de puissance, ces gens de l&rsquo;administration sont tous si compl\u00e8tement absents de la r\u00e9alit\u00e9 et plong\u00e9s dans leurs diatribes id\u00e9ologiques, leurs querelles bureaucratiques et leurs obsessions politiques, qu&rsquo;ils ne mesurent plus le spectacle qu&rsquo;ils offrent. Il est temps, en effet, de d\u00e9tacher la cause \u00e9ventuelle d&rsquo;une guerre (Saddam) et cette guerre \u00e9ventuelle elle-m\u00eame, d&rsquo;une part, des pr\u00e9paratifs de la guerre, d&rsquo;autre part. Il y a l\u00e0 deux choses bien diff\u00e9rentes.<\/p>\n<\/p>\n<p><p>\tSaddam, ses projets, ses vilenies et ses turpitudes, on conna\u00eet puisqu&rsquo;on nous en rebat les oreilles depuis exactement 12 ans. (Hitler n&rsquo;avait pas eu droit \u00e0 tant d&rsquo;\u00e9gards, ni tant d&rsquo;attention dans la dur\u00e9e.) L&rsquo;on sait aujourd&rsquo;hui que, sur ce sujet, l&rsquo;on ne sait rien de pr\u00e9cis, que c&rsquo;est un d\u00e9bat g\u00e9n\u00e9ral, complexe, d\u00e9licat, etc. Bref, un cas pour l&rsquo;analyse rationnelle, la mesure, l&rsquo;\u00e9valuation, etc, o\u00f9 le d\u00e9bat est ouvert : face \u00e0 un Scott Ritter, l&rsquo;ancien chef (am\u00e9ricain) des inspecteurs de l&rsquo;ONU, qui affirme que les capacit\u00e9s en armes de destruction massive de Saddam sont proches d&rsquo;\u00eatre nulles, il y a des affirmations \u00e9pisodiques du contraire, mais aucun accord g\u00e9n\u00e9ral d&rsquo;analyse. Autrement dit, <a href=\"http:\/\/www.washingtonpost.com\/wp-dyn\/articles\/A23545-2002Jul30.html\" class=\"gen\">comme le titrait le Washington Post<\/a> du 31 juillet, \u00ab <em>In Assessing Iraq&rsquo;s Arsenal, The Reality Is Uncertainty<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tCe qui nous int\u00e9resse ici, c&rsquo;est le reste, l&rsquo;autre monde, l&rsquo;autre c\u00f4t\u00e9 du miroir, ce qu&rsquo;on a d\u00e9sign\u00e9, avec tous les guillemets du monde, comme les pr\u00e9paratifs de la guerre. L\u00e0, on se trouve dans le domaine de la fantasmagorie, une sorte de DisneyWorld de la politique et des relations internationales. La fa\u00e7on dont l&rsquo;entreprise de PR de l&rsquo;administration GW jongle avec la cause de la guerre est simplement \u00e9bouriffante,  comme s&rsquo;il nous \u00e9tait dit, droitement, regard plant\u00e9 dans le n\u00f4tre, avec un sourire innocent : Oui, vous comprenez, nous voulons, nous devons faire cette guerre. Mais notre probl\u00e8me, c&rsquo;est de trouver pourquoi.<\/p>\n<\/p>\n<p><p>\tLe site WSWS a recens\u00e9 notamment cet aspect du d\u00e9bat washingtonien, <a href=\"http:\/\/www.wsws.org\/articles\/2002\/aug2002\/iraq-a06.shtml\" class=\"gen\">dans un texte qu&rsquo;il a publi\u00e9 le 6 ao\u00fbt<\/a>. Nous empruntons ce passage du texte WSWS qu&rsquo;on pourrait intituler : \u00e0 propos de la recherche de la cause de la guerre que nous devons absolument faire :<\/p>\n<\/p>\n<p><p>\t\u00ab <em>The political pretext for hostilities with Iraq keeps shifting, as the Bush administration seeks, so far unsuccessfully, to find a pretext that can stampede the public behind its war plans. On one day war against Iraq is necessary because UN weapons inspectors have been absent from the country since 1998, and Baghdad has supposedly resumed the development of chemical, biological and nuclear weapons. (However, when Iraq offered last week to readmit the inspectors, the Bush administration immediately rejected the proposal).<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The next day Hussein&rsquo;s removal from power is declared a must because the Iraqi ruler already has weapons of mass destruction and may give them to Al Qaeda  although the enmity between the Islamic fundamentalism of Al Qaeda and the secular nationalism of Hussein&rsquo;s Ba&rsquo;athist regime is well established.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>A day later it turns out that Hussein must be removed because he might use weapons of mass destruction against American targets himself (although that would be suicide for his regime) or against Israel (which possesses an estimated 200 nuclear bombs).<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>On the morrow Hussein is declared a threat to his Arab neighbors and to the supply of oil from the Persian Gulf to world markets, despite the fact that Iraq signed a boundary agreement with Kuwait giving up all claims on the emirate, and that all of the Gulf states publicly oppose an American attack on Baghdad.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>By the end of the week, Saddam Hussein is declared responsible for the September 11 attacks on the World Trade Center and the Pentagon, justifying a retaliatory war.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>This latestand most desperateattempt to manufacture a casus belli was reported by the Los Angeles Times August 2. The newspaper wrote that the White House and Pentagon had decided to endorse claims that suicide hijacker Mohammed Atta met with an Iraqi official in the Czech Republic several months before September 11, although both the CIA and FBI have dismissed the Czech report as unproven and unfounded. As the front-page LA Times report made clear, the Bush administration made its decision not as a result of new intelligence information, but because it felt the need for a September 11 link to generate support for its war plans.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;intensit\u00e9 de la campagne pour la guerre en Irak est telle, et sur une telle dur\u00e9e, \u00e0 l&rsquo;int\u00e9rieur de la bureaucratie et dans les cercles proches du pouvoir, qu&rsquo;on peut dire que ce cas devient l&rsquo;essentiel de la pr\u00e9occupation et de l&rsquo;activit\u00e9 politique de l&rsquo;administration GW, au d\u00e9pens du reste. (Ainsi, l&rsquo;inexistence de l&rsquo;administration dans la question de la crise du <em>corporate system<\/em> et la crise boursi\u00e8re, et aussi dans les cons\u00e9quences \u00e9conomiques, est due pour l&rsquo;essentielle \u00e0 cette pr\u00e9occupation irakienne de la pr\u00e9paration de la guerre).<\/p>\n<\/p>\n<p><p>\tDe ce point de vue, une comparaison est en train de se faire jour entre l&rsquo;administration Johnson et l&rsquo;administration GW : l&rsquo;obsession irakienne de la seconde vaut en intensit\u00e9 l&rsquo;obsession vietnamienne de la premi\u00e8re. On pourrait parler d&rsquo;une vietnamisation de l&rsquo;administration GW, mais dans son comportement, son fonctionnement et ses conceptions, pas sur le terrain. Cela admis, la diff\u00e9rence saute aux yeux : du temps de Johnson, il s&rsquo;agissait d&rsquo;une vraie guerre ; dans le cas pr\u00e9sent, il s&rsquo;agit d&rsquo;une guerre qu&rsquo;on ne parvient pas \u00e0 faire. Deux citations r\u00e9sument le sentiment dont on veut rendre compte, \u00e0 observer cette situation :<\/p>\n<\/p>\n<p><p>\t \u00ab <em>We seem to be distant observers of our own nation&rsquo;s preparation for war, watchinga process we have nothing to do with and cannot affect.<\/em> \u00bb (Washington <em>Post<\/em>, 12 juillet)<N;<\/p>\n<\/p>\n<p><p>\t \u00ab <em>The Bush administration knows it wants to bomb Iraq and it knows it wants to get rid of Saddam  it just doesn&rsquo;t know when, how or why to do it.<\/em> \u00bb (un journaliste US, cit\u00e9 par <em>The Independent<\/em>, 21 juillet).<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dr\u00f4le de guerre 7 ao\u00fbt 2002 Parfois, l&rsquo;esprit vient o\u00f9 on ne l&rsquo;attend pas. C&rsquo;est le cas de cet \u00e9ditorial du New York Times du 5 ao\u00fbt, o\u00f9 l&rsquo;on distingue une certaine impatience, du type : Il est temps d&rsquo;\u00eatre s\u00e9rieux, non ? Voici l&rsquo;extrait qui nous importe : \u00ab With all their talk about&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[868,3198,857,2866],"class_list":["post-65207","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-bush","tag-gw","tag-irak","tag-johnson"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65207"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65207\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}