{"id":65219,"date":"2002-08-16T00:00:00","date_gmt":"2002-08-16T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2002\/08\/16\/mexique-et-usa-un-rapport-de-puissance-a-puissance\/"},"modified":"2002-08-16T00:00:00","modified_gmt":"2002-08-16T00:00:00","slug":"mexique-et-usa-un-rapport-de-puissance-a-puissance","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2002\/08\/16\/mexique-et-usa-un-rapport-de-puissance-a-puissance\/","title":{"rendered":"Mexique et USA, un rapport \u201cde puissance \u00e0 puissance\u201d"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Mexique et USA, un rapport \u00ab\u00a0de puissance \u00e0 puissance\u00a0\u00bb <\/h2>\n<\/p>\n<p><p>Comme on l&rsquo;a d\u00e9j\u00e0 vu \u00e0 plusieurs reprises, le pr\u00e9sident mexicain Fox repr\u00e9sente aujourd&rsquo;hui le <strong>seul<\/strong> cas d&rsquo;un chef d&rsquo;&Eacute;tat et de gouvernement dans le monde capable de riposter aux USA lorsqu&rsquo;il estime que les int\u00e9r\u00eats ou la dignit\u00e9 du Mexique sont mis en cause. On peut m\u00eame avancer que, dans diff\u00e9rentes occurrences, ce sont les &Eacute;tats-Unis qui reculent diplomatiquement face au Mexique. C&rsquo;est un cas extraordinaire de renversement de rapports entre les deux pays, alors que le Mexique a toujours \u00e9t\u00e9 traditionnellement consid\u00e9r\u00e9 comme une sorte de \u00ab\u00a0colonie\u00a0\u00bb des &Eacute;tats-Unis.<\/p>\n<\/p>\n<p><p>Nous publions ci-dessous une analyse parue dans la Lettre d&rsquo;information <em>de defensa<\/em> en octobre 2001 (<em>de defensa &#038; eurostrat\u00e9gie<\/em>, rubrique \u00ab\u00a0<em>Contexte<\/em>\u00ab\u00a0, Volume 17, n&deg;03 du 10 octobre 2001.), sur la visite de Vicente Fox \u00e0 Washington du d\u00e9but septembre 2001. Nous pensons que ce texte contribuera \u00e0 \u00e9clairer ces \u00e9tonnants rapports entre le Mexique et les &Eacute;tats-Unis.<\/p>\n<\/p>\n<p><p>[Cette publication est \u00e0 lier avec un autre texte, que nous \u00e9ditons aujourd&rsquo;hui, <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=344\">dans la rubrique Faits et Commentaires<\/a>, sur l&rsquo;attitude du pr\u00e9sident Fox vis-\u00e0-vis des &Eacute;tats-Unis, notamment son annulation d&rsquo;une visite au Texas au cours de laquelle Fox devait rencontrer GW Bush, &mdash; annulation que NBC News a comment\u00e9 de la sorte: &laquo; <em>The White House put the brightest face it could on Mexican President Vicente Fox&rsquo;s snub of an invitation to President Bush&rsquo;s Texas ranch, emphasizing what it said are strong ties between the two countries.<\/em> &raquo;.]<\/p>\n<\/p>\n<p><p>dde.org<\/p>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955;font-size:2em;\">L&rsquo;autre Sud<\/h2>\n<\/p>\n<blockquote>\n<p><p>Parlons de la visite \u00e0 Washington le mois dernier (avant 9\/11) de Vicente Fox, le pr\u00e9sident mexicain. Jamais on ne vit \u00e0 Washington un chef d&rsquo;&Eacute;tat \u00e9tranger aussi assur\u00e9 de lui-m\u00eame et de sa \u00ab\u00a0cause\u00a0\u00bb, qui est \u00e9galement une cause am\u00e9ricaine. Fox \u00e9tait venu \u00e0 Washington avec, dans sa besace, une nouvelle arme absolue : l&rsquo;immigration et la soci\u00e9t\u00e9 multiethnique. Cette arme absolue contredit la th\u00e8se du \u00ab\u00a0choc des civilisations\u00a0\u00bb qui a retrouv\u00e9 toute sa vogue avec la crise du 11 septembre.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>C&rsquo;\u00e9tait avant qu&rsquo;on ne parl\u00e2t quasi-exclusivement d&rsquo;Osmana Ben Laden, lors de la visite \u00e0 Washington du pr\u00e9sident mexicain Vicente Fox, les 3-6 septembre 2001. Des commentateurs washingtoniens ont senti qu&rsquo;il se passait quelque chose d&rsquo;important. Tony Karon, de <em>Time<\/em>, nota que la venue de Fox \u00e0 Washington \u00e9tait remarquable \u00e0 cause de ceci : &laquo; <em>Le fait qu&rsquo;un pr\u00e9sident mexicain puisse venir \u00e0 Washington pour demander que les USA changent leurs lois sur l&rsquo;immigration, et soit applaudi pour cela, signifie que nous sommes dans une \u00e9poque nouvelle.<\/em> &raquo; Fox n&rsquo;a pas senti le moindre complexe pour le freiner dans sa d\u00e9marche washingtonienne. Il s&rsquo;est balad\u00e9 \u00e0 Washington presque comme en pays conquis, presque comme chez lui. Avant sa venue, on avait annonc\u00e9 que Fox ferait mieux d&rsquo;oublier l&rsquo;accord envisag\u00e9 sur les immigrants ill\u00e9gaux (r\u00e9gularisation de la situation des 4 millions d&rsquo;ill\u00e9gaux mexicains aux USA) parce que, si GW Bush y \u00e9tait favorable, le Congr\u00e8s, lui, n&rsquo;en voulait pas. Au contraire, Fox vint \u00e0 Washington et r\u00e9clama cet accord pour &laquo; <em>avant la No\u00ebl<\/em> &raquo;, vraiment sans prendre de gants. Et, comme note Karon, on l&rsquo;applaudit, &mdash; notamment au Congr\u00e8s. Quel dirigeant d&rsquo;une puissance quelconque, y compris une puissance dans les petits papiers de Washington, quel Premier ministre britannique ou isra\u00e9lien par exemple, oserait faire cela ? William Norman Grigg, de <em>New American<\/em>, remarque : &laquo; <em>Ce fut la premi\u00e8re fois qu&rsquo;un chef d&rsquo;&Eacute;tat \u00e9tranger se comportait comme le chef d&rsquo;une nation \u00e0 l&rsquo;int\u00e9rieur de notre nation.<\/em> &raquo; Bien vu.<\/p>\n<\/p>\n<p><p>&laquo; <em>Fox aime \u00e0 dire qu&rsquo;il est le pr\u00e9sident \u00ab\u00a0de tous les Mexicains\u00a0\u00bb, utilisant parfois le chiffre de 117 millions de Mexicains, parfois celui de 123 millions de Mexicains, <\/em>remarque Nicholas M. Horrock, de UPI. <em>La population mexicaine du Mexique lui-m\u00eame est de 100 millions et des experts tels que Mark Krikorian, du Center of Immigration Studies, concluent qu&rsquo;il compte <\/em>[un certain nombre] <em>de Mexicains r\u00e9sidant aux USA.<\/em> &raquo; Fox ne s&rsquo;en est jamais cach\u00e9. A l&rsquo;automne dernier, lors d&rsquo;une visite en Californie o&ugrave; les <em>chicanos<\/em> sont d&rsquo;ores et d\u00e9j\u00e0 majoritaires, Fox avait promis \u00e0 ses \u00ab\u00a0compatriotes\u00a0\u00bb qu&rsquo;ils pourraient voter au Mexique et qu&rsquo;ils auraient un jour leurs s\u00e9nateurs au Parlement, \u00e0 Mexico City : la promesse vaut pour les 17 millions de Mexicains non-citoyens US r\u00e9sidant aux USA, et peut-\u00eatre m\u00eame pour les 6 millions de Mexicains (n\u00e9s au Mexique) devenus citoyens US. On a l&rsquo;explication des chiffres 117 millions et 123 millions, et, aussi, de cette fa\u00e7on qu&rsquo;a montr\u00e9e Fox de se sentir un peu \u00ab\u00a0chez lui\u00a0\u00bb \u00e0 Washington.<\/p>\n<\/p>\n<p><p>R\u00e9sumons : jamais un pr\u00e9sident mexicain, repr\u00e9sentant un pays croulant sous la pauvret\u00e9, outrageusement trait\u00e9 par son voisin du Nord comme une sorte de semi-colonie depuis 1847 (fin de la guerre USA-Mexique, avec les USA imposant scandaleusement au Mexique la cession de la Californie, du Nouveau-Mexique, du Nevada et du Texas aux USA), &mdash; jamais un pr\u00e9sident mexicain ne s&rsquo;\u00e9tait senti aussi fort \u00e0 Washington. Dans sa besace, une arme absolue, &mdash; l&rsquo;arme des pauvres, mais dans le seul cas (le cas mexicain) o&ugrave; elle peut \u00eatre utilis\u00e9e avec une efficacit\u00e9 prodigieuse : l&rsquo;immigration. S&rsquo;il n&rsquo;y avait eu l&rsquo;affaire 9\/11 entre temps, nous \u00e9cririons : ce qu&rsquo;on a vu \u00e0 Washington, d\u00e9but septembre, c&rsquo;est la premi\u00e8re menace fondamentale contre l'\u00a0\u00bbempire am\u00e9ricain\u00a0\u00bb ; et l'\u00a0\u00bbempire\u00a0\u00bb dans une telle position qu&rsquo;il ne peut qu&rsquo;applaudir humblement \u00e0 son possible vainqueur. En effet, l&rsquo;ironie est qu&rsquo;en accueillant l&rsquo;installation de Vicente Fox \u00e0 la pr\u00e9sidence, tous les penseurs-<em>business<\/em> des grands instituts US s&rsquo;\u00e9taient r\u00e9jouis de l&rsquo;arriv\u00e9e d&rsquo;un adepte du lib\u00e9ralisme, instruit dans les <em>Business School<\/em> US et ancien patron de Coca-Cola Mexico. L&rsquo;ironie de l&rsquo;ironie est que Fox n&rsquo;a pas de meilleur copain que GW Bush, ancien gouverneur du Texas, parlant espagnol, dont la premi\u00e8re visite lors de son \u00e9lection de 1996 fut pour Mexico City et le pr\u00e9sident mexicain d&rsquo;alors ; GW, \u00e9lu pour affirmer la puissance US, qui, en temps de paix, tremble devant le Congr\u00e8s alors que Fox en fait ce qu&rsquo;il veut, qui claque dans le dos de Fox et se proclame son ami &#8230; Qui est le patron \u00e0 Washington ?, pouvait-on s&rsquo;interroger au soir du 6 septembre, en saluant le d\u00e9part de Fox.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Ironie de l&rsquo;histoire<\/h3>\n<\/p>\n<p><p>La r\u00e9alit\u00e9 est que le Mexique sera l&rsquo;acteur principal sur la sc\u00e8ne int\u00e9rieure des &Eacute;tats-Unis au XXIe si\u00e8cle. Ce pays, avec son contingent de nationaux \u00e0 divers degr\u00e9s expatri\u00e9s au-del\u00e0 du Rio Grande, tient dans ses mains les cartes qui mettent \u00e0 nu la fragilit\u00e9 d\u00e9mographique historique des &Eacute;tats-Unis d&rsquo;Am\u00e9rique. L&rsquo;ironie ne manque pas dans cette affaire, car toutes les caract\u00e9ristiques qui font soi-disant la puissance et l&rsquo;originalit\u00e9 des &Eacute;tats-Unis font \u00e9galement, aujourd&rsquo;hui, celles de Vicente Fox.<\/p>\n<\/p>\n<p><p>&bull; Les USA sont une terre d&rsquo;immigration. Ayant fond\u00e9 leur puissance et leurs ambitions sur l&rsquo;\u00e9conomie, ils ouvrent les bras \u00e0 l&rsquo;immigration qui procure r\u00e9guli\u00e8rement de nouveaux bras et de nouveaux cerveaux. Pour cette raison, l&rsquo;opposition \u00e0 l&rsquo;immigration mexicaine est une attitude plut\u00f4t contre nature, qui a de la peine \u00e0 \u00eatre soutenue avec naturel.<\/p>\n<\/p>\n<p><p>&bull; Les &Eacute;tats-Unis ont admis ces derni\u00e8res ann\u00e9es les limites de leur formule int\u00e9grationniste dite du <em>melting pot<\/em> (en r\u00e9alit\u00e9, il ne faut pas s&rsquo;y tromper, le <em>melting pot<\/em> \u00e9tait la marque du triomphe des WASP dominant la soci\u00e9t\u00e9, les <em>White, Anglo-Saxon, Protestant<\/em> : le <em>melting pot<\/em> revenait, pour chaque immigrant, \u00e0 abandonner ses coutumes et sa culture pour \u00e9pouser les coutumes et la culture dominante, celles des WASP). Le regroupement en communaut\u00e9s ethniques et culturelles marquant cette limite, les USA ont adopt\u00e9 le multiculturalisme : \u00e0 chacun sa culture, \u00e0 chacun sa sp\u00e9cificit\u00e9. Implicitement, il \u00e9tait admis que les WASP, tr\u00e8s affirm\u00e9s culturellement, tr\u00e8s entreprenants, resteraient le groupe dominant. Les <em>hispanos<\/em> changent cela de fond en comble. Autoris\u00e9s <em>de facto<\/em> \u00e0 rester en communaut\u00e9 et \u00e0 garder leurs moeurs et coutumes, ils ne s&rsquo;en privent pas. Ils parlent deux langues (l&rsquo;anglais pour le <em>business<\/em>, l&rsquo;espagnol pour le coeur et l&rsquo;\u00e2me). Ils sont extr\u00eamement dynamiques, \u00e0 cause de leurs capacit\u00e9s dans le <em>business<\/em>, d&rsquo;une religion (le catholicisme) extr\u00eamement entreprenante, et aussi de la facilit\u00e9 qu&rsquo;ils ont \u00e0 se \u00ab\u00a0ressourcer\u00a0\u00bb dans leurs familles ou communaut\u00e9s d&rsquo;origine, au sud du Rio Grande. Demain (dans un peu plus de 30 ans), les <em>hispanos<\/em> deviendront le premier groupe ethnique aux USA, devant les WASP, comme ils le sont d\u00e9j\u00e0 en Californie.<\/p>\n<\/p>\n<p><p>&bull; La forme de la d\u00e9mocratie am\u00e9ricaine, fond\u00e9e sur le groupe de pression, la puissance des groupements d&rsquo;\u00e9lecteurs, permet une identification des <em>hispanos<\/em> en groupe de pression dont le dirigeant naturel serait le pr\u00e9sident mexicain, &mdash; puisque Fox, au contraire de ses pr\u00e9d\u00e9cesseurs, a d\u00e9cid\u00e9 de s&rsquo;int\u00e9resser \u00e0 fond \u00e0 la communaut\u00e9 hispanique des USA. &laquo; <em>Aujourd&rsquo;hui, <\/em>note un commentateur washingtonien, <em>au moins un parlementaire sur 2 doit tenir compte de la communaut\u00e9 hispano de son district ou de son &Eacute;tat pour sa r\u00e9\u00e9lection. Inutile de demander pourquoi, lorsque monsieur Fox monte \u00e0 la tribune du S\u00e9nat, on l&rsquo;\u00e9coute religieusement, et on l&rsquo;applaudit, et on reconna&icirc;t que ses propositions-exigences sont int\u00e9ressantes.<\/em> &raquo; En 1996, les Hispaniques formaient 5% de l&rsquo;\u00e9lectorat, ils feront 9% lors de l&rsquo;\u00e9lection de 2004. Paul Gigot, du Wall Street <em>Journal<\/em>, observe, citant le sp\u00e9cialiste \u00e9lectoral de GW Bush, Matthew Dowd, que &laquo; <em>cette tendance est d&rsquo;ores et d\u00e9j\u00e0 en train de transformer des &Eacute;tats totalement acquis aux r\u00e9publicains, notamment le Nevada et la Floride, en autant de coups de d\u00e9s \u00e9lectoraux. Et le vote hispanique est assur\u00e9 de grandir en importance, que l&rsquo;immigration s&rsquo;accroisse ou pas.<\/em> &raquo; Quand on a \u00e9t\u00e9 \u00e9lu \u00e0 50-50, on sait comment, et tout cela en Floride (tiens donc), voil\u00e0 qui explique qu&rsquo;on soit le copain de Vicente Fox, contre vents et mar\u00e9es.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">9\/11 peut-il influer sur les rapports Mexico-USA ?<\/h3>\n<\/p>\n<p><p>L\u00e0-dessus intervient le coup de tonnerre du 9\/11. Oubli\u00e9, le Mexique ? Cela semble \u00eatre le cas. C&rsquo;est, on s&rsquo;en doute, une r\u00e9ponse trop courte pour qu&rsquo;elle soit jug\u00e9e satisfaisante. Et l&rsquo;on voit tr\u00e8s vite dans quelle mesure 9\/11 peut influer sur les relations am\u00e9ricano-mexicaines, les faire \u00e9voluer, les remettre tout d&rsquo;un coup au premier plan de l&rsquo;actualit\u00e9.<\/p>\n<\/p>\n<p><p>L&rsquo;immigration est sans aucun doute le point qui vient aussit\u00f4t \u00e0 l&rsquo;esprit. Dans les mesures qui se profilent apr\u00e8s l&rsquo;attaque du 11 septembre, tout un train va affecter la s\u00e9curit\u00e9 du territoire, et, notamment, le verrouillage des fronti\u00e8res, le contr\u00f4le beaucoup plus strict des fronti\u00e8res, des entraves beaucoup plus grandes mises aux immigrants et aux non-Am\u00e9ricains en s\u00e9jour, etc. On se trouve alors devant un colossal probl\u00e8me mexicain, qui prend plusieurs aspects :<\/p>\n<\/p>\n<p><p>&bull; que faire de la fronti\u00e8re du Sud, 3.200 kilom\u00e8tres que personne n&rsquo;est jamais parvenue \u00e0 boucler (le Pentagone estime qu&rsquo;il faudrait autour de 200.000-300.000 G.I&rsquo;s pour la boucler), et que Fox aurait voulu, pour r\u00e9gler d\u00e9finitivement le probl\u00e8me, ouvrir compl\u00e8tement en proposant une \u00ab\u00a0union nord-am\u00e9ricaine\u00a0\u00bb (Canada-USA-Mexique) sur le mod\u00e8le de l&rsquo;UE ?<\/p>\n<\/p>\n<p><p>&bull; Que faire des immigrants ill\u00e9gaux mexicains et le projet d&rsquo;une amnistie r\u00e9clam\u00e9 par Fox et approuv\u00e9 par GW est-il encore concevable ?<\/p>\n<\/p>\n<p><p>&bull; Que faire de la circulation, l\u00e9gale celle-l\u00e0 des Hispano-Am\u00e9ricains d&rsquo;origine mexicaine, ou des Mexicains en s\u00e9jour l\u00e9gal aux USA et promis \u00e0 la naturalisation, et qui retournent, les uns et les autres, r\u00e9guli\u00e8rement au Mexique ?<\/p>\n<\/p>\n<p><p>Et ainsi de suite &#8230; Un autre point est moins pr\u00e9cis mais plus pernicieux encore : la vision idyllique des rapports USA-Mexique et du statut de la communaut\u00e9 <em>chicanos<\/em> aux USA implique la poursuite et l&rsquo;accentuation de la politique de soci\u00e9t\u00e9 multiculturelle. Comment vont \u00e9voluer de ce point de vue les &Eacute;tats-Unis, alors qu&rsquo;un formidable courant s\u00e9curitaire, et peut-\u00eatre x\u00e9nophobe (voir le traitement des Ara- bo-Am\u00e9ricains), menace le pays. Au mieux, on serait conduit \u00e0 penser qu&rsquo;une pause est plus que probable sur la voie de certaines mesures, et peut-\u00eatre m\u00eame une incertitude hostile.<\/p>\n<\/p>\n<p><p>D&rsquo;autre part, tout ce qui a \u00e9t\u00e9 \u00e9crit ci-dessus n&rsquo;est pas effac\u00e9 par 9\/11 : que ce soit la pression migratoire des Mexicains, l&rsquo;impossibilit\u00e9 de contr\u00f4ler la fronti\u00e8re de ce Sud-l\u00e0, le poids \u00e9lectoral grandissant des Mexicains\/des Mexicano-Am\u00e9ricains, ce sont des \u00e9l\u00e9ments d&rsquo;une actualit\u00e9 quotidienne qu&rsquo;on ne peut \u00e9carter sous pr\u00e9texte que 9\/11 mobilise toutes les attentions et toutes les \u00e9nergies. Les Mexicano-Am\u00e9ricains sont pour l&rsquo;instant assez \u00e0 leur aise, regroup\u00e9s en communaut\u00e9 et toujours tr\u00e8s proches de leur pays d&rsquo;origine ; mais quelle serait la situation si des tensions venaient \u00e0 na&icirc;tre entre le Mexique et les USA ? A ce point de la r\u00e9flexion et de la situation, nous ne faisons que poser le probl\u00e8me, en rappelant qu&rsquo;il \u00e9tait sur le point d&rsquo;\u00e9voluer d\u00e9cisivement au d\u00e9but septembre parce qu&rsquo;il \u00e9tait devenu si pressant ; par cons\u00e9quent que cette \u00e9volution d\u00e9cisive semble pour l&rsquo;instant suspendue alors qu&rsquo;il reste tout aussi pressant et que les conditions g\u00e9n\u00e9rales de la crise 9\/11 devraient \u00e9videmment le rendre encore bien plus pressant.<\/p>\n<\/p>\n<p><p>Conclusion : le Mexique qui est pass\u00e9 au second plan des probl\u00e8mes am\u00e9ricains ne manquera pas de revenir \u00e0 sa place naturelle, qui est celle que lui valent les 3.200 kilom\u00e8tres de fronti\u00e8re commune : au premier plan. Nous pencherions m\u00eame vers l&rsquo;id\u00e9e que cette question va \u00eatre exacerb\u00e9e par 9\/11, qu&rsquo;elle pourrait devenir tr\u00e8s rapidement explosive, et qu&rsquo;elle va r\u00e9sumer \u00e0 elle toute seul nombre des probl\u00e8mes fondamentaux de l&rsquo;avenir des &Eacute;tats-Unis, implicitement d\u00e9couverts par 9\/11. C&rsquo;est la question m\u00eame de la structure du continent nord-am\u00e9ricain qui est pos\u00e9e, donc la question de l&rsquo;existence des &Eacute;tats-Unis tels qu&rsquo;ils existent aujourd&rsquo;hui. Le probl\u00e8me mexicain est devenu vital pour les &Eacute;tats-Unis parce qu&rsquo;il est devenu un probl\u00e8me int\u00e9rieur, et qu&rsquo;il sera donc une part de la nouvelle \u00e9quation \u00e9tats-unienne qui va na&icirc;tre de la crise 9\/11.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mexique et USA, un rapport \u00ab\u00a0de puissance \u00e0 puissance\u00a0\u00bb Comme on l&rsquo;a d\u00e9j\u00e0 vu \u00e0 plusieurs reprises, le pr\u00e9sident mexicain Fox repr\u00e9sente aujourd&rsquo;hui le seul cas d&rsquo;un chef d&rsquo;&Eacute;tat et de gouvernement dans le monde capable de riposter aux USA lorsqu&rsquo;il estime que les int\u00e9r\u00eats ou la dignit\u00e9 du Mexique sont mis en cause. On&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[868,3288,2943,3248],"class_list":["post-65219","post","type-post","status-publish","format-standard","hentry","category-de-defensa","tag-bush","tag-fox","tag-mexique","tag-washington"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65219"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65219\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}