{"id":65236,"date":"2002-08-31T00:00:00","date_gmt":"2002-08-31T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2002\/08\/31\/question-de-principes\/"},"modified":"2002-08-31T00:00:00","modified_gmt":"2002-08-31T00:00:00","slug":"question-de-principes","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2002\/08\/31\/question-de-principes\/","title":{"rendered":"<strong><em>Question de principes<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Question de principes<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t31 ao\u00fbt 2002  Les Fran\u00e7ais, somme toute, ne sont pas en mauvaise forme. Quelque source, sans doute proche du minist\u00e8re des affaires \u00e9trang\u00e8res, confie \u00e0 Elaine Sciolino, du New York <em>Times<\/em> et de l&rsquo;IHT (le 29 ao\u00fbt), un soulagement, voire une satisfaction \u00e0 peine secr\u00e8te qui semblent \u00eatre ceux de ses pairs : \u00ab <em>French officials also seem to be relieved, even bemused, that it is now the Germans who have taken the lead in taking on the Bush administration for its Iraq policy.<\/em> \u00bb Oui, il y a de l&rsquo;ironie dans la situation actuelle, \u00e0 laquelle de Gaulle, du haut de sa vieille retraite, ne devrait pas \u00eatre insensible.<\/p>\n<\/p>\n<p><p>\tLe texte de Sciolino est int\u00e9ressant. <a href=\" http:\/\/www.iht.com\/articles\/69076.html\" class=\"gen\">Il para\u00eet donc le 29 ao\u00fbt<\/a>, avec le titre sans ambigu\u00eft\u00e9 de : \u00ab <em> France shifting stance on Iraq   In gesture to U.S., Paris will mute criticism on war plans.<\/em> \u00bb Et l&rsquo;on nous explique qu&rsquo;au Quai d&rsquo;Orsay, comme \u00e0 l&rsquo;Elys\u00e9e, on a mis au point une tactique bien dans la tradition fran\u00e7aise qui, depuis Richelieu et Vergennes, et m\u00eame au-del\u00e0, s&rsquo;est toujours piqu\u00e9e de finesse et de r\u00e9alisme. Les deux premiers paragraphes du texte de Sciolino disent tout \u00e0 ce propos :<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>In an important tactical shift, the French government has decided to stop criticizing the United States for its war planning against Iraq, according to senior French officials.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>It is not that the new government of President Jacques Chirac has suddenly embraced the American position that a military campaign to oust President Saddam Hussein of Iraq from power is justifiable and perhaps necessary. Rather, both Chirac and his foreign minister, Dominique de Villepin, have come to the conclusion that it is wiser for France to stress areas of agreement with the United States in order to help moderate American policy and to keep open its options in case the United States decides to wage war unilaterally, the officials said.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tIl y a beaucoup \u00e0 dire sur ces remarques, et d&rsquo;abord qu&rsquo;elles pr\u00e9sentent une \u00e9volution dans un contexte bien incertain, sinon compl\u00e8tement fabriqu\u00e9e pour la cause. Lorsque Sciolino nous parle d&rsquo;un \u00ab <em>important tactical shift<\/em> \u00bb en nous pr\u00e9cisant que le gouvernement fran\u00e7ais \u00ab <em>decided to stop criticizing the United States for its war planning against Iraq<\/em> \u00bb, on en reste un peu coi car il ne nous semble pas que le gouvernement fran\u00e7ais,  par exemple, quand on le compare au coll\u00e8gue Schr\u00f6der (toute l&rsquo;ironie est l\u00e0)  se soit montr\u00e9 particuli\u00e8rement agressif ces derni\u00e8res semaines dans sa critique des pr\u00e9paratifs de guerre de GW.<\/p>\n<\/p>\n<p><p>\tBien. Ces commentaires de Sciolino, d\u00e9cid\u00e9ment bonne petite auxiliaire, sont faits en marge de l&rsquo;annuelle conf\u00e9rence des ambassadeurs, o\u00f9, pendant 3 jours, le corps diplomatique fran\u00e7ais au sens le plus large se rencontre, discute, autour de son ministre puis autour de son pr\u00e9sident, pour r\u00e9ajuster la ligne g\u00e9n\u00e9rale de la diplomatie fran\u00e7aise. Et voil\u00e0 que, le jour o\u00f9 Sciolino fait para\u00eetre son article, le pr\u00e9sident Chirac vient devant ses ambassadeurs au sens large faire son discours traditionnel,  et cela donne ceci (commentaires de la presse \u00e9trang\u00e8re, britannique dans ce cas, int\u00e9ress\u00e9e au premier chef) :<\/p>\n<\/p>\n<p><p>\t&bull; La BBC, le 29 ao\u00fbt, sur son site : \u00ab <em>France speaks out against US war plan.<\/em> \u00bb Avec ce commentaire sans ambguit\u00e9 : \u00ab <em>French President Jacques Chirac has become the latest Western leader to speak out against an American attack on Iraq. He condemned US threats to attack Iraq unilaterally, saying that a United Nations mandate should be sought for military action.<\/em> \u00bb L&rsquo;impression qu&rsquo;on recueille de ce texte ne laisse aucun doute. On la retrouve par ailleurs.<\/p>\n<\/p>\n<p><p>\t&bull; Dans <a href=\"http:\/\/news.independent.co.uk\/europe\/story.jsp?story=328727\" class=\"gen\">The Independent du 30 ao\u00fbt<\/a>, m\u00eame son de cloche, m\u00eame interpr\u00e9tation, m\u00eame commentaire (\u00ab <em> The French President, Jacques Chirac, issued his strongest criticism yet of American plans to attack Iraq yesterday, warning that any \u00a0\u00bbunilateral and pre-emptive\u00a0\u00bb action would run counter to international law.<\/em> \u00bb) Dans les deux cas, c&rsquo;est-\u00e0-dire pour le discours de Chirac, il faut ajouter que ce discours n&rsquo;apporte rien de fondamentalement nouveau \u00e0 la position fran\u00e7aise. On sait que les Fran\u00e7ais n&rsquo;aiment pas, \u00e9videmment, la doctrine de l&rsquo;attaque pr\u00e9ventive ; qu&rsquo;ils jugent que toute attaque ne peut \u00eatre envisag\u00e9e sans l&rsquo;accord de l&rsquo;ONU ; et ainsi de suite &#8230; Tout cela avait \u00e9t\u00e9 d\u00e9j\u00e0 dit \u00e0 plusieurs reprises, notamment lors de la rencontre Schr\u00f6der-Chirac de juin.<\/p>\n<\/p>\n<p><p>\tQue se passe-t-il ? D&rsquo;un c\u00f4t\u00e9, on nous annonce que la France va adoucir tactiquement une attitude de forte critique des \u00c9tats-Unis, que, par ailleurs, on n&rsquo;a gu\u00e8re vue se manifester ces derni\u00e8res semaines. De l&rsquo;autre, on nous pr\u00e9sente un Chirac condamnant fermement les \u00c9tats-Unis alors qu&rsquo;il ne fait que r\u00e9p\u00e9ter, en gros, ce qu&rsquo;il a d\u00e9j\u00e0 dit. <\/p>\n<\/p>\n<p><p>\tEssayons d&rsquo;analyser cette situation en notant que la France seule n&rsquo;est pas en cause, \u00e9videmment, et qu&rsquo;elle agit, dans ce cas, au travers d&rsquo;yeux et d&rsquo;esprits, notamment anglo-saxons, qui sont engag\u00e9s dans la m\u00eame gal\u00e8re et, \u00e0 notre avis, beaucoup moins \u00e0 l&rsquo;aise que la France. Voici plusieurs points :<\/p>\n<\/p>\n<p><p>\t&bull; Depuis le d\u00e9but de la crise (9\/11, puis l&rsquo;Irak aujourd&rsquo;hui), la France n&rsquo;a pas de politique particuli\u00e8re sinon celle de ses principes. Ceux-ci sont r\u00e9affirm\u00e9s de facto. La France n&rsquo;a pas besoin de dire qu&rsquo;elle est contre l&rsquo;attaque de l&rsquo;Irak, cela va de soi et, \u00e9ventuellement, on le dit et on le r\u00e9p\u00e8te pour elle. Cette absence de politique est-elle voulue ou non ? (Une telle absence de politique, si elle \u00e9tait sciemment conduite, pourrait appara\u00eetre comme la plus fine des tactiques.) Elle n&rsquo;est pas voulue, du moins de cette fa\u00e7on d\u00e9lib\u00e9r\u00e9e et calculatrice qui pourrait para\u00eetre machiav\u00e9lique. La France politicienne, intellectuelle et m\u00e9diatique, c&rsquo;est-\u00e0-dire compl\u00e8tement nombriliste, a eu ces derniers mois beaucoup \u00e0 s&rsquo;occuper d&rsquo;elle-m\u00eame, entre les affaires \u00e9lectorales et les affaires tout court, pour trop calculer en mati\u00e8re de politique \u00e9trang\u00e8re.<\/p>\n<\/p>\n<p><p>\t&bull; Mais la France a des principes, un legs de fer donn\u00e9 par de Gaulle, qui se nomment souverainet\u00e9 nationale et ind\u00e9pendance nationale. Par cons\u00e9quent, on interpr\u00e8te sa politique ou sa non-politique pour elle, \u00e0 la lumi\u00e8re de ces principes. Quand un officiel confie \u00e0 une journaliste US que la France va adoucir sa politique vis-\u00e0-vis des USA, la journaliste \u00e9crit de telle fa\u00e7on qu&rsquo;on croit que la France a eu, jusqu&rsquo;ici et conform\u00e9ment \u00e0 ses principes, une politique dure vis-\u00e0-vis des USA qui font pression sur les souverainet\u00e9s et les ind\u00e9pendances nationales. Quand Chirac fait un discours qui r\u00e9affirme la position de la France, la presse britannique en conclut que la France montre les dents d&rsquo;une fa\u00e7on certes remarquable mais conform\u00e9ment \u00e0 ses principes. Tout \u00e7a n&rsquo;existe que parce que la France est aujourd&rsquo;hui, dans le monde occidental (et, sans doute, ailleurs \u00e9galement), le seul pays \u00e0 avoir des principes clairs, intelligibles, \u00e9vidents, pour d\u00e9finir sa position en tant que nation et, par cons\u00e9quent, pour d\u00e9finir les \u00e9vidences de sa politique m\u00eame l\u00e0 o\u00f9 il n&rsquo;y a pas de politique.<\/p>\n<\/p>\n<p><p>\tAu reste, l&rsquo;Am\u00e9rique et la folie irakienne de GW m\u00e9ritent-elle autre chose ? Certains peuvent envisager telle ou telle tactique, pour mod\u00e9rer GW ou l&rsquo;accompagner. Cela occupe les planificateurs mais il ne faut pas trop en attendre quelque effet important que ce soit et, surtout, il ne faut pas trop s&rsquo;y compromettre (voir l&rsquo;\u00e9tat politique de Tony de Blair, qui a cru qu&rsquo;il pourrait avoir une politique dans ce sens). Face \u00e0 l&rsquo;Am\u00e9rique et \u00e0 l&rsquo;Irak, il n&rsquo;y a rien \u00e0 faire aujourd&rsquo;hui que tenir le plus et le mieux possible, comme un bateau doit tenir dans une temp\u00eate, face au grain, et s&rsquo;adapter aux circonstances en prot\u00e9geant ses principes.<\/p>\n<\/p>\n<p><p>\tLa seule politique \u00e0 laquelle la France doit songer, aujourd&rsquo;hui, et avec vigueur, c&rsquo;est \u00e0 une politique europ\u00e9enne. Nous ne sommes pas loin de ce qui pourrait \u00eatre une opportunit\u00e9 exceptionnelle. Les Allemands ont \u00e9t\u00e9 oblig\u00e9s de se mouiller comme jamais, \u00e0 cause des circonstances \u00e9lectorales, et, d\u00e9sormais, Schr\u00f6der et Stoibel font assaut d&rsquo;hostilit\u00e9 \u00e0 l&rsquo;h\u00e9g\u00e9monie am\u00e9ricaine. Les Britanniques sont en dans une situation de plus en plus difficile et vont devoir, \u00e0 un moment ou l&rsquo;autre, l\u00e2cher du lest du c\u00f4t\u00e9 de l&rsquo;Europe pour tenter de regagner le terrain perdu de ce c\u00f4t\u00e9 par une ann\u00e9e d&rsquo;alignement inconditionnel sur Washington. C&rsquo;est le moment pour la France, qui reste la r\u00e9f\u00e9rence de la souverainet\u00e9 et de l&rsquo;ind\u00e9pendance, de se mettre en position comme r\u00e9f\u00e9rence d&rsquo;une politique europ\u00e9enne de s\u00e9curit\u00e9 ind\u00e9pendante, et d&rsquo;exiger des engagements de ses partenaires allemand et britannique.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Question de principes 31 ao\u00fbt 2002 Les Fran\u00e7ais, somme toute, ne sont pas en mauvaise forme. Quelque source, sans doute proche du minist\u00e8re des affaires \u00e9trang\u00e8res, confie \u00e0 Elaine Sciolino, du New York Times et de l&rsquo;IHT (le 29 ao\u00fbt), un soulagement, voire une satisfaction \u00e0 peine secr\u00e8te qui semblent \u00eatre ceux de ses pairs&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[779,2687,3579],"class_list":["post-65236","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-chirac","tag-france","tag-gaullisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65236"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65236\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}