{"id":65251,"date":"2002-09-17T00:00:00","date_gmt":"2002-09-17T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2002\/09\/17\/la-strategie-du-bazar\/"},"modified":"2002-09-17T00:00:00","modified_gmt":"2002-09-17T00:00:00","slug":"la-strategie-du-bazar","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2002\/09\/17\/la-strategie-du-bazar\/","title":{"rendered":"<strong><em>La strat\u00e9gie du bazar<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">La strat\u00e9gie du bazar<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t17 septembre 2002  Iront-ils en guerre ou n&rsquo;iront-ils pas ? Sous quelle forme ? Avec quelle strat\u00e9gie ? Avec quel soutien ? Depuis le 12 septembre (discours de GW), l&rsquo;affaire irakienne est devenue pour une bonne part l&rsquo;affaire de l&rsquo;ONU et celle de la communaut\u00e9 internationale. Inutile de conclure quoi que ce soit, tant la confusion est extr\u00eame, tant les sc\u00e9narios de guerre, les hypoth\u00e8ses d&rsquo;alliance, les propositions de compromis abondent, se croisent et se contredisent ; inutile non plus de se r\u00e9jouir de cet apparent d\u00e9placement vers un pseudo multilat\u00e9ralisme qui n&rsquo;est, de la part des USA, qu&rsquo;une ballade tactique (<a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=376\" class=\"gen\">voir Kagan pour l&rsquo;explication de texte<\/a>).<\/p>\n<\/p>\n<p><p>\tIl faut reconna\u00eetre que la pr\u00e9paration \u00e0 la guerre du Golfe-I pr\u00e9sentait au moins un certain ordre, voire une certaine dignit\u00e9 o\u00f9 l&rsquo;on sentait au moins la tension de la trag\u00e9die \u00e0 venir. Celle-ci, Golfe-II, se pr\u00e9pare dans le d\u00e9sordre le plus complet, d\u00e9sordre intellectuel dans tous les cas, et le reste qui suit, et nous sommes partag\u00e9s entre ce que nous croyons \u00eatre la r\u00e9alit\u00e9 et les diverses virtualit\u00e9s qui composent la pr\u00e9paration de la guerre, entre les sp\u00e9culations guerri\u00e8res et le partage des d\u00e9pouilles.<\/p>\n<\/p>\n<p><p>\tIl faut tout de m\u00eame noter cette r\u00e9alit\u00e9-l\u00e0, que nous nommons la strat\u00e9gie du bazar : la pr\u00e9paration de l&rsquo;apr\u00e8s-Saddam,  c&rsquo;est-\u00e0-dire, essentiellement, le partage du g\u00e2teau p\u00e9trolier de l&rsquo;Irak. D&rsquo;une part, il y a un c\u00f4t\u00e9 peau de l&rsquo;ours puisque, finalement, au cas o\u00f9 on ne l&rsquo;aurait pas not\u00e9, rien n&rsquo;est encore fait. De l&rsquo;autre, il y a une ind\u00e9cence peu banale \u00e0 voir \u00e9tal\u00e9e cette concupiscence \u00e9conomique et p\u00e9troli\u00e8re, \u00e0 lire tous les d\u00e9tails des march\u00e9s et des accords en train de se faire. (Au reste, rien n&rsquo;est fait, r\u00e9p\u00e9tons-le, et cette fois pour les d\u00e9tails des march\u00e9s, et toutes ces pr\u00e9cisions peuvent n&rsquo;\u00eatre, et sont s\u00fbrement pour l&rsquo;essentiel, des sp\u00e9culations vaines et des manoeuvres de d\u00e9sinformation \u00e0 la petite semaine.) Ce qu&rsquo;il nous importe de noter est que cela se dit et s&rsquo;\u00e9crit partout sans soulever d&rsquo;observation s\u00e9rieuse, de protestation substantielle. On parle de la guerre et de ses aspects les plus vils, on parle d&rsquo;un conflit qui, \u00e0 la lumi\u00e8re de ces commentaires, \u00e0 d&rsquo;abord pour but de faire signer quelques contrats, et cela circule dans l&rsquo;indiff\u00e9rence g\u00e9n\u00e9rale.<\/p>\n<\/p>\n<p><p>\tL&rsquo;article <a href=\"http:\/\/www.latimes.com\/templates\/misc\/printstory.jsp?slug=la%2Dfg%2Dbazaar13sep13\" class=\"gen\">du Los Angeles Times du 13 septembre<\/a> donne une excellente mesure de ce qui se dit et se noue, \u00e9ventuellement de ce qui se pr\u00e9pare et se trame si les pr\u00e9visions sont tenues.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>Bush&rsquo;s speech Thursday at the United Nations marked the start of intense behind-the-scenes negotiations to see what inducements will help convert countries that so far have been balking, at least publicly, at joining the anti-Hussein campaign.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>U.S. officials expect the Turks to ask for weapons and debt relief, the Russians and French for access to Iraqi oilfield business, the Qataris for cash to build an air base, and the Jordanians for guarantees of oil and trade. Officials expect many other countries to join the horse trading, and predict that they won&rsquo;t be shy.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Countries in the Middle East take the bazaari approach, said Danielle Pletka, a former Senate aide who now works at the American Enterprise Institute for Public Policy Research. Once they know we want to buy &#8230; the sky&rsquo;s the limit. Said a senior congressional aide, This is a great time to step forward and get something you want from the United States.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tBien \u00e9videmment, la m\u00eame chose se dit et se n\u00e9gocie du c\u00f4t\u00e9 am\u00e9ricain, pour le partage ou la r\u00e9partition pour les soci\u00e9t\u00e9s p\u00e9troli\u00e8res US (avec lesquelles <a href=\"http:\/\/news.independent.co.uk\/world\/politics\/story.jsp?story=333400\" class=\"gen\">beaucoup de dirigeants de l&rsquo;administration ont des liens<\/a>). Les informations g\u00e9n\u00e9rales sur cet aspect des choses sont pr\u00e9sent\u00e9es dans de nombreux articles, dont <a href=\"http:\/\/www.washingtonpost.com\/wp-dyn\/articles\/A18841-2002Sep14.html\" class=\"gen\">celui du Washington Post du 14 septembre<\/a>. Les commentaires, parfois de personnes cit\u00e9es, ne prennent pas de gants, comme on voit ci-dessous, dans l&rsquo;extrait de l&rsquo;article du <em>Post<\/em>, celui de James Woolsey, ancien directeur de la CIA et <em>neo-conservative<\/em> notoire.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>The importance of Iraq&rsquo;s oil has made it potentially one of the administration&rsquo;s biggest bargaining chips in negotiations to win backing from the U.N. Security Council and Western allies for President Bush&rsquo;s call for tough international action against Hussein. All five permanent members of the Security Council &#8212; the United States, Britain, France, Russia and China &#8212; have international oil companies with major stakes in a change of leadership in Baghdad.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>It&rsquo;s pretty straightforward, said former CIA director R. James Woolsey, who has been one of the leading advocates of forcing Hussein from power. France and Russia have oil companies and interests in Iraq. They should be told that if they are of assistance in moving Iraq toward decent government, we&rsquo;ll do the best we can to ensure that the new government and American companies work closely with them. But he added: If they throw in their lot with Saddam, it will be difficult to the point of impossible to persuade the new Iraqi government to work with them.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Indeed, the mere prospect of a new Iraqi government has fanned concerns by non-American oil companies that they will be excluded by the United States, which almost certainly would be the dominant foreign power in Iraq in the aftermath of Hussein&rsquo;s fall. Representatives of many foreign oil concerns have been meeting with leaders of the Iraqi opposition to make their case for a future stake and to sound them out about their intentions.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tToutes ces agitations sont remarquables pour d\u00e9finir le climat \u00e9tabli par cette administration et les conceptions qui l&rsquo;habitent. Lors de Golfe-I, on parla certes du p\u00e9trole, mais d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, \u00e0 la fois strat\u00e9gique et pour l&rsquo;\u00e9conomie am\u00e9ricaine en g\u00e9n\u00e9ral (on se rappelle le \u00ab <MI>jobs, jobs, jobs<D< \u00bb de James Baker, comme r\u00e9ponse \u00e0 une question pos\u00e9e sur les causes de l'engagement US). Cette fois, ce sont les int\u00e9r\u00eats particuliers qui sont \u00e9tal\u00e9s sans la moindre vergogne, sans aucune retenue, sans m\u00eame la conscience de ce que cette situation a d'indigne etc de r\u00e9v\u00e9lateur de l'\u00e9tat d'une soci\u00e9t\u00e9 et d'un syst\u00e8me qui sp\u00e9cule de la sorte. De m\u00eame, les hypoth\u00e8ses d'achat du soutien de l'un ou l'autre membre de l'ONU, comme on achetait les votes \u00e0 la municipalit\u00e9 de Chicago du temps de Capone, a une profonde signification. (On ne peut parler d'accident ou d'exception : la guerre d'Afghanistan est men\u00e9e de cette fa\u00e7on, en achetant le soutien des seigneurs de guerre.) <\/p>\n<\/p>\n<p><p>\tOn a une bonne indication de degr\u00e9, non pas de d\u00e9cadence du syst\u00e8me, mais de sa d\u00e9g\u00e9n\u00e9rescence et de sa perversion. Le cynisme (en g\u00e9n\u00e9ral inconscient, car nous avons affaire \u00e0 des hyst\u00e9riques plus qu&rsquo;\u00e0 des cyniques) va de pair, comme dans cette phrase de Woolsey parlant du nouveau gouvernement, press\u00e9 de r\u00e9partir le g\u00e2teau p\u00e9trolier et manipul\u00e9 par les USA avant m\u00eame d&rsquo;exister, comme d&rsquo;un \u00ab <em> decent government<\/em> \u00bb. <\/p>\n<\/p>\n<p><p>\tIl est difficile de voir dans une structure aussi corrompu un gage d&rsquo;avenir, y compris pour les exp\u00e9ditions coloniales grandioses qu&rsquo;envisagent les grands penseurs martiaux qui fleurissent en son sein, type-Robert Kagan. L&rsquo;Am\u00e9rique actuelle est bien la suite d\u00e9g\u00e9n\u00e9r\u00e9e et enti\u00e8rement pervertie de ce syst\u00e8me  qui a domin\u00e9 la Guerre froide, dont l&rsquo;historien Derek Leebaert, <a href=\"http:\/\/www.amazon.com\/exec\/obidos\/ASIN\/0316518476\/qid=1032235173\/sr=2-1\/ref=sr_2_1\/102-2819633-8308948 \" class=\"gen\">dans son livre Fifty Year Wound<\/a>, \u00e9crit ceci : \u00ab <em>L&rsquo;ascendant de l&rsquo;Am\u00e9rique <\/em>[sur le monde] <em>\u00e9tait celui des enfants de Henry Ford, pas d&rsquo;Andrew Jackson, qui \u00e9taient au travail, cherchant \u00e0 construire un syst\u00e8me, pas un empire. <\/em>[&#8230;] <em>Ce n&rsquo;\u00e9tait pas la domination du monde ; c&rsquo;\u00e9tait une ambivalence domestique. Outre-mer, c&rsquo;\u00e9tait la confusion et l&rsquo;amateurisme.<\/em> \u00bb Les \u00ab <em>enfants d&rsquo;Henry Ford<\/em> \u00bb avaient encore une certaine allure ; ses petits-enfants n&rsquo;ont plus que celle de l&rsquo;actionnaire cupide.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La strat\u00e9gie du bazar 17 septembre 2002 Iront-ils en guerre ou n&rsquo;iront-ils pas ? Sous quelle forme ? Avec quelle strat\u00e9gie ? Avec quel soutien ? Depuis le 12 septembre (discours de GW), l&rsquo;affaire irakienne est devenue pour une bonne part l&rsquo;affaire de l&rsquo;ONU et celle de la communaut\u00e9 internationale. Inutile de conclure quoi que&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3599,857,3600,2804,3598],"class_list":["post-65251","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-bazar","tag-irak","tag-petrole","tag-usa","tag-woolsey"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65251"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65251\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}