{"id":65283,"date":"2002-10-10T00:00:00","date_gmt":"2002-10-10T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2002\/10\/10\/sourde-revolte\/"},"modified":"2002-10-10T00:00:00","modified_gmt":"2002-10-10T00:00:00","slug":"sourde-revolte","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2002\/10\/10\/sourde-revolte\/","title":{"rendered":"<strong><em>Sourde r\u00e9volte<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Sourde r\u00e9volte<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t10 octobre 2002  C&rsquo;est, depuis trois jours, une \u00e9tonnante atmosph\u00e8re. D\u00e9clarations officielles ou semi-officielles, articles de journaux, analyses, etc, allant toutes dans le m\u00eame sens. La situation la plus insolite et la plus grotesque est bien entendu celle o\u00f9 la CIA tente mollement d&rsquo;expliquer comment une lettre qu&rsquo;elle envoie le 7 octobre au Congr\u00e8s ne contredit pas le discours de GW le m\u00eame jour, alors qu&rsquo;elle le contredit effectivement, et de mani\u00e8re flagrante. (<a href=\"http:\/\/www.nytimes.com\/2002\/10\/09\/international\/middleeast\/09IRAQ.html?ex=1035132410&#038;ei=1&#038;en=7ba91cd5310074c6\" class=\"gen\">Le New York Times du 9 octobre 2002 d\u00e9taille les explications de la CIA<\/a>). <\/p>\n<\/p>\n<p><p>\tLes retomb\u00e9es de cette affaire sont d\u00e9j\u00e0 importantes. <a href=\"http:\/\/www.guardian.co.uk\/usa\/story\/0,12271,808970,00.html\" class=\"gen\">Le Guardian du 10 octobre<\/a> en explique la substance :<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em> President George Bush&rsquo;s attempt to maintain public support for military action against Iraq has taken a fresh blow from an unexpected quarter, with the publication of a letter from the CIA stating that while Saddam Hussein poses little threat to America now, a US invasion could push him into retaliating with chemical or biological weapons.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>The unusually detailed public statement, in the form of a letter from the CIA director, George Tenet, to Congress, comes at a highly sensitive moment, potentially damaging Mr Bush&rsquo;s attempt to rally an overwhelming congressional mandate for the use of force against Iraq. In a chilling excerpt, Mr Tenet warned that if Saddam was personally threatened he might seize \u00a0\u00bbhis last chance to exact vengeance by taking a large number of victims with him\u00a0\u00bb. The risk of such an attack, possibly involving weapons of mass destruction, would rise from \u00a0\u00bblow\u00a0\u00bb to \u00a0\u00bbpretty high\u00a0\u00bb were Saddam to feel cornered by US military might.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Such a stark judgment seems likely to increase public anxiety about the prospect of a new war. There is still majority backing for military action, but that support appears to be fading despite a concerted public relations campaign by the administration to put its case.<\/em> \u00bb <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tD&rsquo;une fa\u00e7on plus abrupte, on r\u00e9sumera en observant que GW nous a dit, le 7 octobre, qu&rsquo;il faut attaquer parce que le danger pos\u00e9 par Saddam devient extr\u00eamement grand, voire insupportable. La CIA dit exactement le contraire, que l&rsquo;attaque, justement, peut provoquer des r\u00e9actions de Saddam qui feraient na\u00eetre un danger tr\u00e8s grand. <a href=\"http:\/\/www.nytimes.com\/2002\/10\/09\/international\/middleeast\/09IRAQ.html?ex=1035132410&#038;ei=1&#038;en=7ba91cd5310074c6\" class=\"gen\">L&rsquo;affaire a \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9e par le New York Times du 9 octobre 2002 (d\u00e9j\u00e0 cit\u00e9)<\/a>, dont on retrouve ici la position plut\u00f4t anti-guerre. (Par ailleurs, la presse US est, soit moins nette que le NYT, soit beaucoup plus discr\u00e8te lorsqu&rsquo;il s&rsquo;agit de journaux qui soutiennent la politique de guerre ; signe que cette affaire embarrasse notablement la Maison-Blanche.)<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>The Bush administration pushed Congress today for a broad vote to authorize the president to use force against Iraq. But a new element was injected into the debate by a C.I.A. assessment that Saddam Hussein, while now stopping short of an attack, could become \u00a0\u00bbmuch less constrained\u00a0\u00bb if faced with an American-led force.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The judgment was contained in a letter signed by the deputy C.I.A. director, John McLaughlin, on behalf of George J. Tenet, the director of central intelligence. It was alluded to in a hearing of a Congressional panel investigating the Sept. 11 attacks and then released tonight, after the House opened its debate on Iraq. The letter said \u00a0\u00bbBaghdad for now appears to be drawing a line short of conducting terrorist attacks\u00a0\u00bb with conventional or chemical or biological weapons against the United States.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>\u00a0\u00bbShould Saddam conclude that a U.S.-led attack could no longer be deterred, he probably would become much less constrained in adopting terrorist action,\u00a0\u00bb it continued. It noted that Mr. Hussein could use either conventional terrorism or a weapon of mass destruction as \u00a0\u00bbhis last chance to exact vengeance by taking a large number of victims with him.\u00a0\u00bb<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tD&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, on observe parall\u00e8lement au courrier de la CIA une lev\u00e9e de boucliers contre les arguments de l&rsquo;administration, avanc\u00e9s pour justifier la guerre contre l&rsquo;Irak. Divers articles sont publi\u00e9s dans ce sens, avec attaque g\u00e9n\u00e9ralis\u00e9e contre les arguments avanc\u00e9s par GW lors de son discours du 7, et, en g\u00e9n\u00e9ral, tous les autres arguments de l&rsquo;administration. D\u00e8s le 7 octobre, justement, <a href=\"http:\/\/www.tallahassee.com\/mld\/tallahassee\/news\/politics\/4233223.htm\" class=\"gen\">un article de Warren P. Strobel, Jonathan S. Landay et John Walcott, de Knight Ridder Newspapers<\/a>, avait donn\u00e9 le ton en rapportant diverses confidences d&rsquo;officiels de l&rsquo;administration.<\/p>\n<\/p>\n<p><p>\tLa critique est \u00e0 la fois g\u00e9n\u00e9rale et d\u00e9taill\u00e9e. Il y a par exemple le cas de la citation par Bush, dans son discours, d&rsquo;une soi-disant menace irakienne d&rsquo;un vol d&rsquo;avions sans pilote mena\u00e7ant les USA. L&rsquo;affaire est comment\u00e9e par le <em>Guardian<\/em>, d&rsquo;une mani\u00e8re qui tend \u00e0 montrer qu&rsquo;il s&rsquo;agit d&rsquo;une accusation rocambolesque. Bien \u00e9videmment, une telle capacit\u00e9 d&rsquo;avions sans pilote pouvant effectuer des missions de 10.000 kilom\u00e8tres \u00e0 partir de l&rsquo;Irak est infond\u00e9e, et technologiquement et militairement grotesque.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>In making his case on Monday, Mr Bush made a startling claim that the Iraqi regime was developing drones, or unmanned aerial vehicles (UAVs), which \u00a0\u00bbcould be used to disperse chemical or biological weapons across broad areas\u00a0\u00bb. \u00a0\u00bbWe&rsquo;re concerned that Iraq is exploring ways of using these UAVs for missions targeting the United States,\u00a0\u00bb he warned.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>US military experts confirmed that Iraq had been converting eastern European trainer jets, known as L-29s, into drones, but said that with a maximum range of a few hundred miles they were no threat to targets in the US. \u00a0\u00bbIt doesn&rsquo;t make any sense to me if he meant United States territory,\u00a0\u00bb said Stephen Baker, a retired US navy rear admiral who assesses Iraqi military capabilities at the Washington-based Centre for Defence Information.<\/em> \u00bb <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tLa situation au coeur de cette pol\u00e9mique est bien connue, avec les d\u00e9tournements et les falsifications de renseignement suscit\u00e9s par un pouvoir politique. Ce qu&rsquo;il y a de particulier aujourd&rsquo;hui, c&rsquo;est l&rsquo;ampleur de la manipulation pour obtenir des renseignements convenables pour la cause de la Maison-Blanche, qui semble sans gu\u00e8re de pr\u00e9c\u00e9dent.<\/p>\n<\/p>\n<p><p>\tSelon l&rsquo;ancien chef du contre-espionnage \u00e0 la CIA, Vincent Cannistraro, \u00ab <em>the flow of intelligence to the top levels of the administration had been deliberately skewed by hawks at the Pentagon. CIA assessments are being put aside by the defence department in favour of intelligence they are getting from various Iraqi exiles. Machiavelli warned princes against listening to exiles. Well, that is what is happening now\u00a0\u00bb<\/em> \u00bb. Certaines sources estiment que le fameux d\u00e9partement de l&rsquo;OSI (Office of Strategic Influence) est en plein travail sur cette affaire, pour fabriquer des preuves de toutes sortes. (Il y avait eu  <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=102\" class=\"gen\">une br\u00e8ve pol\u00e9mique en f\u00e9vrier<\/a>, lorsqu&rsquo;on avait appris la cr\u00e9ation de l&rsquo;OSI. Rumsfeld avait du annoncer sa suppression, mais nombre de commentateurs estim\u00e8rent que l&rsquo;OSI subsistait, sous une autre appellation ou d&rsquo;une fa\u00e7on camoufl\u00e9e. C&rsquo;est \u00e9videmment le cas.)<\/p>\n<\/p>\n<p><p>\tD&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, on conclura qu&rsquo;il y a l\u00e0 les signes d&rsquo;une sorte de r\u00e9volte dans la bureaucratie, notamment \u00e0 la CIA ; et aussi, certaines attitudes de prudence pour plus tard. R\u00e9volte contre la falsification et la manipulation auxquelles certains services ou certaines individualit\u00e9s dans la bureaucratie de s\u00e9curit\u00e9 nationale sont forc\u00e9s \u00e0 participer ; prudence prospective de certains, notamment des chefs de la CIA, avec une volont\u00e9 de se d\u00e9marquer officiellement des positions de l&rsquo;administration, pour pouvoir argumenter demain \u00e0 partir de leurs prises de position indirectement publiques d&rsquo;aujourd&rsquo;hui, si l&rsquo;affaire irakienne tourne mal et si des comptes leur sont demand\u00e9s.<\/p>\n<\/p>\n<p><p>\tOn peut voir dans ces divers cas un signe g\u00e9n\u00e9ral que l&rsquo;administration GW est au bout de ses capacit\u00e9s dans ce qu&rsquo;elle peut demander en fait de manipulations et autres \u00e0 sa bureaucratie. Certaines circonstances (la poursuite des manipulations sur une \u00e9chelle consid\u00e9rable ou des incidents s\u00e9rieux sur le terrain ou lors des op\u00e9rations) pourraient faire \u00e9clater cette sorte de r\u00e9volte de la bureaucratie \u00e0 visages un peu plus d\u00e9couverts, jusqu&rsquo;\u00e0 susciter les risques d&rsquo;une crise interne. En attendant, la cause de la guerre contre l&rsquo;Irak ne cesse de se couturer de nombreuses cicatrices et appara\u00eet de plus en plus comme une cause bancale, qu&rsquo;il va devenir extr\u00eamement difficile de pr\u00e9senter d&rsquo;une mani\u00e8re acceptable au niveau m\u00e9diatique.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sourde r\u00e9volte 10 octobre 2002 C&rsquo;est, depuis trois jours, une \u00e9tonnante atmosph\u00e8re. D\u00e9clarations officielles ou semi-officielles, articles de journaux, analyses, etc, allant toutes dans le m\u00eame sens. La situation la plus insolite et la plus grotesque est bien entendu celle o\u00f9 la CIA tente mollement d&rsquo;expliquer comment une lettre qu&rsquo;elle envoie le 7 octobre au&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3104,3198,857],"class_list":["post-65283","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-cia","tag-gw","tag-irak"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65283"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65283\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}