{"id":65336,"date":"2002-11-12T00:00:00","date_gmt":"2002-11-12T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2002\/11\/12\/triple-langage\/"},"modified":"2002-11-12T00:00:00","modified_gmt":"2002-11-12T00:00:00","slug":"triple-langage","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2002\/11\/12\/triple-langage\/","title":{"rendered":"Triple langage"},"content":{"rendered":"<p><h2 class=\"common-article\">Triple langage<\/h2>\n<\/p>\n<p><p>\t11 novembre 2002  Depuis longtemps, depuis que le concept de communication (et, par cons\u00e9quent, celui de propagande) existe, depuis plus avant encore, la question du double langage a exist\u00e9 : deux langages avec celui de la r\u00e9alit\u00e9 et celui de sa transcription officielle, qui va de la transformation \u00e0 la manipulation, \u00e0 la disparition, pour des raisons de bonnes mani\u00e8res, de conformisme, de propagande, voire d&rsquo;humanit\u00e9. Notre \u00e9poque a d\u00e9pass\u00e9 ce stade. Il existe d\u00e9sormais un triple langage, ou, dit autrement, deux syst\u00e8mes de double langage superpos\u00e9s. Un deuxi\u00e8me double langage s&rsquo;est superpos\u00e9 au premier (le double langage utilis\u00e9 par les dirigeants officiels et les \u00e9lites \u00e0 l&rsquo;intention de l&rsquo;opinion publique).<\/p>\n<\/p>\n<p><p>\tUn tr\u00e8s r\u00e9cent exemple se trouve dans les d\u00e9clarations de Valery Giscard d&rsquo;Estaing, pr\u00e9sident de la Convention europ\u00e9enne, \u00e0 propos de l&rsquo;adh\u00e9sion de la Turquie. On ne peut mieux dire \u00e0 ce propos que <LIEN=http:\/\/news.independent.co.uk\/europe\/story.jsp?story=350277ce qu'\u00e9crit The Independent du 9 novembre<D> , en faisant se succ\u00e9der deux paragraphe, l&rsquo;un commen\u00e7ant par : \u00ab <em>The comments were rapidly disowned&#8230;<\/em> \u00bb ; et le suivant par : \u00ab <em>Nevertheless, his sentiments reflect the private views of many European politicians<\/em> \u00bb. Les deux paragraphes en entier :<\/p>\n<\/p>\n<p><p>\t\u00ab <em>The comments were rapidly disowned by the European Commission and even by M. Giscard&rsquo;s vice-president on his 105-strong convention into the future of Europe. Pat Cox, the president of the European Parliament, described M. Giscard&rsquo;s contribution as unhelpful and ill-advised.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Nevertheless, his [Giscard&rsquo;s] sentiments reflect the private views of many European politicians and illustrate that opposition to Turkish membership runs deep. While M. Giscard has no formal say on the issue, his words are certain to polarise views ahead of a crucial summit next month when European leaders must decide what to do about Turkey&rsquo;s application.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tCeci est caract\u00e9ristique : dans la d\u00e9claration de VGE, on met exclusivement en cause la transgression du deuxi\u00e8me double langage, celui qui existe entre hommes politiques, fonctionnaires, bureaucrates, experts, etc, de groupes de pays diff\u00e9rents, de pays diff\u00e9rents, de partis \u00e0 l&rsquo;int\u00e9rieur d&rsquo;un pays, etc. (Par contre, l&rsquo;indiff\u00e9rence a l&rsquo;air d&rsquo;\u00eatre compl\u00e8te, dans ces commentaires, vis-\u00e0-vis du premier double langage, l&rsquo;original et l&rsquo;originel, entre les dirigeants politiques et l&rsquo;opinion publique ; on a l&rsquo;air en g\u00e9n\u00e9ral d&rsquo;avoir peu d&rsquo;int\u00e9r\u00eat pour le fait que la d\u00e9claration de Giscard va \u00e0 l&rsquo;encontre de la dialectique officielle vis-\u00e0-vis du public, qui est de ne pas rejeter la candidature de la Turquie.)<\/p>\n<\/p>\n<p><p>\tLe second double langage se caract\u00e9rise \u00e9galement par le fait qu&rsquo;il ne concerne pas les positions officielles des forces constitu\u00e9es (VGE est alors l&rsquo;exemple extr\u00eame puisqu&rsquo;il empi\u00e8te sur ce domaine des r\u00e9actions officielles, mais il n&rsquo;est pas un repr\u00e9sentant officiel d&rsquo;une force constitu\u00e9e). Il concerne les contacts, m\u00eame officieux, entre ces hommes politiques, fonctionnaires, bureaucrates, experts. Dans des r\u00e9unions informelles interservices, \u00e0 l&rsquo;int\u00e9rieur d&rsquo;institutions internationales (surtout), voire entre minist\u00e8res nationaux ou \u00e0 l&rsquo;int\u00e9rieur de ces minist\u00e8res, dans des s\u00e9minaires, etc, il est des choses qu&rsquo;on ne peut pas dire selon ce double langage. Il y a par exemple le domaine des tabous europ\u00e9ens (il est quasiment impensable d&rsquo;affirmer que l&rsquo;\u00e9largissement est, en plus d&rsquo;\u00eatre hautement contestable d&rsquo;un point de vue politique et institutionnel, une absurdit\u00e9 technique qui risque de conduire \u00e0 des situations graves) ; et, surtout, il y a notre favori, le domaine du jugement trop critique de la politique am\u00e9ricaine (la politique irakienne, la guerre contre la terreur, etc), qui constitue le risque le plus grave de d\u00e9rogation au deuxi\u00e8me double langage.<\/p>\n<\/p>\n<p><p>\tCe ph\u00e9nom\u00e8ne du deuxi\u00e8me double langage est extr\u00eamement p\u00e9nalisant parce qu&rsquo;il emp\u00eache de faire des politiques selon des r\u00e9alit\u00e9s, de n\u00e9gocier sur les r\u00e9alit\u00e9s, d&rsquo;analyser les r\u00e9alit\u00e9s. Il est pour beaucoup dans les diverses paralysies, lenteurs, vell\u00e9it\u00e9s observ\u00e9es dans notre \u00e9poque, dans nos politiques ext\u00e9rieures. Sur ce point pr\u00e9cis des relations Europe-USA, notre opinion est que la position de suj\u00e9tion actuelle de l&rsquo;Europe vis-\u00e0-vis des USA vient beaucoup plus, voire pour l&rsquo;essentiel, de ce double langage emp\u00eachant d&rsquo;aborder ce probl\u00e8me, que de la capacit\u00e9 de l&rsquo;Europe \u00e0 \u00e9carter cette position de suj\u00e9tion, ou que de la volont\u00e9 politique de l&rsquo;Europe de faire ce choix. (En 1993, quand la Cellule de planification de l&rsquo;UEO tentait de faire un d\u00e9compte des unit\u00e9s des pays europ\u00e9ens susceptibles d&rsquo;\u00eatre affect\u00e9es \u00e0 une force europ\u00e9enne, le g\u00e9n\u00e9ral commandant adjoint de cette Cellule nous avait rapport\u00e9 que les difficult\u00e9s \u00e0 obtenir ces pr\u00e9cisions venaient \u00ab <em>\u00e0 95% des conformismes et r\u00e9sistances bureaucratiques qui s&rsquo;expriment par un refus implicite de discuter de certains probl\u00e8mes, et \u00e0 5% des positions politiques hostiles \u00e0 une force europ\u00e9enne<\/em> \u00bb C&rsquo;est effectivement dans la cat\u00e9gorie du deuxi\u00e8me double langage qu&rsquo;il faut classer cette situation du refus de \u00ab <em>discuter de certains probl\u00e8mes<\/em> \u00bb.) <\/p>\n<\/p>\n<p><p>\tPour ce qui est de l&rsquo;explication conjoncturelle, ces pratiques sont une cons\u00e9quence du syst\u00e8me actuel d&rsquo;alliance de moins en moins consenties et de plus en plus impos\u00e9es, notamment avec les USA et \u00e0 l&rsquo;int\u00e9rieur de syst\u00e8mes contr\u00f4l\u00e9s par les USA. Ces ensembles r\u00e9pondaient \u00e0 une coh\u00e9rence et \u00e0 une n\u00e9cessit\u00e9 avouables du temps de la Guerre froide, o\u00f9 l&rsquo;on en \u00e9tait encore aux bribes de cette triple langue de bois, o\u00f9 l&rsquo;on se disait encore droitement les choses dans les rencontres officieuses entre alli\u00e9s. Aujourd&rsquo;hui o\u00f9 les raisons de ces alliances sont beaucoup plus faibles voire inexistantes, ou bien, et, surtout, inavouables, le deuxi\u00e8me double langage, la deuxi\u00e8me langue de bois fonctionne \u00e0 plein r\u00e9gime.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Triple langage 11 novembre 2002 Depuis longtemps, depuis que le concept de communication (et, par cons\u00e9quent, celui de propagande) existe, depuis plus avant encore, la question du double langage a exist\u00e9 : deux langages avec celui de la r\u00e9alit\u00e9 et celui de sa transcription officielle, qui va de la transformation \u00e0 la manipulation, \u00e0 la&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3695,2631,3696,398,2648,3694,2613,3693],"class_list":["post-65336","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-bois","tag-de","tag-double","tag-europe","tag-langage","tag-langue","tag-turquie","tag-vge"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65336"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65336\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}