{"id":65348,"date":"2002-11-21T00:00:00","date_gmt":"2002-11-21T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2002\/11\/21\/more-confortable-avec-le-jsf\/"},"modified":"2002-11-21T00:00:00","modified_gmt":"2002-11-21T00:00:00","slug":"more-confortable-avec-le-jsf","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2002\/11\/21\/more-confortable-avec-le-jsf\/","title":{"rendered":"<strong><em>\u201cMore confortable\u201d avec le JSF<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">More confortable avec le JSF<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t21 novembre 2002  La d\u00e9monstration pr\u00e9c\u00e9derait presque le soup\u00e7on &#8230;  Nous avions \u00e9voqu\u00e9 la chose dans diff\u00e9rents analyses sur le JSF,  mais qu&rsquo;elle soit confirm\u00e9e, et m\u00eame document\u00e9e au-del\u00e0 de toute attente, si vite, dans des termes si d\u00e9pourvus d&rsquo;ambigu\u00eft\u00e9, d&rsquo;une fa\u00e7on si fondamentalement et, sans aucun doute, si ing\u00e9nument cynique (d\u00e9finition de cynisme, pour que nul n&rsquo;en ignore et n&rsquo;aille se perdre dans d&rsquo;inutiles proc\u00e8s d&rsquo;intention : \u00ab <em>M\u00e9pris des convenances, de l&rsquo;opinion, de la morale qui pousse \u00e0 l&rsquo;effronterie ou \u00e0 l&rsquo;impudence<\/em> \u00bb).<\/p>\n<\/p>\n<p><p>\tCi-dessous, voici un entrefilet de la publication <em>Northern Echo<\/em>, un magazine r\u00e9gional britannique (du Yorkshire). Il concerne le futur porte-avions britannique et la question de l&rsquo;offre faite par un consortium conduit par Thal\u00e9s. Il s&rsquo;intitule : \u00ab <em>French out of favour to build new ships<\/em> \u00bb, \u00e0 la date du 18 novembre 2002.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>A French bid to build two Royal Navy aircraft carriers may be scuppered because the US government would rather share technology with a British company.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>French defence group Thales is bidding against the UK&rsquo;s BAE Systems for a \u00a32.9m contract for two 60,000 tonne ships.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Both companies are planning a modular design, and both would spread work around a number of British shipyards including in the North-East, before final assembly in Scotland.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Now, senior Pentagon sources have indicated they would be more comfortable sharing US technology on the vertical take-off stealth Joint Strike Fighter being flown from the carriers with a British company, than with a French one.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>It is understood that officials from the US Navy have made their views known to senior Royal Navy officials in the Ministry of Defence.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>A Pentagon source said: On both a security and a commercial basis, we would be more comfortable sharing the technology with the British, rather than the French. However, there is some technology that is so sensitive that we are not very keen to share it with anyone.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>A spokesman for Thales, which employs 12,000 people in the UK, said the company was a trusted supplier which already worked with the MoD in highly sensitive areas such as electronic warfare and data transfer. The bid team includes the fighter&rsquo;s makers Lockheed Martin, the spokesman added.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tCela fait beaucoup de confirmations en quelques lignes :<\/p>\n<\/p>\n<p><p>\t&bull; Le JSF est <em>off limits<\/em>. Tout ce qui touche de pr\u00e8s ou de loin au JSF devra \u00eatre sous contr\u00f4le am\u00e9ricain. Ainsi, un programme de deux porte-avions britanniques, parce que ces deux navires devraient porter le JSF dans sa version ADAC\/V, devra d\u00e9pendre dans la d\u00e9cision ultime du choix du contractant pour sa production de l&rsquo;accord de l&rsquo;U.S. Navy.<\/p>\n<\/p>\n<p><p>\t&bull; La technologie du JSF sera partag\u00e9e par paliers, selon les notations de s\u00e9curit\u00e9 donn\u00e9e aux participants\/acheteurs : certains auront peu, d&rsquo;autres un peu plus ; les Britanniques auront beaucoup, mais sur la base exclusive de rester totalement dans les mains britanniques (et am\u00e9ricaines).<\/p>\n<\/p>\n<p><p>\t&bull; &#8230; N\u00e9anmoins,  et la pr\u00e9cision est bienvenue, l\u00e0 aussi la confirmation pr\u00e9c\u00e9dant le soup\u00e7on clairement affirm\u00e9 : m\u00eame les Britanniques n&rsquo;auront pas tout et il y a des technologies qui ne sortiront pas des USA. Aucun d\u00e9tail sur ces technologies exclusives.<\/p>\n<\/p>\n<p><p>\t(On consultera sur le site divers textes et analyses sur la question du JSF, aussi bien concernant <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=78\" class=\"gen\">l&rsquo;entr\u00e9e des Britanniques dans le programme<\/a> que la question du JSF en g\u00e9n\u00e9ral, par rapport \u00e0 la probl\u00e9matique europ\u00e9enne expos\u00e9e pendant <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=93\" class=\"gen\">le (faible) d\u00e9bat aux Pays-Bas sur la question d&rsquo;entrer dans le programme<\/a> et, \u00e9galement, le 15 f\u00e9vrier dernier, <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=94\" class=\"gen\">\u00e0 l&rsquo;occasion du choix n\u00e9erlandais<\/a> d&rsquo;entrer dans le programme. Dans toutes ces analyses, on trouvera d&rsquo;autres liens conduisant \u00e0 d&rsquo;autres textes sur le sujet.)<\/p>\n<\/p>\n<p><p>\tLe JSF est donc bien le programme fameux qu&rsquo;on a d\u00e9j\u00e0 commenc\u00e9 \u00e0 d\u00e9crire. Il pose toutes les questions importantes de la s\u00e9curit\u00e9 nationale. Aux Britanniques, il pose la question de savoir si leur engagement pro-am\u00e9ricain est bien <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=327\" class=\"gen\">la meilleure voie du renforcement de la souverainet\u00e9 nationale,<\/a> comme doit l&rsquo;\u00eatre toute acquisition de mat\u00e9riels militaires nouveaux ; il leur pose \u00e9galement la question de savoir si la coop\u00e9ration avec les Am\u00e9ricains n&rsquo;est pas un obstacle infranchissable \u00e0 toute coop\u00e9ration europ\u00e9enne sur les questions d&rsquo;armement, et particuli\u00e8rement avec les Fran\u00e7ais. Pourquoi, avec les Fran\u00e7ais ? R\u00e9ponse ci-dessous, de Denis MacShane.<\/p>\n<\/p>\n<p><\/p>\n<h3>Post-Scriptum : quelques mots d&rsquo;encouragement, \u00ab more confortable \u00bb en un sens, du ministre des Affaires europ\u00e9ennes Denis MacShane<\/h3>\n<\/p>\n<p><p>\tIl y a dix jours, dans <em>Le Figaro<\/em> du 11 novembre, le ministre britannique des Affaires europ\u00e9ennes \u00e9tait interview\u00e9 (titre : \u00ab <em>L&rsquo;Europe ne doit pas se transformer en une sorte d&rsquo;\u00e9picerie<\/em> \u00bb).<\/p>\n<\/p>\n<p><p>\tDennis MacShane affirme que l&rsquo;Europe de la d\u00e9fense est plus que jamais n\u00e9cessaire, et surtout pour Fran\u00e7ais et Britanniques : \u00ab <em>Voici le domaine par excellence o\u00f9 France et Royaume-Uni se doivent de coop\u00e9rer de mani\u00e8re intensive.<\/em> \u00bb Apr\u00e8s 5 questions insistantes du journaliste sur ce th\u00e8me auxquelles MacShane r\u00e9pond par l&rsquo;exaltation des liens de coop\u00e9ration entre Britanniques et Fran\u00e7ais, le ministre britannique tranche, en se r\u00e9f\u00e9rant au sommet franco-anglais de Saint-Malo qui relan\u00e7a la coop\u00e9ration militaire entre les deux pays en d\u00e9cembre 1998 : \u00ab <em>Non seulement <\/em>[l&rsquo;esprit de Saint-Malo] <em>est vivant, mais il est essentiel. Incontournable.<\/em> \u00bb<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>More confortable avec le JSF 21 novembre 2002 La d\u00e9monstration pr\u00e9c\u00e9derait presque le soup\u00e7on &#8230; Nous avions \u00e9voqu\u00e9 la chose dans diff\u00e9rents analyses sur le JSF, mais qu&rsquo;elle soit confirm\u00e9e, et m\u00eame document\u00e9e au-del\u00e0 de toute attente, si vite, dans des termes si d\u00e9pourvus d&rsquo;ambigu\u00eft\u00e9, d&rsquo;une fa\u00e7on si fondamentalement et, sans aucun doute, si ing\u00e9nument&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3703,3158,250,3705,3704],"class_list":["post-65348","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-britanniques","tag-francais","tag-jsf","tag-macshane","tag-porte-avions"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65348"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65348\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}