{"id":65384,"date":"2002-12-16T00:00:00","date_gmt":"2002-12-16T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2002\/12\/16\/beyond-history\/"},"modified":"2002-12-16T00:00:00","modified_gmt":"2002-12-16T00:00:00","slug":"beyond-history","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2002\/12\/16\/beyond-history\/","title":{"rendered":"<strong><em>\u00abBeyond History&#8230;\u00bb<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">\u00abBeyond History&#8230;\u00bb<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t16 d\u00e9cembre 2002  Un article de <em>The Independent<\/em>, en date du 15 d\u00e9cembre 2002, <a href=\"http:\/\/news.independent.co.uk\/world\/americas\/story.jsp?story=361736\" class=\"gen\">pr\u00e9sente les armes-miracle qui vont \u00eatre employ\u00e9es contre l&rsquo;Irak,<\/a> dans le conflit imminent qui va \u00e9videmment avoir lieu. \u00c9videmment, il s&rsquo;agit d&rsquo;armes am\u00e9ricaines. Une fois de plus, le conflit va r\u00e9volutionner l&rsquo;art de la guerre. Ce fut le cas en 1991 (Golfe), en 1995 (Bosnie), en 1999 (Kosovo), en 2001 (Afghanistan). A chaque fois, le monde, \u00e9videmment \u00e9poustoufl\u00e9, est convi\u00e9 \u00e0 s&rsquo;exclamer devant une nouvelle limite repouss\u00e9e dans la ma\u00eetrise quasiment surr\u00e9aliste de la guerre \u00e9lectronique, technologique et postmoderne. Cette fois ne d\u00e9mentira pas le reste : on nous promet un conflit si rapide que l&rsquo;ONU aura \u00e0 peine le temps de ne pas voter ou de voter biebn, selon la ligne g\u00e9n\u00e9rale.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>The American weaponry likely to be deployed in any military strike against Iraq is so advanced and hi-tech that some was not even ready to be used in the operation in Afghanistan just 12 months ago.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>With an armoury including satellite imagery that can distinguish a tank from a bus, even through thick cloud, to microwave bombs that can destroy electrical and computer systems without hurting civilians, military planners preparing for war are confident that any strike would be completed in little more than a week.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The first Gulf War was fought like the Second World War, with air dominance  pounding their defences, softening up the forces and then going in, said Daniel Gour\u00e9, a military analyst with the Washington-based Lexington Institute think tank. This will be speedier, more precise  an effects-based operation. It will be much more surgical, both in the use of explosive force and in the overall operation.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tSuit la description plus pr\u00e9cise des nouvelles armes-miracle. Elles sont toutes pr\u00e9sent\u00e9es comme devant instaurer des conditions compl\u00e8tement nouvelles dans le conflit qui se pr\u00e9pare ; des conditions si nouvelles que ce conflit, plus qu&rsquo;un conflit qui serait un banc d&rsquo;essai pour de nouvelles armes (une sorte de ni\u00e8me guerre d&rsquo;Espagne), appara\u00eet comme devant \u00eatre l&rsquo;accomplissement d&rsquo;une sup\u00e9riorit\u00e9 non seulement militaire et technologique, mais quasiment d&rsquo;une sup\u00e9riorit\u00e9 de civilisation.<\/p>\n<\/p>\n<p><p>\tL&rsquo;\u00e9tat d&rsquo;esprit qui pr\u00e9side \u00e0 cette pr\u00e9sentation laisse augurer du langage qui sera employ\u00e9 et de l&rsquo;interpr\u00e9tation qui sera donn\u00e9 de ce conflit. Aucune r\u00e9f\u00e9rence n&rsquo;est faite aux \u00e9vidents travers de l&#8217;emploi de ces armes dans cette sorte de conflits, <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=433\" class=\"gen\">que ce soit les travers directs,<\/a> avec les pertes colat\u00e9rales paradoxalement d\u00fbes \u00e0 la tr\u00e8s grande pr\u00e9cision de ces syst\u00e8mes (ce que <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=198\" class=\"gen\">nous avons nomm\u00e9 les erreurs de grande pr\u00e9cision<\/a>) ; que ce soit les travers g\u00e9n\u00e9raux, avec les tactiques utilis\u00e9es, qui impliquent d&rsquo;\u00e9carter <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=284\" class=\"gen\">toute sorte de travail d&rsquo;engagement terrestre et de pacification.<\/a> (La guerre d&rsquo;Afghanistan a vu succ\u00e9der \u00e0 une victoire ultra-rapide un d\u00e9sordre larv\u00e9 qui est maintenant structurel et fait du territoire afghan, \u00e0 part la vitrine de Kaboul, un territoire incontr\u00f4l\u00e9 aux mains de divers groupes de seigneurs de la guerre, de chefs locaux, de bandes diverses.)<\/p>\n<\/p>\n<p><p>\tLe plus int\u00e9ressant et le plus notable se trouve dans cet \u00e9tat d&rsquo;esprit sur la guerre nouvelle qu&rsquo;on nous annonce, cette dialectique enivr\u00e9e et exalt\u00e9e qui rejoint <em>de facto<\/em> dans son intensit\u00e9 un autre \u00e9pisode am\u00e9ricain tr\u00e8s r\u00e9cent. Le 10 juin 1998, le directeur de la Federal Reserve Alan Greenspan t\u00e9moignait devant le Congr\u00e8s sur les questions \u00e9conomiques. Il mentionna explicitement l&rsquo;existence d&rsquo;une \u00e9cole d&rsquo;\u00e9conomistes qui consid\u00e9rait sans la moindre r\u00e9serve que le <em>boom<\/em> boursier qui battait alors son plein, ainsi que l&rsquo;enrichissement qui se poursuivait \u00e0 un rythme acc\u00e9l\u00e9r\u00e9, ressortaient d&rsquo;une nouvelle \u00e9conomie qui s&rsquo;\u00e9tait d\u00e9gag\u00e9e des r\u00e8gles (des contraintes) de l&rsquo;Histoire : une nouvelle \u00e9conomie \u00ab <em>beyond history<\/em> \u00bb. Greenspan pr\u00e9cisait qu&rsquo;il ne croyait pas \u00e0 cette th\u00e9orie mais sa pr\u00e9sentation devant le Congr\u00e8s lui donnait la caution d&rsquo;une appr\u00e9ciation de s\u00e9rieux. C&rsquo;est effectivement l&rsquo;impression que donna l&rsquo;Am\u00e9rique de Wall Street pendant cette p\u00e9riode, d&rsquo;une Am\u00e9rique qui s&rsquo;\u00e9tait install\u00e9e dans une p\u00e9riode post-historique, affranchie des r\u00e8gles et de contraintes de l&rsquo;Histoire,  \u00ab <em>beyond history<\/em> \u00bb.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est la m\u00eame impression qu&rsquo;on \u00e9prouve devant le <em>decorum<\/em> et l&rsquo;appr\u00e9ciation intellectuelle qui sont en train de s&rsquo;installer autour du conflit irakien, lequel qui semble \u00eatre d\u00e9cortiqu\u00e9, pes\u00e9, comment\u00e9, \u00e9largi, prolong\u00e9, etc, avant m\u00eame qu&rsquo;il soit fait et avant m\u00eame qu&rsquo;on ait trouv\u00e9 et fabriqu\u00e9 de toutes pi\u00e8ces un <em>casus belli<\/em> pour le faire. C&rsquo;est un conflit d\u00e9sormais parfaitement \u00ab <em>beyond history<\/em> \u00bb. Cette situation montre que l&rsquo;exaltation am\u00e9ricaniste du temps de Clinton, exaltation quasiment de type m\u00e9taphysique, s&rsquo;est accrue et renforc\u00e9e pour toucher les mati\u00e8res militaires et strat\u00e9giques, c&rsquo;est-\u00e0-dire la mati\u00e8res expansionniste et imp\u00e9rialiste par excellence. (L&rsquo;interpr\u00e9tation \u00e9conomiste de cette fi\u00e8vre m\u00e9taphysique pouvait encore \u00eatre consid\u00e9r\u00e9e comme int\u00e9rieure, m\u00eame si les ramifications de l&rsquo;\u00e9conomie boursi\u00e8re US sont internationales.) La future guerre contre l&rsquo;Irak \u00e9chappe d\u00e9j\u00e0 \u00e0 l&rsquo;Histoire, pour mettre en \u00e9vidence, cette fois de fa\u00e7on d\u00e9finitive comme \u00e0 chaque fois, que l&rsquo;Am\u00e9rique exceptionnelle a ma\u00eetris\u00e9 et bris\u00e9 l&rsquo;histoire courante (celle de nous tous) pour s&rsquo;installer \u00ab <em>beyond history<\/em> \u00bb &#8230;<\/p>\n<\/p>\n<p><p>\tChacun fera ce qu&rsquo;il veut de la poursuite \u00e0 son terme de l&rsquo;analogie : on sait que la nouvelle \u00e9conomie \u00ab <em>beyond history<\/em> \u00bb qui devait installer une histoire diff\u00e9rente, qui devait \u00eatre essentiellement une non-histoire apr\u00e8s que l&rsquo;Am\u00e9rique ait ma\u00eetris\u00e9e l&rsquo;histoire commune \u00e0 tous, s&rsquo;est termin\u00e9e brutalement en avril 2000 avec le d\u00e9but de l&rsquo;effondrement boursier. Aujourd&rsquo;hui, on n&rsquo;en parle plus gu\u00e8re.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abBeyond History&#8230;\u00bb 16 d\u00e9cembre 2002 Un article de The Independent, en date du 15 d\u00e9cembre 2002, pr\u00e9sente les armes-miracle qui vont \u00eatre employ\u00e9es contre l&rsquo;Irak, dans le conflit imminent qui va \u00e9videmment avoir lieu. \u00c9videmment, il s&rsquo;agit d&rsquo;armes am\u00e9ricaines. Une fois de plus, le conflit va r\u00e9volutionner l&rsquo;art de la guerre. Ce fut le cas&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[2947,857,3519],"class_list":["post-65384","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-amerique","tag-irak","tag-technologie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65384"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65384\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}