{"id":65461,"date":"2003-02-07T00:00:00","date_gmt":"2003-02-07T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2003\/02\/07\/notre-drole-davant-guerre-rubrique-contexte-volume-18-n08-du-10-janvier-2003\/"},"modified":"2003-02-07T00:00:00","modified_gmt":"2003-02-07T00:00:00","slug":"notre-drole-davant-guerre-rubrique-contexte-volume-18-n08-du-10-janvier-2003","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2003\/02\/07\/notre-drole-davant-guerre-rubrique-contexte-volume-18-n08-du-10-janvier-2003\/","title":{"rendered":"<strong><em>Notre dr\u00f4le d&rsquo;avant-guerre<\/em><\/strong> \u2014 Rubrique Contexte, Volume 18 n\u00b008 du 10 janvier 2003"},"content":{"rendered":"<p><h3>Notre dr\u00f4le d&rsquo;avant-guerre  Rubrique Contexte, Volume 18 n\u00b008 du 10 janvier 2003<\/h3>\n<\/p>\n<p><p>\tDans ce num\u00e9ro du d\u00e9but de l&rsquo;ann\u00e9e 2003, cette r\u00e9flexion sur la guerre qui nous attend et les effets qu&rsquo;on pourrait pr\u00e9voir, non sur le th\u00e9\u00e2tre de la guerre ou sur la situation politique, mais sur notre psychologie.<\/p>\n<\/p>\n<p><p>\tCela dure depuis 14 mois : une guerre pr\u00e9par\u00e9e, annonc\u00e9e, planifi\u00e9e de sang-froid, contre un pays affaibli et \u00e9cras\u00e9 comme par avance, au son d&rsquo;une recherche cynique d&rsquo;un casus belli qui permette de pr\u00e9texter l&rsquo;attaque. Voil\u00e0 les conditions de la r\u00e9alit\u00e9, celles qui ne sont pas dites, qui n&rsquo;apparaissent pas dans les discours id\u00e9ologique, mais qui ne cessent de peser sur notre psychologie (parlons de cela, laissons le mot conscience de c\u00f4t\u00e9). Notre psychologie subira le terrible contre-coup de cette \u00e9preuve. Quelle que soit la rapidit\u00e9 de notre victoire, la puissance de leur d\u00e9faite, le caract\u00e8re irr\u00e9sistible de la force qui les soumettra, il faut savoir que nous, Occidentaux, nous n&rsquo;en sortirons pas indemnes.<\/p>\n<\/p>\n<p><\/p>\n<h2 class=\"common-article\">Notre dr\u00f4le d&rsquo;avant-guerre<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\tComme \u00e0 l&rsquo;habitude, commen\u00e7ons par les r\u00e9serves d&rsquo;usage assorties des contre-r\u00e9serves \u00e9galement d&rsquo;usage.<\/p>\n<\/p>\n<p><p>\t&bull; Saddam est un dictateur peu fr\u00e9quentable qui m\u00e9riterait d&rsquo;\u00eatre chass\u00e9 du pouvoir. Pour autant, il n&rsquo;est pas le seul, d&rsquo;autres dictateurs m\u00e9ritent le m\u00eame sort. Ils ne sont pas inqui\u00e9t\u00e9s.<\/p>\n<\/p>\n<p><p>\t&bull; Saddam a eu des mauvaises pens\u00e9es en fait d&rsquo;armes de destruction massive, a lanc\u00e9 des programmes, a utilis\u00e9 certaines armes (chimiques). Pour autant, d&rsquo;autres ont fait de m\u00eame, sans qu&rsquo;on les inqui\u00e8te.<\/p>\n<\/p>\n<p><p>\t&bull; Certains avancent que Saddam est une menace. Les faits sont tr\u00e8s faibles, sinon inexistants, d&rsquo;autant que l&rsquo;Irak est affaibli et plac\u00e9 sous constante surveillance. Devant ce constat, les partisans de Saddam-menace retraitent en disant qu&rsquo;il faut agir parce qu&rsquo;un jour il y aura une menace, ce qui est une argumentation bien faible. L&rsquo;argument de la menace, le seul qui serait imp\u00e9ratif, est aussi le plus faible d&rsquo;entre tous.<\/p>\n<\/p>\n<p><p>\tCe dernier point r\u00e9duit les autres \u00e0 peu de chose en montrant que l&rsquo;Irak (la menace irakienne, la guerre contre l&rsquo;Irak, etc) est une question \u00e0 d\u00e9battre plus qu&rsquo;une question \u00e0 trancher. Voil\u00e0 qui introduit notre analyse.<\/p>\n<\/p>\n<p><p>\tNous n&rsquo;abordons pas la question irakienne sur le point de savoir si la guerre va avoir lieu ;  si la guerre \u00e9ventuellement lanc\u00e9e contre l&rsquo;Irak est juste et\/ou justifi\u00e9e moralement ;  si l&rsquo;\u00e9valuation de la menace irakienne est fond\u00e9e. Tout cela, qui est du domaine de la r\u00e9alit\u00e9, \u00e0 d\u00e9battre, \u00e0 \u00e9valuer, \u00e0 appr\u00e9hender, etc, n&rsquo;entre pas dans notre propos.<\/p>\n<\/p>\n<p><p>\tOn sait que notre d\u00e9march\u00e9 est en g\u00e9n\u00e9ral essentiellement psychologique, que c&rsquo;est la psychologie, notamment collective, qui nous int\u00e9resse. La faiblesse consid\u00e9rable des r\u00e9alit\u00e9s politiques, la faiblesse correspondante des hommes politiques, laissent le champ libre au domaine psychologique non contr\u00f4l\u00e9, sans d\u00e9marches politiques construites pour le structurer. Les causes de cette situation rarissime o\u00f9 l&rsquo;homme n&rsquo;a plus l&rsquo;\u00e9cran de la raison appliqu\u00e9e entre sa psychologie et ce qu&rsquo;on lui pr\u00e9sente comme \u00e9tant l&rsquo;histoire, sont essentiellement l&rsquo;\u00e9volution des technologies des communications, la corruption psychologique que celle-ci cause, la perte du sens de la r\u00e9alit\u00e9 par la raison.<\/p>\n<\/p>\n<p><\/p>\n<h3>Le caract\u00e8re unique de la guerre contre l&rsquo;Irak : pr\u00e9sent\u00e9e, maniganc\u00e9e, planifi\u00e9e, conduite, gagn\u00e9e, interpr\u00e9t\u00e9e sur la place publique avant qu&rsquo;elle n&rsquo;ait \u00e9t\u00e9 faite<\/h3>\n<\/p>\n<p><p>\tL&rsquo;\u00e9poque est propice aux jugements cat\u00e9goriques : sans pr\u00e9c\u00e9dent, jamais auparavant,   et nous-m\u00eames ne nous en privons pas. Les \u00e9v\u00e9nements conduisent le commentaire \u00e0 cet \u00e9gard, et c&rsquo;est encore le cas ici. Pour ce que nous en savons et sans pr\u00e9juger de ce qu&rsquo;elle sera, si elle a lieu, cette guerre est sans pr\u00e9c\u00e9dent \u00e0 cause de son avant-guerre. Ce que nous voyons depuis un peu plus d&rsquo;un an, ce que&rsquo; nous entendons, ce que nous lisons, nous ne l&rsquo;avons jamais connu auparavant.<\/p>\n<\/p>\n<p><p>\tCette guerre est annonc\u00e9e explicitement depuis octobre 2001. Depuis la fin de l&rsquo;ann\u00e9e 2001, sa planification est expos\u00e9e en place publique (fuites diverses et concurrentes dans la presse) ; la tactique est d\u00e9battue, les buts de guerre sont analys\u00e9s, modifi\u00e9s, etc ; les coalitions sont constitu\u00e9es et d\u00e9faites, l&rsquo;opposition se mobilise, des manifestations ont lieu ; la conception m\u00eame de la guerre est expos\u00e9e, et ses suites idem (d\u00e9mocratisation du Moyen-Orient tout entier, \u00e9ventuellement attaque contre l&rsquo;Iran, voire la Syrie, etc) ; le nouveau gouvernement irakien est constitu\u00e9, le gouverneur militaire (US) nomm\u00e9, les r\u00e8gles de 1`occupation \u00e9tablies. Il s&rsquo;agit d&rsquo;une \u00e9norme accumulation d&rsquo;appr\u00e9ciations, de perceptions, de r\u00e9v\u00e9lations, de supputations, de d\u00e9clarations, qui finissent par faire penser que, non seulement cette guerre est acquise, non seulement qu&rsquo;elle va se faire, mais qu&rsquo;elle se fait d&rsquo;ores et d\u00e9j\u00e0, qu&rsquo;elle a commenc\u00e9 et, qu&rsquo;en fait, elle n&rsquo;a pas vraiment besoin de la r\u00e9alit\u00e9 pour poursuivre son chemin.<\/p>\n<\/p>\n<p><p>\tPendant ce temps, quelle a \u00e9t\u00e9 la r\u00e9alit\u00e9 justement ? Un aspect l\u00e9gal s&rsquo;est d\u00e9velopp\u00e9 avec la r\u00e9solution 1441 de l&rsquo;ONU. On sait toutes les manoeuvres, pressions, mensonges, constructions qui l&rsquo;ont accompagn\u00e9e ; combien, \u00e0 partir d&rsquo;un texte dont 1`esprit est de recommander une d\u00e9marche pacifique, ont eu lieu des d\u00e9marches \u00e9hont\u00e9es de recherche syst\u00e9matique, de fabrication, de manipulation, en vue de d\u00e9terminer un truc quelconque, n&rsquo;importe quoi fait l&rsquo;affaire, qui pourrait servir de casus belli ; on sait, enfin, que la politique qui a accompagn\u00e9 cette affaire a \u00e9t\u00e9 transform\u00e9e en une pantalonnade indigne, qui pour pouvoir enfin atteindre \u00e0 la position si esp\u00e9r\u00e9e de pouvoir d\u00e9clencher ce qui n&rsquo;est rien d&rsquo;autre qu&rsquo;une agression, qui pour tenter de d\u00e9tourner de son but ce groupe dont la pens\u00e9e semble se r\u00e9sumer \u00e0 un effrayant et \u00e9trange d\u00e9sir de guerre, de sang et de destruction.<\/p>\n<\/p>\n<p><p>\tA c\u00f4t\u00e9 de cela, la r\u00e9alit\u00e9 ; c&rsquo;est ce que nous nommerions l&rsquo;esprit de la loi ; et la r\u00e9solution 1441, c&rsquo;\u00e9tait une tentative de r\u00e9installer la r\u00e9alit\u00e9 \u00e0 la place qui est la sienne, qui est cette lapalissade que pour appr\u00e9cier une situation historique rien ne vaut la r\u00e9f\u00e9rence \u00e0 la r\u00e9alit\u00e9. En d&rsquo;autres mots, la r\u00e9solution 1441 \u00e9tait une fa\u00e7on de dire qu&rsquo;avec une nation de 25 millions d&rsquo;habitants, assomm\u00e9e par une effrayante d\u00e9faite, une effrayante dictature et un effrayant embargo de dix ans qui a fait autour d&rsquo;un million de morts, avec cette nation r\u00e9duite \u00e0 un \u00e9tat \u00e9conomique d&rsquo;une \u00e9poque d&rsquo;il y a trois ou quatre si\u00e8cles, sa population contrainte \u00e0 des conditions \u00e9pouvantables, ses moyens militaires r\u00e9duits \u00e0 l&rsquo;obsolescence \u00e9vidente, son comportement soumis \u00e0 une constante surveillance assortie d&rsquo;attaques quotidiennes quasiment de routine, la meilleure fa\u00e7on d&rsquo;agir pour le reste du monde (y compris les USA, tiens) \u00e9rig\u00e9 en juge, accusateur, avocat et policier en m\u00eame temps, est d&rsquo;inspecter, de mesurer, de compter, d&rsquo;une fa\u00e7on \u00e9videmment pacifique. Ne pas comprendre cela, c&rsquo;est laisser l&rsquo;esprit succomber \u00e0 la tentation de la sauvagerie et de la l\u00e2chet\u00e9 r\u00e9unies. (L\u00e2chet\u00e9 \u00e9videmment, parce que c&rsquo;en est une irr\u00e9m\u00e9diablement de toujours se trouver dans une position o\u00f9 la plus formidable puissance du monde en arrive \u00e0 d\u00e9sirer irr\u00e9sistiblement l&rsquo;agression contre une force toujours infiniment plus faible qu&rsquo;elle, infiniment amoindrie par des mesures coercitives qui ont pr\u00e9c\u00e9d\u00e9, et ainsi de suite. Cela nous en dit long sur la piteuse psychologie du champion. Ne pas sentir cela, c&rsquo;est \u00eatre b\u00eate, tout simplement.)<\/p>\n<\/p>\n<p><p>\tMais cette r\u00e9alit\u00e9, on le constate chaque jour, n&rsquo;a aucune utilit\u00e9 puisque nous pr\u00e9parons fr\u00e9n\u00e9tiquement la guerre.<\/p>\n<\/p>\n<p><\/p>\n<h3>Voil\u00e0 une \u00e9poque o\u00f9 s&rsquo;impose cette v\u00e9rit\u00e9 \u00e9tonnante  : il ne suffit plus de dire que la r\u00e9alit\u00e9 n&rsquo;a aucun sens, il faut ajouter qu&rsquo;elle n&rsquo;a aucune utilit\u00e9, bref, \u00e0 la poubelle, la r\u00e9alit\u00e9 <\/h3>\n<\/p>\n<p><p>\tC&rsquo;est \u00e0 dessein que nous utilisons ce mot compl\u00e8tement trivial, voire obsc\u00e8ne, et sans aucun doute absurde, d`utilit\u00e9pour qualifier la r\u00e9alit\u00e9  : nous sommes dans un temps historique o\u00f9 des dirigeants politiques de la puissance qu&rsquo;on sait peuvent \u00eatre amen\u00e9s \u00e0 croire (penser ne convient pas), que la r\u00e9alit\u00e9 n&rsquo;est pas utile. Nous sommes loin du mensonge, bien s\u00fbr, ou de ces trucs qu&rsquo;on appelle d\u00e9sinformation pour se faire croire qu&rsquo;on reste dans un domaine technique.<\/p>\n<\/p>\n<p><p>\tEn effet, notre domaine est d\u00e9sormais de l&rsquo;ordre du m\u00e9taphysique (litt\u00e9ralement  : \u00ab <em>ce qui suit les questions de physique<\/em> \u00bb, c&rsquo;est-\u00e0-dire  : \u00ab <em>ce qui englobe, d\u00e9passe, transcende la physique <\/em> \u00bb). Notre commentaire doit l&rsquo;\u00eatre \u00e9galement, il doit transcender la r\u00e9alit\u00e9 soi-disant observable puisqu&rsquo;il n&rsquo;y a plus de r\u00e9alit\u00e9. On ne peut plus s&rsquo;en tenir aux faits lorsque les faits sont jug\u00e9s selon leur aspect utilitaire, et \u00e9ventuellement jet\u00e9s \u00e0 la poubelle s&rsquo;ils sont jug\u00e9s d&rsquo;une utilit\u00e9 douteuse. (Ou, si l&rsquo;on veut  : quelle quotation au Dow Jones, la r\u00e9alit\u00e9  ? Nulle, certes.) Cette guerre,  ou plut\u00f4t, pour ce qu&rsquo;on peut en juger, cet avant-guerre n&rsquo;a d&rsquo;int\u00e9r\u00eat r\u00e9el que pour ses effets secrets mais d&rsquo;une puissance inou\u00efe sur notre psychologie. Nous nous attachons donc \u00e0 cette seule r\u00e9alit\u00e9 rescap\u00e9e de toutes les manigances  : la r\u00e9alit\u00e9 psychologique.<\/p>\n<\/p>\n<p><p>\tLe fait (!) est que nous avons diss\u00e9qu\u00e9, pr\u00e9par\u00e9, modifi\u00e9, d\u00e9battu, d&rsquo;un acte qui est une attaque d\u00e9lib\u00e9r\u00e9e et de sang-froid. Qu&rsquo;importe la victime ici, seuls comptent l&rsquo;acte et les traces qu&rsquo;il laissera dans notre psychologie. Cela, certes, c&rsquo;est sans pr\u00e9c\u00e9dent, \u00e0 ce degr\u00e9 de publicit\u00e9, de supputations publiques et de duplicit\u00e9 complaisamment expos\u00e9e, d&rsquo;analyses soi-disant rationnelles. L&rsquo;agression n&rsquo;est plus une agression, elle est devenue une connivence g\u00e9n\u00e9rale o\u00f9 la Raison a \u00e9t\u00e9 impliqu\u00e9e, et de force, et sans discuter. Notre rationalisation de la guerre contre l&rsquo;Irak (y compris par ONU interpos\u00e9e, qui perd d&rsquo;un coup toute la vertu de son intention primitive si, la r\u00e9solution 1441 devient la feuille de vigne qui sanctifie l&rsquo;attaque), notre rationalisation c&rsquo;est l&rsquo;implication de la raison par les hyst\u00e9riques qui sont par manigances dans une position de direction ou d&rsquo;influence, dans un projet dont la folie profonde devrait rapidement devenir manifeste. Au fonds nous sommes en train de fondre la raison dans notre folie. Si la crapule-Saddam r\u00e9alisait cela, il en rirait encore, apr\u00e8s sa d\u00e9faite et sa liquidation in\u00e9luctables, selon les promesses de Rumsfeld-Wolfowitz, et nous saurions alors que c&rsquo;\u00e9tait bien le Diable.  ou, disons, pour \u00eatre plus mesur\u00e9 et pour pouvoir continuer \u00e0 en juger, un excellent auxiliaire du Diable. (Il y en eut parmi les plumes les plus prestigieuses pour faire l&rsquo;hypoth\u00e8se, m\u00eame pour plaisanter, \u00e0 telle ou telle occasion o\u00f9 une attaque \u00e9pisodique contre lui faisait une excellente diversion, que Saddam aurait pu \u00eatre \u00ab <em>pay\u00e9 par la CIA<\/em> \u00bb  nous citons l\u00e0 un texte de Thierry de Montbrial de septembre 1994, termin\u00e9 par cette question en forme de plaisanterie, certes, et qui a toute sa place dans le d\u00e9bat.)<\/p>\n<\/p>\n<p><p>\tNotre prospective est donc que nous sortirons \u00e9puis\u00e9s par cette guerre. Non par les pertes, non par les p\u00e9rip\u00e9ties guerri\u00e8res, car de ce c\u00f4t\u00e9 nous ne jouons pas au devin en observant que bien des choses sont possibles,  mais \u00e9puis\u00e9s par cette tension psychologique de l&rsquo;imposture \u00e9rig\u00e9e en r\u00e9alit\u00e9 que nous nous sommes impos\u00e9s. \u00ab <em>Truth is the first casualty of the war<\/em> \u00bb, ont-ils l&rsquo;habitude de dire ; certes non, la v\u00e9rit\u00e9 ne sera pas la premi\u00e8re victime de la guerre parce qu&rsquo;elle ne participe pas \u00e0 la guerre, qu&rsquo;elle a \u00e9t\u00e9 foutue \u00e0 la poubelle depuis longtemps. La premi\u00e8re victime de cette guerre sera,  c&rsquo;est d&rsquo;ores et d\u00e9j\u00e0 notre psychologie.<\/p>\n<\/p>\n<p><p>\tNotre conclusion est que l&rsquo;attaque de l&rsquo;Irak est dans la parfaite lign\u00e9e de 9\/11. C&rsquo;est la m\u00eame hyst\u00e9rie qui fut d\u00e9cha\u00een\u00e9e chez nous par cette attaque, qui nous pousse aujourd&rsquo;hui \u00e0 cette guerre par\u00e9e de vertus immenses, et qui est d&rsquo;abord une \u00e9norme th\u00e9rapie en forme de spectacle, pour cent, mille, un million d&rsquo;esprits malades. C&rsquo;est pr\u00eater \u00e0 Saddam, comme hier \u00e0 Milosevic mais ce n&rsquo;\u00e9tait qu&rsquo;un hors d&rsquo;oeuvre, des vertus th\u00e9rapeutiques qu&rsquo;il ne peut avoir.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notre dr\u00f4le d&rsquo;avant-guerre Rubrique Contexte, Volume 18 n\u00b008 du 10 janvier 2003 Dans ce num\u00e9ro du d\u00e9but de l&rsquo;ann\u00e9e 2003, cette r\u00e9flexion sur la guerre qui nous attend et les effets qu&rsquo;on pourrait pr\u00e9voir, non sur le th\u00e9\u00e2tre de la guerre ou sur la situation politique, mais sur notre psychologie. Cela dure depuis 14 mois&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[857,3832,3099],"class_list":["post-65461","post","type-post","status-publish","format-standard","hentry","category-de-defensa","tag-irak","tag-occidentaux","tag-psychologie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65461"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65461\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}