{"id":65533,"date":"2003-03-24T00:00:00","date_gmt":"2003-03-24T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2003\/03\/24\/nos-temps-asymetriques\/"},"modified":"2003-03-24T00:00:00","modified_gmt":"2003-03-24T00:00:00","slug":"nos-temps-asymetriques","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2003\/03\/24\/nos-temps-asymetriques\/","title":{"rendered":"<strong><em>Nos temps asym\u00e9triques<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Nos temps asym\u00e9triques<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t24 mars 2003  La journ\u00e9e du 23 mars 2003 n&rsquo;est pas n\u00e9cessairement un tournant de la guerre en Irak, mais c&rsquo;est au moins un symbole, un signe et un p\u00e9nible rappel de la r\u00e9alit\u00e9 du monde. La puissance am\u00e9ricaine, qui s&rsquo;est envol\u00e9e dans une chevauch\u00e9e pr\u00e9sent\u00e9e comme hollywoodienne dans les 3 premiers jours de guerre, surmont\u00e9e par l&rsquo;extraordinaire puissance de feu a\u00e9rienne, se trouve confront\u00e9e \u00e0 la r\u00e9alit\u00e9 sordide, sanglante, d\u00e9bilitante, cruelle de la guerre de gu\u00e9rilla dans les villes irakiennes. La strat\u00e9gie des Am\u00e9ricains est alors de contourner ces poches de r\u00e9sistance pour filer vers Bagdad, objectif central,  mais l\u00e0-bas, pour quoi faire ? A un moment ou l&rsquo;autre, il faudra bien entrer dans la (les) ville(s) et l'(les) investir.<\/p>\n<\/p>\n<p><p>\tNous nous r\u00e9f\u00e9rons notamment \u00e0 <a href=\"http:\/\/news.ft.com\/servlet\/ContentServer?pagename=FT.com\/StoryFT\/FullStory&#038;c=StoryFT&#038;cid=1048313060824&#038;p=1012571727092\" class=\"gen\">ce texte du Financial Times<\/a> que nous reprenons <a href=\"http:\/\/www.dedefensa.org\/choix.php?link_id=2293&#038;comm=1\" class=\"gen\">par ailleurs dans Nos Choix comment\u00e9s<\/a>. Ce texte, un parmi d&rsquo;autres certes, est une bonne image de la guerre qui est en train de prendre sa place dans l&rsquo;aventure irakienne des Am\u00e9ricains. D&rsquo;ores et d\u00e9j\u00e0, les \u00e9v\u00e9nements nous inspirent trois remarques. On notera qu&rsquo;elles sont essentiellement psychologiques, cette mati\u00e8re o\u00f9 le syst\u00e8me am\u00e9ricaniste est d&rsquo;une stupidit\u00e9 totale.<\/p>\n<\/p>\n<p><p>\t&bull; Les Am\u00e9ricains s&rsquo;attendaient \u00e0 ce que les Irakiens les accueillent en lib\u00e9rateurs. Ce n&rsquo;est pas compl\u00e8tement le cas, malgr\u00e9 que la guerre ait commenc\u00e9 par le Sud, suppos\u00e9 favorable aux Occidentaux. Nous en sommes, du c\u00f4t\u00e9 de Washington, au stade ultime du virtualisme,  \u00e0 croire librement (les USA sont une soci\u00e9t\u00e9 libre, indiscutablement) les mensonges hollywoodiens que dispensent les r\u00e9seaux des hommes de communication charg\u00e9s de pr\u00e9senter l&rsquo;image du monde virtualiste \u00e0 ce m\u00eame Washington. Le r\u00e9sultat, sinistre par l&rsquo;analogie, est que les soldats US subissent le m\u00eame choc psychologique que les soldats du Pacte de Varsovie en 1968, en Tch\u00e9coslovaquie (on leur avait dit qu&rsquo;ils allaient prot\u00e9ger les Tch\u00e8ques contre les revanchards allemands). Ce n&rsquo;est pas rien : cela suppose une grave perte de moral pour des soldats qui sont, par tradition et par syst\u00e8me, psychologiquement fragiles.<\/p>\n<\/p>\n<p><p>\t&bull; L&rsquo;\u00e9tat d&rsquo;esprit des chefs, des \u00e9tats-majors, etc, est caract\u00e9ris\u00e9 par la peur du risque, la couardise, la crainte des sanctions de l&rsquo;impopularit\u00e9 m\u00e9diatique en cas de pertes. La tactique de contournement des villes qui r\u00e9sistent est expliqu\u00e9e d&rsquo;une fa\u00e7on savante, par des consid\u00e9rations techniques et autres (certains, fort inqui\u00e9tantes au reste, notamment le manque d&rsquo;effectifs US) ; elle est per\u00e7ue d&rsquo;abord, et le sera par les Irakiens, comme la peur de se battre dans des conditions de gu\u00e9rilla.<\/p>\n<\/p>\n<p><p>\t&bull; On voit que nous prenons garde de parler des Am\u00e9ricains, pas des Britanniques. Les Britanniques sont des combattants d&rsquo;une toute autre trempe que les Am\u00e9ricains. Mais ils sont compl\u00e8tement aux ordres des Am\u00e9ricains. Cette circonstance pourrait faire que leurs qualit\u00e9s guerri\u00e8res soient compl\u00e8tement gaspill\u00e9es par la tactique g\u00e9n\u00e9rale. Il est \u00e0 craindre que l&rsquo;alliance avec la plus grande superpuissance de l&rsquo;histoire d\u00e9clenche en g\u00e9n\u00e9ral une osmose malheureuse o\u00f9 les Europ\u00e9ens perdront leurs vertus de guerriers (qui sont tr\u00e8s r\u00e9elles contrairement \u00e0 la propagande atlantiste qu&rsquo;on r\u00e9p\u00e8te \u00e0 longueur de journ\u00e9e).<\/p>\n<\/p>\n<p><p>\tQue se passe-t-il en Irak ? La question pos\u00e9e est de savoir si le conflit, voulu par les US comme une bataille technologique de tr\u00e8s haute intensit\u00e9, ne risque pas de se transformer en bataille asym\u00e9trique o\u00f9, finalement, \u00e0 cause du terrain (les villes) et des conditions, c&rsquo;est le combattant le plus frustre mais le plus d\u00e9termin\u00e9 qui impose ses conditions de combat. En ce sens \u00e9galement, le temps travaille contre les Am\u00e9ricains. Il faut qu&rsquo;ils l&#8217;emportent vite, pour \u00e9carter ces risques d&rsquo;enlisement dans des batailles asym\u00e9triques. S&rsquo;ils n&rsquo;y parviennent pas, c&rsquo;est effectivement le risque vietnamien qui les guette,  non pas un risque mat\u00e9riel mais un risque psychologique, un enlisement psychologique, avec des forces au moral toujours plus bas, inadapt\u00e9es \u00e0 la bataille et ainsi de suite.<\/p>\n<\/p>\n<p><p>\tCi-dessous, rappel de quelques sc\u00e8nes, sentiments, erreurs et doutes, tels qu&rsquo;ils sont retranscrits dans l&rsquo;article que nous citons,  jusqu&rsquo;\u00e0 cette erreur si caract\u00e9ristique de hisser la banni\u00e8re \u00e9toil\u00e9e au-dessus d&rsquo;une maison d&rsquo;une ville (par ailleurs non r\u00e9duite !), en signe de victoire, notamment pour les cam\u00e9ras TV, pour rappeler la sc\u00e8ne semblable \u00e0 Okinawa en 1945 (objet d&rsquo;une photo puis d&rsquo;une sculpture fameuse) ; tout cela, typiquement hollywoodien, pour d\u00e9couvrir brusquement que l&rsquo;effet aupr\u00e8s des populations locales est d\u00e9sastreux, que cela fait envahisseurs, et remettre pr\u00e9cipitamment le drapeau irakien &#8230;<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>Militarily, the outcome of the battle is not in doubt, since the coalition has complete air superiority and an overwhelming advantage in firepower. But events in southern Iraq since Friday when US marines briefly raised the Stars and Stripes over Umm Qasr before realising the gesture made them look more like occupiers than liberators suggest the war will be much more complicated than President George W. Bush had hoped.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>One problem for the Americans is that however much the Iraqis hate Saddam Hussein, they do not appear to be overjoyed in the Shia Muslim south, at least about the prospect of a US occupation.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Reporters travelling independently in southern Iraq say some residents of Safwan, another town on the Kuwaiti border, were openly hostile to the coalition forces, although others said they were happy that President Bush was seeking to end the rule of President Hussein.<\/em> \u00bb<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos temps asym\u00e9triques 24 mars 2003 La journ\u00e9e du 23 mars 2003 n&rsquo;est pas n\u00e9cessairement un tournant de la guerre en Irak, mais c&rsquo;est au moins un symbole, un signe et un p\u00e9nible rappel de la r\u00e9alit\u00e9 du monde. La puissance am\u00e9ricaine, qui s&rsquo;est envol\u00e9e dans une chevauch\u00e9e pr\u00e9sent\u00e9e comme hollywoodienne dans les 3 premiers&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-65533","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65533"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65533\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}