{"id":65539,"date":"2003-03-27T00:00:00","date_gmt":"2003-03-27T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2003\/03\/27\/un-site-antiwar-ferme-aux-usa\/"},"modified":"2003-03-27T00:00:00","modified_gmt":"2003-03-27T00:00:00","slug":"un-site-antiwar-ferme-aux-usa","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2003\/03\/27\/un-site-antiwar-ferme-aux-usa\/","title":{"rendered":"<strong><em>Un site antiwar ferm\u00e9 aux USA<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Un site antiwar ferm\u00e9 aux USA<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t27 mars 2003  Il nous est arriv\u00e9 d&rsquo;utiliser en le relayant pour l&rsquo;un ou l&rsquo;autre texte le site antiwar am\u00e9ricain YellowTimes.org. Depuis trois jours, nous avions remarqu\u00e9 l&rsquo;impossibilit\u00e9 d&rsquo;y acc\u00e9der. Le site WSWS.org vient de donner l&rsquo;explication de ces difficult\u00e9s dans <a href=\"http:\/\/www.wsws.org\/articles\/2003\/mar2003\/webs-m26.shtml\" class=\"gen\">un texte publi\u00e9 hier<\/a>, et que nous reproduisons ci-dessous int\u00e9gralement, pour mieux pr\u00e9senter l&rsquo;information (le texte est de Henry Michaels, collaborateur de WSWS.org, et nous le publions avec les restrictions d&rsquo;usage quant \u00e0 la forme de cette d\u00e9marche d&#8217;emprunt) :<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>While the major US media outlets have readily complied with Pentagon requests not to show footage and pictures of captured or dead American soldiers, one US-based web site has been shut down by its Internet provider, VortechHosting.com, for showing the images.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>YellowTimes.org, a six-month-old antiwar and media criticism site, first reported that it was temporarily shut down Sunday night for publishing inappropriate graphic material. After removing pictures of civilian Iraqi deaths and injuries, along with photos of the American POWs, the site was allowed to re-appear.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>However, the site has since been closed down again, together with its email facilities. In a message to the site&rsquo;s publisher Erich Marquardt, Vortech Hosting referred directly to the Pentagon-requested policy adopted by the major networks:<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em> As NO&rsquo; TV station in the US is allowing any dead US solders or POWs to be displayed &#8230; we will not either. We understand free press and all, but we don&rsquo;t want someone&rsquo;s family member to see them on some site. It is disrespectful, tacky &#038; disgusting. No mother, brother, sister, wife or child should see their loved one plastered all over the net wounded or dead.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Marquardt told the WSWS he did not believe that Vortech, a private company operating from Orlando, Florida, had acted under direct official pressure, because he had no evidence to suggest that was the case. Nevertheless, the site&rsquo;s closure is a blatant violation of the constitutional right of free speech and a direct product of the government&rsquo;s campaign of censorship.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>VortechHosting is the second provider company to shut down YellowTimes. In February, another company claimed that the site was using too many of its resources, after the site published an article by Imad Khadduri, a former Iraqi nuclear scientist.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Khadduri, who was instrumental in Iraq&rsquo;s nuclear weapons program in the 1980s and early 1990s, charged that allegations by US Secretary of State Colin Powell and others concerning the competence and progress of the Iraqi nuclear weapons program were baseless and untrue.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t&#8230; Aujourd&rsquo;hui, quand nous allons sur le site <a href=\"http:\/\/www.yellowtimes.org\/\" class=\"gen\">YellowTimes,<\/a> nous y lisons l&rsquo;inscription suivante : \u00ab <em>Welcome to YellowTimes.org. Currently our site is down while we upgrade our servers.  Please check back in a few days.  Thank you.  YellowTimes.org.<\/em> \u00bb Il est donc probable que YellowTimes rouvre son site, et on esp\u00e8re prochainement. Bien entendu, nous attendons avec impatience cette r\u00e9ouverture car le mat\u00e9riel que YellowTimes met en ligne nous est pr\u00e9cis et contribue \u00e0 entretenir le courant de libert\u00e9 sur Internet.<\/p>\n<\/p>\n<p><p>\tPour le reste, qu&rsquo;est-ce que nous dit cette aventure,  outre que les USA et Internet sont sous un r\u00e9gime de libert\u00e9 dr\u00f4lement surveill\u00e9e, pas loin d&rsquo;\u00eatre une censure de fer dans un gant de velours un peu r\u00eache, ce que nous n&rsquo;ignorions plus ? Cette aventure nous dit que les processus de la censure sont effectivement d&rsquo;influence et de conformisme, de fa\u00e7on \u00e0 ce que soient conserv\u00e9es saines et sauves les bonnes consciences et l&rsquo;apparence des lois fondamentales (c&rsquo;est-\u00e0-dire la lettre de la loi, l&rsquo;esprit de la loi \u00e9tant, lui, syst\u00e9matiquement viol\u00e9). C&rsquo;est \u00e0 la fois une hypocrisie et une chance,  ce qui conduit \u00e0 recommander de ne pas \u00eatre dupe de la premi\u00e8re et de profiter sans le moindre soup\u00e7on de vergogne de la seconde.<\/p>\n<\/p>\n<p><p>\tCela confirme le climat et les perspectives aux \u00c9tats-Unis : un conformisme massif en faveur du gouvernement de la part, c&rsquo;est-\u00e0-dire de l&rsquo;opinion officielle soutenue par la force et tr\u00e8s souvent relay\u00e9e par les pouvoirs d&rsquo;argent et en g\u00e9n\u00e9ral par les structures li\u00e9es de pr\u00e8s ou de loin au pouvoir. Mais cette situation n&rsquo;est pas g\u00e9n\u00e9rale, en ce sens qu&rsquo;elle n&rsquo;est pas syst\u00e9matique. (D&rsquo;autres sites ont publi\u00e9 des photos de prisonniers US en Irak et n&rsquo;ont pas \u00e9t\u00e9 ferm\u00e9s par leurs serveurs.) L&rsquo;attaque contre les libert\u00e9s civiles, notamment contre les r\u00e9seaux non-conformistes et dissidents, est retenue au tout dernier moment par la n\u00e9cessit\u00e9 de respecter les grandes lignes de la loi,  conformisme pour conformisme, le pouvoir est aussi oblig\u00e9 de s&rsquo;y conformer (!) pour ne pas perdre ce qui lui reste de r\u00e9putation, et, ainsi, ne pas se mettre en mauvaise posture vis-\u00e0-vis du public (des sondages), ce qui constitue aux USA un handicap de cr\u00e9dibilit\u00e9 insurmontable. L&rsquo;esprit de la censure est l\u00e0 mais l&rsquo;application n&rsquo;est pas facile ; s&rsquo;il s&rsquo;agit effectivement de quelque chose qui n&rsquo;est pas loin d&rsquo;\u00eatre une censure de fer, cela ne l&rsquo;est pas tout \u00e0 fait en d\u00e9pit de la corruption psychologique accomplie des dirigeants.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un site antiwar ferm\u00e9 aux USA 27 mars 2003 Il nous est arriv\u00e9 d&rsquo;utiliser en le relayant pour l&rsquo;un ou l&rsquo;autre texte le site antiwar am\u00e9ricain YellowTimes.org. Depuis trois jours, nous avions remarqu\u00e9 l&rsquo;impossibilit\u00e9 d&rsquo;y acc\u00e9der. Le site WSWS.org vient de donner l&rsquo;explication de ces difficult\u00e9s dans un texte publi\u00e9 hier, et que nous reproduisons&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[2826,3911],"class_list":["post-65539","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-censure","tag-yellowtimes"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65539"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65539\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}