{"id":65544,"date":"2003-03-30T00:00:00","date_gmt":"2003-03-30T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2003\/03\/30\/lexemple-belge-suite\/"},"modified":"2003-03-30T00:00:00","modified_gmt":"2003-03-30T00:00:00","slug":"lexemple-belge-suite","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2003\/03\/30\/lexemple-belge-suite\/","title":{"rendered":"L&rsquo;exemple belge (suite)"},"content":{"rendered":"<p><h2 class=\"common-article\">L&rsquo;exemple belge (suite)<\/h2>\n<\/p>\n<p><p>\t30 mars 2003  La Belgique <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=540\" class=\"gen\">continue<\/a> \u00e0 \u00eatre fascinante, dans la mesure o\u00f9 elle nous montre comment, \u00e0 partir d&rsquo;une base et d&rsquo;une tradition politiques d&rsquo;une m\u00e9diocrit\u00e9 extr\u00eame,  le syst\u00e8me en place depuis 1947-48, qui en conna\u00eet en cette mati\u00e8re de la m\u00e9diocrit\u00e9,  elle engage des actes d&rsquo;une importance majeure et non exempts de dignit\u00e9. Elle y est aid\u00e9e par l&rsquo;aveuglement am\u00e9ricain ; les Am\u00e9ricains, incapables de se concentrer sur plus d&rsquo;une crise \u00e0 la fois, et c&rsquo;est de l&rsquo;Irak dont il s&rsquo;agit, traitent la crise euro-atlantique avec une d\u00e9sinvolture type-Rumsfeld et laissent faire des choses qui d\u00e9truisent le syst\u00e8me d&rsquo;h\u00e9g\u00e9monie par influence et consentement qu&rsquo;ils ont mis en place depuis 1945.<\/p>\n<\/p>\n<p><p>\tL&rsquo;affaire belge du moment, c&rsquo;est celle du trait\u00e9 bilat\u00e9ral de 1971, clairement sign\u00e9 dans le cadre ultra-l\u00e9galiste et quasi souverain (\u00e0 l&rsquo;\u00e9poque) de l&rsquo;OTAN, autorisant l&rsquo;utilisation sans restriction de l&rsquo;espace a\u00e9rien et des voies de communication en Belgique par les USA, d\u00e8s lors qu&rsquo;il y a un  \u00e9tat de crise act\u00e9 par une position officielle de l&rsquo;OTAN, et confirm\u00e9 \u00e9videmment par le vote unanime de ses membres. Le trait\u00e9 de 1971 est une grossi\u00e8re annihilation de la souverainet\u00e9 nationale belge, mais qui n&rsquo;a n\u00e9cessit\u00e9 aucune pression particuli\u00e8re des USA, aucune attitude \u00e0-la-Bush ou type-Rumsfeld. Il a \u00e9t\u00e9 sign\u00e9 (secr\u00e8tement) en 1971 en toute conscience et en toute bonne conscience, sous la pression, \u00e0 la fois des dangers de la Guerre froide, du poids sovi\u00e9tique (ce qu&rsquo;on en percevait) et de la pr\u00e9sence US en Europe (ce qu&rsquo;on en percevait),  et enfin sous la pression indiscutable de cette quasi-l\u00e9gitimit\u00e9 qu&rsquo;exer\u00e7ait \u00e0 cette \u00e9poque l&rsquo;OTAN sur ses membres europ\u00e9ens, surtout les plus faibles et les plus petits.<\/p>\n<\/p>\n<p><p>\tQuelques donn\u00e9es sur la situation actuelle :<\/p>\n<\/p>\n<p><p>\t&bull; Le 13 septembre 2001, l&rsquo;OTAN d\u00e9cide (vote n\u00e9cessairement unanime de ses 19 membres) que, dans le cas de l&rsquo;attaque du 11 septembre, l&rsquo;article 5 est d&rsquo;application. Concr\u00e8tement, cela signifie que l&rsquo;OTAN porte aide et assistance aux USA et qu&rsquo;il y a effectivement \u00e9tat de crise. Tout cela n&rsquo;a aucun sens, le bon sens le dit aussit\u00f4t (l&rsquo;OTAN \u00e0 l&rsquo;aide des USA  !). Tout cela est du bricolage du secr\u00e9taire g\u00e9n\u00e9ral, dont on sait les tendances et accointances ; son objectif est de donner un r\u00f4le \u00e0 l&rsquo;OTAN, qui n&rsquo;en a plus aucun, et cela ne peut se faire que par une mesure d&rsquo;alignement sur les USA. De cela, les USA n&rsquo;ont cure, ils le montreront 13 jours plus tard (visite de Wolfowitz \u00e0 l&rsquo;OTAN) en venant informer les autres que les USA n&rsquo;ont rien \u00e0 faire de l&rsquo;OTAN dans cette affaire. (D&rsquo;ores et d\u00e9j\u00e0, les Belges ont leur diff\u00e9rence. Ils sont les plus acharn\u00e9s contre cette initiative de Lord Robertson of Port Eillen, qu&rsquo;ils consid\u00e8rent comme une basse manoeuvre. On ne leur donne pas tort. Depuis, les relations entre la Belgique et le secr\u00e9taire g\u00e9n\u00e9ral manquent de plus en plus d&rsquo;am\u00e9nit\u00e9.)<\/p>\n<\/p>\n<p><p>\t&bull; L&rsquo;essentiel pour nous, ici, est bien qu&rsquo;il y a \u00e9tat de crise, qui rend l&rsquo;accord de 1971 d&rsquo;application.<\/p>\n<\/p>\n<p><p>\t&bull; Un saut de 16 mois. La situation euro-atlantique s&rsquo;est tendue et la Belgique est \u00e0 la pointe de la r\u00e9sistance anti-US. La guerre va avoir lieu en Irak, les USA commencent \u00e0 d\u00e9placer leurs forces d&rsquo;Allemagne vers le Golfe. Certaines transitent par la Belgique, sans la moindre information pour les Belges (les convois US se pr\u00e9sentent aux postes fronti\u00e8res et entrent sur les autoroutes belges, comme vous et moi avec une caravane). Cette d\u00e9sinvolture agace ; le trait\u00e9 1971, m\u00eame s&rsquo;il est sur le fond un complet abandon de souverainet\u00e9, entend y mettre quelque forme et fait un devoir aux Am\u00e9ricains d&rsquo;informer les Belges de tout transit de forces militaires US sur leur territoire. Les USA type-Rumsfeld ne s&#8217;embarrassent pas de telles mani\u00e8res.<\/p>\n<\/p>\n<p><p>\t&bull; L&rsquo;agacement n\u00e9 de la d\u00e9sinvolture, ou de l&rsquo;impolitesse US, va grimper vers un paroxysme au fur et \u00e0 mesure que la fi\u00e8vre anti-guerre fait de m\u00eame. Le gouvernement belge, le monde politique belge vont y \u00eatre sensibles au point o\u00f9 ils vont mettre d&rsquo;actualit\u00e9 cette question du transit US. Vertu chatouilleuse pour la souverainet\u00e9 ? Il y a de cela (un petit peu) et, d&rsquo;autre part, il y a une p\u00e9riode \u00e9lectorale. La m\u00e9diocrit\u00e9 du syst\u00e8me nourrit sa tr\u00e8s paradoxale et compl\u00e8tement involontaire grandeur.<\/p>\n<\/p>\n<p><p>\t&bull; Certains (les Verts\/\u00e9colos, principalement) veulent purement et simplement une interdiction imm\u00e9diate de transit. Dans la fi\u00e8vre, certains ministres non-Verts succombent un instant au charme de cette intransigeance (Louis Michel, affaires \u00e9trang\u00e8res, et Flahaut, d\u00e9fense, il y a deux semaines \u00e0 la t\u00e9l\u00e9vision). L&rsquo;affaire devient du pur juridisme, car sur le fond, qui est politique, tout le monde est d\u00e9sormais emport\u00e9 par l&rsquo;unanimit\u00e9 de l&rsquo;\u00e9vidence (n\u00e9cessit\u00e9 de d\u00e9noncer ce trait\u00e9). La position du gouvernement, plus ou moins impos\u00e9e pour certains, est de dire qu&rsquo;il y a un trait\u00e9 et qu&rsquo;on ne peut que le respecter tant qu&rsquo;il existe. (Argument de la vertu : les Belges ne vont pas faire ce qu&rsquo;ils reprochent aux Am\u00e9ricains de faire, de violer les trait\u00e9s. Contre-argument de la vertu : l&rsquo;ONU n&rsquo;a pas autoris\u00e9 cette guerre, c&rsquo;est une guerre ill\u00e9gale, la Belgique est donc fond\u00e9e \u00e0 refuser son aide \u00e0 cette guerre parce que le trait\u00e9 de l&rsquo;ONU a pr\u00e9\u00e9minence sur l&rsquo;accord bilat\u00e9ral de 1971.)<\/p>\n<\/p>\n<p><p>\t&bull; Laissons tout cela et observons le r\u00e9sultat, qui est n\u00e9cessairement un compromis \u00e0 la belge pour \u00e9viter une crise au sein du gouvernement \u00e0 deux mois des \u00e9lections : on va ren\u00e9gocier l&rsquo;accord bilat\u00e9ral de 1971, c&rsquo;est-\u00e0-dire l&rsquo;abroger dans les r\u00e8gles ; cela prend du temps et cela sera sans doute le fait du prochain gouvernement. Le ministre Louis Michel dit que les USA ne feront pas de complications. (<em>bis repetitat<\/em> : les USA, tout entier concentr\u00e9s sur l&rsquo;Irak, ne prennent aucune attention particuli\u00e8re \u00e0 leur front europ\u00e9en.) Des partis se prononcent effectivement, d&rsquo;ores et d\u00e9j\u00e0, pour l&rsquo;abrogation de l&rsquo;accord dans le cadre l\u00e9gal d&rsquo;une consultation avec les amis US (c&rsquo;est le cas des socialistes francophones, embo\u00eetant le pas aux Verts, mais avec plus de retenue),  et toujours ces \u00e9lections en ligne de mire pour garder le fer au feu, pour emp\u00eacher que la question soit mise de c\u00f4t\u00e9 (en Belgique, on dit, comme partout  : encommisionn\u00e9e.)<\/p>\n<\/p>\n<p><p>\tEt voil\u00e0, comment la Belgique a ouvert la bo\u00eete de Pandore. Le premier parmi les pays OTAN compl\u00e8tement soumis \u00e0 la souverainet\u00e9 OTAN\/USA de la Guerre Froide, elle remet en cause un des textes secrets de cette abdication de souverainet\u00e9. Dans le climat actuel, le reste va suivre, comme on d\u00e9tricote un chandail. On va parler du stationnement ou pas d&rsquo;armes nucl\u00e9aires US en Europe ; on va parler d&rsquo;accords secrets au niveau des services de renseignement  ; on va parler des dispositions des coop\u00e9rations dans le domaine des armements ; etc. Cette lessive est non seulement n\u00e9cessaire, elle est in\u00e9vitable. Les \u00e9v\u00e9nements y pressent. On laisse l&rsquo;esprit libre de vagabonder pour mesurer l&rsquo;ampleur des cons\u00e9quences d&rsquo;un tel \u00e9v\u00e9nement, lorsque l&rsquo;Europe mesurera le degr\u00e9 de sa suj\u00e9tion juridique aux \u00c9tats-Unis, impos\u00e9e durant la Guerre froide aux d\u00e9pens de sa souverainet\u00e9.<\/p>\n<\/p>\n<p><p>\t(Cela vaut pour les institutions comme pour les pays. La Commission europ\u00e9enne, par exemple, vit compl\u00e8tement dans l&rsquo;\u00e9ther irrationnel de ces illusions pr\u00e9-9\/11 et du temps de la Guerre froide o\u00f9 l&rsquo;alliance am\u00e9ricaine \u00e9tait un acte de foi. On sait peu, bien s\u00fbr, que la Commission re\u00e7oit chaque ann\u00e9e dans ses services des stagiaires US dont certains viennent du d\u00e9partement d&rsquo;\u00c9tat et d&rsquo;autres du Pentagone. La r\u00e9ciproque n&rsquo;est pas accept\u00e9e. Pourquoi ? Parce que le d\u00e9partement d&rsquo;\u00c9tat et le Pentagone fonctionnent dans une situation de confidentialit\u00e9 \u00e0 laquelle des fonctionnaires de la Commission ne peuvent pr\u00e9tendre \u00e9chapper.)<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;exemple belge (suite) 30 mars 2003 La Belgique continue \u00e0 \u00eatre fascinante, dans la mesure o\u00f9 elle nous montre comment, \u00e0 partir d&rsquo;une base et d&rsquo;une tradition politiques d&rsquo;une m\u00e9diocrit\u00e9 extr\u00eame, le syst\u00e8me en place depuis 1947-48, qui en conna\u00eet en cette mati\u00e8re de la m\u00e9diocrit\u00e9, elle engage des actes d&rsquo;une importance majeure et non&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3106,2645,584],"class_list":["post-65544","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-froide","tag-guerre","tag-otan"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65544"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65544\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}