{"id":65566,"date":"2003-04-12T00:00:00","date_gmt":"2003-04-12T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2003\/04\/12\/lenigme-rumsfeld-et-les-conservateurs-dechires\/"},"modified":"2003-04-12T00:00:00","modified_gmt":"2003-04-12T00:00:00","slug":"lenigme-rumsfeld-et-les-conservateurs-dechires","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2003\/04\/12\/lenigme-rumsfeld-et-les-conservateurs-dechires\/","title":{"rendered":"<strong><em>L&rsquo;\u00e9nigme Rumsfeld et les \u201cconservateurs\u201d d\u00e9chir\u00e9s<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">L&rsquo;\u00e9nigme Rumsfeld et les conservateurs d\u00e9chir\u00e9s<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t12 avril 2003  La question que nous posions <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=682\" class=\"gen\">le 3 avril dernier concernant le secr\u00e9taire \u00e0 la d\u00e9fense Rumsfeld<\/a> est bien s\u00fbr compl\u00e8tement d&rsquo;actualit\u00e9, et beaucoup plus vite qu&rsquo;on ne pouvait attendre. C&rsquo;est la question de savoir quelle politique Rumsfeld va suivre, lui qui occupe d\u00e9sormais une position de plus grande puissance qu&rsquo;il n&rsquo;a jamais eue auparavant.<\/p>\n<\/p>\n<p><p>\tA premi\u00e8re vue, la question para\u00eet futile tant il appara\u00eet \u00e9vident que Rumsfeld doive suivre la ligne ultra-dure, belliciste, d&rsquo;occupation maximale des territoires ext\u00e9rieurs et de pouss\u00e9e interventionniste. Dans le texte que nous signalons plus haut, nous faisions r\u00e9f\u00e9rence \u00e0 une analyse de Jim Lobe qui envisageait le contraire, estimant que Rumsfeld appartient \u00e0 la cat\u00e9gorie des nationalistes. Lobe introduisait une nuance politique am\u00e9ricaine bien r\u00e9elle.<\/p>\n<\/p>\n<p><p>\tLa politique que pr\u00f4nent les n\u00e9o-conservateurs (Wolfowitz, Perle et les autres), qui a \u00e9t\u00e9 adopt\u00e9e par le parti r\u00e9publicain, n&rsquo;est pas naturelle \u00e0 ce m\u00eame parti r\u00e9publicain. On s&rsquo;en aper\u00e7oit, avec le durcissement spectaculaire et dramatique de l&rsquo;opposition entre r\u00e9publicains dits pal\u00e9o-conservateurs (les r\u00e9publicains conservateurs traditionnels qui se sont eux-m\u00eames donn\u00e9s ce nom) et les n\u00e9o-conservateurs, qui se disent conservateurs mais sont de plus en plus pr\u00e9sent\u00e9s comme des lib\u00e9raux super-interventionnistes, venus de la gauche et de l&rsquo;extr\u00eame-gauche (trotskiste). Un professeur de philosophie, William Rusher, constate qu&rsquo;il y a aujourd&rsquo;hui une guerre civile au sein de la droite conservatrice. Une pal\u00e9o-conservatrice, Ilana Mercer, l&rsquo;approuve <a href=\"http:\/\/www.worldnetdaily.com\/news\/article.asp?ARTICLE_ID=31949\" class=\"gen\">dans un article publi\u00e9 le 9 avril<\/a>  un texte o\u00f9 elle d\u00e9signe ostensiblement les n\u00e9o-conservateurs sous le nom de sociaux-d\u00e9mocrates globalistes, ou gauchistes (\u00ab <em>global social democrats or rank leftists<\/em> \u00bb). C&rsquo;est un signe r\u00e9v\u00e9lateur de la tension qui existe entre ces groupes.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>William Rusher of the Claremont Institute is right. There is an ideological war between Bush&rsquo;s social democrats, known as neoconservatives, and those of us who stand on the Old Right, namely paleoconservatives and paleolibertarians.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>Rusher, however, is not about to tell his readers what it is about the set of policies which neoconservatives support that makes them global social democrats or rank leftists. It&rsquo;s probably more accurate to speak both of modern-day liberals and neoconservatives as proponents of a highly centralized  and hence dictatorial  managerial form of government, except that, as we&rsquo;ve seen in the past two weeks, the neoconservatives are far more dangerous to liberty, life and livelihoods.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tWilliam Rusher se r\u00e9f\u00e8re notamment \u00e0 un article de David Frum, le 7 avril dans <em>National Review<\/em>, attaquant violemment les pal\u00e9o-conservateurs en lan\u00e7ant contre eux une accusation impardonnable pour des conservateurs patriotes : trahison. Rusher fait l&rsquo;analyse que ce d\u00e9bat est fondamental, parce que son r\u00e9sultat va influencer la politique \u00e9trang\u00e8re des USA pour les 30 prochaines ann\u00e9es. Rusher <a href=\"http:\/\/www.worldnetdaily.com\/news\/article.asp?ARTICLE_ID=31861\" class=\"gen\">estime que l&rsquo;article de Frum a mis le feu aux poudres<\/a>, que la droite conservatrice (ou ce qui est d\u00e9sign\u00e9 comme tel puisque l&rsquo;on tend \u00e0 d\u00e9nier aux n\u00e9o-conservateurs le titre de conservateurs) va \u00eatre d\u00e9sormais d\u00e9chir\u00e9e.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>Observers who keep an eye on the internal dynamics of the conservative movement registered a seismic event scoring 8.0 on the political Richter scale when the April 7 issue of National Review, the movement&rsquo;s leading journal, ran an eight-page cover essay by David Frum entitled Unpatriotic Conservatives  A war against America.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>Under that unappetizing heading, the magazine grouped some famous names and others well known to students of conservatism, including Pat Buchanan, Robert Novak, Llewellyn Rockwell, Thomas Fleming, Samuel Francis, Scott McConnell, Justin Raimondo, Joseph Sobran, Jude Wanniski, Taki Theodoracopulos and Paul Gottfried. If unpatriotic at first seems a strange word to apply to these people, Frum is determined to make it stick. His condemnation is sweeping and uncompromising:<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>Only the boldest of them as yet explicitly acknowledge their wish to see the United States defeated in the War on Terror. But they are thinking about defeat, and wishing for it, and they will take pleasure in it if it should happen. They began by hating the neoconservatives. They came to hate their party and this president. They have finished by hating their country. &#8230; In a time of danger, they have turned their backs on their country. Now we turn our backs on them.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tC&rsquo;est dans ce contexte qu&rsquo;il faut placer la question sur la position de Rumsfeld. En th\u00e9orie, Rumsfeld semblerait plus proche des vrais conservateurs, voire des pal\u00e9o-conservateurs, que des n\u00e9o-conservateurs. Avant le 11 septembre 2001, il \u00e9tait partisan de retraits substantiels de forces US \u00e0 l&rsquo;\u00e9tranger ; aujourd&rsquo;hui, il reste effectivement partisan de retraits d&rsquo;Europe et de Cor\u00e9e du Sud (des n\u00e9gociations sont en cours avec la Cor\u00e9e du Sud pour explorer cette voie). Ces mesures sont de la sorte que r\u00e9clament les pal\u00e9o-conservateurs. Sur la question du stationnement des troupes US en Irak, Rumsfeld a montr\u00e9 derni\u00e8rement quelques prudences, voire des r\u00e9ticences, laissant entendre qu&rsquo;il faudrait qu&rsquo;elles quittent le pays d\u00e8s que l&rsquo;essentiel de leur mission de reconstruction serait achev\u00e9.<\/p>\n<\/p>\n<p><p>\tLes menaces de Rumsfeld contre la Syrie semblent-elles, au contraire, le placer dans l&rsquo;autre camp, celui des n\u00e9o-conservateurs interventionnistes ? C&rsquo;est possible. Rien n&rsquo;est simple aujourd&rsquo;hui, \u00e0 Washington, o\u00f9 le pouvoir est \u00e9clat\u00e9 en une multitude de tendances, de groupes de pressions, d&rsquo;int\u00e9r\u00eats priv\u00e9s. Il faut pourtant savoir qu&rsquo;existe cette inconnue-Rumsfeld et qu&rsquo;elle se place \u00e0 l&rsquo;arri\u00e8re-plan d&rsquo;une querelle id\u00e9ologique tr\u00e8s intense, tr\u00e8s haineuse, entre deux courants se disant conservateurs et s&rsquo;excluant l&rsquo;un l&rsquo;autre. La fin de la guerre contre l&rsquo;Irak d\u00e9charge certains d&rsquo;entre eux d&rsquo;un devoir de r\u00e9serve qu&rsquo;ils s&rsquo;\u00e9taient impos\u00e9s, comme Patrick Buchanan, qui a soutenu la guerre contre l&rsquo;Irak par devoir, <a href=\"http:\/\/www.worldnetdaily.com\/news\/article.asp?ARTICLE_ID=31953\" class=\"gen\"> <\/p>\n<\/p>\n<p><p>\tmais qui retrouve sa libert\u00e9 critique.<\/a><\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>America stands on the threshold of military victory. But the fear and loathing of America in the Islamic world is on a scale none of us has ever known. President Bush has an opportunity to alter this harsh and hateful perception. If he will honor his commitment to rebuild an Iraq ruined by dictatorship, sanctions and war, if he will let the Iraqis choose their own leaders, if he will bring American occupation troops home at the earliest possible date, he can give the lie to the myth that America seeks an empire in the Islamic world.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>But he must first tell Woolsey, Perle &#038; Co. that he, not they, runs U.S. foreign policy. It is all up to him. Republic or Empire. The president alone will decide.<\/em> \u00bb<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00e9nigme Rumsfeld et les conservateurs d\u00e9chir\u00e9s 12 avril 2003 La question que nous posions le 3 avril dernier concernant le secr\u00e9taire \u00e0 la d\u00e9fense Rumsfeld est bien s\u00fbr compl\u00e8tement d&rsquo;actualit\u00e9, et beaucoup plus vite qu&rsquo;on ne pouvait attendre. C&rsquo;est la question de savoir quelle politique Rumsfeld va suivre, lui qui occupe d\u00e9sormais une position de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3335,3831],"class_list":["post-65566","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-buchanan","tag-neo-conservateurs"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65566"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65566\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}