{"id":65573,"date":"2003-04-17T00:00:00","date_gmt":"2003-04-17T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2003\/04\/17\/la-chute-de-la-presse-americaine-ou-la-chute-dun-mythe-qui-na-jamais-ete-justifie-par-la-realite-historique\/"},"modified":"2003-04-17T00:00:00","modified_gmt":"2003-04-17T00:00:00","slug":"la-chute-de-la-presse-americaine-ou-la-chute-dun-mythe-qui-na-jamais-ete-justifie-par-la-realite-historique","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2003\/04\/17\/la-chute-de-la-presse-americaine-ou-la-chute-dun-mythe-qui-na-jamais-ete-justifie-par-la-realite-historique\/","title":{"rendered":"<strong><em>La chute de la presse am\u00e9ricaine, \u2014 ou la chute d&rsquo;un mythe qui n&rsquo;a jamais \u00e9t\u00e9 justifi\u00e9 par la r\u00e9alit\u00e9 historique<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">La chute de la presse am\u00e9ricaine,  ou la chute d&rsquo;un mythe qui n&rsquo;a jamais \u00e9t\u00e9 justifi\u00e9 par la r\u00e9alit\u00e9 historique <\/h2>\n<\/p>\n<p><\/p>\n<p><p>\tLa presse am\u00e9ricaine, quel mythe. Il faut \u00e9couter parler Christine Ockrent de son stage de d\u00e9part chez CBS, \u00e0 la fin des ann\u00e9es 1970. Elle qui n&rsquo;a pas peur de l&rsquo;assurance et de la s\u00fbret\u00e9 de soi, devient soudain tout miel, comme un \u00e9l\u00e8ve parle de son ma\u00eetre, un croyant de son Dieu. C&rsquo;est effectivement la r\u00e9putation qu&rsquo;a la presse US en France,  en France, particuli\u00e8rement, sans aucun doute.<\/p>\n<\/p>\n<p><p>\tLa v\u00e9n\u00e9ration de la presse US en France s&rsquo;est install\u00e9e fermement dans les ann\u00e9es 1960, avec la p\u00e9n\u00e9tration des formules de journalisme US (<em>L&rsquo;Express<\/em> devenant un <em>news-magazine<\/em> \u00e0 l&rsquo;imitation de <em>Time<\/em> en 1964). La r\u00e9f\u00e9rence devint le journalisme \u00e0 l&rsquo;am\u00e9ricaine, privil\u00e9giant la vitesse, la bri\u00e8vet\u00e9, le fait de pr\u00e9f\u00e9rence au commentaire comme gage d&rsquo;objectivit\u00e9 (sans prendre garde au caract\u00e8re fondamental de cette m\u00e9thode, la tendance \u00e0 la s\u00e9lectivit\u00e9 des faits par les Anglo-Saxons). De ce tournant des ann\u00e9es 1960 est n\u00e9 le monde de la communication d&rsquo;aujourd&rsquo;hui (presse, t\u00e9l\u00e9vision, publicit\u00e9, relations publiques), dont l&rsquo;orientation politique, mais par la voie technique plus que par l&rsquo;id\u00e9ologie, est \u00e9videmment pro-am\u00e9ricaine.<\/p>\n<\/p>\n<p><p>\tDepuis cette \u00e9poque, avec le point d&rsquo;orgue du Watergate, la presse US, pour les professionnels fran\u00e7ais du domaine, c&rsquo;est une r\u00e9f\u00e9rence ultime et multiple  professionnalisme, int\u00e9grit\u00e9, ind\u00e9pendance par rapport au pouvoir politique, valeurs morales qui d\u00e9passent les engagements partisans et les notions de devoirs nationaux. C&rsquo;est dire si le comportement de la presse US, depuis le 11 septembre 2001, a remu\u00e9 plus d&rsquo;une \u00e2me journalistique parisienne.<\/p>\n<\/p>\n<p><p>\tNous vous pr\u00e9sentons trois textes, successivement, dans un ordre chronologique inverse, histoire d&rsquo;arriver peu \u00e0 peu au coeur du probl\u00e8me. Nous pensons qu&rsquo;avec ces trois textes, on peut se faire une meilleure id\u00e9e de la r\u00e9alit\u00e9 de la presse am\u00e9ricaine.<\/p>\n<\/p>\n<p><p>\t&bull; Un texte extrait de <em>Marianne<\/em> du 7 avril 2003, pr\u00e9sentant le ph\u00e9nom\u00e8ne de la chute de la r\u00e9putation des m\u00e9dias anglo-saxons depuis le 11 septembre 2001.<\/p>\n<\/p>\n<p><p>\t&bull; Un texte publi\u00e9 dans <em>de defensa<\/em>, dans la rubrique <em>Contexte<\/em>, du Volume 13, n\u00b011 du 25 f\u00e9vrier 1998. Ce texte avait \u00e9t\u00e9 \u00e9crit en commentaire de la vague de critiques apr\u00e8s la r\u00e9v\u00e9lation de l&rsquo;affaire Lewinski par un site d&rsquo;Internet, reprenant une information dont <em>Newsweek<\/em> avait diff\u00e9r\u00e9 la publication. Ensuite, l&rsquo;affaire Lewinski s&rsquo;\u00e9tait transform\u00e9e en un ouragan m\u00e9diatique et les m\u00e9thodes de la presse US, surtout ses centres d&rsquo;int\u00e9r\u00eat, avaient \u00e9t\u00e9 mises en question en Europe, surtout en France. Le mythe de la presse lib\u00e9rale et s\u00e9rieuse se trouvait mis \u00e0 mal dans la mesure o\u00f9 la presse attaquait, pour une raison jug\u00e9e futile ou d\u00e9plac\u00e9e, \u00e0 la suite d&rsquo;une enqu\u00eate o\u00f9 certains voyaient un complot d&rsquo;extr\u00eame-droite, un pr\u00e9sident qui \u00e9tait le favori des milieux intellectuels fran\u00e7ais. <\/p>\n<\/p>\n<p><p>\t&bull; Un extrait du <em>Voyage en Am\u00e9rique<\/em>, de Charles Dickens, chapitre XVIII, Derniers commentaires (\u00e9dit\u00e9 chez Ph\u00e9bus, Paris, 1994). On a les appr\u00e9ciations du grand \u00e9crivain anglais, apr\u00e8s un voyage en Am\u00e9rique en 1842. Ce livre est celui d&rsquo;une d\u00e9ception terrible,  de l&rsquo;image idyllique que le jeune Dickens se faisait de l&rsquo;Am\u00e9rique \u00e0 la r\u00e9alit\u00e9 qu&rsquo;il d\u00e9couvre. <\/p>\n<\/p>\n<p><\/p>\n<h2 class=\"common-article\">La chute des m\u00e9dias anglo-saxons<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t<strong>Marianne, 7 avril 2003<\/strong><\/p>\n<\/p>\n<p><p>\tC&rsquo;\u00e9tait un mythe. Lorsque, en France, on voulut concevoir des hebdomadaires \u00ab modernes \u00bb, on les baptisa \u00ab <em>news-magazines<\/em> \u00bb et on prit pour mod\u00e8les <em>Times<\/em> et <em>Newsweek<\/em>. Chaque fois que des journalistes r\u00eav\u00e8rent de cr\u00e9er des quotidiens ind\u00e9pendants de qualit\u00e9, ils affirm\u00e8rent vouloir faire un <em>Washington Post<\/em>. Les mod\u00e8les de journaux populaires, pendant quatre d\u00e9cennies, furent anglais. <em>Le Parisien<\/em>, par exemple, n&rsquo;en \u00e9tait que le d\u00e9calque. C&rsquo;est encore en r\u00e9f\u00e9rence au journalisme \u00ab anglo-saxon \u00bb que les m\u00e9dias fran\u00e7ais se convertirent \u00e0 l&rsquo;investigation. Et chacun chercha \u00e0 r\u00e9aliser son \u00ab Watergate \u00bb. Le reportage \u00e0 \u00ab l&rsquo;am\u00e9ricaine \u00bb, l&rsquo;enqu\u00eate \u00e0 \u00ab l&rsquo;am\u00e9ricaine \u00bb, \u00e9taient cens\u00e9s constituer un <em>must<\/em>. L&rsquo;objectivit\u00e9 anglo-saxonne, caract\u00e9ris\u00e9e par une s\u00e9paration stricte entre l&rsquo;information et le commentaire, \u00e9tait partout donn\u00e9e en exemple.<\/p>\n<\/p>\n<p><p>\tOr, qu&rsquo;a-t-on d\u00e9couvert en quelques mois ? Qu&rsquo;une sale guerre avait \u00e9t\u00e9 rendue possible, comme pr\u00e9justifi\u00e9e (comme du temps d&rsquo;Hearst) par une sale presse. Cette presse-l\u00e0 \u00e9tait anglo-saxonne ! Aucun m\u00e9dia fran\u00e7ais n&rsquo;aurait os\u00e9 atteindre les sommets de d\u00e9lires propagandistes nourris par une logorrh\u00e9e x\u00e9nophobe qu&rsquo;ont franchis, pour leur part, le <em>Sun<\/em>, le <em>Daily Telegraph<\/em> ou le <em>Daily Mail<\/em> de Londres, le <em>Wall Street journal<\/em>, le <em>Washington Times<\/em> ou le <em>New York Post<\/em> aux Etats-Unis. Le mythique <em>Washington Post<\/em> lui-m\u00eame s&rsquo;est fait, jusqu&rsquo;\u00e0 ces derniers jours, le v\u00e9hicule non distanci\u00e9 de la phras\u00e9ologie autosatisfaite qui a conduit l&rsquo;Am\u00e9rique \u00e0 se pr\u00e9cipiter dans l&rsquo;infernal bourbier irakien. Aussi biais\u00e9es et orient\u00e9es soient- elles, les informations d&rsquo;Al-Jazira se sont r\u00e9v\u00e9l\u00e9es finalement plus fiables que celles de CNN ; les m\u00e9dias irakiens n&rsquo;ont presque rien \u00e0 envier \u00e0 certains networks am\u00e9ricains du groupe Murdoch, tel Fox News qui, sur fond de musique martiale, promotionne la guerre comme un spectacle de vari\u00e9t\u00e9s.<\/p>\n<\/p>\n<p><p>\tCertaines t\u00e9l\u00e9visions vont jusqu&rsquo;\u00e0 censurer les images de \u00ab d\u00e9g\u00e2ts collat\u00e9raux \u00bb les reporters d&rsquo;outre-Atlantique ont presque tous quitt\u00e9 Bagdad (donc aucun t\u00e9moignage de ce c\u00f4t\u00e9), et l&rsquo;un des rares qui \u00e9tait rest\u00e9 a \u00e9t\u00e9 licenci\u00e9 pour avoir \u00e9voqu\u00e9 \u00f9 la t\u00e9l\u00e9vision irakienne l&rsquo;\u00e9chec du plan Rumsfeld. Douze jours apr\u00e8s le d\u00e9but de l&rsquo;offensive, la plupart des Am\u00e9ricains n&rsquo;\u00e9taient toujours pas inform\u00e9s de ce qui se passait r\u00e9ellement sur le terrain de la vraie guerre.<\/p>\n<\/p>\n<p><p>\tPour toute une g\u00e9n\u00e9ration de journalistes, les m\u00e9dias anglo-saxons constitu\u00e8rent un phare. Bien que le <em>Guardian<\/em>, le <em>Mirror<\/em> ou le <em>New York Times<\/em> aient sauv\u00e9 l&rsquo;honneur, il semble bien que la guerre d&rsquo;Irak ait contribu\u00e9 \u00e0 l&rsquo;\u00e9teindre.<\/p>\n<\/p>\n<p><\/p>\n<h2 class=\"common-article\">\u00ab Cette presse r\u00e9put\u00e9e si s\u00e9rieuse \u00bb<\/h2>\n<\/p>\n<p><p>\t\u00ab <em>Qu&rsquo;est-ce qui a bien pu tourner la t\u00eate de cette presse r\u00e9put\u00e9e si s\u00e9rieuse<\/em> ? \u00bb interroge gravement <em>Le Nouvel Observateur<\/em> \u00e0 propos du scandale <em>Monicagate<\/em>. Il y a une r\u00e9ponse toute pr\u00eate, qui est une tangente : \u00ab <em>Tout simple : la vitesse de l&rsquo;information, et la comp\u00e9tition effr\u00e9n\u00e9e que se livrent les m\u00e9dias.<\/em> \u00bb Autrement dit : un accident, ou bien une nouvelle orientation qui n&rsquo;a rien \u00e0 voir avec les qualit\u00e9s morales de cette presse (car c&rsquo;est bien moralement, c&rsquo;est-\u00e0-dire vertueusement qu&rsquo;il faut entendre le terme \u00ab <em>s\u00e9rieux<\/em> \u00bb) ; sa r\u00e9putation reste justifi\u00e9e par son pass\u00e9. Autrement dit encore : tout ce que nous pensions et pensons encore de la presse am\u00e9ricaine reste justifi\u00e9. C&rsquo;est l\u00e0 l&rsquo;essentiel de l&rsquo;argument : la presse am\u00e9ricaine, comme tout le reste lorsqu&rsquo;il s&rsquo;agit de l&rsquo;Am\u00e9rique, est l&rsquo;objet de la m\u00eame interpr\u00e9tation dont est par\u00e9e l&rsquo;id\u00e9e am\u00e9ricaine, jusqu&rsquo;\u00e0 faire repr\u00e9senter l&rsquo;Am\u00e9rique comme une image conforme \u00e0 l&rsquo;<em>American Dream<\/em>. Bien qu&rsquo;europ\u00e9en, le d\u00e9bat est surtout fran\u00e7ais, sans aucun doute.<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;impose par cons\u00e9quent de chercher \u00e0 voir ce qu&rsquo;il en est exactement : la r\u00e9alit\u00e9 et l&rsquo;histoire de la presse am\u00e9ricaine justifient-elles le cr\u00e9dit qu&rsquo;on lui accorde d&rsquo;instinct ? Dans ce pays, la presse a n\u00e9cessairement un r\u00f4le capital ; pas tant par les vertus et le r\u00f4le quasi-institutionnel qu&rsquo;on lui pr\u00eate dans la machinerie de fonctionnement du syst\u00e8me de l&rsquo;am\u00e9ricanisme (ce sont l\u00e0 des appr\u00e9ciations chronologiquement secondaires) que par la place qui lui y est n\u00e9cessairement d\u00e9volue dans la recette initiale. Le syst\u00e8me de l&rsquo;am\u00e9ricanisme \u00e9tant d&rsquo;essence \u00e9conomiste et organis\u00e9e par les puissances d&rsquo;argent, son but ontologique est d&#8217;emp\u00eacher le pouvoir (ou assez de pouvoir pour \u00eatre d\u00e9cisif) d&rsquo;\u00eatre transf\u00e9r\u00e9 vers le politique pour \u00e9viter la possibilit\u00e9 d&rsquo;une tendance r\u00e9formiste. Il favorise ainsi au maximum l&rsquo;individualisme (par ailleurs si n\u00e9cessaire pour une \u00e9conomie fond\u00e9e sur le consum\u00e9risme et sur l&rsquo;initiative individuelle) : ses effets de dispersion des citoyens lui donne un r\u00f4le essentiel dans l&rsquo;entreprise de contenir l&rsquo;action politique. (Paradoxe : l&rsquo;extr\u00eame libert\u00e9 individuelle,y compris d&rsquo;exprimer toutes les opinions politiques du monde, interdit la coh\u00e9sion minimale indispensable \u00e0 un mouvement r\u00e9formiste s\u00e9rieux. Seul Roosevelt put transgresser cette r\u00e8gle en 1933-35, par une action dont l&rsquo;ampleur et la rapidit\u00e9 avaient effectivement un caract\u00e8re r\u00e9formiste. Mais c&rsquo;\u00e9tait la Grande Crise, et c&rsquo;\u00e9tait cela ou p\u00e9rir.) C&rsquo;est dans ce cadre qu&rsquo;il faut appr\u00e9cier l&rsquo;importance de la presse, organis\u00e9e en contre-pouvoir critique et irresponsable : une machinerie mise en place pour conforter l&rsquo;individualisme et par cons\u00e9quent, et sans le vouloir n\u00e9cessairement, contrecarrer toute organisation d&rsquo;un pouvoir politique r\u00e9formiste s\u00e9rieux.<\/p>\n<\/p>\n<p><p>\tCe qui caract\u00e9rise la presse aux \u00c9tats-Unis n&rsquo;est donc pas les vertus qu&rsquo;on lui pr\u00eate, dont la promotion est du domaine du sentimentalisme pur, mais bien le r\u00f4le actif majeur qu&rsquo;elle tient dans le syst\u00e8me. Il y a cette diff\u00e9rence essentielle avec la presse europ\u00e9enne : les puissances d&rsquo;argent ont compris d\u00e8s l&rsquo;origine son importance ontologique au syst\u00e8me en tant que ph\u00e9nom\u00e8ne social et non pas politique. D\u00e8s l&rsquo;origine, la presse b\u00e9n\u00e9ficia d&rsquo;un cadre l\u00e9gal favorable \u00e0 ses activit\u00e9s et de moyens importants. D\u00e8s l&rsquo;origine, elle occupa cette place essentielle qu&rsquo;on lui voit aujourd&rsquo;hui ; mais c&rsquo;\u00e9tait affaire de puissance et de libert\u00e9 d&rsquo;action, pas de vertu.<\/p>\n<h3>Un caract\u00e8re existant d\u00e8s l&rsquo;origine<\/h3>\n<\/p>\n<p><p>\tLa presse am\u00e9ricaine fit, d\u00e8s l&rsquo;origine \u00e9galement, son travail : chercher et d\u00e9busquer l&rsquo;in\u00e9dit et le sensationnel, attaquer l\u00e0 o\u00f9 cela l&rsquo;arrangeait, d\u00e9fendre qui elle avait int\u00e9r\u00eat \u00e0 d\u00e9fendre. Les recettes qu&rsquo;on d\u00e9nonce aujourd&rsquo;hui fonctionnaient d\u00e9j\u00e0. Elle \u00e9tait, comme toute presse, d&rsquo;une f\u00e9rocit\u00e9 irresponsable qui supplante all\u00e9grement celle qu&rsquo;on lui reproche aujourd&rsquo;hui. En t\u00e9moignent ces deux extraits, l&rsquo;un de 1795 (<em>The General Advertiser<\/em>), l&rsquo;autre de 1802 (<em>The New-England Palladium and Commercial Advertiser<\/em>) :<\/p>\n<\/p>\n<p><p>\t&bull; \u00ab <em>Si jamais une nation a \u00e9t\u00e9 d\u00e9bauch\u00e9e par un homme, c&rsquo;est la nation am\u00e9ricaine par Washington. Si jamais une nation a souffert de l&rsquo;influence indigne d&rsquo;un homme, c&rsquo;est la nation am\u00e9ricaine par l&rsquo;influence de Washington. Si jamais une nation a \u00e9t\u00e9 tromp\u00e9e par un homme, c&rsquo;est la nation am\u00e9ricaine par Washington.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t&bull; \u00ab <em>Si l&rsquo;infid\u00e8le Jefferson \u00e9tait \u00e9lu \u00e0 la pr\u00e9sidence, le sceau de la mort serait alors pos\u00e9 sur notre religion, nos \u00e9glises seraient prostr\u00e9es, et une prostitu\u00e9e d&rsquo;infamante r\u00e9putation, connue sous le nom de D\u00e9esse de la Raison, pr\u00e9siderait le sanctuaire aujourd&rsquo;hui consacr\u00e9e aux Plus Hautes pens\u00e9es.<\/em> \u00bb (1802)<\/p>\n<\/p>\n<p><p>\tEn 1899, Theodore Dreiser entama sa carri\u00e8re d&rsquo;\u00e9crivain qui allait le conduire aux plus hauts sommets de la litt\u00e9rature am\u00e9ricaine. Il s&rsquo;imposa comme le chef de file de l&rsquo;\u00e9cole naturaliste du XXe si\u00e8cle, pessimiste et sombre comme de l&rsquo;encre, infatigable critique du syst\u00e8me social am\u00e9ricain. II avait puis\u00e9 dans son m\u00e9tier de journaliste-<em>reporter<\/em> tout ce qui allait nourrir son oeuvre : \u00ab [D]<em>e cette \u00e9poque date mon contact r\u00e9el avec la vie  meurtres, incendie criminel, viol, sodomie, chantage, corruption, fourberie et faux t\u00e9moignage de toutes les fa\u00e7ons possibles.<\/em> \u00bb <\/p>\n<h3>Un caract\u00e8re historiquement constant<\/h3>\n<\/p>\n<p><p>\tLa presse am\u00e9ricaine sut de tous les temps pratiquer, par sa constante pression sur les acteurs des faits publics sensationnels, cette d\u00e9marche m\u00e9diatique qu&rsquo;on assimile parfois \u00e0 de la pers\u00e9cution. Charles Lindbergh con\u00e7ut une haine farouche \u00e0 l&rsquo;encontre de la presse \u00e0 la suite du comportement de celle-ci \u00e0 l&rsquo;\u00e9gard de sa famille et de lui-m\u00eame lors de l&rsquo;enl\u00e8vement et de l&rsquo;assassinat de son fils, en 1934. II s&rsquo;exila pendant cinq ann\u00e9es et refusa jusqu&rsquo;\u00e0 sa mort, en 1974, le moindre interview.<\/p>\n<\/p>\n<p><p>\tLe comportement de la presse am\u00e9ricaine dans les temps de crise ne s&rsquo;accorda jamais de fa\u00e7on syst\u00e9matique \u00e0 aucune vertu particuli\u00e8re. Dans son livre <em>J&rsquo;ai choisi MacCarthy<\/em>, Harvey Matusow, qui collabora comme t\u00e9moin professionnel avec le s\u00e9nateur du Wisconsin durant les ann\u00e9es 1950-54, d\u00e9crit les relations de McCarthy avec la presse, particuli\u00e8rement avec ce qu&rsquo;il nomme \u00ab <em>la presse maccarthyste<\/em> \u00bb, avec Willard Edwards du Chicago <em>Tribune<\/em>, avec Fulton Lewis Jr. et Ed Nellor, chroniqueurs radiodiffus\u00e9s. Ces journalistes relayaient syst\u00e9matiquement les informations calomnieuses et diffamatoires du groupe McCarthy, ils appliquaient scrupuleusement les consignes qui en \u00e9manaient, favorisaient les manoeuvres parlementaires et judiciaire. A l&rsquo;inverse, McCarthy devait affronter quelques adversaires de taille comme Drew Pearson et les fr\u00e8res Alsop, qui n&rsquo;avaient pas froid aux yeux. <\/p>\n<\/p>\n<p><p>\tDurant la crise du Viet-n\u00e2m, la presse fut au premier rang de la bataille politique. Les partisans de la guerre utilisaient les informations officielles sans trop s&rsquo;interroger \u00e0 leur propos. Ses adversaires (parfois, partisans reconvertis avec le temps et le cours des \u00e9v\u00e9nements), ne repoussaient pas les comportements douteux. \u00ab <em>A la fin de 1968<\/em>, \u00e9crivit dans son livre <em>Between Fact and Fiction<\/em> le journaliste Jay Epstein, <em>Jack Fern, un producteur de NBC, proposa \u00e0 Robert J. Northshield une s\u00e9rie en trois parties montrant que le T\u00eat<\/em> [la bataille du T\u00eat, en f\u00e9vrier 1968, remport\u00e9e militairement par les Am\u00e9ricains] <em>avait \u00e9t\u00e9, en fait, une victoire d\u00e9cisive pour l Am\u00e9rique.<\/em> [&#8230;] <em>Le projet fut rejet\u00e9 parce que, raconta Northshield plus tard, dans l&rsquo;esprit du public le T\u00eat \u00e9tait d\u00e9j\u00e0 r\u00e9pertori\u00e9 comme une d\u00e9faite, et c&rsquo;\u00e9tait donc une d\u00e9faite am\u00e9ricaine .<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tCe survol rapide permet de conclure : puissante, capable, investigatrice jusqu&rsquo;\u00e0 l&rsquo;inquisition au pire, la presse am\u00e9ricaine l&rsquo;a toujours \u00e9t\u00e9 ; vertueuse, objective, respectueuse des faits, c&rsquo;est-\u00e0-dire \u00ab <em>s\u00e9rieuse<\/em> \u00bb au fond, elle ne le fut pas plus qu&rsquo;une autre.<\/p>\n<h3>Le <em>Watergate<\/em>, ou le label de la vertu<\/h3>\n<\/p>\n<p><p>\tL&rsquo;affaire du <em>Watergate<\/em> est \u00e0 la base de la \u00ab <em>r\u00e9putation<\/em> \u00bb vertueuse de la presse am\u00e9ricaine. De ce point de vue, elle appara\u00eet presque trop belle : une enqu\u00eate partie de rien, men\u00e9e avec une opini\u00e2tret\u00e9 sans pareille, d\u00e9brouillant peu \u00e0 peu l&rsquo;\u00e9cheveau d&rsquo;un comportement \u00e9videmment scandaleux, soulevant un pays entier jusqu&rsquo;\u00e0 une de ses plus graves crises constitutionnelles, et achevant sur la capitulation sans conditions du coupable, l&rsquo;homme le plus puissant (en principe) de l&rsquo;Am\u00e9rique. Le regard jet\u00e9 alors de l&rsquo;ext\u00e9rieur sur la presse am\u00e9ricaine devint sans nuance : le plus grand professionnalisme du monde mis au service de la sauvegarde de la d\u00e9mocratie et de ses vertus morales.<\/p>\n<\/p>\n<p><p>\tReste que le comportement de la presse \u00e0 l&rsquo;encontre de Nixon fut celui d&rsquo;un acharnement inquisiteur extraordinaire, et qu&rsquo;il fut d\u00e9ploy\u00e9 alors qu&rsquo;aucune certitude n&rsquo;existait quant \u00e0 sa culpabilit\u00e9. Entre les affirmations v\u00e9rifi\u00e9es, bien des ragots furent lanc\u00e9s et jamais retranch\u00e9s. A ce moment, les journalistes n&rsquo;\u00e9taient pas n\u00e9cessairement vertueux ; ils \u00e9taient impitoyables, et ils faisaient leur m\u00e9tier comme ils l&rsquo;ont toujours fait, sans frein, d\u00e9cid\u00e9s \u00e0 aller jusqu&rsquo;au bout m\u00eame s&rsquo;ils aboutissaient \u00e0 un cul-de-sac. Il n&rsquo;y avait pas chez Woodward et Bernstein, les deux journalistes du <em>Post<\/em> \u00e0 la base de l&rsquo;enqu\u00eate, de certitude de la culpabilit\u00e9 du Pr\u00e9sident ; il y avait l&rsquo;intuition d&rsquo;un bon coup, une attitude bien plus journalistique que vertueuse. Celle-ci, la vertu, vint apr\u00e8s, au secours de la victoire. Que serait le jugement port\u00e9 sur l&rsquo;activit\u00e9 de la presse dans le cas d&rsquo;un <em>Watergate<\/em> aboutissant \u00e0 la mise en \u00e9vidence de l&rsquo;innocence de Nixon, sinon le m\u00eame qu&rsquo;on porte aujourd&rsquo;hui sur son activit\u00e9 \u00e0 l&rsquo;encontre de Clinton ? Mais on retint la vertu venue couronner la victoire et l&rsquo;on en con\u00e7ut r\u00e9troactivement une r\u00e9putation \u00ab <em>s\u00e9rieuse<\/em> \u00bb (vertueuse) pour la presse.<\/p>\n<h3>L\u00e0 o\u00f9 le jugement moral doit s&rsquo;exercer<\/h3>\n<\/p>\n<p><p>\tAujourd&rsquo;hui, c&rsquo;est \u00e0 partir de ces \u00e9l\u00e9ments fort troubles qu&rsquo;on porte un jugement, cette fois dans le sens d&rsquo;une condamnation, sur la presse am\u00e9ricaine dans l&rsquo;affaire dite <em>Monicagate<\/em>. Comme si elle avait failli \u00e0 sa vertu. C&rsquo;est un jugement de substance qui n&rsquo;est pas vraiment justifi\u00e9.<\/p>\n<\/p>\n<p><p>\tLe scandale n&rsquo;a rien mis en \u00e9vidence qui soit particulier \u00e0 la presse am\u00e9ricaine (c&rsquo;est pourquoi le <em>Monicagate<\/em> a \u00e9t\u00e9 compar\u00e9e \u00e0 la mort de la princesse Diana, qui n&rsquo;a rien d&rsquo;am\u00e9ricain, quant \u00e0 l&rsquo;activit\u00e9 m\u00e9diatique). Il a mis en \u00e9vidence, une fois de plus, l&rsquo;\u00e9volution des techniques journalistiques suscit\u00e9e sans surprise par l&rsquo;\u00e9volution des technologies et la pression des conditions et des n\u00e9cessit\u00e9s \u00e9conomiques. <em>Stricto sensu<\/em>, rien ni personne n&rsquo;est vraiment responsable d&rsquo;une fa\u00e7on fondamentale, et s&rsquo;arr\u00eater au seul cas de la presse n&rsquo;a gu\u00e8re de sens. On aborde le probl\u00e8me de fa\u00e7on tronqu\u00e9e et par cons\u00e9quent on le d\u00e9nature (et certains y ont int\u00e9r\u00eat) si on ne va pas \u00e0 son coeur, surtout lorsque celui-ci est anim\u00e9 par le poids d&rsquo;un domaine financier \u00e9crasant et la pression d&rsquo;une comp\u00e9tition exacerb\u00e9e. Le ph\u00e9nom\u00e8ne sans aucun doute extraordinaire du comportement de la presse am\u00e9ricaine dans le <em>Monicagate<\/em>,  extraordinaire jusqu&rsquo;\u00e0 changer la substance et l&rsquo;\u00e9volution de l&rsquo;\u00e9v\u00e9nement,  est un ph\u00e9nom\u00e8ne d&rsquo;ordre \u00e9conomique et id\u00e9ologique et nullement un ph\u00e9nom\u00e8ne de presse. On peut porter un jugement moral sur lui, si on s&rsquo;en pr\u00e9occupe, mais il doit concerner un ph\u00e9nom\u00e8ne \u00e9conomique et id\u00e9ologique et nullement un ph\u00e9nom\u00e8ne de presse.<\/p>\n<\/p>\n<p><\/p>\n<h2 class=\"common-article\">Ce que Charles Dickens pensait de la presse am\u00e9ricaine<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\tOn peut bien construire des \u00e9coles dans l&rsquo;Est, l&rsquo;Ouest, le Nord et le Sud, et former des ma\u00eetres par dizaines de milliers ; l&rsquo;Universit\u00e9 peut se bien porter, les \u00e9glises peuvent \u00eatre bond\u00e9es, la temp\u00e9rance peut gagner du terrain, et la connaissance au sens large se r\u00e9pandre dans le pays \u00e0 pas de g\u00e9ant ; mais, tant que la presse quotidienne approchera de l&rsquo;\u00e9tat d&rsquo;abjection dans lequel elle se trouve pr\u00e9sentement, on ne pourra compter sur un redressement moral dans ce pays. Les valeurs morales ne peuvent que r\u00e9gresser et r\u00e9gresseront d&rsquo;ann\u00e9e en ann\u00e9e ; le sentiment populaire ne peut que se d\u00e9grader d&rsquo;ann\u00e9e en ann\u00e9e ; le Congr\u00e8s et le S\u00e9nat ne pourront, d&rsquo;ann\u00e9e en ann\u00e9e, que se d\u00e9consid\u00e9rer aux yeux des honn\u00eates gens ; et d&rsquo;ann\u00e9e en ann\u00e9e, la m\u00e9moire des p\u00e8res de la R\u00e9volution sera toujours plus outrag\u00e9e par la mauvaise vie de leurs enfants d\u00e9g\u00e9n\u00e9r\u00e9s.<\/p>\n<\/p>\n<p><p>\tIl va sans dire que dans la quantit\u00e9 de feuilles publi\u00e9es aux \u00c9tats-Unis, certaines jouissent d&rsquo;une bonne r\u00e9putation et d&rsquo;un grand cr\u00e9dit. Et j&rsquo;ai retir\u00e9 plaisir et b\u00e9n\u00e9fice de mes rencontres avec des hommes accomplis li\u00e9s \u00e0 de telles publications. Mais celles-ci sont rares, quand les autres sont l\u00e9gion ; et l&rsquo;influence des bonnes ne suffit pas \u00e0 tenir en \u00e9chec le poison moral des mauvaises.<\/p>\n<\/p>\n<p><p>\tParmi les gens de bien, parmi les personnes r\u00e9fl\u00e9chies et bien inform\u00e9es, au sein des professions lib\u00e9rales, au sein du barreau et de la magistrature, tout le monde, comme on s&rsquo;en doute, convient du caract\u00e8re vicieux de ces inf\u00e2mes journaux. On soutient parfois  je ne dirai pas bizarrement, car il est naturel de chercher des excuses \u00e0 pareil scandale  que leur influence n&rsquo;est pas aussi grande qu&rsquo;on pourrait le supposer. Qu&rsquo;on me pardonne d&rsquo;affirmer que rien ne fonde ce plaidoyer, et que chaque fait et chaque d\u00e9tail tendent directement \u00e0 la conclusion inverse.<\/p>\n<\/p>\n<p><p>\tQuand chacun, quelles que soient ses qualit\u00e9s intellectuelles et morales, pourra atteindre \u00e0 n&rsquo;importe quelle distinction publique sans pr\u00e9alablement plier le genou et ramper devant ce monstre de d\u00e9pravation ; quand tout homme de m\u00e9rite sera \u00e0 l&rsquo;abri de ses attaques ; quand la confiance sera \u00e9pargn\u00e9e et que tout accord honorable et d\u00e9cent aura droit \u00e0 un d\u00e9but de consid\u00e9ration ; quand, dans ce pays de libert\u00e9, chacun jouira de la libert\u00e9 d&rsquo;opinion et pr\u00e9tendra penser et s&rsquo;exprimer par lui-m\u00eame, sans platement se r\u00e9f\u00e9rer \u00e0 une censure qu&rsquo;il ex\u00e8cre et m\u00e9prise en raison de son ignorance crasse et de sa vile improbit\u00e9 ; quand ceux qui ressentent le plus vivement son infamie et l&rsquo;opprobre qui en rejaillit sur la nation et qui entre eux d\u00e9noncent le plus violemment cet \u00e9tat de chose oseront au vu de tous l&rsquo;\u00e9craser sous leur talon, alors je croirai que son influence diminue et que les hommes sont en train de recouvrer la raison. Mais tant que cette presse glissera un oeil mauvais dans chaque foyer, et posera une main douteuse sur toutes les fonctions de l&rsquo;\u00c9tat, du pr\u00e9sident au postier, et tant qu&rsquo;avec la calomnie pour seule marchandise, elle sera la litt\u00e9rature standard d&rsquo;une multitude qui lit le journal ou ne lit pas du tout, son caract\u00e8re odieux p\u00e8sera sur le pays et son action n\u00e9faste restera manifeste au sein de la r\u00e9publique.<\/p>\n<\/p>\n<p><p>\tPour ceux qui sont habitu\u00e9s aux principaux journaux anglais ou aux estimables journaux du continent europ\u00e9en, et sont accoutum\u00e9s \u00e0 bien autre chose en fait de publications, il sera impossible, en l&rsquo;absence de morceaux choisis pour lesquels je n&rsquo;ai ni la place ni l&rsquo;inclination, de se faire une id\u00e9e pr\u00e9cise de cette effrayante machine. Mais quiconque souhaite confirmation de mon propos sur ce sujet peut se rendre en tout lieu de Londres o\u00f9 l&rsquo;on trouve des exemplaires de ces feuilles, et se former sa propre opinion.<\/p>\n<\/p>\n<p><p>\tIl serait bon, cela ne fait aucun doute, que le peuple am\u00e9ricain dans son ensemble go\u00fbte un peu moins le r\u00e9el et un peu plus l&rsquo;id\u00e9al. Il serait bon qu&rsquo;il soit encourag\u00e9 dans le sens de l&rsquo;all\u00e9gresse et de la gaiet\u00e9 de cur, et cultive plus largement ce qui est beau sans \u00eatre \u00e9minemment et directement utile. Mais ici, je pense que peut \u00eatre raisonnablement prise en compte la protestation g\u00e9n\u00e9rale \u00ab nous sommes un pays neuf \u00bb, couramment avanc\u00e9e pour jeter un voile sur des d\u00e9fauts assez injustifiables, qui conviennent mieux \u00e0 la lente croissance d&rsquo;un vieux pays ; et j&rsquo;esp\u00e8re encore apprendre que la nation am\u00e9ricaine conna\u00eet des divertissements autres que la politique vue \u00e0 travers les journaux.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La chute de la presse am\u00e9ricaine, ou la chute d&rsquo;un mythe qui n&rsquo;a jamais \u00e9t\u00e9 justifi\u00e9 par la r\u00e9alit\u00e9 historique La presse am\u00e9ricaine, quel mythe. Il faut \u00e9couter parler Christine Ockrent de son stage de d\u00e9part chez CBS, \u00e0 la fin des ann\u00e9es 1970. Elle qui n&rsquo;a pas peur de l&rsquo;assurance et de la s\u00fbret\u00e9&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[8],"tags":[934,3940,3941,3942],"class_list":["post-65573","post","type-post","status-publish","format-standard","hentry","category-notre-bibliotheque","tag-clinton","tag-dickens","tag-lewinsky","tag-marianne"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65573"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65573\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}