{"id":65623,"date":"2003-05-28T00:00:00","date_gmt":"2003-05-28T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2003\/05\/28\/un-triomphe-pour-leurope-et-un-defi-pour-les-usa\/"},"modified":"2003-05-28T00:00:00","modified_gmt":"2003-05-28T00:00:00","slug":"un-triomphe-pour-leurope-et-un-defi-pour-les-usa","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2003\/05\/28\/un-triomphe-pour-leurope-et-un-defi-pour-les-usa\/","title":{"rendered":"<strong><em>Un \u201ctriomphe\u201d pour l&rsquo;Europe et un d\u00e9fi pour les USA<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Un triomphe pour l&rsquo;Europe et un d\u00e9fi pour les USA<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t28 mai 2003  L&rsquo;Europe, quoiqu&rsquo;elle en veuille selon qu&rsquo;elle est la vieille Europe ou la <em>new Europe<\/em>, est encha\u00een\u00e9e \u00e0 la logique de la puissance que les \u00c9tats-Unis imposent aux relations internationales. S&rsquo;il y a unipolarit\u00e9, ce n&rsquo;est pas au niveau de la structure du monde comme le pr\u00e9tend Tony Blair pour donner un alibi \u00e0 sa politique, c&rsquo;est au niveau de la logique de la dynamique des relations internationales. D\u00e8s lors que le principal acteur impose une logique de la puissance, celle-ci, par son poids et son potentiel de destruction, entra\u00eene le reste. L&rsquo;Europe est condamn\u00e9e \u00e0 l&rsquo;Europe-puissance, ou bien \u00e0 ne pas exister.<\/p>\n<\/p>\n<p><p>\tLa journ\u00e9e d&rsquo;hier est une illustration de cette r\u00e9alit\u00e9. Trois d\u00e9cisions ont \u00e9t\u00e9 prises, auxquelles on ajoutera, comme une cerise symbolique sur le g\u00e2teau, l&rsquo;annonce de <a href=\"http:\/\/www.iht.com\/articles\/97699.html\" class=\"gen\">la performance de l&rsquo;euro qui a atteint son record absolu par rapport au dollar<\/a>, \u00e0 $1,19, avant de retomber l\u00e9g\u00e8rement. On comprend que la logique que nous d\u00e9crivons, et notre commentaire, conduisent \u00e0 une appr\u00e9ciation qui se d\u00e9veloppe par rapport \u00e0 une concurrence entre l&rsquo;Europe et les \u00c9tats-Unis.<\/p>\n<\/p>\n<p><p>\tLes trois d\u00e9cisions d&rsquo;hier sont les suivantes :<\/p>\n<\/p>\n<p><p>\t&bull; La signature du contrat entre sept pays europ\u00e9ens et Airbus pour le lancement de l&rsquo;A400M de transport militaire strat\u00e9gique, et la production de 180 exemplaires. Le programme a un fort potentiel d&rsquo;exportation. (L&rsquo;Allemagne ach\u00e8te 60 exemplaires, la France 50, l&rsquo;Espagne 27, le Royaume-Uni 25, la Belgique 7, le Luxembourg 1. Le programme est \u00e9valu\u00e9 \u00e0 20 milliards d&rsquo;euros.)<\/p>\n<\/p>\n<p><p>\t&bull; Le lancement du syst\u00e8me de navigation par satellite Galileo a \u00e9t\u00e9 formellement d\u00e9cid\u00e9 (premier lancement d&rsquo;un satellite, septembre 2005) . Ce syst\u00e8me est concurrent du syst\u00e8me GPS, am\u00e9ricain.<\/p>\n<\/p>\n<p><p>\t&bull; L&rsquo;Agence Spatiale Europ\u00e9enne a d\u00e9cid\u00e9 de relancer le lanceur spatial Ariane 5 (achat de nouveaux lanceurs, commande de la version 5ECA pour lancements doubles), ce qui devrait contribuer \u00e0 sortir le consortium de ses difficult\u00e9s \u00e9conomiques.<\/p>\n<\/p>\n<p><p>\tNous ne nous attachons pas aux aspects \u00e9conomiques et industriels de ces d\u00e9cisions. Consid\u00e9r\u00e9es de la sorte (\u00e9conomiquement et industriellement), ces d\u00e9cisions apparaissent comme innocentes. D&rsquo;autre part, et toujours consid\u00e9r\u00e9es <em>stricto sensu<\/em>, elles constituent en g\u00e9n\u00e9ral des d\u00e9cisions d\u00e9fensives (Ariane) ou tardives et illustratives des difficult\u00e9s europ\u00e9ennes (A400M, Galileo). Sous ce regard, elles seraient plut\u00f4t le signe de la faiblesse et des h\u00e9sitations europ\u00e9ennes, d&rsquo;ailleurs une appr\u00e9ciation assez proche des r\u00e9alit\u00e9s.<\/p>\n<\/p>\n<p><p>\tConsid\u00e9r\u00e9es d&rsquo;un point de vue politique et strat\u00e9gique, l&rsquo;appr\u00e9ciation est compl\u00e8tement boulevers\u00e9e, exactement inverse : ce sont trois pas en avant de l&rsquo;Europe dans le domaine strat\u00e9gique souverain de l&rsquo;industrie strat\u00e9gique par excellence,  l&rsquo;industrie a\u00e9rospatiale. C&rsquo;est de ce point de vue que les USA observeront ces trois d\u00e9cisions, et ils les percevront comme un d\u00e9fi de puissance (au grand dam des Europ\u00e9ens, n&rsquo;en doutons pas et soyons compatissants \u00e0 leur \u00e9gard). Par exemple, certains Europ\u00e9ens n&rsquo;ignorent pas que les principales agences de s\u00e9curit\u00e9 nationale des USA consid\u00e8rent la destruction de Galileo (par blocage, abandon, etc) comme \u00ab <em>la deuxi\u00e8me priorit\u00e9 strat\u00e9gique des \u00c9tats-Unis pour les 5 prochaines ann\u00e9es<\/em> \u00bb. Les Am\u00e9ricains iront m\u00eame jusqu&rsquo;\u00e0 consid\u00e9rer que certains de leurs amis en Europe (UK, Espagne, Italie), en participant \u00e0 l&rsquo;un ou\/et l&rsquo;autre de ces programmes, ne font rien moins que trahir leur engagement pro-am\u00e9ricain.<\/p>\n<\/p>\n<p><p>\tOn peut argumenter justement qu&rsquo;il s&rsquo;agit d&rsquo;une interpr\u00e9tation, par rapport \u00e0 la r\u00e9alit\u00e9. C&rsquo;est vrai. Cela correspond aux m\u00e9thodes actuelles et \u00e0 la structure psychologique m\u00eame de la perception de la puissance aujourd&rsquo;hui. L&rsquo;aspect offensif et strat\u00e9gique d&rsquo;affirmation d&rsquo;une Europe-puissance a, de ce point de vue, autant de r\u00e9alit\u00e9 que le soi-disant triomphe am\u00e9ricain en Irak, dont on sait combien <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=747\" class=\"gen\">il est cousu de fil blanc<\/a>.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est la perception qui compte, puisque les Am\u00e9ricains le veulent ainsi. Cette perception dit que l&rsquo;Europe s&rsquo;affirme comme une puissance, au travers de ces trois d\u00e9cisions. C&rsquo;est ainsi que les Am\u00e9ricains les interpr\u00e9teront. Ils y verront un d\u00e9fi majeur jet\u00e9 \u00e0 leur propre puissance.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un triomphe pour l&rsquo;Europe et un d\u00e9fi pour les USA 28 mai 2003 L&rsquo;Europe, quoiqu&rsquo;elle en veuille selon qu&rsquo;elle est la vieille Europe ou la new Europe, est encha\u00een\u00e9e \u00e0 la logique de la puissance que les \u00c9tats-Unis imposent aux relations internationales. S&rsquo;il y a unipolarit\u00e9, ce n&rsquo;est pas au niveau de la structure du&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[4009,4010,3431],"class_list":["post-65623","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-a400m","tag-ariane","tag-galileo"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65623"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65623\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}