{"id":65626,"date":"2003-05-30T00:00:00","date_gmt":"2003-05-30T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2003\/05\/30\/le-dod-va-t-il-reussir-son-regime-change-a-londres\/"},"modified":"2003-05-30T00:00:00","modified_gmt":"2003-05-30T00:00:00","slug":"le-dod-va-t-il-reussir-son-regime-change-a-londres","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2003\/05\/30\/le-dod-va-t-il-reussir-son-regime-change-a-londres\/","title":{"rendered":"<strong><em>Le DoD va-t-il r\u00e9ussir son \u201cregime change\u201d \u00e0 Londres ?<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Le DoD va-t-il r\u00e9ussir son regime change \u00e0 Londres ?<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t30 mai 2003  Nous vivons des temps \u00e9tonnants. La guerre qui devait durer des mois est finie depuis un mois et demi, apr\u00e8s trois semaines, et d\u00e9j\u00e0 la vraie guerre atteint son r\u00e9gime de croisi\u00e8re. La vraie guerre ? Celle qu&rsquo;on m\u00e8ne pour savoir pourquoi on a d\u00e9clench\u00e9 la guerre, l&rsquo;autre, celle de trois semaines. Bref, l&rsquo;affaire des WMD (appelons-les Weapons of Mass Destruction parce que, vraiment, c&rsquo;est une affaire anglo-saxonne).<\/p>\n<\/p>\n<p><p>\tAujourd&rsquo;hui, \u00e9tape suppl\u00e9mentaire : la vraie guerre des WMD n&rsquo;est m\u00eame plus de savoir s&rsquo;il y en a. Cela, aujourd&rsquo;hui, certains semblent s&rsquo;en d\u00e9sint\u00e9resser, et m\u00eame r\u00e9v\u00e9ler qu&rsquo;ils ne s&rsquo;y int\u00e9ress\u00e8rent jamais vraiment  disons, sauf quelques parlementaires, \u00e9ditorialistes, ministres, etc, du Royaume-Uni, qui s&rsquo;engag\u00e8rent dans cette guerre sur la foi de l&rsquo;existence pour eux indubitable de ces WMD. C&rsquo;est l\u00e0 que le scandale menace de prendre des allures de crise. Face \u00e0 l&rsquo;incroyable impudence des Am\u00e9ricains, essentiellement Rumsfeld-Wolfowitz au DoD, la fureur des Britanniques ne cesse d&rsquo;enfler, et l&rsquo;on peut commencer \u00e0 penser qu&rsquo;\u00e0 nouveau, hors-guerre pourrait-on dire, Tony Blair est s\u00e9rieusement menac\u00e9.<\/p>\n<\/p>\n<p><p>\tD\u00e9veloppons les deux aspects relev\u00e9s ci-dessus :<\/p>\n<\/p>\n<p><p>\t&bull; Apr\u00e8s des pr\u00e9cisions de Rumsfeld mercredi soir, disant n\u00e9gligemment qu&rsquo;effectivement, il n&rsquo;y a peut-\u00eatre pas de WMD en Irak, c&rsquo;est <a href=\"http:\/\/news.independent.co.uk\/world\/middle_east\/story.jsp?story=410730\" class=\"gen\">une d\u00e9claration de Wolfowitz<\/a> (dans une interview \u00e0 <em>Vanity Fair<\/em>) nous disant que l&rsquo;argument des WMD n&rsquo;\u00e9tait que cela,  un argument qui avait l&rsquo;avantage de mettre un terme \u00e0 une dispute bureaucratique en trouvant une logique sur laquelle tout le monde s&rsquo;accordait. Bref, l&rsquo;argument-WMD n&rsquo;a \u00e9t\u00e9 retenu que pour des motifs internes \u00e0 Washington, et nullement \u00e0 cause de son existence hypoth\u00e9tique. (D&rsquo;autres r\u00e9v\u00e9lations sont faites par Wolfowitz, notamment sur la n\u00e9cessit\u00e9 de conqu\u00e9rir l&rsquo;Irak pour remplacer l&rsquo;Arabie o\u00f9 les forces US ne pouvaient plus rester, et sur l&rsquo;activisme de Wolfowitz pour lancer une attaque contre l&rsquo;Irak aussit\u00f4t apr\u00e8s le 11 septembre, \u00e0 la place de l&rsquo;Afghanistan.)<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>The Bush administration focused on alleged weapons of mass destruction as the primary justification for toppling Saddam Hussein by force because it was politically convenient, a top-level official at the Pentagon has acknowledged. The extraordinary admission comes in an interview with Paul Wolfowitz, the Deputy Defence Secretary, in the July issue of the magazine Vanity Fair. <\/em><\/p>\n<\/p>\n<p><p>\t(&#8230;)<\/p>\n<\/p>\n<p><p>\t\u00bb <em>For bureaucratic reasons we settled on one issue, weapons of mass destruction, because it was the one reason everyone could agree on, Mr Wolfowitz tells the magazine. The comments suggest that, even for the US administration, the logic that was presented for going to war may have been an empty shell. They come to light, moreover, just two days after Mr Wolfowitz&rsquo;s immediate boss, Donald Rumsfeld, the Defence Secretary, conceded for the first time that the arms might never be found.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>The failure to find a single example of the weapons that London and Washington said were inside Iraq only makes the embarrassment more acute. Voices are increasingly being raised in the US  and Britain  demanding an explanation for why nothing has been found.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Most striking is the fact that these latest remarks come from Mr Wolfowitz, recognised widely as the leader of the hawks&rsquo; camp in Washington most responsible for urging President George Bush to use military might in Iraq. The magazine article reveals that Mr Wolfowitz was even pushing Mr Bush to attack Iraq immediately after the 11 September attacks in the US, instead of invading Afghanistan.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t&bull; Les r\u00e9actions au Royaume-Uni sont de plus en plus vives, comme le montre notamment un article de <a href=\"http:\/\/argument.independent.co.uk\/commentators\/story.jsp?story=410664\" class=\"gen\">Robin Cook, ce matin dans The Independent<\/a>. Le ministre d\u00e9missionnaire, sur la d\u00e9fensive au moment de la victoire en Irak, est aujourd&rsquo;hui compl\u00e8tement accusateur et met en question toute la politique de Tony Blair d&rsquo;alignement sur Washington.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>As Donald Rumsfeld might express it, we have been suckered. Britain was conned into a war to disarm a phantom threat in which not even our major ally really believed. The truth is that the US chose to attack Iraq not because it posed a threat, but because they knew it was weak and expected its military to collapse.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>It is a truth that leaves the British government in an uncomfortable position. This week Tony Blair was pleading for everyone to show patience and to wait for weapons to be found. There is an historic problem with this plea. The war only took place because the coalition powers lost patience with Hans Blix and refused his plea for a few more months to complete his disarmament tasks.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>There is also a growing problem of transatlantic politics with the British Prime Minister&rsquo;s plea for more time. The US administration wanted the war to achieve regime change and now they have got it they do not see why they need to keep up the pretence that they fought it to deliver disarmament. The more time passes, the greater the gulf will widen between the obliging candour on the US side that there never was a weapons threat and the desperate obfuscation on the British side that we might still find one.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>There is always a bigger problem in denying reality than in admitting the truth. The time has come when the British government needs to concede that we did not go to war because Saddam was a threat to our national interests. We went to war for reasons of US foreign policy and Republican domestic politics.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>One advantage of such clarity is that it would help prevent us from being suckered a second time. Which brings us to Rumsfeld&rsquo;s latest sabre-rattling against Iran. (&#8230;) <\/em> <\/p>\n<\/p>\n<p><p>\t(&#8230;)<\/p>\n<\/p>\n<p><p>\t\u00bb <em>The blanket hostility to Iran of the Bush administration has undermined the reformers and provided a welcome shot in the arm to the ayatollahs.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>British policy on Iran makes sense in securing the advance of the reformers, which is in the interests of ourselves and of the Iranian people. This time we must make clear to the White House that we are not going to subordinate Britain&rsquo;s interests to a US policy of confrontation. Iran must not become the next Iraq.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tCes \u00e9v\u00e9nements sont extraordinaires, comme toute cette crise ne cesse de nous conduire dans un domaine compl\u00e8tement inexplor\u00e9 auparavant, fait d&rsquo;inconscience, d&rsquo;indiff\u00e9rence aux vrais probl\u00e8mes, de manipulation du mensonge, etc. L&rsquo;attitude d&rsquo;indiff\u00e9rence du Pentagone au sort de Tony Blair et \u00e0 l&rsquo;alliance britannique dans cette affaire est stup\u00e9fiante, et ne peut s&rsquo;expliquer que par l&rsquo;\u00e9tat d&rsquo;esprit r\u00e9gnant \u00e0 Washington, d&rsquo;arrogance, de suffisance, voire d&rsquo;auto-d\u00e9sinformation sur les r\u00e9alit\u00e9s. Washington vit en plein virtualisme, int\u00e9ress\u00e9 par ses seules querelles internes, par la seule bataille entre les groupes d&rsquo;int\u00e9r\u00eats autour du pouvoir. <\/p>\n<\/p>\n<p><p>\tBien entendu, Tony Blair se trouve (une fois de plus) directement menac\u00e9 dans cette affaire, et, \u00e0 plus ou moins br\u00e8ve \u00e9ch\u00e9ance, la politique d&rsquo;alignement sur Washington. Le deuxi\u00e8me point est \u00e9videmment le plus important.  Si Blair continue \u00e0 soutenir la fiction des WMD, la politique de Londres sera mise en question en d\u00e9pit de lui, disons d\u00e8s son d\u00e9part, qui pourrait venir assez vite.<\/p>\n<\/p>\n<p><p>\tLe probl\u00e8me pour Blair est que, de plus en plus, cette affaire des WMD ne concerne plus les WMD. Les affirmations de Rumsfeld-Wolfowitz signifient que la d\u00e9cision de partir en guerre a \u00e9t\u00e9 prise sans aucune r\u00e9f\u00e9rence \u00e0 la r\u00e9alit\u00e9, simplement parce que cette guerre \u00e9tait voulue \u00e0 l&rsquo;int\u00e9rieur de Washington, au DoD pr\u00e9cis\u00e9ment. C&rsquo;est-\u00e0-dire que l&rsquo;existence ou pas des WMD n&rsquo;a plus tellement d&rsquo;importance, reste la d\u00e9marche de Washington qui a tromp\u00e9 Londres, ou, dans tous les cas, nombre de d\u00e9put\u00e9s et de dirigeants du parti travailliste. (Bien entendu, le cas est d&rsquo;autant plus spectaculaire qu&rsquo;on ne trouve pas de WMD.) Un tel scandale devrait mettre entre les deux capitales une telle mesure de m\u00e9fiance qu&rsquo;on voit mal la politique d&rsquo;alignement sur Washington, voire les <em>special relationships<\/em> elles-m\u00eames, survivre tr\u00e8s longtemps \u00e0 Tony Blair.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le DoD va-t-il r\u00e9ussir son regime change \u00e0 Londres ? 30 mai 2003 Nous vivons des temps \u00e9tonnants. La guerre qui devait durer des mois est finie depuis un mois et demi, apr\u00e8s trois semaines, et d\u00e9j\u00e0 la vraie guerre atteint son r\u00e9gime de croisi\u00e8re. La vraie guerre ? Celle qu&rsquo;on m\u00e8ne pour savoir pourquoi&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-65626","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65626"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65626\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}