{"id":65638,"date":"2003-06-09T00:00:00","date_gmt":"2003-06-09T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2003\/06\/09\/harvard-1978-le-defi-premonitoire-desoljenitsyne\/"},"modified":"2003-06-09T00:00:00","modified_gmt":"2003-06-09T00:00:00","slug":"harvard-1978-le-defi-premonitoire-desoljenitsyne","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2003\/06\/09\/harvard-1978-le-defi-premonitoire-desoljenitsyne\/","title":{"rendered":"Harvard, 1978 : le d\u00e9fi pr\u00e9monitoire de\u00a0Soljenitsyne"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Harvard, 1978 : le d\u00e9fi pr\u00e9monitoire de Soljenitsyne<\/h2>\n<\/p>\n<p><p>Le 8 juin 1978, Alexandre Soljenitsyne, qui venait de s&rsquo;installer aux USA apr\u00e8s avoir quitt\u00e9 l&rsquo;URSS en 1974, donna un important discours \u00e0 Harvard. On a retenu effectivement l&rsquo;expression de \u00ab\u00a0discours de Harvard\u00a0\u00bb. Bien entendu, Soljenitsyne y condamna le communisme et c\u00e9l\u00e9bra la libert\u00e9. La surprise vint du jugement qu&rsquo;il porta sur l&rsquo;Occident.<\/p>\n<\/p>\n<p><p>Loin d&rsquo;applaudir au r\u00e9gime lib\u00e9ral occidental, et particuli\u00e8rement en Am\u00e9rique, il porta au contraire un jugement s\u00e9v\u00e8re sur lui. Le discours, auquel assistaient Jimmy et Rosalynn Carter, fut un choc pour les Am\u00e9ricains.<\/p>\n<\/p>\n<p><p>&laquo; <em>But should I be asked, instead, whether I would propose the West, such as it is today, as a model to my country, I would frankly have to answer negatively. No, I could not recommend your society as an ideal for the transformation of ours. Through deep suffering, people in our own country have now achieved a spiritual development of such intensity that the Western system in its present state of spiritual exhaustion does not look attractive. Even those characteristics of your life which I have just enumerated are extremely saddening.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>A fact which cannot be disputed is the weakening of human personality in the West while in the East it has become firmer and stronger. Six decades for our people and three decades for the people of Eastern Europe; during that time we have been through a spiritual training far in advance of Western experience. The complex and deadly crush of life has produced stronger, deeper, and more interesting personalities than those generated by standardized Western well-being. Therefore, if our society were to be transformed into yours, it would mean an improvement in certain aspects, but also a change for the worse on some particularly significant points.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>La critique des valeurs occidentales de Soljenitsyne est particuli\u00e8rement pertinente aujourd&rsquo;hui. Elle explique au reste pourquoi Soljenitsyne, malgr\u00e9 son immense popularit\u00e9, devint rapidement aussi un objet de malaise pour la plupart des intellectuels occidentaux, align\u00e9s \u00e9videmment sur les standards occidentaux (am\u00e9ricanistes), souvent presque aussi efficacement que ne l&rsquo;\u00e9taient les intellectuels communistes. Un passage comme celui-ci est compl\u00e8tement d&rsquo;actualit\u00e9 aujourd&rsquo;hui, d&rsquo;une fa\u00e7on presque caricaturale  :<\/p>\n<\/p>\n<p><p>&laquo; <em>Without any censorship in the West, fashionable trends of thought and ideas are fastidiously separated from those that are not fashionable, and the latter, without ever being forbidden have little chance of finding their way into periodicals or books or being heard in colleges. Your scholars are free in the legal sense, but they are hemmed in by the idols of the prevailing fad. There is no open violence, as in the East; however, a selection dictated by fashion and the need to accommodate mass standards frequently prevents the most independent-minded persons from contributing to public life and gives rise to dangerous herd instincts that block dangerous herd development.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Soljenitsyne est vieux aujourd&rsquo;hui, et presque oubli\u00e9, dans tous les cas compl\u00e8tement \u00ab\u00a0pass\u00e9 de mode\u00a0\u00bb comme l&rsquo;est une vieille barbe qui ennuie avec ses discours. Y a-t-il une marque plus certaine de la qualit\u00e9 de sa pens\u00e9e ? Il faut relire le \u00ab\u00a0discours de Harvard\u00a0\u00bb pour bien comprendre qu&rsquo;il y eut des esprits, sortis de l&rsquo;enfer du <em>goulag<\/em> communiste, pour voir venir la catastrophe d&rsquo;apr\u00e8s le communisme.<\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p>________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955;font-size:2em;\">Un monde divis\u00e9<\/h2>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955;font-size:1.25em;\">Par Alexandre Soljenitsyne, Harvard University, 8 juin 1978<\/h3>\n<\/p>\n<p><\/p>\n<p>Je suis tr\u00e8s sinc\u00e8rement heureux de me trouver ici parmi vous, \u00e0 l&rsquo;occasion du 327e anniversaire de la fondation de cette universit\u00e9 si ancienne et si illustre. La devise de Harvard est  VERITAS. La v\u00e9rit\u00e9 est rarement douce \u00e0 entendre ; elle est presque toujours am\u00e8re. Mon discours d&rsquo;aujourd&rsquo;hui contient une part de v\u00e9rit\u00e9 ; je vous l&rsquo;apporte en ami, non en adversaire.<\/p>\n<\/p>\n<p><p>Il y a trois ans, aux Etats-Unis, j&rsquo;ai \u00e9t\u00e9 amen\u00e9 \u00e0 dire des choses que l&rsquo;on a rejet\u00e9es, qui ont paru inacceptables. Aujourd&rsquo;hui, nombreux sont ceux qui acquiescent \u00e0 mes propos d&rsquo;alors&#8230;<\/p>\n<\/p>\n<p><p>Le d\u00e9clin du courage est peut-\u00eatre le trait le plus saillant de l&rsquo;Ouest aujourd&rsquo;hui pour un observateur ext\u00e9rieur. Le monde occidental a perdu son courage civique, \u00e0 la fois dans son ensemble et singuli\u00e8rement, dans chaque pays, dans chaque gouvernement, dans chaque pays, et bien s&ucirc;r, aux Nations Unies. Ce d\u00e9clin du courage est particuli\u00e8rement sensible dans la couche dirigeante et dans la couche intellectuelle dominante, d&rsquo;o&ugrave; l&rsquo;impression que le courage a d\u00e9sert\u00e9 la soci\u00e9t\u00e9 toute enti\u00e8re. Bien s&ucirc;r, il y a encore beaucoup de courage individuel mais ce ne sont pas ces gens-l\u00e0 qui donnent sa direction \u00e0 la vie de la soci\u00e9t\u00e9. Les fonctionnaires politiques et intellectuels manifestent ce d\u00e9clin, cette faiblesse, cette irr\u00e9solution dans leurs actes, leurs discours et plus encore, dans les consid\u00e9rations th\u00e9oriques qu&rsquo;ils fournissent complaisamment pour prouver que cette mani\u00e8re d&rsquo;agir, qui fonde la politique d&rsquo;un &Eacute;tat sur la l\u00e2chet\u00e9 et la servilit\u00e9, est pragmatique, rationnelle et justifi\u00e9e, \u00e0 quelque hauteur intellectuelle et m\u00eame morale qu&rsquo;on se place. Ce d\u00e9clin du courage, qui semble aller ici ou l\u00e0 jusqu&rsquo;\u00e0 la perte de toute trace de virilit\u00e9, se trouve soulign\u00e9 avec une ironie toute particuli\u00e8re dans les cas o&ugrave; les m\u00eames fonctionnaires sont pris d&rsquo;un acc\u00e8s subit de vaillance et d&rsquo;intransigeance, \u00e0 l&rsquo;\u00e9gard de gouvernements sans force, de pays faibles que personne ne soutient ou de courants condamn\u00e9s par tous et manifestement incapables de rendre un seul coup. Alors que leurs langues s\u00e8chent et que leurs mains se paralysent face aux gouvernements puissants et aux forces mena\u00e7antes, face aux agresseurs et \u00e0 l&rsquo;Internationale de la terreur. Faut-il rappeler que le d\u00e9clin du courage a toujours \u00e9t\u00e9 consid\u00e9r\u00e9 comme le signe avant coureur de la fin ?<\/p>\n<p><\/p>\n<p>Quand les &Eacute;tats occidentaux modernes se sont form\u00e9s, fut pos\u00e9 comme principe que les gouvernements avaient pour vocation de servir l&rsquo;homme, et que la vie de l&rsquo;homme \u00e9tait orient\u00e9e vers la libert\u00e9 et la recherche du bonheur (en t\u00e9moigne la d\u00e9claration am\u00e9ricaine d&rsquo;Ind\u00e9pendance). Aujourd&rsquo;hui, enfin, les d\u00e9cennies pass\u00e9es de progr\u00e8s social et technique ont permis la r\u00e9alisation de ces aspirations : un &Eacute;tat assurant le bien-\u00eatre g\u00e9n\u00e9ral. Chaque citoyen s&rsquo;est vu accorder la libert\u00e9 tant d\u00e9sir\u00e9e, et des biens mat\u00e9riels en quantit\u00e9 et en qualit\u00e9 propres \u00e0 lui procurer, en th\u00e9orie, un bonheur complet, mais un bonheur au sens appauvri du mot, tel qu&rsquo;il a cours depuis ces m\u00eames d\u00e9cennies.<\/p>\n<\/p>\n<p><p>Au cours de cette \u00e9volution, cependant, un d\u00e9tail psychologique a \u00e9t\u00e9 n\u00e9glig\u00e9 : le d\u00e9sir permanent de poss\u00e9der toujours plus et d&rsquo;avoir une vie meilleure, et la lutte en ce sens, ont imprim\u00e9 sur de nombreux visages \u00e0 l&rsquo;Ouest les marques de l&rsquo;inqui\u00e9tude et m\u00eame de la d\u00e9pression, bien qu&rsquo;il soit courant de cacher soigneusement de tels sentiments. Cette comp\u00e9tition active et intense finit par dominer toute pens\u00e9e humaine et n&rsquo;ouvre pas le moins du monde la voie \u00e0 la libert\u00e9 du d\u00e9veloppement spirituel.<\/p>\n<p><\/p>\n<p>L&rsquo;ind\u00e9pendance de l&rsquo;individu \u00e0 l&rsquo;\u00e9gard de nombreuses formes de pression \u00e9tatique a \u00e9t\u00e9 garantie ; la majorit\u00e9 des gens ont b\u00e9n\u00e9fici\u00e9 du bien-\u00eatre, \u00e0 un niveau que leurs p\u00e8res et leurs grands-p\u00e8res n&rsquo;auraient m\u00eame pas imagin\u00e9 ; il est devenu possible d&rsquo;\u00e9lever les jeunes gens selon ces id\u00e9aux, de les pr\u00e9parer et de les appeler \u00e0 l&rsquo;\u00e9panouissement physique, au bonheur, au loisir, \u00e0 la possession de biens mat\u00e9riels, l&rsquo;argent, les loisirs, vers une libert\u00e9 quasi illimit\u00e9e dans le choix des plaisirs. Pourquoi devrions-nous renoncer \u00e0 tout cela ? Au nom de quoi devrait-on risquer sa pr\u00e9cieuse existence pour d\u00e9fendre le bien commun, et tout sp\u00e9cialement dans le cas douteux o&ugrave; la s\u00e9curit\u00e9 de la nation aurait \u00e0 \u00eatre d\u00e9fendue dans un pays lointain ?<\/p>\n<\/p>\n<p><p>M\u00eame la biologie nous enseigne qu&rsquo;un haut degr\u00e9 de confort n&rsquo;est pas bon pour l&rsquo;organisme. Aujourd&rsquo;hui, le confort de la vie de la soci\u00e9t\u00e9 occidentale commence \u00e0 \u00f4ter son masque pernicieux.<\/p>\n<p><\/p>\n<p>La soci\u00e9t\u00e9 occidentale s&rsquo;est choisie l&rsquo;organisation la plus appropri\u00e9e \u00e0 ses fins, une organisation que j&rsquo;appellerais l\u00e9galiste. Les limites des droits de l&rsquo;homme et de ce qui est bon sont fix\u00e9es par un syst\u00e8me de lois ; ces limites sont tr\u00e8s l\u00e2ches. Les hommes \u00e0 l&rsquo;Ouest ont acquis une habilet\u00e9 consid\u00e9rable pour utiliser, interpr\u00e9ter et manipuler la loi, bien que paradoxalement les lois tendent \u00e0 devenir bien trop compliqu\u00e9es \u00e0 comprendre pour une personne moyenne sans l&rsquo;aide d&rsquo;un expert. Tout conflit est r\u00e9solu par le recours \u00e0 la lettre de la loi, qui est consid\u00e9r\u00e9e comme le fin mot de tout. Si quelqu&rsquo;un se place du point de vue l\u00e9gal, plus rien ne peut lui \u00eatre oppos\u00e9 ; nul ne lui rappellera que cela pourrait n&rsquo;en \u00eatre pas moins ill\u00e9gitime. Impensable de parler de contrainte ou de renonciation \u00e0 ces droits, ni de demander de sacrifice ou de geste d\u00e9sint\u00e9ress\u00e9 : cela para&icirc;trait absurde. On n&rsquo;entend pour ainsi dire jamais parler de retenue volontaire : chacun lutte pour \u00e9tendre ses droits jusqu&rsquo;aux extr\u00eames limites des cadres l\u00e9gaux.<\/p>\n<\/p>\n<p><p> J&rsquo;ai v\u00e9cu toute ma vie sous un r\u00e9gime communiste, et je peux vous dire qu&rsquo;une soci\u00e9t\u00e9 sans r\u00e9f\u00e9rent l\u00e9gal objectif est particuli\u00e8rement terrible. Mais une soci\u00e9t\u00e9 bas\u00e9e sur la lettre de la loi, et n&rsquo;allant pas plus loin, \u00e9choue \u00e0 d\u00e9ployer \u00e0 son avantage le large champ des possibilit\u00e9s humaines. La lettre de la loi est trop froide et formelle pour avoir une influence b\u00e9n\u00e9fique sur la soci\u00e9t\u00e9. Quand la vie est tout enti\u00e8re tiss\u00e9e de relations l\u00e9galistes, il s&rsquo;en d\u00e9gage une atmosph\u00e8re de m\u00e9diocrit\u00e9 spirituelle qui paralyse les \u00e9lans les plus nobles de l&rsquo;homme.<\/p>\n<p><\/p>\n<p>Et il sera tout simplement impossible de relever les d\u00e9fis de notre si\u00e8cle mena\u00e7ant arm\u00e9s des seules armes d&rsquo;une structure sociale l\u00e9galiste.<\/p>\n<p><\/p>\n<p>Aujourd&rsquo;hui la soci\u00e9t\u00e9 occidentale nous r\u00e9v\u00e8le qu&rsquo;il r\u00e8gne une in\u00e9galit\u00e9 entre la libert\u00e9 d&rsquo;accomplir de bonnes actions et la libert\u00e9 d&rsquo;en accomplir de mauvaises. Un homme d&rsquo;Etat qui veut accomplir quelque chose d&rsquo;\u00e9minemment constructif pour son pays doit agir avec beaucoup de pr\u00e9cautions, avec timidit\u00e9 pourrait-on dire. Des milliers de critiques h\u00e2tives et irresponsables le heurtent de plein fouet \u00e0 chaque instant. Il se trouve constamment expos\u00e9 aux traits du Parlement, de la presse. Il doit justifier pas \u00e0 pas ses d\u00e9cisions, comme \u00e9tant bien fond\u00e9es et absolument sans d\u00e9fauts. Et un homme exceptionnel, de grande valeur, qui aurait en t\u00eate des projets inhabituels et inattendus, n&rsquo;a aucune chance de s&rsquo;imposer : d&#8217;embl\u00e9e on lui tendra mille pi\u00e8ges. De ce fait, la m\u00e9diocrit\u00e9 triomphe sous le masque des limitations d\u00e9mocratiques.<\/p>\n<p><\/p>\n<p>Il est ais\u00e9 en tout lieu de saper le pouvoir administratif, et il a en fait \u00e9t\u00e9 consid\u00e9rablement amoindri dans tous les pays occidentaux. La d\u00e9fense des droits individuels a pris de telles proportions que la soci\u00e9t\u00e9 en tant que telle est d\u00e9sormais sans d\u00e9fense contre les initiatives de quelques-uns. Il est temps, \u00e0 l&rsquo;Ouest, de d\u00e9fendre non pas tant les droits de l&rsquo;homme que ses devoirs.<\/p>\n<p><\/p>\n<p>D&rsquo;un autre c\u00f4t\u00e9, une libert\u00e9 destructrice et irresponsable s&rsquo;est vue accorder un espace sans limite. Il s&rsquo;av\u00e8re que la soci\u00e9t\u00e9 n&rsquo;a plus que des d\u00e9fenses infimes \u00e0 opposer \u00e0 l&rsquo;ab&icirc;me de la d\u00e9cadence humaine, par exemple en ce qui concerne le mauvais usage de la libert\u00e9 en mati\u00e8re de violence morale faite aux enfants, par des films tout pleins de pornographie, de crime, d&rsquo;horreur. On consid\u00e8re que tout cela fait partie de la libert\u00e9, et peut \u00eatre contrebalanc\u00e9, en th\u00e9orie, par le droit qu&rsquo;ont ces m\u00eames enfants de ne pas regarder er de refuser ces spectacles. L&rsquo;organisation l\u00e9galiste de la vie a prouv\u00e9 ainsi son incapacit\u00e9 \u00e0 se d\u00e9fendre contre la corrosion du mal&#8230;<\/p>\n<p><\/p>\n<p>L&rsquo;\u00e9volution s&rsquo;est faite progressivement, mais il semble qu&rsquo;elle ait eu pour point de d\u00e9part la bienveillante conception humaniste selon laquelle l&rsquo;homme, ma&icirc;tre du monde, ne porte en lui aucun germe de mal, et tout ce que notre existence offre de vici\u00e9 est simplement le fruit de syst\u00e8mes sociaux erron\u00e9s qu&rsquo;il importe d&rsquo;amender. Et pourtant, il est bien \u00e9trange de voir que le crime n&rsquo;a pas disparu \u00e0 l&rsquo;Ouest, alors m\u00eame que les meilleures conditions de vie sociale semblent avoir \u00e9t\u00e9 atteintes. Le crime est m\u00eame bien plus pr\u00e9sent que dans la soci\u00e9t\u00e9 sovi\u00e9tique, mis\u00e9rable et sans loi&#8230;<\/p>\n<\/p>\n<p><p>La presse, aussi, bien s&ucirc;r, jouit de la plus grande libert\u00e9. Mais pour quel usage ? Quelle responsabilit\u00e9 s&rsquo;exerce sur le journaliste, ou sur un journal, \u00e0 l&rsquo;encontre de son lectorat, ou de l&rsquo;histoire ? S&rsquo;ils ont tromp\u00e9 l&rsquo;opinion publique en divulguant des informations erron\u00e9es, ou de fausses conclusions, si m\u00eame ils ont contribu\u00e9 \u00e0 ce que des fautes soient commises au plus haut degr\u00e9 de l&rsquo;Etat, avons-nous le souvenir d&rsquo;un seul cas, o&ugrave; le dit journaliste ou le dit journal ait exprim\u00e9 quelque regret ? Non, bien s&ucirc;r, cela porterait pr\u00e9judice aux ventes. De telles erreurs peut bien d\u00e9couler le pire pour une nation, le journaliste s&rsquo;en tirera toujours. &Eacute;tant donn\u00e9 que l&rsquo;on a besoin d&rsquo;une information cr\u00e9dible et imm\u00e9diate, il devient obligatoire d&rsquo;avoir recours aux conjectures, aux rumeurs, aux suppositions pour remplir les trous, et rien de tout cela ne sera jamais r\u00e9fut\u00e9 ; ces mensonges s&rsquo;installent dans la m\u00e9moire du lecteur. Combien de jugements h\u00e2tifs, irr\u00e9fl\u00e9chis, superficiels et trompeurs sont ainsi \u00e9mis quotidiennement, jetant le trouble chez le lecteur, et le laissant ensuite \u00e0 lui-m\u00eame ? La presse peut jouer le r\u00f4le d&rsquo;opinion publique, ou la tromper. De la sorte, on verra des terroristes peints sous les traits de h\u00e9ros, des secrets d&rsquo;Etat touchant \u00e0 la s\u00e9curit\u00e9 du pays divulgu\u00e9s sur la place publique, ou encore des intrusions sans vergogne dans l&rsquo;intimit\u00e9 de personnes connues, en vertu du slogan : &laquo; tout le monde a le droit de tout savoir &raquo;. Mais c&rsquo;est un slogan faux, fruit d&rsquo;une \u00e9poque fausse ; d&rsquo;une bien plus grande valeur est ce droit confisqu\u00e9, le droit des hommes de ne pas savoir, de ne pas voir leur \u00e2me divine \u00e9touff\u00e9e sous les ragots, les stupidit\u00e9s, les paroles vaines. Une personne qui m\u00e8ne une vie pleine de travail et de sens n&rsquo;a absolument pas besoin de ce flot pesant et incessant d&rsquo;information. Autre chose ne manquera pas de surprendre un observateur venu de l&rsquo;Est totalitaire, avec sa presse rigoureusement univoque : on d\u00e9couvre un courant g\u00e9n\u00e9ral d&rsquo;id\u00e9es privil\u00e9gi\u00e9es au sein de la presse occidentale dans son ensemble, une sorte d&rsquo;esprit du temps, fait de crit\u00e8res de jugement reconnus par tous, d&rsquo;int\u00e9r\u00eats communs, la somme de tout cela donnant le sentiment non d&rsquo;une comp\u00e9tition mais d&rsquo;une uniformit\u00e9. Il existe peut-\u00eatre une libert\u00e9 sans limite pour la presse, mais certainement pas pour le lecteur : les journaux ne font que transmettre avec \u00e9nergie et emphase toutes ces opinions qui ne vont pas trop ouvertement contredire ce courant dominant.<\/p>\n<p><\/p>\n<p>Sans qu&rsquo;il y ait besoin de censure, les courants de pens\u00e9e, d&rsquo;id\u00e9es \u00e0 la mode sont s\u00e9par\u00e9s avec soin de ceux qui ne le sont pas, et ces derniers, sans \u00eatre \u00e0 proprement parler interdits, n&rsquo;ont que peu de chances de percer au milieu des autres ouvrages et p\u00e9riodiques, ou d&rsquo;\u00eatre relay\u00e9s dans le sup\u00e9rieur. Vos \u00e9tudiants sont libres au sens l\u00e9gal du terme, mais ils sont prisonniers des idoles port\u00e9es aux nues par l&rsquo;engouement \u00e0 la mode. Sans qu&rsquo;il y ait, comme \u00e0 l&rsquo;Est, de violence ouverte, cette s\u00e9lection op\u00e9r\u00e9e par la mode, ce besoin de tout conformer \u00e0 des mod\u00e8les standards, emp\u00eachent les penseurs les plus originaux d&rsquo;apporter leur contribution \u00e0 la vie publique et provoquent l&rsquo;apparition d&rsquo;un dangereux esprit gr\u00e9gaire qui fait obstacle \u00e0 un d\u00e9veloppement digne de ce nom. Aux &Eacute;tats-Unis, il m&rsquo;est arriv\u00e9 de recevoir des lettres de personnes \u00e9minemment intelligentes &#8230; peut-\u00eatre un professeur d&rsquo;un petit coll\u00e8ge perdu, qui aurait pu beaucoup pour le renouveau et le salut de son pays, mais le pays ne pouvait l&rsquo;entendre, car les m\u00e9dia n&rsquo;allaient pas lui donner la parole. Voil\u00e0 qui donne naissance \u00e0 de solides pr\u00e9jug\u00e9s de masse, \u00e0 un aveuglement qui \u00e0 notre \u00e9poque est particuli\u00e8rement dangereux. <\/p>\n<\/p>\n<p><p>Il est universellement admis que l&rsquo;Ouest montre la voie au monde entier vers le d\u00e9veloppement \u00e9conomique r\u00e9ussi, m\u00eame si dans les derni\u00e8res ann\u00e9es il a pu \u00eatre s\u00e9rieusement entam\u00e9 par une inflation chaotique. Et pourtant, beaucoup d&rsquo;hommes \u00e0 l&rsquo;Ouest ne sont pas satisfaits de la soci\u00e9t\u00e9 dans laquelle ils vivent. Ils la m\u00e9prisent, ou l&rsquo;accusent de ne plus \u00eatre au niveau de maturit\u00e9 requis par l&rsquo;humanit\u00e9. Et beaucoup sont amen\u00e9s \u00e0 glisser vers le socialisme, ce qui est une tentation fausse et dangereuse. J&rsquo;esp\u00e8re que personne ici pr\u00e9sent ne me suspectera de vouloir exprimer une critique du syst\u00e8me occidental dans l&rsquo;id\u00e9e de sugg\u00e9rer le socialisme comme alternative. Non, pour avoir connu un pays o&ugrave; le socialisme a \u00e9t\u00e9 mis en oeuvre, je ne me prononcerai pas en faveur d&rsquo;une telle alternative. Mais si l&rsquo;on me demandait si, en retour, je pourrais proposer l&rsquo;Ouest, en son \u00e9tat actuel, comme mod\u00e8le pour mon pays, il me faudrait en toute honn\u00eatet\u00e9 r\u00e9pondre par la n\u00e9gative. Non, je ne prendrais pas votre soci\u00e9t\u00e9 comme mod\u00e8le pour la transformation de la mienne. On ne peut nier que les personnalit\u00e9s s&rsquo;affaiblissent \u00e0 l&rsquo;Ouest, tandis qu&rsquo;\u00e0 l&rsquo;Est elles ne cessent de devenir plus fermes et plus fortes. Bien s&ucirc;r, une soci\u00e9t\u00e9 ne peut rester dans des ab&icirc;mes d&rsquo;anarchie, comme c&rsquo;est le cas dans mon pays. Mais il est tout aussi avilissant pour elle de rester dans un \u00e9tat affadi et sans \u00e2me de l\u00e9galisme, comme c&rsquo;est le cas de la v\u00f4tre. Apr\u00e8s avoir souffert pendant des d\u00e9cennies de violence et d&rsquo;oppression, l&rsquo;\u00e2me humaine aspire \u00e0 des choses plus \u00e9lev\u00e9es, plus br&ucirc;lantes, plus pures que celles offertes aujourd&rsquo;hui par les habitudes d&rsquo;une soci\u00e9t\u00e9 massifi\u00e9e, forg\u00e9es par l&rsquo;invasion r\u00e9voltante de publicit\u00e9s commerciales, par l&rsquo;abrutissement t\u00e9l\u00e9visuel, et par une musique intol\u00e9rable.<\/p>\n<p><\/p>\n<p>Tout cela est sensible pour de nombreux observateurs partout sur la plan\u00e8te. Le mode de vie occidental appara&icirc;t de moins en moins comme le mod\u00e8le directeur. Il est des sympt\u00f4mes r\u00e9v\u00e9lateurs par lesquels l&rsquo;histoire lance des avertissements \u00e0 une soci\u00e9t\u00e9 menac\u00e9e ou en p\u00e9ril. De tels avertissements sont, en l&rsquo;occurrence, le d\u00e9clin des arts, ou le manque de grands hommes d&rsquo;Etat. Et il arrive parfois que les signes soient particuli\u00e8rement concrets et explicites. Le centre de votre d\u00e9mocratie et de votre culture est-il priv\u00e9 de courant pendant quelques heures, et voil\u00e0 que soudainement des foules de citoyens am\u00e9ricains se livrent au pillage et au grabuge. C&rsquo;est que le vernis doit \u00eatre bien fin, et le syst\u00e8me social bien instable et mal en point.<\/p>\n<p><\/p>\n<p>Mais le combat pour notre plan\u00e8te, physique et spirituel, un combat aux proportions cosmiques, n&rsquo;est pas pour un futur lointain ; il a d\u00e9j\u00e0 commenc\u00e9. Les forces du Mal ont commenc\u00e9 leur offensive d\u00e9cisive. Vous sentez d\u00e9j\u00e0 la pression qu&rsquo;elles exercent, et pourtant, vos \u00e9crans et vos \u00e9crits sont pleins de sourires sur commande et de verres lev\u00e9s. Pourquoi toute cette joie ?<\/p>\n<p><\/p>\n<p>Comment l&rsquo;Ouest a-t-il pu d\u00e9cliner, de son pas triomphal \u00e0 sa d\u00e9bilit\u00e9 pr\u00e9sente ? A-t-il connu dans son \u00e9volution des points de non-retour qui lui furent fatals, a-t-il perdu son chemin ? Il ne semble pas que cela soit le cas. L&rsquo;Ouest a continu\u00e9 \u00e0 avancer d&rsquo;un pas ferme en ad\u00e9quation avec ses intentions proclam\u00e9es pour la soci\u00e9t\u00e9, main dans la main avec un progr\u00e8s technologique \u00e9tourdissant. Et tout soudain il s&rsquo;est trouv\u00e9 dans son \u00e9tat pr\u00e9sent de faiblesse. Cela signifie que l&rsquo;erreur doit \u00eatre \u00e0 la racine, \u00e0 la fondation de la pens\u00e9e moderne. Je parle de la vision du monde qui a pr\u00e9valu en Occident \u00e0 l&rsquo;\u00e9poque moderne. Je parle de la vision du monde qui a pr\u00e9valu en Occident, n\u00e9e \u00e0 la Renaissance, et dont les d\u00e9veloppements politiques se sont manifest\u00e9s \u00e0 partir des Lumi\u00e8res. Elle est devenue la base da la doctrine sociale et politique et pourrait \u00eatre appel\u00e9e l&rsquo;humanisme rationaliste, ou l&rsquo;autonomie humaniste : l&rsquo;autonomie proclam\u00e9e et pratiqu\u00e9e de l&rsquo;homme \u00e0 l&rsquo;encontre de toute force sup\u00e9rieure \u00e0 lui. On peut parler aussi d&rsquo;anthropocentrisme : l&rsquo;homme est vu au centre de tout.<\/p>\n<\/p>\n<p><p>Historiquement, il est probable que l&rsquo;inflexion qui s&rsquo;est produite \u00e0 la Renaissance \u00e9tait in\u00e9vitable. Le Moyen &Acirc;ge en \u00e9tait venu naturellement \u00e0 l&rsquo;\u00e9puisement, en raison d&rsquo;une r\u00e9pression intol\u00e9rable de la nature charnelle de l&rsquo;homme en faveur de sa nature spirituelle. Mais en s&rsquo;\u00e9cartant de l&rsquo;esprit, l&rsquo;homme s&#8217;empara de tout ce qui est mat\u00e9riel, avec exc\u00e8s et sans mesure. La pens\u00e9e humaniste, qui s&rsquo;est proclam\u00e9e notre guide, n&rsquo;admettait pas l&rsquo;existence d&rsquo;un mal intrins\u00e8que en l&rsquo;homme, et ne voyait pas de t\u00e2che plus noble que d&rsquo;atteindre le bonheur sur terre. Voil\u00e0 qui engagea la civilisation occidentale moderne naissante sur la pente dangereuse de l&rsquo;adoration de l&rsquo;homme et de ses besoins mat\u00e9riels. Tout ce qui se trouvait au-del\u00e0 du bien-\u00eatre physique et de l&rsquo;accumulation de biens mat\u00e9riels, tous les autres besoins humains, caract\u00e9ristiques d&rsquo;une nature subtile et \u00e9lev\u00e9e, furent rejet\u00e9s hors du champ d&rsquo;int\u00e9r\u00eat de l&rsquo;Etat et du syst\u00e8me social, comme si la vie n&rsquo;avait pas un sens plus \u00e9lev\u00e9. De la sorte, des failles furent laiss\u00e9es ouvertes pour que s&rsquo;y engouffre le mal, et son haleine putride souffle librement aujourd&rsquo;hui. Plus de libert\u00e9 en soi ne r\u00e9sout pas le moins du monde l&rsquo;int\u00e9gralit\u00e9 des probl\u00e8mes humains, et m\u00eame en ajoute un certain nombre de nouveaux.<\/p>\n<\/p>\n<p><p>Et pourtant, dans les jeunes d\u00e9mocraties, comme la d\u00e9mocratie am\u00e9ricaine naissante, tous les droits de l&rsquo;homme individuels reposaient sur la croyance que l&rsquo;homme est une cr\u00e9ature de Dieu. C&rsquo;est-\u00e0-dire que la libert\u00e9 \u00e9tait accord\u00e9e \u00e0 l&rsquo;individu de mani\u00e8re conditionnelle, soumise constamment \u00e0 sa responsabilit\u00e9 religieuse. Tel fut l&rsquo;h\u00e9ritage du si\u00e8cle pass\u00e9.<\/p>\n<p><\/p>\n<p>Toutes les limitations de cette sorte s&rsquo;\u00e9mouss\u00e8rent en Occident, une \u00e9mancipation compl\u00e8te survint, malgr\u00e9 l&rsquo;h\u00e9ritage moral de si\u00e8cles chr\u00e9tiens, avec leurs prodiges de mis\u00e9ricorde et de sacrifice. Les &Eacute;tats devinrent sans cesse plus mat\u00e9rialistes. L&rsquo;Occident a d\u00e9fendu avec succ\u00e8s, et m\u00eame surabondamment, les droits de l&rsquo;homme, mais l&rsquo;homme a vu compl\u00e8tement s&rsquo;\u00e9tioler la conscience de sa responsabilit\u00e9 devant Dieu et la soci\u00e9t\u00e9. Durant ces derni\u00e8res d\u00e9cennies, cet \u00e9go\u00efsme juridique de la philosophie occidentale a \u00e9t\u00e9 d\u00e9finitivement r\u00e9alis\u00e9, et le monde se retrouve dans une cruelle crise spirituelle et dans une impasse politique. Et tous les succ\u00e8s techniques, y compris la conqu\u00eate de l&rsquo;espace, du Progr\u00e8s tant c\u00e9l\u00e9br\u00e9 n&rsquo;ont pas r\u00e9ussi \u00e0 racheter la mis\u00e8re morale dans laquelle est tomb\u00e9 le XX\u00e8me si\u00e8cle, que personne n&rsquo;aurait pu encore soup\u00e7onner au XIX\u00e8me si\u00e8cle.<\/p>\n<p><\/p>\n<p>L&rsquo;humanisme dans ses d\u00e9veloppements devenant toujours plus mat\u00e9rialiste, il permit avec une incroyable efficacit\u00e9 \u00e0 ses concepts d&rsquo;\u00eatre utilis\u00e9s d&rsquo;abord par le socialisme, puis par le communisme, de telle sorte que Karl Marx p&ucirc;t dire, en 1844, que &laquo; le communisme est un humanisme naturalis\u00e9 &raquo;.  Il s&rsquo;est av\u00e9r\u00e9 que ce jugement \u00e9tait loin d&rsquo;\u00eatre faux. On voit les m\u00eames pierres aux fondations d&rsquo;un humanisme alt\u00e9r\u00e9 et de tout type de socialisme : un mat\u00e9rialisme sans frein, une lib\u00e9ration \u00e0 l&rsquo;\u00e9gard de la religion et de la responsabilit\u00e9 religieuse, une concentration des esprits sur les structures sociales avec une approche pr\u00e9tendument scientifique. Ce n&rsquo;est pas un hasard si toutes les promesses rh\u00e9toriques du communisme sont centr\u00e9es sur l&rsquo;Homme, avec un grand H, et son bonheur terrestre. A premi\u00e8re vue, il s&rsquo;agit d&rsquo;un rapprochement honteux : comment, il y aurait des points communs entre la pens\u00e9e de l&rsquo;Ouest et de l&rsquo;Est aujourd&rsquo;hui ? L\u00e0 est la logique du d\u00e9veloppement mat\u00e9rialiste&#8230;<\/p>\n<p><\/p>\n<p>Je ne pense pas au cas d&rsquo;une catastrophe amen\u00e9e par une guerre mondiale, et aux changements qui pourraient en r\u00e9sulter pour la soci\u00e9t\u00e9. Aussi longtemps que nous nous r\u00e9veillerons chaque matin, sous un soleil paisible, notre vie sera in\u00e9vitablement tiss\u00e9e de banalit\u00e9s quotidiennes. Mais il est une catastrophe qui pour beaucoup est d\u00e9j\u00e0 pr\u00e9sente pour nous. Je veux parler du d\u00e9sastre d&rsquo;une conscience humaniste parfaitement autonome et irr\u00e9ligieuse.<\/p>\n<p><\/p>\n<p>Elle a fait de l&rsquo;homme la mesure de toutes choses sur terre, l&rsquo;homme imparfait, qui n&rsquo;est jamais d\u00e9nu\u00e9 d&rsquo;orgueil, d&rsquo;\u00e9go\u00efsme, d&rsquo;envie, de vanit\u00e9, et tant d&rsquo;autres d\u00e9fauts. Nous payons aujourd&rsquo;hui les erreurs qui n&rsquo;\u00e9taient pas apparues comme telles au d\u00e9but de notre voyage. Sur la route qui nous a amen\u00e9s de la Renaissance \u00e0 nos jours, notre exp\u00e9rience s&rsquo;est enrichie, mais nous avons perdu l&rsquo;id\u00e9e d&rsquo;une entit\u00e9 sup\u00e9rieure qui autrefois r\u00e9fr\u00e9nait nos passions et notre irresponsabilit\u00e9.<\/p>\n<\/p>\n<p><p>Nous avions plac\u00e9 trop d&rsquo;espoirs dans les transformations politico-sociales, et il se r\u00e9v\u00e8le qu&rsquo;on nous enl\u00e8ve ce que nous avons de plus pr\u00e9cieux : notre vie int\u00e9rieure. A l&rsquo;Est, c&rsquo;est la foire du Parti qui la foule aux pieds, \u00e0 l&rsquo;Ouest la foire du Commerce : ce qui est effrayant, ce n&rsquo;est m\u00eame pas le fait du monde \u00e9clat\u00e9, c&rsquo;est que les principaux morceaux en soient atteints d&rsquo;une maladie analogue. Si l&rsquo;homme, comme le d\u00e9clare l&rsquo;humanisme, n&rsquo;\u00e9tait n\u00e9 que pour le bonheur, il ne serait pas n\u00e9 non plus pour la mort. Mais corporellement vou\u00e9 \u00e0 la mort, sa t\u00e2che sur cette terre n&rsquo;en devient que plus spirituelle : non pas un gorgement de quotidiennet\u00e9, non pas la recherche des meilleurs moyens d&rsquo;acquisition, puis de joyeuse d\u00e9pense des biens mat\u00e9riels, mais l&rsquo;accomplissement d&rsquo;un dur et permanent devoir, en sorte que tout le chemin de notre vie devienne l&rsquo;exp\u00e9rience d&rsquo;une \u00e9l\u00e9vation avant tout spirituelle : quitter cette vie en cr\u00e9atures plus hautes que nous n&rsquo;y \u00e9tions entr\u00e9s.<\/p>\n<\/p>\n<p><p>Il est imp\u00e9ratif que nous revoyions \u00e0 la hausse l&rsquo;\u00e9chelle de nos valeurs humaines. Sa pauvret\u00e9 actuelle est effarante. Il n&rsquo;est pas possible que l&rsquo;aune qui sert \u00e0 mesurer l&rsquo;efficacit\u00e9 d&rsquo;un pr\u00e9sident se limite \u00e0 la question de combien d&rsquo;argent l&rsquo;on peut gagner, ou de la pertinence de la construction d&rsquo;un gazoduc. Ce n&rsquo;est que par un mouvement volontaire de mod\u00e9ration de nos passions, sereine et accept\u00e9e par nous, que l&rsquo;humanit\u00e9 peut s&rsquo;\u00e9lever au-dessus du courant de mat\u00e9rialisme qui emprisonne le monde.<\/p>\n<p><\/p>\n<p>Quand bien m\u00eame nous serait \u00e9pargn\u00e9 d&rsquo;\u00eatre d\u00e9truits par la guerre, notre vie doit changer si elle ne veut pas p\u00e9rir par sa propre faute. Nous ne pouvons nous dispenser de rappeler ce qu&rsquo;est fondamentalement la vie, la soci\u00e9t\u00e9. Est-ce vrai que l&rsquo;homme est au-dessus de tout ? N&rsquo;y a-t-il aucun esprit sup\u00e9rieur au-dessus de lui ? Les activit\u00e9s humaines et sociales peuvent-elles l\u00e9gitimement \u00eatre r\u00e9gl\u00e9es par la seule expansion mat\u00e9rielle ? A-t-on le droit de promouvoir cette expansion au d\u00e9triment de l&rsquo;int\u00e9grit\u00e9 de notre vie spirituelle ?<\/p>\n<p><\/p>\n<p>Si le monde ne touche pas \u00e0 sa fin, il a atteint une \u00e9tape d\u00e9cisive dans son histoire, semblable en importance au tournant qui a conduit du Moyen-\u00e2ge \u00e0 la Renaissance. Cela va requ\u00e9rir de nous un embrasement spirituel. Il nous faudra nous hisser \u00e0 une nouvelle hauteur de vue, \u00e0 une nouvelle conception de la vie, o&ugrave; notre nature physique ne sera pas maudite, comme elle a pu l&rsquo;\u00eatre au Moyen-\u00e2ge, mais, ce qui est bien plus important, o&ugrave; notre \u00eatre spirituel ne sera pas non plus pi\u00e9tin\u00e9, comme il le fut \u00e0 l&rsquo;\u00e8re moderne. Notre ascension nous m\u00e8ne \u00e0 une nouvelle \u00e9tape anthropologique. Nous n&rsquo;avons pas d&rsquo;autre choix que de monter : toujours plus haut.<\/p>\n<\/p>\n<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\"> <\/h2><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Harvard, 1978 : le d\u00e9fi pr\u00e9monitoire de Soljenitsyne Le 8 juin 1978, Alexandre Soljenitsyne, qui venait de s&rsquo;installer aux USA apr\u00e8s avoir quitt\u00e9 l&rsquo;URSS en 1974, donna un important discours \u00e0 Harvard. On a retenu effectivement l&rsquo;expression de \u00ab\u00a0discours de Harvard\u00a0\u00bb. Bien entendu, Soljenitsyne y condamna le communisme et c\u00e9l\u00e9bra la libert\u00e9. La surprise vint&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[8],"tags":[3643,4034,3161,4032,4035,4033],"class_list":["post-65638","post","type-post","status-publish","format-standard","hentry","category-notre-bibliotheque","tag-carter","tag-communisme","tag-dissidence","tag-harvard","tag-liberalisme","tag-soljenitsyne"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65638"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65638\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}