{"id":65647,"date":"2003-06-15T00:00:00","date_gmt":"2003-06-15T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2003\/06\/15\/apres-tout-sont-ils-si-mauvais-ces-talibans\/"},"modified":"2003-06-15T00:00:00","modified_gmt":"2003-06-15T00:00:00","slug":"apres-tout-sont-ils-si-mauvais-ces-talibans","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2003\/06\/15\/apres-tout-sont-ils-si-mauvais-ces-talibans\/","title":{"rendered":"<strong><em>Apr\u00e8s tout, sont-ils si mauvais ces talibans ?<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Apr\u00e8s tout, sont-ils si mauvais ces talibans ?<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t15 juin 2003  La guerre contre la terreur est litt\u00e9ralement \u00e9puisante, particuli\u00e8rement pour les professeurs de morale vertueuse en Occident. C&rsquo;est-\u00e0-dire qu&rsquo;il faut suivre et adapter la morale aux circonstances, en \u00e9vitant l&rsquo;\u00e9cueil du ridicule (mortel dans les salons).<\/p>\n<\/p>\n<p><p>\tUne chose, au moins, restait s\u00fbre dans notre vision sentimentale du monde : la justesse morale de l&rsquo;attaque am\u00e9ricaine contre l&rsquo;Afghanistan et, \u00e0 l&rsquo;inverse, la noirceur morale et ind\u00e9l\u00e9bile des talibans. Cela fut une grande cause d&rsquo;une saison germanopratine au moins, notamment une grande cause f\u00e9ministe, avec ces pauvres afghanes lourdement emprisonn\u00e9es dans leur carcan de tissu. L&rsquo;un des premiers <em>shows<\/em> de la lib\u00e9ration de l&rsquo;Afghanistan (et l&rsquo;un des seuls) fut celui du d\u00e9voilement des femmes afghanes.<\/p>\n<\/p>\n<p><p>\tAujourd&rsquo;hui, il semble qu&rsquo;il faille d\u00e9chanter, dans tous les cas du point de vue de notre vertu occidentale. Des indications s\u00e9rieuses, venues de l&rsquo;excellent site <em>atimes.com<\/em> (tr\u00e8s bon sur ces questions li\u00e9es \u00e0 l&rsquo;Afghanistan), nous annoncent que des contacts ont \u00e9t\u00e9 pris <a href=\"http:\/\/atimes.com\/atimes\/Central_Asia\/EF14Ag01.html\" class=\"gen\">entre Am\u00e9ricains et talibans,<\/a> sous les auspices des Pakistanais (autres mauvais de la pi\u00e8ce, qui apparaissent pourtant toujours en selle). Du c\u00f4t\u00e9 US, c&rsquo;est le FBI qui serait impliqu\u00e9, et l&rsquo;ISI (renseignement) du c\u00f4t\u00e9 pakistanais. Une rencontre aurait eu lieu r\u00e9cemment sur la base pakistanaise de Samungli, pr\u00e8s de Quetta. Les Am\u00e9ricains sont demandeurs et ils posent la question : les talibans sont-ils pr\u00eats \u00e0 participer au pouvoir en Afghanistan ? En jeu, la situation en Afghanistan, qui ne cesse de se d\u00e9t\u00e9riorer.<\/p>\n<\/p>\n<p><p>\tLes Am\u00e9ricains posent quatre conditions, les talibans en refusent une et sont souples sur les autres. On s&rsquo;est vu une fois, on se reverra sans doute. Extraits :<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>The source told Asia Times Online that four conditions were put to the Taliban before any form of reconciliation can take place that could potentially lead to them having a role in the Kabul government, whose present authority is in essence limited to the capital:<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>* Mullah Omar must be removed as supreme leader of the Taliban.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>* All Pakistani, Arab and other foreign fighters currently engaged in operations against international troops in Afghanistan must be thrown out of the country.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>* Any US or allied soldiers held captive must be released.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>* Afghans currently living abroad, notably in the United States and England, must be given a part in the government  through being allowed to contest elections  even though many do not even speak their mother tongue, such as Dari or Pashtu.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Apparently, the Taliban refused the first condition point blank, but showed some flexibility on the other terms. As such, this first preliminary contact made little headway. It is not known whether there will be further meetings, but given the fact that the reason for staging the talks in the first place remains unchanged, more contact can be expected.<\/em> \u00bb <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tIl est difficile de faire un commentaire sur la question elle-m\u00eame du retour \u00e9ventuel des talibans. On doit se montrer plus g\u00e9n\u00e9ral, pour observer combien la guerre contre la terreur est d\u00e9sormais entr\u00e9e dans le domaine de ses contradictions internes les plus radicales et, par cons\u00e9quent, les plus mortelles dans une \u00e9poque m\u00e9diatique et virtualiste qui ne survit que par l&rsquo;affirmation martel\u00e9e d&rsquo;une morale d&rsquo;apparence. L&rsquo;essentiel est de d\u00e9fendre l&rsquo;apparence de cette morale. C&rsquo;est cela qui est ici mis en cause.<\/p>\n<\/p>\n<p><p>\tAvec l&rsquo;apr\u00e8s-guerre irakien qui montre les plus grandes difficult\u00e9s et des contradictions \u00e9galement d\u00e9stabilisatrices pour la cause occidentale (d\u00e9veloppement de l&rsquo;islamisme, absence de WMD irakiennes, etc), ce d\u00e9veloppement afghan ajoute \u00e0 la confusion. Il mesure l&rsquo;essoufflement du grand projet de l&rsquo;administration GW et des extr\u00e9mistes am\u00e9ricanistes. Il devrait contribuer \u00e0 accentuer la grande crise du modernisme occidental, qui ne cesse elle-m\u00eame de se trouver confront\u00e9e \u00e0 ses contradictions.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s tout, sont-ils si mauvais ces talibans ? 15 juin 2003 La guerre contre la terreur est litt\u00e9ralement \u00e9puisante, particuli\u00e8rement pour les professeurs de morale vertueuse en Occident. C&rsquo;est-\u00e0-dire qu&rsquo;il faut suivre et adapter la morale aux circonstances, en \u00e9vitant l&rsquo;\u00e9cueil du ridicule (mortel dans les salons). Une chose, au moins, restait s\u00fbre dans notre&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3236,2838,4041,3379],"class_list":["post-65647","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-afghanistan","tag-fbi","tag-isi","tag-pakistan"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65647"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65647\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}