{"id":65664,"date":"2003-07-05T00:00:00","date_gmt":"2003-07-05T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2003\/07\/05\/gw-et-berlusconi-letrange-facon-de-mesurer-la-crise\/"},"modified":"2003-07-05T00:00:00","modified_gmt":"2003-07-05T00:00:00","slug":"gw-et-berlusconi-letrange-facon-de-mesurer-la-crise","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2003\/07\/05\/gw-et-berlusconi-letrange-facon-de-mesurer-la-crise\/","title":{"rendered":"<strong><em>GW et Berlusconi : l&rsquo;\u00e9trange fa\u00e7on de mesurer la crise<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">GW et Berlusconi : l&rsquo;\u00e9trange fa\u00e7on de mesurer la crise<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t5 juillet 2003  En deux jours, deux hommes ont fait parler d&rsquo;eux d&rsquo;une bien \u00e9trange fa\u00e7on. Ces deux hommes ne sont pas, para\u00eet-il, n&rsquo;importe qui, ou monsieur tout-le-monde comme on dit dans la presse chic. Il s&rsquo;agit d&rsquo;un pr\u00e9sident, sorte d&rsquo;Empereur \u00e0 ses heures, et d&rsquo;un Premier ministre, milliardaire dans les affaires \u00e0 toutes les heures.<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit de GW avec son \u00ab <em>Bring em on !<\/em> \u00bb (le <a href=\"http:\/\/www.dedefensa.org\/choix.php?link_id=2787&#038;comm=1\" class=\"gen\">qu&rsquo;ils y viennent ! adress\u00e9 aux Irakiens anti-US attaquant les troupes US<\/a>) ; de Berlusconi avec sa remarque comparant \u00e0 un <em>Kapo<\/em> de camp de concentration nazi un d\u00e9put\u00e9 allemand qui l&rsquo;interrogeait sur sa fa\u00e7on d&rsquo;intervenir dans le judiciaire pour r\u00e9gler ses affaires personnelles. Ces deux \u00e9pisodes, compl\u00e8tement sans int\u00e9r\u00eat en eux-m\u00eames, sont au contraire tr\u00e8s int\u00e9ressants parce qu&rsquo;ils sont indirectement si r\u00e9v\u00e9lateurs de choses et de situations d&rsquo;habitude cach\u00e9es.<\/p>\n<\/p>\n<p><p>\tD&rsquo;abord, il y a le constat des dimensions extraordinaires qu&rsquo;ont pris ces mots en soi sans int\u00e9r\u00eat, et qui semblent pourtant en avoir beaucoup puisqu&rsquo;on s&rsquo;y arr\u00eate d&rsquo;une fa\u00e7on aussi insistante. A Washington, le mot de GW touche un nerf tr\u00e8s sensible \u00e0 propos de la pr\u00e9sence des forces US en Irak ; et un autre nerf pas moins sensible, qui concerne GW lui-m\u00eame, ce qu&rsquo;il vaut, ce qu&rsquo;il dit, et pourquoi, etc. <\/p>\n<\/p>\n<p><p>\tConcernant Berlusconi, la r\u00e9action n&rsquo;est pas moins r\u00e9v\u00e9latrice. Les commentaires sont nombreux, certains prenant une allure extr\u00eamement grave jusqu&rsquo;\u00e0 mettre en cause Berlusconi lui-m\u00eame, sa capacit\u00e9 \u00e0 diriger son pays et,  plus encore,  sa capacit\u00e9 \u00e0 repr\u00e9senter l&rsquo;Europe. Les deux analyses, parmi d&rsquo;autres certes, que fait <a href=\"http:\/\/news.independent.co.uk\/europe\/story.jsp?story=421528\" class=\"gen\">le quotidien The Independent de cet incident sont r\u00e9v\u00e9latrices,<\/a> y compris cette <a href=\"http:\/\/news.independent.co.uk\/europe\/story.jsp?story=421537\" class=\"gen\">observation \u00e9tonnante<\/a> selon laquelle la remarque de Berlusconi constitue un argument particuli\u00e8rement solide en faveur des propositions de Giscard d&rsquo;Estaing. (Ce qui revient \u00e0 dire dans ce cas qu&rsquo;en acceptant la proposition de Giscard sur la pr\u00e9sidence de l&rsquo;UE, on \u00e9vite qu&rsquo;un Berlusconi se trouve en position de repr\u00e9senter l&rsquo;Europe.)<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>His comments might have boosted the case for replacing the EU&rsquo;s system of rotating presidencies with a semi-permanent president of the council. That has been proposed by the former French president Val\u00e9ry Giscard d&rsquo;Estaing, who is drawing up a draft constitution for the EU.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tLes deux cas, GW et Berlusconi, sont-ils si diff\u00e9rents ? Rien n&rsquo;est moins s\u00fbr, si on laisse de c\u00f4t\u00e9 le contenu de ces remarques, leur signification, leur contexte, etc. Deux choses nous semblent int\u00e9ressantes, finalement, \u00e0 propos de ces affaires mineures en soi : les deux personnages qui ont fait ces remarques d&rsquo;une part, les cons\u00e9quences de ces remarques qui auraient d\u00fb rester ce qu&rsquo;elles \u00e9taient, d\u00e9plac\u00e9es mais anodines, d&rsquo;autre part.<\/p>\n<\/p>\n<p><p>\t&bull; Le probl\u00e8me est que ces deux personnages occupent des fonctions supr\u00eames. Leurs interventions qui sont du m\u00eame calibre dans le domaine de la cr\u00e9ativit\u00e9 et de l&rsquo;intensit\u00e9 d\u00e9notent chez eux une recherche de l&rsquo;effet face \u00e0 une situation d\u00e9sagr\u00e9able, qui place, ou dont ils s&rsquo;imaginent qu&rsquo;elle les place dans une position o\u00f9 leur image de dirigeant politique pourrait \u00eatre ternie par le soup\u00e7on d&rsquo;incomp\u00e9tence, de corruption, de ridicule, etc. Il n&rsquo;est question que d&rsquo;image, de posture, d&rsquo;apparence et d&rsquo;effet. Il n&rsquo;y a chez eux aucune recherche de profondeur, aucune attention pour la moindre finesse, ni la moindre recherche de compr\u00e9hension de la substance d&rsquo;un probl\u00e8me, etc. Ce ne sont ni des hommes politiques, ni <em>a fortiori<\/em> des hommes d&rsquo;\u00c9tat. Ce sont des personnages jouant un r\u00f4le, et un r\u00f4le qu&rsquo;ils jugent eux-m\u00eames \u00eatre de la plus grande hauteur,  d&rsquo;o\u00f9 leur susceptibilit\u00e9 devant la menace d&rsquo;une situation o\u00f9 ils pourraient appara\u00eetre comme de mauvais figurants de leur r\u00f4le. La vanit\u00e9 a \u00e9videmment sa place dans leur comportement mais il y a surtout ce d\u00e9sir de bien faire qui caract\u00e9rise leur d\u00e9marche d&rsquo;hommes n&rsquo;ayant jamais rien eu de commun avec la substance de la politique et qui jouent le r\u00f4le d&rsquo;hommes qui doivent n\u00e9cessairement avoir du commun avec la substance de la politique. Quelles que soient leurs qualit\u00e9s ou leurs d\u00e9fauts par ailleurs, GW et Berlusconi paraissent dans ces \u00e9pisodes comme des figurants ayant bien mal \u00e9t\u00e9 instruits de leurs r\u00f4les ; il est vrai qu&rsquo;ils ont pour ma\u00eetres des hommes de communication et non des politologues. En un mot, on est stup\u00e9fait que le syst\u00e8me (ils font tous partie du m\u00eame lot) ne soit pas capable de produire autre chose que cela, des figurants d&rsquo;un autre calibre. <\/p>\n<\/p>\n<p><p>\t&bull; Les r\u00e9actions si violentes qu&rsquo;on observe,  surtout pour Berlusconi mais, finalement, pas tellement moins pour GW,  montrent qu&rsquo;il y a une perception g\u00e9n\u00e9rale que ces personnages sont gravement insuffisants, qu&rsquo;ils manient bien mal l&rsquo;apparence de probl\u00e8mes qui existent, dont la substance est extr\u00eamement grave. Ces r\u00e9actions extr\u00eames montrent que le sentiment g\u00e9n\u00e9ral existe qu&rsquo;un syst\u00e8me si totalement fond\u00e9 sur l&rsquo;image, la dissimulation g\u00e9n\u00e9rale et syst\u00e9matique des r\u00e9alit\u00e9s, bref du syst\u00e8me qu&rsquo;on peut nommer virtualisme, arrive \u00e0 ses limites avec des personnages de cette sorte, mis dans des situations qui leur correspondent si peu qu&rsquo;on peut craindre, dans certains cas, des r\u00e9actions tr\u00e8s difficiles \u00e0 contr\u00f4ler.<\/p>\n<\/p>\n<p><p>\tBien s\u00fbr, ces observations sont faites en se nourrissant d&rsquo;un contexte g\u00e9n\u00e9ral de fonctionnement du syst\u00e8me qu&rsquo;on conna\u00eet. Elles ne sont pas tomb\u00e9es du ciel, de m\u00eame que les deux remarques ne sont pas vraiment une surprise. Il s&rsquo;agit plut\u00f4t de la concr\u00e9tisation d&rsquo;une situation g\u00e9n\u00e9rale. Il y a dans la population habituelle du syst\u00e8me la perception instinctive et diffuse, mais tr\u00e8s forte, au travers de ces deux incidents et des r\u00e9actions qu&rsquo;ils ont provoqu\u00e9es, que ce m\u00eame syst\u00e8me est dans une crise profonde et qu&rsquo;il n&rsquo;est pas loin du blocage.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>GW et Berlusconi : l&rsquo;\u00e9trange fa\u00e7on de mesurer la crise 5 juillet 2003 En deux jours, deux hommes ont fait parler d&rsquo;eux d&rsquo;une bien \u00e9trange fa\u00e7on. Ces deux hommes ne sont pas, para\u00eet-il, n&rsquo;importe qui, ou monsieur tout-le-monde comme on dit dans la presse chic. Il s&rsquo;agit d&rsquo;un pr\u00e9sident, sorte d&rsquo;Empereur \u00e0 ses heures, et&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-65664","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65664"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65664\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}