{"id":65677,"date":"2003-07-14T00:00:00","date_gmt":"2003-07-14T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2003\/07\/14\/loption-bae-de-blair-ou-le-suicide-technologique-dune-nation\/"},"modified":"2003-07-14T00:00:00","modified_gmt":"2003-07-14T00:00:00","slug":"loption-bae-de-blair-ou-le-suicide-technologique-dune-nation","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2003\/07\/14\/loption-bae-de-blair-ou-le-suicide-technologique-dune-nation\/","title":{"rendered":"<strong><em>L&rsquo;option BAE de Blair, \u2014 ou le suicide technologique d&rsquo;une nation<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">L&rsquo;option BAE de Blair,  ou le suicide technologique d&rsquo;une nation<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t14 juillet 2003 Blair a l&rsquo;intention ferme et d\u00e9finitive d&rsquo;exiger, et d&rsquo;obtenir \u00e9ventuellement, un comportement responsable des Am\u00e9ricains en mati\u00e8re de transfert de technologies. C&rsquo;est ce que Blair doit dire \u00e0 GW Bush. Un article tr\u00e8s court, en date du 12 juillet, <a href=\"http:\/\/www.nytimes.com\/financialtimes\/business\/FT1057562345223.html?pagewanted=print&#038;position\" class=\"gen\">du Financial Times\/New York Times<\/a> fait un point approximatif sur cette question. (Nous revenons sur cet article apr\u00e8s l&rsquo;avoir d\u00e9j\u00e0 cit\u00e9 hier, <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=806\" class=\"gen\">dans notre pr\u00e9sentation g\u00e9n\u00e9rale du voyage de Blair.<\/a>) Nous le publions ci-dessous pour pouvoir mieux pr\u00e9senter les observations qu&rsquo;il appelle, qui vont plus loin, finalement, que de simples observations sur une situation bilat\u00e9rale courante. (L&rsquo;article, de Dan Roberts et Peter Spiegel \u00e0 Londres, est intitul\u00e9 : \u00ab <em>Blair to ask US to share defence technology<\/em> \u00bb).<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>Tony Blair, the UK prime minister, is to ask President George W. Bush next week for the US to share more sensitive defence technology  as a precursor to talks on the possible American purchase of Britain&rsquo;s largest arms maker. Mr Blair is visiting Washington on Thursday for talks expected to include a shopping list of requests aimed at fostering closer security co-operation.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The issue of technology transfer is central to growing attempts to find a US partner for BAE Systems, formerly British Aerospace. BAE believes it needs to be part of one of the big five US defence contractors to close the rapidly growing gap between UK and US military technology.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The argument is understood to be winning support within the premier&rsquo;s office in Downing Street, which has veto over any sale, so long as the Americans guaranteed that British factories would have full access to the latest research. Technology transfer is likely to be on the agenda next week, said one government insider. If we are going to be fighting side by side, it is in US interests to make sure Britain has access to the same equipment. But we don&rsquo;t think it is in the UK&rsquo;s interest for BAE to be linked up if our factories will simply end up doing the metal-bashing.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Sir Richard Evans, BAE&rsquo;s chairman, recently warned that Britain&rsquo;s air force might have to cede control over crucial modifications to its new generation of F-35 fighters because Lockheed Martin, BAE&rsquo;s US partner on the project, was refusing to share vital source codes for the control software. Frustration at such restrictions has driven BAE to seek bids from potential US partners and begin convincing Downing Street to countenance the sale of a national champion.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Treasury officials are understood to be relaxed about the plan, believing foreign ownership would make it easier to negotiate cheaper procurement contracts on a level playing field.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tCet article vaut effectivement quelques commentaires. Il indique que non seulement l&rsquo;argument de BAE, en faveur d&rsquo;une fusion de BAE avec une soci\u00e9t\u00e9 US, \u00ab <em>is understood to be winning support within the premier&rsquo;s office in Downing Street<\/em> \u00bb, mais, plus encore, que BAE est en train de manipuler directement le Premier ministre britannique \u00e0 son avantage. (Encore peut-on se demander s&rsquo;il y a manipulation ou complicit\u00e9 \u00e0 cet \u00e9gard ?) L&rsquo;argument est un m\u00e9lange d&rsquo;imp\u00e9ratifs techniques qui sont compl\u00e8tement sans fondement, et d&rsquo;arguments politiques qui renvoient directement \u00e0 la schizophr\u00e9nie de Tony Blair \u00e0 propos de l&rsquo;alliance avec les USA.<\/p>\n<\/p>\n<p><p>\tLes Britanniques, notamment \u00e0 travers le cas du programme JSF\/F-35, d\u00e9couvrent chaque jour un peu plus que les transferts de technologies US vers eux sont inexistants. On a vu les avertissements \u00e0 ce sujet, <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=748\" class=\"gen\">notamment de sir Richard Evans, pr\u00e9sident de BAE.<\/a> C&rsquo;est alors que BAE se tourne vers le gouvernement et lui dit : \u00ab <em>BAE believes it needs to be part of one of the big five US defence contractors to close the rapidly growing gap between UK and US military technology.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tCette phrase est un amalgame de r\u00e9alit\u00e9 et d&rsquo;une inexactitude qui touche au mensonge d\u00e9lib\u00e9r\u00e9. La r\u00e9alit\u00e9 dans cette phrase, c&rsquo;est ce qu&rsquo;on commence \u00e0 \u00e9noncer, sans terminer : si BAE veut profiter des transferts de technologies US, il faut qu&rsquo;il fusionne avec une soci\u00e9t\u00e9 US,  i.e., qu&rsquo;il devienne US lui-m\u00eame, car c&rsquo;est bien ce qui va se passer. L&rsquo;inexactitude, ou mensonge en langage populaire, se trouve dans cette phrase de pure propagande : \u00ab <em>the rapidly growing gap between UK and US military technology<\/em> \u00bb (\u00e0 moins que BAE parle pour lui-m\u00eame ?). Le <em>technological gap<\/em> en pleine expansion, entre UK (l&rsquo;Europe par extension) et les USA, est une sornette. Exemple r\u00e9cent, sans doute connu de BAE : lorsqu&rsquo;un pays comme les USA se dit int\u00e9ress\u00e9 par le <em>Storm Shadow<\/em>, missile de croisi\u00e8re europ\u00e9en, jusqu&rsquo;\u00e0 envisager de l&rsquo;acheter, c&rsquo;est qu&rsquo;il n&rsquo;y a pas de foss\u00e9 technologique au profit des USA entre les USA et l&rsquo;Europe. (Produire un tel missile de croisi\u00e8re implique une base technologique aux capacit\u00e9s g\u00e9n\u00e9rales \u00e0 mesure de ce syst\u00e8me. Le Pentagone, qui a vu le <em>Storm Shadow<\/em> europ\u00e9en en action en Irak, avec la RAF, reconna\u00eet la sup\u00e9riorit\u00e9 du missile europ\u00e9en sur ses propres cruise missiles.)  S&rsquo;il y a un foss\u00e9 entre USA et Europe (UK), c&rsquo;est un foss\u00e9 budg\u00e9taire, entre le budget-gaspillage titanesque du Pentagone et la situation europ\u00e9enne. Ce qui int\u00e9resse BAE, et ses actionnaires \u00e9videmment, c&rsquo;est plus de contrats et plus d&rsquo;argent, et c&rsquo;est au Pentagone qu&rsquo;on le trouve. La technologie est une question secondaire pour BAE.<\/p>\n<\/p>\n<p><p>\tLa proposition implicite de BAE revient donc \u00e0 cette double r\u00e9alit\u00e9 :<\/p>\n<\/p>\n<p><p>\t&bull; L&rsquo;argumentation de BAE est en fait financi\u00e8re et \u00e9conomique, et nullement technologique.<\/p>\n<\/p>\n<p><p>\t&bull; Si BAE fusionne avec un conglom\u00e9rat am\u00e9ricain, la question de la technologie sera r\u00e9solue par l&rsquo;absurde. BAE devient compl\u00e8tement US, a acc\u00e8s \u00e0 toutes les technologies mais doit respecter les m\u00eames restrictions officielles US pour le transfert des technologies.<\/p>\n<\/p>\n<p><p>\tSur ce dernier point, Philip Chaston, commentateur conservateur du site <a href=\"http:\/\/www.electricreview.com\/cgi\/viewnews.cgi?id=1057704648\" class=\"gen\">Electric Review,<\/a> fait quelques remarques, o\u00f9 il met en \u00e9vidence implicitement cette situation \u00e9trange o\u00f9 il semble bien que les fonctionnaires britanniques soient de plus en plus occup\u00e9s \u00e0 se convaincre de l&rsquo;existence de situations qui n&rsquo;existent pas (on retrouve une atmosph\u00e8re similaire \u00e0 <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=768\" class=\"gen\">celle que d\u00e9crit Charles Grant pour le cas du Foreign Office<\/a>) :<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>Boeing is planning to merge with BAE in the same way as I merged with a takeaway Chinese meal last night. BAE would be inside the belly of the giant US beast. It would be acquired, subsumed, taken over, devoured.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Intriguingly, when I talk to ministers and government officials about this potential risk, they seem unperturbed. How so? Well the imperative, they think, is to secure access for BAE to US technology, which is far and away the best in the world. And, slightly to my surprise, they seem to believe that the US government will not prohibit the transfer of such valuable and sensitive knowhow.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tLe dernier argument des Britanniques pour avoir acc\u00e8s \u00e0 la technologie US, et donc contr\u00f4ler leur propre production de syst\u00e8mes d&rsquo;arme, c&rsquo;est qu&rsquo;ils doivent pouvoir le faire pour mieux op\u00e9rer avec les Am\u00e9ricains. L&rsquo;on sait d&rsquo;autre part (voir notamment <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=807\" class=\"gen\">ce qu&rsquo;en dit Mongrot<\/a>) que l&rsquo;\u00e9volution militaire britannique \u00e0 cet \u00e9gard va \u00eatre de s&rsquo;orienter vers une quasi-int\u00e9gration <em>de facto<\/em> dans les structures US. Le r\u00e9sultat probable, apr\u00e8s quelque d\u00e9lai de d\u00e9cence, sera l&rsquo;acquisition de mat\u00e9riel US produit par Lockheed Martin (BAE), ou Boeing (BAE), pour le contingent britannique de l&rsquo;U.S. Army.<\/p>\n<\/p>\n<p><p>\tNous parlons de suicide technologique d&rsquo;une nation, ce qui suppose qu&rsquo;il y a encore une nation. On peut commencer \u00e0 s&rsquo;interroger \u00e0 ce propos, \u00e0 propos du Royaume-Uni dans la voie suivie actuellement. Selon la r\u00e9ponse la plus probable, c&rsquo;est alors, certainement, que Tony Blair aura, comme il le d\u00e9sire, sa place assur\u00e9e dans l&rsquo;histoire.<\/p>\n<\/p>\n<p><\/p>\n<h3>&#8230; Peut-on dire pour autant qu&rsquo;ils (Britanniques et Am\u00e9ricains) sont compl\u00e8tement int\u00e9gr\u00e9s les uns aux autres jusqu&rsquo;\u00e0 la non-existence des Britanniques ?<\/h3>\n<\/p>\n<p><p>\tPeut-on dire pour autant que le complot des partisans de l&rsquo;am\u00e9ricanisation du Royaume-Uni est en train de l&#8217;emporter ? A c\u00f4t\u00e9 de l&rsquo;\u00e9vidente r\u00e9ponse positive que sugg\u00e8rent BAE et compagnie, il y a d&rsquo;autres situations qui sugg\u00e8rent des r\u00e9serves s\u00e9rieuses, y compris sur le fait qu&rsquo;il y ait complot,  c&rsquo;est alors plut\u00f4t l&rsquo;hypoth\u00e8se d&rsquo;un immense d\u00e9sordre qui doit \u00eatre explor\u00e9e. Que penser du climat existant entre les services de renseignement britanniques et am\u00e9ricains ?  Il suffit de lire l&rsquo;article du <em>Guardian<\/em> <a href=\"http:\/\/www.guardian.co.uk\/Iraq\/Story\/0,2763,997704,00.html\" class=\"gen\">de ce jour<\/a> pour \u00eatre fix\u00e9. Ci-dessous, extraits choisis,  nous conduisant \u00e0 la conclusion qu&rsquo;aujourd&rsquo;hui, le bateau anglo-am\u00e9ricain est un bateau ivre.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>Relations between British and American intelligence agencies, a central pivot of the special relationship, are in disarray over disputed claims about Iraq&rsquo;s attempts to procure weapons of mass destruction. In a dispute with serious political repercussions for Tony Blair and George Bush, the CIA and MI6 have made it clear that they do not believe each other&rsquo;s intelligence, notably about a claim that Iraq was trying to obtain uranium from the west African state of Niger for nuclear weapons.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>While George Tenet, the CIA&rsquo;s director, is expressing doubts about the claim, MI6 is adamant it is accurate. Documents claiming that Iraq was seeking uranium from Niger have turned out to be forgeries. But British intelligence sources said yesterday that MI6 had separate information to back the claim. MI6 was provided the information by a third party which insisted neither the source nor the intelligence could be passed on.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Certain protocols have to be observed, an intelligence official said yesterday. He added that if Britain failed to respect such protocols, sources would refuse to provide MI6 with intelligence again.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Whitehall officials suggested yesterday that the claims came from a close ally but one which did not want Britain to give it to the US as a further pretext for war. It is extremely rare for Britain not to pass on intelligence to the US, even more so when it refers to a common enemy, in this case, Iraq.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>In the past, the CIA&rsquo;s station chief in London has had close links with Whitehall&rsquo;s joint intelligence committee, the body which compiled the government&rsquo;s controversial September dossier.<\/em> \u00bb<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;option BAE de Blair, ou le suicide technologique d&rsquo;une nation 14 juillet 2003 Blair a l&rsquo;intention ferme et d\u00e9finitive d&rsquo;exiger, et d&rsquo;obtenir \u00e9ventuellement, un comportement responsable des Am\u00e9ricains en mati\u00e8re de transfert de technologies. C&rsquo;est ce que Blair doit dire \u00e0 GW Bush. Un article tr\u00e8s court, en date du 12 juillet, du Financial Times\/New&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[868,3435,250,1205],"class_list":["post-65677","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-bush","tag-cooperation","tag-jsf","tag-transatlantique"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65677"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65677\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}