{"id":65727,"date":"2003-09-01T00:00:00","date_gmt":"2003-09-01T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2003\/09\/01\/il-est-temps-que-nous-changions-de-fond-en-comble-dit-gargantua\/"},"modified":"2003-09-01T00:00:00","modified_gmt":"2003-09-01T00:00:00","slug":"il-est-temps-que-nous-changions-de-fond-en-comble-dit-gargantua","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2003\/09\/01\/il-est-temps-que-nous-changions-de-fond-en-comble-dit-gargantua\/","title":{"rendered":"<strong><em>Il est temps que nous changions de fond en comble, dit Gargantua<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Il est temps que nous changions de fond en comble, dit Gargantua<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t1er septembre 2003  La r\u00e9flexion bat son plein \u00e0 Washington, vieille habitude de Washington. Le <em>Washington Times<\/em>, qui relaie souvent les milieux militaires et ultra-conservateurs, nous dit, dans un \u00e9ditorial signifiant qu&rsquo;il s&rsquo;agit de la position du journal, que <a href=\"http:\/\/www.washtimes.com\/op-ed\/20030829-082028-3218r.htm\" class=\"gen\">l&rsquo;arm\u00e9e am\u00e9ricaine va devoir changer de fond en comble<\/a>. Cette d\u00e9claration nous surprend, d&rsquo;abord selon une remarque de bon sens : nous pensions que ce changement de fond en comble \u00e9tait d\u00e9j\u00e0 en cours, puisque Rumsfeld nous en parle depuis pratiquement son arriv\u00e9e. (On ajoutera que tout le monde, secr\u00e9taires \u00e0 la d\u00e9fense, g\u00e9n\u00e9raux, etc nous en parlent depuis la premi\u00e8re Guerre du Golfe, depuis la chute du Mur de Berlin, depuis l&rsquo;arriv\u00e9e de Gorbatchev et ainsi de suite, en remontant selon le pointill\u00e9&#8230;)\/<\/p>\n<\/p>\n<p><p>\tLe premier paragraphe de cet \u00e9ditorial est remarquable parce qu&rsquo;il contient toutes les donn\u00e9es de ce probl\u00e8me complexe qu&rsquo;est aujourd&rsquo;hui la puissance am\u00e9ricaine et, implicitement, les limites \u00e0 pr\u00e9voir, voire les contresens, qu&rsquo;on pourrait trouver dans les solutions qui seraient apport\u00e9es.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>The U.S. military commitments to Iraq, Afghanistan and other battlefields in the global war on terrorism are likely to be long-lasting. Before resolving the issue of whether to expand the U.S. military force structure to meet the commitments of the war, there is an immediate need for the types of forces most suited to the new kind of warfare. In addition to investing in high-value force options, there is also a need to spend money on different types of capabilities to integrate these forces into the new warfare. For a generation, the U.S. military has prepared forces able to defeat any opponent on the battlefield. What we now have to improvise is a capability to build upon this battlefield success in order to win a lasting victory in the war on terror.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tOn nous dit ainsi, et successivement :<\/p>\n<\/p>\n<p><p>\t&bull; On se trouve (avec l&rsquo;Irak) devant une nouvelle sorte de guerre, avant de songer \u00e0 augmenter les forces il faut songer \u00e0 les modifier. Cette appr\u00e9ciation qui a l&rsquo;air de bon sens se r\u00e9v\u00e8le \u00eatre une lapalissade us\u00e9e jusqu&rsquo;\u00e0 la corde. Cela fait plus de 10 ans (et si l&rsquo;on veut, on pourrait remonter \u00e0 Kennedy instituant une \u00e9cole de lutte contre-gu\u00e9rilla au d\u00e9but des ann\u00e9es 1960) que les nouvelles conditions de la guerre se sont r\u00e9v\u00e9l\u00e9es (Somalie, Ha\u00efti, Yougoslavie, etc) et il semblerait d&rsquo;apr\u00e8s ce qu&rsquo;on nous dit dans ce texte que rien de s\u00e9rieux n&rsquo;ait \u00e9t\u00e9 fait. Pourquoi plus aujourd&rsquo;hui qu&rsquo;hier ?<\/p>\n<\/p>\n<p><p>\t&bull; On remarque pourtant que l&rsquo;arm\u00e9e US a pr\u00e9par\u00e9 pendant une g\u00e9n\u00e9ration une machine de guerre capable d&rsquo;\u00e9craser tout adversaire dans une bataille conventionnelle de haute intensit\u00e9 (\u00ab <em> For a generation, the U.S. military has prepared forces able to defeat any opponent on the battlefield<\/em> \u00bb), et l&rsquo;on n&rsquo;a rien \u00e0 redire \u00e0 cela. Au contraire, il nous est annonc\u00e9 que cette structure a prouv\u00e9 toute son efficacit\u00e9 (\u00ab <em> What we now have to improvise is a capability to build upon this battlefield success in order to win a lasting victory in the war on terror.<\/em> \u00bb), donc qu&rsquo;elle \u00e9tait n\u00e9cessaire et utile (allusion aux deux guerres contre l&rsquo;Irak).<\/p>\n<\/p>\n<p><p>\t&bull; A aucun moment n&rsquo;est \u00e9tabli de lien de cause \u00e0 effet entre tous ces \u00e9v\u00e9nements. (Cette absence de lien de cause \u00e0 effet est caract\u00e9ristique de la psychologie moderniste, particuli\u00e8rement de la psychologie am\u00e9ricaniste). Ainsi est-il jug\u00e9 n\u00e9cessaire que l&rsquo;arm\u00e9e am\u00e9ricaine ait \u00e9t\u00e9 ce qu&rsquo;elle est encore (une machine pour les guerres conventionnelles) autant qu&rsquo;il est jug\u00e9 n\u00e9cessaire qu&rsquo;elle se transforme d\u00e9cisivement. D&rsquo;une part, il y a de l&rsquo;illogisme dans le propos : selon cette logique, pourquoi l&rsquo;arm\u00e9e conventionnelle ne serait-elle pas encore n\u00e9cessaire demain puisqu&rsquo;elle l&rsquo;a \u00e9t\u00e9 hier dans des circonstances d\u00e9j\u00e0 \u00e9tablies et conformes \u00e0 celles qu&rsquo;on conna\u00eet aujourd&rsquo;hui ? C&rsquo;est alors qu&rsquo;il faudrait deux arm\u00e9es, une conventionnelle et l&rsquo;autre pas ? Est-ce bien raisonnable ? D&rsquo;autre part, nulle part on ne se demande si la situation aggrav\u00e9e o\u00f9 l&rsquo;on se trouve aujourd&rsquo;hui, n\u00e9cessitant une r\u00e9forme d&rsquo;urgence des forces arm\u00e9es, n&rsquo;est pas justement due \u00e0 la sorte de victoire emport\u00e9e d&rsquo;une fa\u00e7on conventionnelle. (Cela revient \u00e0 la question de savoir si le chaos d&rsquo;aujourd&rsquo;hui n&rsquo;est pas l&rsquo;enfant direct de la victoire de mars-avril dernier, ce qui nous para\u00eet l&rsquo;\u00e9vidence et qui n&rsquo;est absolument pas envisag\u00e9 par les Am\u00e9ricains.)<\/p>\n<\/p>\n<p><p>\tCes diverses remarques laissent profond\u00e9ment sceptiques, et sur le processus d&rsquo;une r\u00e9forme des forces arm\u00e9es US, et sur la capacit\u00e9 am\u00e9ricaine de r\u00e9forme, et sur la compr\u00e9hension m\u00eame des Am\u00e9ricains de la r\u00e9forme n\u00e9cessaire. Elles nous font comprendre comment la r\u00e9action am\u00e9ricaine apr\u00e8s le 11 septembre 2001 se d\u00e9finit aujourd&rsquo;hui par un \u00e9chec chaque jour plus complet et plus pr\u00e9occupant, caract\u00e9ris\u00e9 principalement par le chaos irakien. Elles nous font mesurer combien la puissance am\u00e9ricaine est, en r\u00e9alit\u00e9, c&rsquo;est-\u00e0-dire dans la r\u00e9alit\u00e9, une compl\u00e8te impuissance.<\/p>\n<\/p>\n<p><p>\tEn guise de post-scriptum, on observera que, m\u00eame du point de vue le plus simple, le point de vue technique (les \u00e9quipements), les Am\u00e9ricains ont les plus grandes difficult\u00e9s du monde \u00e0 aller vers une r\u00e9forme. <a href=\"http:\/\/www.washtimes.com\/national\/20030825-112408-7613r.htm\" class=\"gen\">L&rsquo;exemple du nouveau v\u00e9hicule l\u00e9ger de combat Stryker est \u00e9difiant<\/a>. Ce syst\u00e8me, \u00e9tudi\u00e9 de longue date, co\u00fbteux, d\u00e9velopp\u00e9 avec attention, envisag\u00e9 \u00e9videmment pour les situations de conflits asym\u00e9triques o\u00f9 les forces US ont \u00e0 affronter des adversaires irr\u00e9guliers, terroristes, gu\u00e9rillas, etc, se r\u00e9v\u00e8le notamment vuln\u00e9rable aux armes RPG (lance-grenades de fabrication sovi\u00e9tique). On sait depuis longtemps, depuis un demi-si\u00e8cle, depuis les aventures cubaines, le Viet-n\u00e2m, etc, que les deux armes de pr\u00e9dilection de tous les irr\u00e9guliers du monde sont le fusil d&rsquo;assaut AK-47 et le lanceur individuel de grenades RPG-7. Et voil\u00e0 qu&rsquo;il se pourrait que le <em>Stryker<\/em> soit vuln\u00e9rable \u00e0 l&rsquo;un des deux &#8230;<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>The Army&rsquo;s new state-of-the art infantry vehicle slated to make its combat debut in Iraq in October is vulnerable to the kind of rocket-propelled grenades now being used by Saddam Hussein&rsquo;s guerrillas, a consultant&rsquo;s report charges.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The Army, which rebuts the report&rsquo;s findings, plans to send 300 Stryker armored vehicles and 3,600 soldiers to Iraq. This first Stryker brigade will help put down the resistance that has killed more 60 American troopers since May 1. It will also be a preview of a lighter, more mobile Army for the 21st century.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>But a report prepared for Rep. James H. Saxton, New Jersey Republican, says the vehicle is ill-suited for such warfare. Poorly armored and entirely vulnerable to RPGs, states the glossy, 108-page report prepared July 18 by consultant Victor O&rsquo;Reilly.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il est temps que nous changions de fond en comble, dit Gargantua 1er septembre 2003 La r\u00e9flexion bat son plein \u00e0 Washington, vieille habitude de Washington. Le Washington Times, qui relaie souvent les milieux militaires et ultra-conservateurs, nous dit, dans un \u00e9ditorial signifiant qu&rsquo;il s&rsquo;agit de la position du journal, que l&rsquo;arm\u00e9e am\u00e9ricaine va devoir&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[2623,568,3320,4109],"class_list":["post-65727","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-bureaucratie","tag-dod","tag-reforme","tag-stryker"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65727"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65727\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}