{"id":65749,"date":"2003-09-26T00:00:00","date_gmt":"2003-09-26T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2003\/09\/26\/out-of-bagdad\/"},"modified":"2003-09-26T00:00:00","modified_gmt":"2003-09-26T00:00:00","slug":"out-of-bagdad","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2003\/09\/26\/out-of-bagdad\/","title":{"rendered":"<strong><em>Out of Bagdad?<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Out of Bagdad?<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t26 septembre 2003  <a href=\"http:\/\/www.iht.com\/articles\/111288.html\" class=\"gen\">Un article de William Pfaff ce matin<\/a> vient renforcer, et de fa\u00e7on tr\u00e8s pr\u00e9cise, des rumeurs de plus en plus insistantes sur le d\u00e9sengagement am\u00e9ricain d&rsquo;Irak. Pfaff donne ces pr\u00e9cisions : \u00ab <em> Despite the optimism at the Pentagon about Iraqi operations, Tuesday&rsquo;s speeches at the United Nations General Assembly may actually prove to be a step toward an American retreat from Baghdad, possibly before the end of this year.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tWilliam Pfaff \u00e9voque une tactique \u00e0 propos de laquelle des hypoth\u00e8ses ont d\u00e9j\u00e0 \u00e9t\u00e9 faites : un repli des forces US sur des bases fortement prot\u00e9g\u00e9es, la s\u00e9curit\u00e9 des centres urbains \u00e9tant laiss\u00e9e aux Irakiens. <\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>The military in Baghdad is now planning how to get out of the present mess. What&rsquo;s being discussed is a military retreat into several well-defended bases well away from the capital and Iraq&rsquo;s other cities. These undoubtedly are mostly the same bases Washington had in mind before the war as permanent U.S. installations.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t\u00bb <em>The idea is to hand over Iraq&rsquo;s security to newly recruited Iraqi police and militias, as well as to whatever multinational force the United States can put together.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tCette perspective est dans l&rsquo;air parce que, depuis quelques semaines et l&rsquo;aggravation de la situation sur le terrain, la coalition interventionniste de l&rsquo;\u00e9quipe GW Bush s&rsquo;est fractionn\u00e9e, principalement en deux. Les jusqu&rsquo;auboutistes n\u00e9o-conservateurs sont de plus en plus isol\u00e9s, tandis que les nationalistes interventionnistes men\u00e9s par Rumsfeld envisagent de plus en plus un retrait. (Dans des d\u00e9clarations <a href=\"http:\/\/news.ft.com\/servlet\/ContentServer?pagename=FT.com\/StoryFT\/FullStory&#038;c=StoryFT&#038;cid=1059480137901\" class=\"gen\">faites hier devant le Congr\u00e8s<\/a>, Rumsfeld confirme cette analyse lorsqu&rsquo;il pr\u00e9sente les cr\u00e9dits de $87 milliards demand\u00e9s par l&rsquo;administration comme une strat\u00e9gie de sortie d&rsquo;Irak.)<\/p>\n<\/p>\n<p><p>\tDans sa <a href=\"http:\/\/www.antiwar.com\/justin\/j091703.html\" class=\"gen\">chronique du 17 septembre<\/a>, Justin Raimundo faisait un long commentaire sur cette question (\u00ab <em>Donald Rumsfeld, Peacenik? Rummy wants out  and the neocons are hopping mad<\/em> \u00bb). La veille, sur <em>atimes.com<\/em>, Jim Lobe, qu&rsquo;on sait particuli\u00e8rement bien inform\u00e9, avait largement d\u00e9velopp\u00e9 l&rsquo;hypoth\u00e8se, en citant notamment <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=522\" class=\"gen\">l&rsquo;excellent Charles Kupchan<\/a>.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>Pentagon chief Donald Rumsfeld, on the other hand, is dead-set against deploying yet more troops to join the 180,000 now in Iraq and Kuwait. And while he, like the neo-cons, opposes conceding any substantial political role for the UN or anyone else, his preferred option is to transfer power directly to the Iraqis as quickly as possible, even at the risk that reconstituted security forces would be insufficiently cleansed of elements of the former regime&rsquo;s Ba&rsquo;ath Party.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>It&rsquo;s clear now that Rumsfeld is not interested in remaking Iraq&rsquo;, said Charles Kupchan, a foreign-policy analyst at the Washington, DC, office of the New York-based Council on Foreign Relations. He wants to get the hell out of there.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tLes signes ne manquent donc plus pour envisager un retrait strat\u00e9gique des Am\u00e9ricains, dans tous les cas loin des zones \u00e0 risque pour les forces am\u00e9ricaines. D&rsquo;ailleurs, ce m\u00eame Jim Lobe nous avertissait, <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=682\" class=\"gen\">d\u00e8s le d\u00e9but avril<\/a>, sur la possibilit\u00e9 d&rsquo;une politique de retrait de Rumsfeld, alors m\u00eame qu&rsquo;il n&rsquo;\u00e9tait pas question de difficult\u00e9s sur le terrain, bien au contraire. Nous sommes revenus sur le sujet, <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=701\" class=\"gen\">quelques jours plus tard, le 12 avril<\/a>. Bien entendu, la d\u00e9gradation de la situation a servi d&rsquo;\u00e9l\u00e9ment dramatique pour cette question du retrait.<\/p>\n<\/p>\n<p><p>\tS&rsquo;il semble acquis qu&rsquo;on aille d\u00e9sormais vers une sorte ou l&rsquo;autre de retrait, ou repli am\u00e9ricain, la crise n&rsquo;en est pas finie pour autant. Simplement, elle va changer de th\u00e9\u00e2tre d&rsquo;op\u00e9ration. Elle va se d\u00e9placer vers le coeur de cet empire qui n&rsquo;a eu ni le temps ni les moyens de s&rsquo;affirmer,  et cela, justement, va peser lourd. Une telle \u00e9volution (retrait ou repli) signifie, qu&rsquo;on le veuille ou non, une d\u00e9faite majeure de la politique GW. Cela, en pleine ann\u00e9e \u00e9lectorale. Toutes les grandes questions vont \u00eatre pos\u00e9es, celle de l&#8217;empire, celle aussi de la stabilit\u00e9 d&rsquo;un r\u00e9gime qui permet de telles aventures sans m\u00eame en recueillir un succ\u00e8s d\u00e9cisif pour des campagnes aussi r\u00e9duites que celles de l&rsquo;Afghanistan et de l&rsquo;Irak.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Out of Bagdad? 26 septembre 2003 Un article de William Pfaff ce matin vient renforcer, et de fa\u00e7on tr\u00e8s pr\u00e9cise, des rumeurs de plus en plus insistantes sur le d\u00e9sengagement am\u00e9ricain d&rsquo;Irak. Pfaff donne ces pr\u00e9cisions : \u00ab Despite the optimism at the Pentagon about Iraqi operations, Tuesday&rsquo;s speeches at the United Nations General Assembly&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-65749","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65749"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65749\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}