{"id":65792,"date":"2003-11-12T00:00:00","date_gmt":"2003-11-12T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2003\/11\/12\/la-privatisation-et-linternationalisation-de-lelection-du-president-us\/"},"modified":"2003-11-12T00:00:00","modified_gmt":"2003-11-12T00:00:00","slug":"la-privatisation-et-linternationalisation-de-lelection-du-president-us","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2003\/11\/12\/la-privatisation-et-linternationalisation-de-lelection-du-president-us\/","title":{"rendered":"<strong><em>La \u201cprivatisation\u201d et l&rsquo;\u201cinternationalisation\u201d de l&rsquo;\u00e9lection du pr\u00e9sident US<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">La privatisation et l&rsquo;internationalisation de l&rsquo;\u00e9lection du pr\u00e9sident US<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t12 novembre 2003  La d\u00e9cision de Georges Soros, investisseur d&rsquo;origine hongroise et \u00e9toile classique depuis une quinzaine d&rsquo;ann\u00e9es du monde internationale de la finance et de l&rsquo;investissement, <a href=\"http:\/\/www.guardian.co.uk\/uselections2004\/story\/0,13918,1083165,00.html\" class=\"gen\">d&rsquo;entrer en guerre contre la r\u00e9\u00e9lection de GW Bush<\/a> ouvre une nouvelle p\u00e9riode dans l&rsquo;histoire de l&rsquo;Am\u00e9rique. Soros ne sera d&rsquo;ailleurs pas seul dans cet effort, il s&rsquo;associe <a href=\"http:\/\/www.guardian.co.uk\/uselections2004\/story\/0,13918,1082777,00.html\" class=\"gen\">\u00e0 Peter Lewis, milliardaire et propri\u00e9taire de compagnies d&rsquo;assurance<\/a>. <\/p>\n<\/p>\n<p><p>\tSoros a d\u00e9j\u00e0 entrepris divers actions, dont la\t publication d&rsquo;un livre, <em>The Buble of the American Supremacy<\/em>. Ses attaques contre GW et la politique am\u00e9ricaine sont d&rsquo;une violence extr\u00eame puisque, chez lui, l&rsquo;assimilation de l&rsquo;administration GW Bush aux Nazis est chose courante. (Soros est d&rsquo;origine hongrois mais il est naturalis\u00e9 am\u00e9ricain depuis quelques ann\u00e9es.)<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>In the book, <\/em>[Soros argues] <em>that the US is doing itself immeasurable harm by its heavy-handed role in the world. The dominant position the United States occupies in the world is the element of reality that is being distorted, he writes, according to an excerpt to be published in next month&rsquo;s Atlantic Monthly magazine. The proposition that the United States will be better off if it uses its position to impose its values and interests everywhere is the misconception. It is exactly by not abusing its power that America attained its current position.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The Bush administration&rsquo;s war on terrorism cannot be won, he argues, but is instead ushering in a permanent state of war. He uses the emotive terms like supremacist ideology deliberately, saying that some of the rhetoric coming from the White House reminds him of his childhood in Nazi-occupied Hungary.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>When I hear Bush say, You&rsquo;re either with us or against us,&rsquo; it reminds me of the Germans, he said in yesterday&rsquo;s interview. My experiences under Nazi and Soviet rule have sensitised me.<\/em> \u00bb <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tL&rsquo;intrusion du milliardaire Soros constitue un \u00e9l\u00e9ment nouveau d&rsquo;importance dans la vie politique am\u00e9ricaine. Sp\u00e9culateur (ou investisseur en langue chic) international, Am\u00e9ricain par simple accident et prise en compte d&rsquo;int\u00e9r\u00eats classiques, Soros reste marqu\u00e9 par un internationalisme appuy\u00e9 et son origine d&rsquo;Europe centrale. Son intervention dans la vie politique am\u00e9ricaine est celle d&rsquo;un homme hors de la sph\u00e8re washingtonienne, une intervention du dehors si l&rsquo;on veut.<\/p>\n<\/p>\n<p><p>\tD&rsquo;autre part, il s&rsquo;agit \u00e9videmment d&rsquo;un \u00e9v\u00e9nement exceptionnel par son caract\u00e8re priv\u00e9. Une fortune priv\u00e9 (deux avec l&rsquo;autre milliardaire Lewis) jette un d\u00e9fi au pr\u00e9sident am\u00e9ricain en lui affirmant qu&rsquo;il ne sera pas r\u00e9\u00e9lu, gr\u00e2ce \u00e0 une action m\u00e9diatique diverse (TV, radio, journaux, etc). C&rsquo;est une \u00e9trange privatisation du domaine politique le plus haut. Le parti r\u00e9publicain a l&rsquo;impudence de jeter les hauts cris, en d\u00e9non\u00e7ant l&rsquo;intervention de l&rsquo;argent, au motif hypocrite que les deux milliardaires ne sont pas soumis aux r\u00e8gles des limites des donations. Les r\u00e9publicains ont montr\u00e9, avec l&rsquo;administration GW Bush, l&rsquo;ampleur de leur corruption par le <em>Big Business<\/em> et leurs critiques sont n\u00e9cessairement li\u00e9es \u00e0 cette contradiction. Elles n&rsquo;ont ainsi pas la moindre consistance.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab [Soros&rsquo;] <em>remarks have infuriated the Republican party, which has accused him of promoting his interests with the steady flow of money to like-minded institutions, and avoiding federal limits on donations to political parties  an allegation which Democrats consistently level at big business for its links with the Republicans.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>George Soros has purchased the Democratic party, said Christine Iverson, a Republican national committee spokeswoman.<\/em> \u00bb <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tDans le cas Soros, il y a deux choses : la critique de l&rsquo;administration GW Bush, qui est une chose classique aujourd&rsquo;hui, quoique dite dans des termes extraordinairement radicaux. La seconde est beaucoup plus int\u00e9ressante. C&rsquo;est l&rsquo;intervention d\u00e9sormais massive et sans le moindre contr\u00f4le de forces internationales et de forces priv\u00e9es dans le processus \u00e9lectoral am\u00e9ricain. (Cela rejoint en un sens <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=923\" class=\"gen\">les remarques que nous faisions hier sur les d\u00e9mocrates se r\u00e9f\u00e9rant \u00e0 l&rsquo;ONU, \u00e0 l&rsquo;OTAN et \u00e0 l&rsquo;Europe<\/a>.) La fonction pr\u00e9sidentielle et le processus politique lui-m\u00eame en sont compl\u00e8tement d\u00e9valoris\u00e9s. Mais \u00e0 qui la faute  ? Au monde politique US dans son enti\u00e8ret\u00e9,  mais avec les r\u00e9publicains qui ne le c\u00e8dent \u00e0 personne, eux qui, depuis Reagan, n&rsquo;ont cess\u00e9 de privatiser la vie politique am\u00e9ricaine, la soumettant aux forces de l&rsquo;argent, nationales ou internationales. L&rsquo;arch\u00e9type de cette situation, c&rsquo;est l&rsquo;administration Bush bien plus que l&rsquo;intervention de Soros.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La privatisation et l&rsquo;internationalisation de l&rsquo;\u00e9lection du pr\u00e9sident US 12 novembre 2003 La d\u00e9cision de Georges Soros, investisseur d&rsquo;origine hongroise et \u00e9toile classique depuis une quinzaine d&rsquo;ann\u00e9es du monde internationale de la finance et de l&rsquo;investissement, d&rsquo;entrer en guerre contre la r\u00e9\u00e9lection de GW Bush ouvre une nouvelle p\u00e9riode dans l&rsquo;histoire de l&rsquo;Am\u00e9rique. Soros ne&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[868,4163],"class_list":["post-65792","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-bush","tag-soros"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65792"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65792\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}