{"id":65798,"date":"2003-11-18T00:00:00","date_gmt":"2003-11-18T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2003\/11\/18\/le-triomphe-virtualiste-de-gw-dans-les-rues-videes-par-la-vigilance-policiere\/"},"modified":"2003-11-18T00:00:00","modified_gmt":"2003-11-18T00:00:00","slug":"le-triomphe-virtualiste-de-gw-dans-les-rues-videes-par-la-vigilance-policiere","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2003\/11\/18\/le-triomphe-virtualiste-de-gw-dans-les-rues-videes-par-la-vigilance-policiere\/","title":{"rendered":"<strong><em>Le triomphe virtualiste de GW dans les rues vid\u00e9es par la vigilance polici\u00e8re <\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Le triomphe virtualiste de GW dans les rues vid\u00e9es par la vigilance polici\u00e8re <\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t18 novembre 2003  Le fait le plus extraordinaire dans la visite de GW Bush en Angleterre se trouve dans la transformation d&rsquo;un non-\u00e9v\u00e9nement politique en une apparence d&rsquo;\u00e9v\u00e9nement politique fondamental sans que rien du contenu de l&rsquo;\u00e9v\u00e9nement lui-m\u00eame n&rsquo;ait chang\u00e9, simplement par la pression g\u00e9n\u00e9r\u00e9e par cet \u00e9v\u00e9nement, par la perception ainsi suscit\u00e9e.<\/p>\n<\/p>\n<p><p>\tCette rencontre fut d\u00e9cid\u00e9e en septembre 2002. Elle devait \u00eatre une simple mais glorieuse promenade de victoire pour les deux chefs de gouvernement victorieux en Irak,  puisque, d\u00e9j\u00e0 en septembre 2002, l&rsquo;essentiel \u00e9tait programm\u00e9 \u00e0 cet \u00e9gard, notamment le d\u00e9fil\u00e9 de la victoire. Aucun point politique fondamental n&rsquo;\u00e9tait \u00e9videmment pr\u00e9vu en septembre 2002, et rien n&rsquo;est venu modifier cette perspective : il n&rsquo;existe aucun point fondamental de discussion entre Britanniques et Am\u00e9ricains dans ce qui est dit et qui est discut\u00e9 ouvertement entre eux, qui, n\u00e9cessite aujourd&rsquo;hui une r\u00e9union \u00e0 ce niveau. Cette rencontre a \u00e9t\u00e9 consid\u00e9r\u00e9e par certains comme une simple s\u00e9ance de photographie,  certains avec d\u00e9rision, certains avec rage, certains encore en acceptant cette vision g\u00e9n\u00e9rale mais en protestant contre elle (<a href=\"http:\/\/www.telegraph.co.uk\/opinion\/main.jhtml?xml=\/opinion\/2003\/11\/16\/do1606.xml&#038;sSheet=\/opinion\/2003\/11\/16\/ixop.html \" class=\"gen\">voir All this just for a photograph with the Queen?, question de Mark Steyn dans le Daily Telegraph<\/a>)<\/p>\n<\/p>\n<p><p>\tAujourd&rsquo;hui, l&rsquo;\u00e9v\u00e9nement est devenu dramatique par le biais de l&rsquo;argumentation diverse qui entoure la visite,  d\u00e9marche fondamentalement virtualiste. On en appelle aux <em>special relationships<\/em>, qui pour les r\u00e9affirmer comme si elles \u00e9taient fondamentalement menac\u00e9es, qui pour les d\u00e9noncer comme une infamie trop longtemps accept\u00e9e. Le pauvre Tony Blair s&rsquo;est oblig\u00e9 \u00e0 ressortir ses tr\u00e9molos sur la guerre contre la terreur, pour affirmer, sur ce ton churchillien qui semble d\u00e9sormais un peu us\u00e9 :  \u00ab <em>Now is not the time to waver but see it through. <\/em>[&#8230;] <em>Britain should stand firm with the United States of America in defeating terrorism wherever it is and delivering us safely from what I genuinely believe is the security threat of the 21st century.<\/em> \u00bb Il faut du souffle pour dire cela apr\u00e8s avoir fabriqu\u00e9 de toutes pi\u00e8ces, en Irak m\u00eame, le nouveau centre international du champ d&rsquo;essai de tous les terrorismes possibles et imaginables.<\/p>\n<\/p>\n<p><p>\tOn passe sur les effarantes mesures de s\u00e9curit\u00e9 prises par les Am\u00e9ricains, d&rsquo;une fa\u00e7on souvent horripilante pour les Britanniques, et par ces m\u00eames Britanniques, parce qu&rsquo;il faut tout de m\u00eame para\u00eetre croire aussi bien \u00e0 l&rsquo;existence du pr\u00e9sident am\u00e9ricain, \u00e0 l&rsquo;existence des liens d&rsquo;amiti\u00e9 entre les deux pays, \u00e0 l&rsquo;existence d&rsquo;une menace terroriste \u00e9pouvantable. Tout cela alimente pour le compte <a href=\"http:\/\/www.wsws.org\/articles\/2003\/nov2003\/bush-n18.shtml\" class=\"gen\">les rumeurs de montage, de fabrication provocatrice d&rsquo;un complot terroriste<\/a>. Londres vit au rythme d&rsquo;une quasi-crise de nerfs, <a href=\"http:\/\/news.independent.co.uk\/uk\/politics\/story.jsp?story=464815\" class=\"gen\">avec 16.000 policiers mobilis\u00e9s<\/a> pour prot\u00e9ger un pr\u00e9sident am\u00e9ricain qui vient \u00ab <em>just for a photograph with the Queen<\/em> \u00bb.<\/p>\n<\/p>\n<p><p>\tLes sondages rendent bien compte de la confusion r\u00e9gnant aujourd&rsquo;hui au Royaume-Uni devant cette visite qui \u00e0 la fois d\u00e9clenche toutes les col\u00e8res pour d\u00e9noncer GW et mobilise toutes les \u00e9nergies pour applaudir malgr\u00e9 tout \u00e0 l&rsquo;amiti\u00e9 avec l&rsquo;Am\u00e9rique. On a donc r\u00e9uni des r\u00e9sultats \u00e0 la fois contradictoires et similaires, dont les interpr\u00e9tations de r\u00e9ponses assez proches sont aux antipodes pour proposer des conclusions radicalement diff\u00e9rentes. Le <em>Guardian<\/em> offre <a href=\"http:\/\/www.guardian.co.uk\/usa\/story\/0,12271,1087544,00.html\" class=\"gen\">son propre sondage<\/a> qu&rsquo;il pr\u00e9sente sous le titre extr\u00eamement encourageant de \u00ab <em>Protests begin but majority backs Bush visit as support for war surges<\/em> \u00bb. Le site <em>WorldNet Daily<\/em> reprend <a href=\"http:\/\/worldnetdaily.com\/news\/article.asp?ARTICLE_ID=35646\" class=\"gen\">un sondage Sunday Times\/AFP<\/a> et le pr\u00e9sente sous ce titre sans espoir de : \u00ab <em>1 in 3 Brits call Bush stupid  Poll: Majority consider U.S. leader threat to world peace<\/em> \u00bb (Voir ces deux textes restitu\u00e9s sur notre site <a href=\"http:\/\/www.dedefensa.org\/choix.php?link_id=3391&#038;comm=1\" class=\"gen\">dans la rubrique Nos Choix Comment\u00e9s<\/a>.)<\/p>\n<\/p>\n<p><p>\tQui a raison, qui a tort ? Nous nous trouvons dans une grande entreprise de sauvegarde d&rsquo;une politique anglo-saxonne compl\u00e8tement virtualiste, dont il faut continuer de faire la promotion malgr\u00e9 les chocs impitoyables de la r\u00e9alit\u00e9. Cette visite, sur le fond, n&rsquo;a pas le moindre sens ni le moindre int\u00e9r\u00eat. Elle sert \u00e0 illustrer le d\u00e9sarroi des puissances soi-disant dominantes, dont la politique n&rsquo;a plus que de lointaines et \u00e9pisodiques proximit\u00e9s avec la r\u00e9alit\u00e9. La politique, aujourd&rsquo;hui, semble \u00eatre r\u00e9duite au charcutage sans fin d&rsquo;une image offerte comme seul t\u00e9moignage de la substance des choses&#8230; \u00ab <em>Just for a photograph with the Queen<\/em> \u00bb, certes mais ce sera une photo brouill\u00e9e, floue, confuse et incompr\u00e9hensible. Le d\u00e9sordre bushiste paradant en triomphe, dans les rues de Londres vid\u00e9es par la pr\u00e9sence polici\u00e8re, comme dans un film d&rsquo;Antonioni ou dans une toile de Dali.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le triomphe virtualiste de GW dans les rues vid\u00e9es par la vigilance polici\u00e8re 18 novembre 2003 Le fait le plus extraordinaire dans la visite de GW Bush en Angleterre se trouve dans la transformation d&rsquo;un non-\u00e9v\u00e9nement politique en une apparence d&rsquo;\u00e9v\u00e9nement politique fondamental sans que rien du contenu de l&rsquo;\u00e9v\u00e9nement lui-m\u00eame n&rsquo;ait chang\u00e9, simplement par&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-65798","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65798"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65798\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}