{"id":65802,"date":"2003-11-21T00:00:00","date_gmt":"2003-11-21T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2003\/11\/21\/en-assistant-a-leffondrement-infini-de-lempire\/"},"modified":"2003-11-21T00:00:00","modified_gmt":"2003-11-21T00:00:00","slug":"en-assistant-a-leffondrement-infini-de-lempire","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2003\/11\/21\/en-assistant-a-leffondrement-infini-de-lempire\/","title":{"rendered":"En assistant \u00e0 l&rsquo;effondrement infini de l&#8217;empire&#8230;"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">En assistant \u00e0 l&rsquo;effondrement infini de l&#8217;empire&#8230;<\/h2>\n<\/p>\n<p><p>21 novembre 2003 &ndash; La semaine fut \u00e9puisante \u00e0 Londres pour les duettistes Tony &#038; George, &mdash; le mois aussi, et le trimestre pas moins, &mdash; et l&rsquo;ann\u00e9e, ne m&rsquo;en parlez pas&#8230; La situation semble comme un vertige, dans les deux sens qu&rsquo;on peut donner au mot, le vacillement de l&rsquo;esprit et l&rsquo;encha&icirc;nement irr\u00e9sistible des situations. On peut \u00eatre s&ucirc;r que ceci explique cela et inversement. (Je soup\u00e7onne l&rsquo;Histoire de profiter de notre folie g\u00e9n\u00e9rale pour faire avancer les choses plus vite qu&rsquo;il ne faudrait. L&rsquo;Histoire va vite, aujourd&rsquo;hui.)<\/p>\n<\/p>\n<p><p>Au-del\u00e0 de la semaine, du mois et du trimestre, et de l&rsquo;ann\u00e9e, nous sommes invit\u00e9s, presque simultan\u00e9ment \u00e0 notre r\u00e9alisation de l&rsquo;\u00e9v\u00e9nement, presque \u00ab\u00a0historiquement\u00a0\u00bb en un sens puisque nous l&rsquo;interpr\u00e9tons \u00e0 l&rsquo;instant o&ugrave; il se fait, &mdash; nous sommes invit\u00e9s \u00e0 assister \u00e0 l&rsquo;effondrement de l&#8217;empire. Cela se passe dans les sables irakiens et cette circonstance g\u00e9ographique et strat\u00e9gique mesure la d\u00e9rision de cet empire, autant que la d\u00e9rision des commentaires de ses z\u00e9lateurs acharn\u00e9s et stipendi\u00e9s en mesure la puissance. Le probl\u00e8me est de ne pas se laisser emporter par cet effondrement qui ressemble \u00e0 une outre pleine qui se vide, \u00e0 un souffl\u00e9 ti\u00e8de qui s&rsquo;affaisse&#8230;<\/p>\n<\/p>\n<p><p><a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=929\">Certaines descriptions des op\u00e9rations de l&rsquo;U.S.Army en Irak<\/a>, dans le cadre de la nouvelle tactique dite <strong><em>get-tough<\/em><\/strong>, laissent absolument r\u00eaveurs sur la fa\u00e7on d&rsquo;\u00eatre et la fa\u00e7on d&rsquo;agir de la plus puissante force militaire du monde, et la fa\u00e7on dont elle se pr\u00e9pare effectivement \u00e0 perdre cette guerre picrocolinesque. Ces sc\u00e8nes irakiennes ach\u00e8vent de confirmer le jugement de d\u00e9rision qu&rsquo;on ne peut qu&rsquo;avoir sur ce ph\u00e9nom\u00e8ne, qui est celui d&rsquo;une fausse puissance dont la seule capacit\u00e9 est celle de la d\u00e9monstration, comme fait un voyageur de commerce en vadrouille dans une ville du Middle West (avec la diff\u00e9rence que ceux-l\u00e0, ils tuent). Disons, pour panser quelques plaies d&rsquo;experts dont c&rsquo;est la lumi\u00e8re de l&rsquo;esprit de parler avec \u00e9motion de cette puissance qui les met en transes, type derviches tourneurs, que c&rsquo;est la d\u00e9rision la plus ch\u00e8re du monde ($400 milliards par an). Cela fait plus s\u00e9rieux et cela permet au secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;OTAN d&rsquo;avoir des tr\u00e9molos dans la voix avant de partir \u00e0 la retraite.<\/p>\n<\/p>\n<p><p>Depuis la proclamation publique, par fuites interpos\u00e9es, que la CIA allait d\u00e9sormais jusqu&rsquo;\u00e0 envisager une \u00ab\u00a0d\u00e9faite\u00a0\u00bb am\u00e9ricaine, une sorte d&rsquo;ivresse n\u00e9gative s&rsquo;est empar\u00e9e des esprits. D&rsquo;autres rapports surgissent, <a class=\"gen\" href=\"http:\/\/news.independent.co.uk\/world\/middle_east\/story.jsp?story=465083\">pr\u00e9disant encore plus pr\u00e9cis\u00e9ment cette issue<\/a>. A Washington, aujourd&rsquo;hui, la perspective d&rsquo;une \u00ab\u00a0d\u00e9faite\u00a0\u00bb est \u00e0 la mode. Elle ferait presque valser \u00e0 la hausse l&rsquo;indice Dow Jones. On danse sur le volcan et il faut bien dire que le rythme est endiabl\u00e9, type Michael Jackson et <strong><em>Neverland<\/em><\/strong>.<\/p>\n<\/p>\n<p><p>Le plus poignant, le plus surr\u00e9aliste, c&rsquo;est sans doute le coup de l&rsquo;incendiaire, dont les comiques Tony &#038; George, avec hier matin l&rsquo;acolyte Jack Straw (secr\u00e9taire au Foreign Office) sont des sp\u00e9cialistes r\u00e9guli\u00e8rement r\u00e9cidivistes, et qui nous a \u00e9t\u00e9 \u00e9videmment rejou\u00e9 avec la Turquie. Apr\u00e8s chaque vague d&rsquo;attentats, rendue \u00e9videmment possible par leur intervention qui cr\u00e9e d&rsquo;une fa\u00e7on extraordinairement efficace un centre terroriste au centre du Moyen-Orient, ils viennent vous dire, gravissimes, menton \u00e0 la Churchill : nous vous l&rsquo;avions bien dit, la menace est grave. Sur le pourtour de la M\u00e9diterran\u00e9e, quand on prend un pompier qui met le feu \u00e0 la for\u00eat pour pouvoir s&rsquo;engager sur le sentier de la guerre et avertir le monde que l&rsquo;incendie gronde, on le met en cabane. Leur reconversion est toute trouv\u00e9e. Ils iront surveiller les pompiers fous et, avec eux, ils joueront aux pyromanes. Bient\u00f4t les pompiers fous redeviendront sains d&rsquo;esprit et s&rsquo;enfuiront, \u00e9pouvant\u00e9s, en criant : \u00ab\u00a0Au feu, ils sont fous !\u00a0\u00bb. La boucle sera boucl\u00e9e.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En assistant \u00e0 l&rsquo;effondrement infini de l&#8217;empire&#8230; 21 novembre 2003 &ndash; La semaine fut \u00e9puisante \u00e0 Londres pour les duettistes Tony &#038; George, &mdash; le mois aussi, et le trimestre pas moins, &mdash; et l&rsquo;ann\u00e9e, ne m&rsquo;en parlez pas&#8230; La situation semble comme un vertige, dans les deux sens qu&rsquo;on peut donner au mot, le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[9],"tags":[705,868,3104,857],"class_list":["post-65802","post","type-post","status-publish","format-standard","hentry","category-messagerie","tag-blair","tag-bush","tag-cia","tag-irak"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65802"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65802\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}