{"id":65830,"date":"2003-12-30T00:00:00","date_gmt":"2003-12-30T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2003\/12\/30\/pour-etre-lempire-du-monde-il-faut-les-moyens\/"},"modified":"2003-12-30T00:00:00","modified_gmt":"2003-12-30T00:00:00","slug":"pour-etre-lempire-du-monde-il-faut-les-moyens","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2003\/12\/30\/pour-etre-lempire-du-monde-il-faut-les-moyens\/","title":{"rendered":"<strong><em>Pour \u00eatre l&rsquo;Empire du monde, il faut les moyens<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Pour \u00eatre l&rsquo;Empire du monde, il faut les moyens<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t30 d\u00e9cembre 2003  Cet <a href=\"http:\/\/www.iht.com\/articles\/123094.html\" class=\"gen\">\u00e9ditorial du New York Times<\/a> est particuli\u00e8rement impressionnant et significatif. Le sujet qu&rsquo;il traite devrait \u00eatre entendu si les observations faites sur la puissance am\u00e9ricaine n&rsquo;\u00e9taient pas obscurcies par des r\u00e9actions \u00e9motionnelles de fascination dissimul\u00e9es derri\u00e8re des attitudes pr\u00e9tendument raisonnables. Le New York <em>Times<\/em> nous dit que les forces arm\u00e9es am\u00e9ricaines sont au bord d&rsquo;une crise grave, puisque dans l&rsquo;incapacit\u00e9 de soutenir encore tr\u00e8s longtemps,  c&rsquo;est une question de mois, voire de semaines,  les engagements am\u00e9ricains en cours, sans m\u00eame parler de nouveaux engagements, comme les id\u00e9ologues de l&rsquo;interventionnisme en \u00e9voquent souvent la possibilit\u00e9.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>More than a third of the U.S. Army&rsquo;s active-duty combat troops are now in Iraq, and by spring the Pentagon plans to let most of them come home for urgently needed rest. Many will have served longer than a normal overseas tour and under extremely harsh conditions. When the 130,000 Americans rotate out for home leave, nearly the same number will rotate in. At that point, should the United States need to send additional fighters anywhere else in the world, it will have dangerously few of them to spare.<\/em><\/p>\n<\/p>\n<p><p>\t(&#8230;)<\/p>\n<\/p>\n<p><p>\t\u00bb <em>Meanwhile, if a sudden crisis were to erupt in North Korea, Afghanistan or elsewhere, the Pentagon might be hard pressed to respond. For a time, it could make do by sending tired troops back into action, mobilizing reserves and borrowing forces from areas that are quiet but still volatile. Such expedients have severe long-term costs. The White House must recognize the damage its unilateralism is inflicting on the army and change course before the damage becomes harder to undo.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tLes forces arm\u00e9es am\u00e9ricaines craquent de partout et, d\u00e9sormais, vivent d&rsquo;exp\u00e9dients. Ainsi, cette information d\u00e9velopp\u00e9e par <a href=\"http:\/\/www.washingtonpost.com\/wp-dyn\/articles\/A36979-2003Dec28.html\" class=\"gen\">le Washington Post concernant les mesures d&rsquo;interdiction de l&rsquo;U.S. Army<\/a> pour emp\u00eacher des soldats arriv\u00e9s au terme de leur contrat, d&rsquo;effectivement quitter l&rsquo;arm\u00e9e. Le <em>Post<\/em> parle de ces \u00ab <em>thousands of soldiers forbidden to leave military service under the Army&rsquo;s stop-loss orders, intended to stanch the seepage of troops, through retirement and discharge, from a military stretched thin by its burgeoning overseas missions. It reflects the fact that the military is too small, which nobody wants to admit, said Charles Moskos of Northwestern University, a leading military sociologist.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tLa mesure prise par le Pentagone pour maintenir les unit\u00e9s actuelles \u00e0 leur niveau ne repr\u00e9sente rien d&rsquo;autre qu&rsquo;une mobilisation d\u00e9guis\u00e9e et forc\u00e9e, puisque ces soldats se trouvent d\u00e9sormais sous les drapeaux contre leur gr\u00e9. Le Washington <em>Post<\/em> parle pour ces soldats, qui sont 40.000 aujourd&rsquo;hui pour l&rsquo;U.S. Army, d&rsquo;une \u00ab <em>involuntary servitude<\/em> \u00bb, selon une expression totalement absurde,  comment imaginer une <em>voluntary servitude<\/em> quand <em>servitude<\/em> est par d\u00e9finition une contrainte ? Cette expression absurde, justement, refl\u00e8te l&#8217;embarras o\u00f9 cette situation met les autorit\u00e9s et les commentateurs, dans la mesure o\u00f9 il s&rsquo;agit d&rsquo;un arbitraire g\u00e9n\u00e9ralis\u00e9, qui tend \u00e0 faire d&rsquo;une situation exceptionnelle une situation structurelle difficilement justifiable.<\/p>\n<\/p>\n<p><p>\tPar ailleurs, et pour rester pratique, la description de la situation de l&rsquo;U.S. Army explique l&rsquo;utilisation extensive de cette technique.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>By prohibiting soldiers and officers from leaving the service at retirement or the expiration of their contracts, military leaders have breached the Army&rsquo;s manpower limit of 480,000 troops, a ceiling set by Congress. In testimony before the Senate Armed Services Committee last month, Gen. Peter Schoomaker, the Army chief of staff, disclosed that the number of active-duty soldiers has crept over the congressionally authorized maximum by 20,000 and now registered 500,000 as a result of stop-loss orders. Several lawmakers questioned the legality of exceeding the limit by so much.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Our goal is, we want to have units that are stabilized all the way down from the lowest squad up through the headquarters elements, said Brig. Gen. Howard B. Bromberg, director of enlisted personnel management in the Army&rsquo;s Human Resources Command. Stop-loss allows us to do that. When a unit deploys, it deploys, trains and does its missions with the same soldiers.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>In a recent profile of an Army infantry battalion deployed in Kuwait and on its way to Iraq, the commander, Lt. Col. Karl Reed, told the Army Times he could have lost a quarter of his unit in the coming year had it not been for the stop-loss order. And that means a new 25 percent, Reed told the Army Times. I would have had to train them and prepare them to go on the line. Given where we are, it will be a 24-hour combat operation; therefore it&rsquo;s very difficult to bring new folks in and integrate them.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tL&rsquo;int\u00e9r\u00eat de l&rsquo;\u00e9ditorial du journal new yorkais (diffus\u00e9 \u00e9galement dans l&rsquo;International <em>Herald Tribune<\/em>, qui a une client\u00e8le tr\u00e8s diff\u00e9rente) est de deux ordres :<\/p>\n<\/p>\n<p><p>\t&bull; D&rsquo;une part, il d\u00e9crit clairement, de fa\u00e7on tranchante, une r\u00e9alit\u00e9 qui est d&rsquo;\u00e9vidence, mais qui continue \u00e0 ne pas \u00eatre prise en compte dans les analyses, les projections et les raisonnements des non-Am\u00e9ricains, particuli\u00e8rement des Europ\u00e9ens. La toute-puissance militaire am\u00e9ricaine, donc l&rsquo;utilisation de la puissance militaire comme un instrument maniable par la diplomatie am\u00e9ricaine, est un mythe complet. La seule r\u00e9elle puissance absolue am\u00e9ricaine pour l&rsquo;instant est une extraordinaire capacit\u00e9 d&rsquo;influence, paralysant la pens\u00e9e de toute la communaut\u00e9 militaro-experte de l&rsquo;Europe occidentale et la fixant sur quelques clich\u00e9s grossiers.<\/p>\n<\/p>\n<p><p>\t&bull; D&rsquo;autre part, ce texte nous conduit \u00e0 une r\u00e9flexion encore plus int\u00e9ressante, o\u00f9 le journal met en parall\u00e8le les capacit\u00e9s militaires r\u00e9elles des USA avec leurs ambitions politiques d&rsquo;h\u00e9g\u00e9monie. L\u00e0 aussi, il s&rsquo;agit pour les Europ\u00e9ens d&rsquo;une d\u00e9marche intellectuelle in\u00e9dite, dont ils s&rsquo;av\u00e8rent semble-t-il compl\u00e8tement incapables tant, pour eux, la puissance am\u00e9ricaine ne s&rsquo;accorde qu&rsquo;avec la notion de toute puissance sans la moindre restriction. Nous int\u00e9resse moins, ici, l&rsquo;id\u00e9e que propose le New York <em>Times<\/em> de revenir \u00e0 telle ou telle politique de coop\u00e9ration que l&rsquo;affirmation sans ambages ni restriction que les USA n&rsquo;ont absolument pas les moyens de mener une politique militaire globale dans l&rsquo;\u00e9tat actuel de leurs forces (avec un budget militaire de $400 milliards). Il faut \u00e9videmment avoir \u00e0 l&rsquo;esprit que les USA sont aujourd&rsquo;hui en train de s&rsquo;\u00e9puiser dans une campagne men\u00e9e dans un pays de 25 millions d&rsquo;habitants, au niveau technologique et militaire arri\u00e9r\u00e9, alors que l&rsquo;ambition affirm\u00e9e de certains dirigeants US \u00e9tait, il y a peu encore, de lancer en rapide succession plusieurs autres campagnes du m\u00eame type pour arriver \u00e0 une position  d&rsquo;h\u00e9g\u00e9monie militaire absolue, et que ces projets \u00e9taient pris pour argent comptant.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em> &#8230;the Bush administration is pushing America&rsquo;s peacetime armed forces toward their limits. Washington will not be able to sustain the mismatch between unrealistic White House ambitions and finite Pentagon means much longer without long-term damage to America&rsquo;s military strength. The only solution is for the Bush administration to return to foreign policy sanity, starting with a more cooperative, less vindictive approach to European allies who could help share America&rsquo;s military burdens.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Most American strategists fear at least a temporary upsurge in attacks in Iraq as the troop rotations get under way and maneuvering to produce an interim Iraqi government intensifies. More than 100,000 American troops will be needed for many more months, unless the Bush administration starts wooing NATO allies instead of snubbing them. Eventually, the Iraqi recruits now being hurriedly trained may provide some relief. Yet there are doubts about their military competence and political reliability, and fears that if Washington is in too much of a hurry, it will succeed only in recreating Saddam Hussein&rsquo;s old security forces in new American-issued uniforms.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Meanwhile, if a sudden crisis were to erupt in North Korea, Afghanistan or elsewhere, the Pentagon might be hard pressed to respond. For a time, it could make do by sending tired troops back into action, mobilizing reserves and borrowing forces from areas that are quiet but still volatile. Such expedients have severe long-term costs. The White House must recognize the damage its unilateralism is inflicting on the army and change course before the damage becomes harder to undo.<\/em> \u00bb<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour \u00eatre l&rsquo;Empire du monde, il faut les moyens 30 d\u00e9cembre 2003 Cet \u00e9ditorial du New York Times est particuli\u00e8rement impressionnant et significatif. Le sujet qu&rsquo;il traite devrait \u00eatre entendu si les observations faites sur la puissance am\u00e9ricaine n&rsquo;\u00e9taient pas obscurcies par des r\u00e9actions \u00e9motionnelles de fascination dissimul\u00e9es derri\u00e8re des attitudes pr\u00e9tendument raisonnables. Le New&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-65830","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65830"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65830\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}