{"id":65850,"date":"2004-01-21T00:00:00","date_gmt":"2004-01-21T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2004\/01\/21\/levolution-des-relations-usa-ue-de-mal-en-pis-comme-prevu\/"},"modified":"2004-01-21T00:00:00","modified_gmt":"2004-01-21T00:00:00","slug":"levolution-des-relations-usa-ue-de-mal-en-pis-comme-prevu","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2004\/01\/21\/levolution-des-relations-usa-ue-de-mal-en-pis-comme-prevu\/","title":{"rendered":"<strong><em>L&rsquo;\u00e9volution des relations USA-UE : de mal en pis, comme pr\u00e9vu<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">L&rsquo;\u00e9volution des relations USA-UE : de mal en pis, comme pr\u00e9vu<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t21 janvier 2004  Hors des pitreries s\u00e9mantiques sur la vieille Europe et la <em>new Europe<\/em>, la situation euro-am\u00e9ricaine \u00e9volue r\u00e9guli\u00e8rement vers l&rsquo;\u00e9loignement des positions des deux partenaires,  \u00e9loignement des conceptions, \u00e9loignement des perceptions, \u00e9loignement des \u00e9tats d&rsquo;esprit, bref tout ce qui constitue le fondement d&rsquo;une politique. Cet \u00e9loignement n&rsquo;\u00e9tant pas sanctionn\u00e9, ni par des d\u00e9clarations de prise en compte, ni par une modification des structures existantes, il a pour effet un accroissement r\u00e9gulier des tensions sans raisons strictement identifi\u00e9es.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est la marque de l&rsquo;\u00e9volution des relations euro-am\u00e9ricaines : une \u00e9volution vers un antagonisme sans raison apparente, d&rsquo;autant plus dangereux, et surtout incontr\u00f4lable lorsqu&rsquo;il fera sentir des effets violents et pressants \u00e0 l&rsquo;occasion de l&rsquo;une ou l&rsquo;autre crise. On a mesur\u00e9 cela lors de la crise \u00e0 l&rsquo;OTAN, en janvier-f\u00e9vrier 2003. Elle a pris des allures de grande rupture alors qu&rsquo;elle ne comprenait <em>stricto sensu<\/em> qu&rsquo;un nombre extr\u00eamement r\u00e9duit de nations (la France et la Belgique) et portait sur un sujet tr\u00e8s mineur (transf\u00e9rer des armes d\u00e9fensives de l&rsquo;OTAN \u00e0 la Turquie, risquant de pousser \u00e0 une provocation conflictuelle avec l&rsquo;Irak, ou bien, plus justement, aggravant l&rsquo;impasse d&rsquo;une solution, diplomatique \u00e0 l&rsquo;ONU, selon les manigances am\u00e9ricaines). Si cette fausse-vraie crise a pris cette allure, c&rsquo;est parce qu&rsquo;elle exprimait indirectement tant de non-dits et de pens\u00e9es non exprim\u00e9es.<\/p>\n<\/p>\n<p><p>\tAujourd&rsquo;hui, on peut mesurer l&rsquo;\u00e9volution des pens\u00e9es r\u00e9elles \u00e0 cet \u00e9gard, lors d&rsquo;enqu\u00eates qui sont faites hors des dossiers pressants ou des d\u00e9clarations officielles. C&rsquo;est le cas des deux r\u00e9cents articles de John Vinocur dans l&rsquo;International <em>Herald Tribune<\/em>, l&rsquo;un qui est consacr\u00e9 <a href=\"http:\/\/www.iht.com\/articles\/125491.html\" class=\"gen\">au sentiment g\u00e9n\u00e9ral de l&rsquo;establishment US vis-\u00e0-vis de l&rsquo;Europe<\/a>, l&rsquo;autre, publi\u00e9 le lendemain (le 20 janvier), <a href=\"http:\/\/www.iht.com\/articles\/125649.html\" class=\"gen\">qui tente de restituer le m\u00eame sentiment, mais des Europ\u00e9ens pour les Am\u00e9ricains<\/a>. Sans la moindre surprise, on a la confirmation du climat d\u00e9testable r\u00e9gnant entre les deux continents, entre indiff\u00e9rence m\u00e9prisante et hostilit\u00e9 d\u00e9daigneuse.<\/p>\n<\/p>\n<p><p>\tL&rsquo;un des textes de Vinocur est particuli\u00e8rement int\u00e9ressant dans la mesure o\u00f9, au travers d&rsquo;une ou l&rsquo;autre pr\u00e9cision qu&rsquo;il rapporte de ses entretiens aux \u00c9tats-Unis, il appara\u00eet que les conceptions les plus extr\u00e9mistes (celles des n\u00e9o-conservateurs) sont en train de s&rsquo;installer dans la pens\u00e9e g\u00e9n\u00e9rale. Le conformisme du syst\u00e8me \u00e9tant d&rsquo;une force consid\u00e9rable, cette diffusion et cette installation ont toutes les chances de s&rsquo;accro\u00eetre encore, et la politique extr\u00e9miste de l&rsquo;administration GW elle-m\u00eame de s&rsquo;institutionnaliser.<\/p>\n<\/p>\n<p><p>\tDe m\u00eame, on voit que la politique agressive, anti-europ\u00e9enne de l&rsquo;administration GW Bush, cette politique dite de d\u00e9sagr\u00e9gation consistant \u00e0 tenter de diviser les Europ\u00e9ens n&rsquo;est mise en cause par certains,  notamment chez les experts de tendance d\u00e9mocrate,<D> que dans la mesure o\u00f9 elle n&rsquo;est pas assez efficacement anti-europ\u00e9enne (dans le sens d&rsquo;un frein \u00e0 une r\u00e9elle politique europ\u00e9enne).   <\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>In reality, the great change on the U.S. side of European-American relations since the September 2001 terrorist attacks on New York and Washington may be in the ready acceptance here of the neoconservative Robert Kagan&rsquo;s characterization of two similar cultures with markedly different views on the use of power and military force.<\/em><\/p>\n<\/p>\n<p><p>\t(&#8230;)<\/p>\n<\/p>\n<p><p>\t\u00bb <em>James Steinberg, who served under Clinton as deputy national security adviser and now directs the foreign policy studies program of the Brookings Institution, believes that the Democratic presidential candidates have much greater regard for the experience of the Europeans and are much more in touch with European motivations. If Americans don&rsquo;t have a deep conviction one way or the other on Europe, he said, the decline in regard for Europe is less sharp in the United States than it is in the other direction within the European Union.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>All the same, he told a visitor, a Democratic administration is going to be much more unilateralist than the Europeans want.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Steinberg accuses the Bush administration of not supporting EU integration, preferring to deal with individual European countries than a European whole. But he hardly sees the end-goal of such integration with the eyes of those Europeans who would want the EU to function as a counterweight to the United States.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>I think more integration actually would have isolated the French and the Germans, he said, noting their effort to speak in Europe&rsquo;s name against the United States on Iraq. What so angered the other Europeans is the way the French and the Germans went off on their own.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Chancellor Gerhard Schr\u00f6der doesn&rsquo;t give a damn about Europe, Steinberg said. And the other Europeans see the French and the Germans as miscreants.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>But even among opponents of the Bush administration&rsquo;s take on Europe, wanting a more respectful, more cooperative relationship does not necessarily come combined with a sense of apology or regret on what they share, if tacitly, with the administration. More than a few critics of a neoconservative view of Europe acknowledge the emergence of palpably different visions of the world, and a genuine diminution in identical values. Ivo Daalder, who served on the National Security Council under Clinton, and has written a critical new book about Bush&rsquo;s foreign policy, believes that the value gap is a lot larger than we think.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tDans ce contexte, on doit  aussi rappeler les d\u00e9clarations du g\u00e9n\u00e9ral finlandais Hagglund, pr\u00e9sident du Comit\u00e9 militaire de l&rsquo;Union europ\u00e9enne, \u00e0 Stockholm, le 17 janvier. Elles constituent un signe int\u00e9ressant. Hagglund affirme nettement <a href=\"http:\/\/www.alertnet.org\/thenews\/newsdesk\/STA853854.htm\" class=\"gen\">une volont\u00e9 et une capacit\u00e9 europ\u00e9ennes de d\u00e9fense du continent, sans les Am\u00e9ricains<\/a>. Cette d\u00e9claration n&rsquo;a pas \u00e9t\u00e9 faite par hasard, ni sans rapport avec le contexte g\u00e9n\u00e9ral. Elle montre un certain agacement des autorit\u00e9s europ\u00e9ennes devant l&rsquo;activisme anti-europ\u00e9en des Am\u00e9ricains, qui se manifeste jusque dans les institutions et services europ\u00e9ens charg\u00e9s des questions militaires. Elle compl\u00e8te le tableau g\u00e9n\u00e9ral en montrant qu&rsquo;une aggravation des relations euro-am\u00e9ricaines, telle qu&rsquo;on la ressent comme possible aujourd&rsquo;hui, se traduira \u00e9videmment, du c\u00f4t\u00e9 europ\u00e9en, par une affirmation d&rsquo;ind\u00e9pendance militaire aujourd&rsquo;hui tout \u00e0 fait possible. <\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>The European Union&rsquo;s top military official suggested on Sunday that American and European forces should be responsible for their own territorial defence and only cooperate on major crises outside their regions.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Finnish general, Gustav Hagglund, who is chairman of the EU&rsquo;s military committee, told a defence conference it was time Europe shouldered the defence of the continent itself.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>The American and the European pillars (of NATO) would be responsible for their respective territorial defences, and would together engage in crisis management outside their own territories, Hagglund told the conference in Salen, 450 km (280 miles) northwest of Stockholm.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>My prediction is that this will happen within the next decade, he told a news conference later.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tCette attitude europ\u00e9enne est rendue d&rsquo;autant plus possible par une perte sensible de la consid\u00e9ration des Europ\u00e9ens pour la puissance am\u00e9ricaine, en fonction des \u00e9v\u00e9nements en Irak. Les Europ\u00e9ens commencent \u00e0 admettre ce qui est une \u00e9vidence depuis un certain temps d\u00e9j\u00e0 pour ceux qui \u00e9tudient la machine militaire am\u00e9ricaine : derri\u00e8re la puissance d&rsquo;influence qui fait croire \u00e0 une puissance absolue, presque magique, les r\u00e9alit\u00e9s montrent des faiblesses graves. <\/p>\n<\/p>\n<p><p>\t(Signe de cette \u00e9volution de l&rsquo;appr\u00e9ciation de la puissance europ\u00e9enne, cette citation de Fran\u00e7ois Heisbourg dans <em>Dossiers Europ\u00e9ens<\/em>, d\u00e9cembre 2003  : <\/p>\n<\/p>\n<p><p>\t\u00ab <em>&#8230;Les \u00c9tats-Unis ne sont pas pour autant un empire exer\u00e7ant son h\u00e9g\u00e9monie. Ils ne peuvent pas occuper durablement un territoire, sauf \u00e0 consentir des pertes de mobilit\u00e9 strat\u00e9gique dans d&rsquo;autres parties du monde. On voit donc leurs limites m\u00eame en mati\u00e8re de d\u00e9fense. Politiquement, les \u00c9tats-Unis n&rsquo;ont m\u00eame pas pu convaincre leurs voisins les plus proches  le Canada et le Mexique  de les soutenir pendant la crise irakienne.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>D\u00e8s lors, nous sommes dans un syst\u00e8me international o\u00f9 le pouvoir d&rsquo;influence directe de l&rsquo;une quelconque des puissances qui le compose est relativement faible, m\u00eame s&rsquo;il s&rsquo;agit de la seule superpuissance que sont les \u00c9tats-Unis.<\/em> \u00bb)<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00e9volution des relations USA-UE : de mal en pis, comme pr\u00e9vu 21 janvier 2004 Hors des pitreries s\u00e9mantiques sur la vieille Europe et la new Europe, la situation euro-am\u00e9ricaine \u00e9volue r\u00e9guli\u00e8rement vers l&rsquo;\u00e9loignement des positions des deux partenaires, \u00e9loignement des conceptions, \u00e9loignement des perceptions, \u00e9loignement des \u00e9tats d&rsquo;esprit, bref tout ce qui constitue le fondement&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3116,4213],"class_list":["post-65850","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-hagglund","tag-heisbourg"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65850"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65850\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}