{"id":65869,"date":"2004-02-13T00:00:00","date_gmt":"2004-02-13T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2004\/02\/13\/bae-stonecipher-et-la-unhappy-end-dun-american-dream\/"},"modified":"2004-02-13T00:00:00","modified_gmt":"2004-02-13T00:00:00","slug":"bae-stonecipher-et-la-unhappy-end-dun-american-dream","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2004\/02\/13\/bae-stonecipher-et-la-unhappy-end-dun-american-dream\/","title":{"rendered":"<strong><em>BAE, Stonecipher et la unhappy end d&rsquo;un American Dream<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">BAE, Stonecipher et la unhappy end d&rsquo;un American Dream<\/h2>\n<\/p>\n<p><p>\t13 f\u00e9vrier 2004  Ancien vice-pr\u00e9sident de Boeing parti \u00e0 la retraite et rappel\u00e9 en d\u00e9cembre 2003 au poste supr\u00eame, Harry Stonecipher est aussi un dur. Il ne le cache pas, indirectement mais abruptement,  lorsqu&rsquo;il parle de son pr\u00e9d\u00e9cesseur, qui vient de d\u00e9missionner devant la situation tr\u00e8s d\u00e9licate de Boeing : \u00ab [Phil] <em>Condit is a much nicer man than I am<\/em> \u00bb.<\/p>\n<\/p>\n<p><p>\tUn tr\u00e8s r\u00e9cent voyage de Stonecipher au Royaume-Uni a secou\u00e9 les Britanniques. Rompant avec la temporisation et les sourires d\u00e9sol\u00e9s mais polis de Condit, Stonecipher est venu dire clairement que Boeing n&rsquo;est pas du tout int\u00e9ress\u00e9 par une alliance avec le britannique BAE. (Ce serait pourtant, selon les formules envisag\u00e9es par les Britanniques, une v\u00e9ritable absorption de BAE, o\u00f9 les Britanniques passeraient sous certaines fourches caudines des Am\u00e9ricains. Cela n&rsquo;\u00e9branle pas Stonecipher.) Un long et int\u00e9ressant <a href=\"http:\/\/observer.guardian.co.uk\/business\/story\/0,6903,1143260,00.html\" class=\"gen\">article de l&rsquo;Observer du 8 f\u00e9vrier<\/a> d\u00e9crit la visite de Stonecipher et ses d\u00e9marches concernant BAE.<\/p>\n<\/p>\n<p><p>\t\u00ab <em>That is how Stonecipher has approached his first visit to the UK as chief executive officer  as a Yank who sees nothing wrong in being brusque to the rather-too-polite Brits. We don&rsquo;t know what he said at his meeting with Defence Secretary Geoff Hoon last Monday, but after congratulating him on still being in a job, he may have had some choice words about why the UK recently chose Airbus over Boeing for its \u00a313 billion RAF mid-air refuelling programme.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>He also said he didn&rsquo;t fancy BAE Systems as a merger partner and that the relationship was over. None of Condit&rsquo;s flirting  the UK&rsquo;s prime contractor was just chucked. And he has uncomplimentary reflections on Europe&rsquo;s aerospace effort, spearheaded by Eads and Airbus (of which Eads owns 80 per cent).<\/em> \u00bb <\/p>\n<\/p>\n<p><p>\tPour les Britanniques, la r\u00e9ponse de Stonecipher, autant dans le ton que dans la forme, ferme d\u00e9finitivement les portes \u00e0 une grande op\u00e9ration transatlantique, style UK-USA. Cela conduit \u00e0 un climat \u00e9trange \u00e0 Londres, o\u00f9 la politique la plus pro-am\u00e9ricaine depuis longtemps, accompagn\u00e9e d&rsquo;affirmations cat\u00e9goriques concernant le sort de BAE,  du fameux <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=557\" class=\"gen\">\u00abBAE is no longer British\u00bb<\/a> aux consid\u00e9rations sur une compl\u00e8te <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=833\" class=\"gen\">am\u00e9ricanisation de BAE<\/a>,  est d\u00e9sormais doubl\u00e9e par une r\u00e9alit\u00e9 de plus en plus europ\u00e9enne. C&rsquo;est le cas au niveau des acquisitions, o\u00f9 les contractants europ\u00e9ens sont favoris\u00e9s, comme <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=987\" class=\"gen\">pour le march\u00e9 des ravitailleurs en vol<\/a>.<\/p>\n<\/p>\n<p><p>\tVoici la derni\u00e8re surprise de cette \u00e9trange \u00e9volution confirmant l&rsquo;impossibilit\u00e9 de la coop\u00e9ration avec les USA,  plus la politique UK que nous qualifierons d&rsquo;apparence est proche des Am\u00e9ricains et d\u00e9sireuse de se rapprocher d&rsquo;eux, moins ce rapprochement a lieu,  : il s&rsquo;agit de la suggestion relev\u00e9e ici et l\u00e0 que, finalement, pourquoi pas ?, BAE pourrait se tourner vers une solution europ\u00e9enne.<\/p>\n<\/p>\n<p><p>\tPassage choisi de l&rsquo;<em>Observer<\/em> :<\/p>\n<\/p>\n<p><p>\t\u00ab <em>In fact, Eads, with a market capitalisation of 12bn, is a fraction of Boeing ($50bn), and compares with Lockheed ($22bn), General Dynamics and Northrop Grumman (both about $18bn). Some senior figures in the UK industry are now saying that Eads, BAE and Thales should team up to create one European player capable of competing with the Americans. But that is not yet Stonecipher&rsquo;s problem.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tCette allusion dans l&rsquo;article de <em>The Observer<\/em> n&rsquo;est pas pass\u00e9e inaper\u00e7ue. Elle indique un r\u00e9el climat, une \u00e9volution s\u00e9rieuse en cours au Royaume-Uni, un tournant compl\u00e8tement paradoxal de BAE vers une orientation europ\u00e9enne. Diff\u00e9rentes indications existent selon lesquelles des pressions officielles US se manifestent pour la revente de certaines grosses acquisitions am\u00e9ricaines de BAE,  selon la logique bien am\u00e9ricaine que, puisque BAE n&rsquo;a pas r\u00e9ussi \u00e0 se faire manger par un partenaire am\u00e9ricain, personne n&rsquo;ayant d&rsquo;app\u00e9tit \u00e0 cet \u00e9gard, BAE redevient aussi suspect qu&rsquo;un vulgaire fran\u00e7ais, et qu&rsquo;alors il serait pr\u00e9f\u00e9rable de revendre.<\/p>\n<\/p>\n<p><p>\tLa d\u00e9monstration est \u00e9poustouflante de rapidit\u00e9, de la fausset\u00e9 g\u00e9n\u00e9rale et fondamentale de toute tentative s\u00e9rieuse transatlantique dans le domaine des armements. M\u00eame chose pour la politique Blair du pont transatlantique ; que faire lorsqu&rsquo;une des rives s&rsquo;\u00e9loigne ? (Et l&rsquo;on pourrait ajouter la triste cerise sur le g\u00e2teau de <a href=\"http:\/\/www.guardian.co.uk\/Iraq\/Story\/0,2763,1147271,00.html\" class=\"gen\">la marginalisation des soci\u00e9t\u00e9s UK<\/a> dans l&rsquo;attribution des contrats de reconstruction en Irak.)<\/p>\n<\/p>\n<p><p>\tLa porte est ouverte pour une s\u00e9rieuse affaire JSF au Royaume-Uni, c&rsquo;est-\u00e0-dire la remise en question du choix de l&rsquo;avion US. D\u00e8s lors que l&rsquo;avion a des probl\u00e8mes (<a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=977\" class=\"gen\">c&rsquo;est le cas<\/a>), d\u00e8s lors que les int\u00e9r\u00eats de l&rsquo;industrie d&rsquo;armement commencent \u00e0 tourner le dos aux USA, le choix du JSF devient un sujet beaucoup plus contestable et qu&rsquo;il devient de bonne politique de contester. Ceci est peut-\u00eatre un signe : l&rsquo;hebdomadaire <a href=\"http:\/\/www.aviationnow.com\/awin\/awin_awst\/awin_awst_story.jsp?issueDate=2004-02-09&#038;story=xml\/awst_xml\/2004\/02\/09\/AW_02_09_2004_p30-01.xml\" class=\"gen\">Aviation Week &#038; Space Technology du 9 f\u00e9vrier<\/a> publie un long article sur les inqui\u00e9tudes britanniques, o\u00f9 il \u00e9crit notamment que \u00ab <em>Britain is being forced to revisit its assumptions as to its choice of a Joint Strike Fighter variant amid concern over performance aspects of the short takeoff and vertical landing version of the fighter.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>Worries over weight growth and its impact on the potential performance of the F-35B is resulting in the British Defense Ministry re-examining the rationale for its selection. The JSF will provide the platform for the navy and air force&rsquo;s Joint Combat Aircraft (JCA).<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BAE, Stonecipher et la unhappy end d&rsquo;un American Dream 13 f\u00e9vrier 2004 Ancien vice-pr\u00e9sident de Boeing parti \u00e0 la retraite et rappel\u00e9 en d\u00e9cembre 2003 au poste supr\u00eame, Harry Stonecipher est aussi un dur. Il ne le cache pas, indirectement mais abruptement, lorsqu&rsquo;il parle de son pr\u00e9d\u00e9cesseur, qui vient de d\u00e9missionner devant la situation tr\u00e8s&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3192,250,4221,4222],"class_list":["post-65869","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-boeing","tag-jsf","tag-stonecipher","tag-telegraoh"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65869"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65869\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}