{"id":65878,"date":"2004-02-24T00:00:00","date_gmt":"2004-02-24T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2004\/02\/24\/lenchanteur-nous-parle-des-etats-unis-lamerique-dans-les-memoires-doutre-tombe\/"},"modified":"2004-02-24T00:00:00","modified_gmt":"2004-02-24T00:00:00","slug":"lenchanteur-nous-parle-des-etats-unis-lamerique-dans-les-memoires-doutre-tombe","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2004\/02\/24\/lenchanteur-nous-parle-des-etats-unis-lamerique-dans-les-memoires-doutre-tombe\/","title":{"rendered":"<strong><em>L&rsquo;Enchanteur nous parle des \u00c9tats-Unis, \u2014 L&rsquo;Am\u00e9rique dans les \u201cM\u00e9moires d&rsquo;outre-tombe\u201d<\/em><\/strong>"},"content":{"rendered":"<p><h3>L&rsquo;Enchanteur nous parle des \u00c9tats-Unis,  L&rsquo;Am\u00e9rique dans les M\u00e9moires d&rsquo;outre-tombe<\/h3>\n<\/p>\n<p><p>\t&bull; <strong>L&rsquo;extrait<\/strong> : En fait, des passages significatifs des <em>M\u00e9moires d&rsquo;outre-tombe<\/em>, rapportant des jugements du voyageur fran\u00e7ais aux \u00c9tats-Unis, en 1791-93. On y trouve \u00e9galement la confrontation de ces jugements de l&rsquo;explorateur jeune avec des r\u00e9flexions apport\u00e9es plus tard, vingt ou trente ans plus tard, lors de la r\u00e9daction des <em>M\u00e9moires<\/em>, par un Chateaubriand exp\u00e9riment\u00e9.<\/p>\n<\/p>\n<p><p>\t&bull; <strong>L&rsquo;auteur<\/strong> : nous \u00e9viterons de lui faire l&rsquo;injure d&rsquo;une pr\u00e9sentation qui serait inutile. Chateaubriand est bien s\u00fbr l&rsquo;un des plus grands \u00e9crivains de langue fran\u00e7aise. Il a cr\u00e9\u00e9, avec ses <em>M\u00e9moires d&rsquo;outre-tombe<\/em>, un genre sp\u00e9cifique au g\u00e9nie fran\u00e7ais, celui de m\u00e9morialiste, historien et inspecteur des psychologies humaines. M\u00eame si l&rsquo;oeuvre est consid\u00e9r\u00e9e comme singuli\u00e8rement subjective, et souvent consid\u00e9r\u00e9e avec m\u00e9fiance du point de vue de son apport historique, elle reste un t\u00e9moignage sans \u00e9quivalent d&rsquo;une \u00e9poque centrale de l&rsquo;histoire de France. Plus qu&rsquo;elle ne nous fait comprendre la R\u00e9volution et l&rsquo;Empire, elle nous fait ressentir la tension et la force de la p\u00e9riode. Cela est sans prix lorsque cela vient d&rsquo;un homme comme Chateaubriand.<\/p>\n<\/p>\n<p><p>\t&bull; <strong>Les circonstances<\/strong>  sont celles de l&rsquo;exil quand il n&rsquo;\u00e9tait pas encore un calvaire. Chateaubriand quitta la France r\u00e9volutionnaire dont il ne supportait plus le spectacle sanglant et vulgaire, pour un voyage en Am\u00e9rique, d&rsquo;exploration et de d\u00e9couverte. Cette partie de l&rsquo;exil de Chateaubriand est encore pleine d&rsquo;\u00e9lan m\u00eame si l&rsquo;Am\u00e9rique lui m\u00e9nagea quelques d\u00e9convenues.<\/p>\n<\/p>\n<p><p>\t&bull; <strong>La situation<\/strong> est celle du Fran\u00e7ais d\u00e9couvrant et d\u00e9crivant l&rsquo;Am\u00e9rique. Il est bon d&rsquo;observer combien des remarques de Chateaubriand gardent aujourd&rsquo;hui toute leur valeur, voire leur actualit\u00e9. Le ph\u00e9nom\u00e8ne am\u00e9ricain est fix\u00e9 d\u00e8s l&rsquo;origine : fascination d&rsquo;abord, suivie d&rsquo;un d\u00e9senchantement certain. Les r\u00e9alit\u00e9s, quand il s&rsquo;agit de l&rsquo;Am\u00e9rique, pardonnent moins que dans nombre d&rsquo;autres cas. <\/p>\n<\/p>\n<p><\/p>\n<h2 class=\"common-article\">L&rsquo;Am\u00e9rique dans Les M\u00e9moires d&rsquo;outre-tombe<\/h2>\n<\/p>\n<p><\/p>\n<h3>9.Les \u00c9tats-Unis aujourd&rsquo;hui.<\/h3>\n<\/p>\n<p><p>\tSi je revoyais aujourd&rsquo;hui les \u00c9tats-Unis, je ne les reconna\u00eetrais plus  : l\u00e0 o\u00f9 j&rsquo;ai laiss\u00e9 des for\u00eats, je trouverais des champs cultiv\u00e9s  ; l\u00e0 o\u00f9 je me suis fray\u00e9 un sentier \u00e0 travers les halliers, je voyagerais sur de grandes routes  ; aux Natchez, au lieu de la hutte de C\u00e9luta, s&rsquo;\u00e9l\u00e8ve une ville d&rsquo;environ cinq mille habitants  ; Chactas pourrait \u00eatre aujourd&rsquo;hui d\u00e9put\u00e9 au Congr\u00e8s. J&rsquo;ai re\u00e7u derni\u00e8rement une brochure imprim\u00e9e chez les <em>Ch\u00e9rokis<\/em>, laquelle m&rsquo;est adress\u00e9e dans l&rsquo;int\u00e9r\u00eat de ces sauvages, comme <em>au d\u00e9fenseur de la libert\u00e9 de la presse<\/em>.<\/p>\n<\/p>\n<p><p>\tIl y a chez les Muscogulges, les Siminoles, les Chickasas, une cit\u00e9 d&rsquo;Ath\u00e8nes, une autre de Marathon, une autre de Carthage, une autre de Memphis, une autre de Sparte, une autre de Florence  ; on trouve un comt\u00e9 de la Colombie et un comt\u00e9 de Marengo  : la gloire de tous les pays a plac\u00e9 un nom dans ces m\u00eames d\u00e9serts o\u00f9 j&rsquo;ai rencontr\u00e9 le p\u00e8re Aubry et l&rsquo;obscure Atala. Le Kentucky montre un Versailles  ; un territoire appel\u00e9 Bourbon a pour capitale un Paris.<\/p>\n<\/p>\n<p><p>\tTous les exil\u00e9s, tous les opprim\u00e9s qui se sont retir\u00e9s en Am\u00e9rique y ont port\u00e9 la m\u00e9moire de leur patrie.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t<em>&#8230; Falsi Simoentis ad undam Libabat cineri Andromache.<\/em><\/p>\n<\/p>\n<p><\/p>\n<p><p>\tLes \u00c9tats-Unis offrent dans leur sein, sous la protection de la libert\u00e9, une image et un souvenir de la plupart des lieux c\u00e9l\u00e8bres de l&rsquo;antiquit\u00e9 et de la moderne Europe dans son jardin de la campagne de Rome, Adrien avait fait r\u00e9p\u00e9ter les monuments de son empire.<\/p>\n<\/p>\n<p><p>\tTrente-trois grandes routes sortent de Washington, comme autrefois les voies romaines partaient du Capitole ; elles aboutissent, en se ramifiant, \u00e0 la circonf\u00e9rence des \u00c9tats-Unis, et tracent une circulation de 25.747 milles. Sur un grand nombre de ces routes, les postes sont mont\u00e9es. On prend la diligence pour l&rsquo;Ohio ou pour Niagara, comme de mon temps on prenait un guide ou un interpr\u00e8te indien. Ces moyens de transport sont doubles : des lacs et des rivi\u00e8res existent partout, li\u00e9s ensemble par des canaux ; on peut voyager le long des chemins de terre sur des chaloupes \u00e0 rames et \u00e0 voiles, ou sur des coches d&rsquo;eau, ou sur des bateaux \u00e0 vapeur. Le combustible est in\u00e9puisable, puisque des for\u00eats immenses couvrent des mines de charbon \u00e0 fleur de terre.<\/p>\n<\/p>\n<p><p>\tLa population des \u00c9tats-Unis s&rsquo;est accrue de dix ans en dix ans, depuis 1790 jusqu&rsquo;en 1820, dans la proportion de trente-cinq individus sur cent. On pr\u00e9sume qu&rsquo;en 1830, elle sera de douze millions huit cent soixante-quinze mille \u00e2mes. En continuant \u00e0 doubler tous les vingt-cinq ans, elle serait en 1855 de vingt-cinq millions sept cent cinquante mille \u00e2mes, et vingt-cinq ans plus tard, en 1880, elles d\u00e9passerait cinquante millions.<\/p>\n<\/p>\n<p><p>\tCette s\u00e8ve humaine fait fleurir de toutes parts le d\u00e9sert. Les lacs du Canada, nagu\u00e8re sans voiles, ressemblent aujourd&rsquo;hui \u00e0 des docks o\u00f9 des fr\u00e9gates, des corvettes, des cutters, des barques, se croisent avec les pirogues et les canots indiens, comme les gros navires et les gal\u00e8res se m\u00ealent aux pinques, aux chaloupes et aux ca\u00efques dans les eaux de Constantinople.<\/p>\n<\/p>\n<p><p>\tLe Mississipi, le Missouri, l&rsquo;Ohio, ne coulent plus dans la solitude : des trois-m\u00e2ts les remontent, plus de deux cents bateaux \u00e0 vapeur en vivifient les rivages.<\/p>\n<\/p>\n<p><p>\tCette immense navigation int\u00e9rieure, qui suffirait seule \u00e0 la prosp\u00e9rit\u00e9 des \u00c9tats-Unis, ne ralentit point leurs exp\u00e9ditions lointaines. Leur vaisseaux courent toutes les mers, se livrent \u00e0 toutes les esp\u00e8ces d&rsquo;entreprises, prom\u00e8nent le pavillon \u00e9toil\u00e9 du couchant, le long de ces rivages de l&rsquo;aurore qui n&rsquo;ont jamais connu que la servitude.<\/p>\n<\/p>\n<p><p>\tPour achever ce tableau surprenant, il se faut repr\u00e9senter des villes comme Boston, New-York, Philadelphie, Baltimore, Charlestown, Savanah, la Nouvelle-Orl\u00e9ans, \u00e9clair\u00e9es la nuit, remplies de chevaux et de voitures, orn\u00e9es de caf\u00e9s, de mus\u00e9es, de biblioth\u00e8ques, de salles de danse et de spectacle, offrant toutes les jouissances du luxe.<\/p>\n<\/p>\n<p><p>\t[Ajoutez (a) une administration laborieuse, cultivant chaque branche du commerce et de l&rsquo;agriculture, une police attentive, am\u00e9liorant les \u00e9tablissements de s\u00fbret\u00e9 et de bienfaisance, une prosp\u00e9rit\u00e9 native donnant l&rsquo;essor \u00e0 l&rsquo;esprit d&rsquo;association, et s&rsquo;agrandissant \u00e0 son tour de cet esprit, une \u00e9norme accumulation de capitaux alimentant l&rsquo;activit\u00e9 d&rsquo;une marine aventureuse  : voyez une dette pr\u00eate \u00e0 s&rsquo;\u00e9teindre, un cr\u00e9dit qui centuplerait les ressources nationales, si l&rsquo;on avait jamais besoin d&rsquo;y recourir, une masse de terres concessionnables, autre tr\u00e9sor entre les mains du Congr\u00e8s ; voyez ces fortifications \u00e0 l&rsquo;entr\u00e9e des havres et des rivi\u00e8res qui mettent le pays \u00e0 l&rsquo;abri d&rsquo;une invasion, ces maisons g\u00e9n\u00e9rales pour l&rsquo;\u00e9ducation publique, ces coll\u00e8ges particuliers pour les \u00e9tudes sp\u00e9ciales, ces amphith\u00e9\u00e2tres, ces observatoires, ces phares de la science, aux confins des t\u00e9n\u00e8bres sauvages, toutes les religions, toutes les opinions vivant de paix, travaillant de concert \u00e0 rendre meilleure l&rsquo;esp\u00e8ce humaine et \u00e0 d\u00e9velopper son intelligence  : tels sont les prodiges de la libert\u00e9.]<\/p>\n<\/p>\n<p><\/p>\n<h3>10.Les lettres aux \u00c9tats-Unis (a).<\/h3>\n<\/p>\n<p><p>\tToutefois, il ne faut pas chercher aux \u00c9tats-Unis ce qui distingue l&rsquo;homme des autres \u00eatres de la cr\u00e9ation, ce qui est son extrait d&rsquo;immortalit\u00e9 et l&rsquo;ornement de ses jours les lettres sont inconnues dans la nouvelle R\u00e9publique, quoiqu&rsquo;elles soient appel\u00e9es par une foule d&rsquo;\u00e9tablissements. L&rsquo;Am\u00e9ricain a remplac\u00e9 les op\u00e9rations intellectuelles par les op\u00e9rations positives ; ne lui imputez point \u00e0 inf\u00e9riorit\u00e9 sa m\u00e9diocrit\u00e9 dans les arts, car ce n&rsquo;est pas de ce c\u00f4t\u00e9 qu&rsquo;il a port\u00e9 son attention. Jet\u00e9 par diff\u00e9rentes causes sur un sol d\u00e9sert, l&rsquo;agriculture et le commerce ont \u00e9t\u00e9 l&rsquo;objet de ses soins ; avant de penser, il faut vivre ; avant de planter des arbres, il faut les abattre, afin de labourer. Les colons primitifs, l&rsquo;esprit rempli de controverses religieuses, portaient, il est vrai, la passion de la dispute jusqu&rsquo;au sein des for\u00eats ; mais il fallait qu&rsquo;ils marchassent d&rsquo;abord \u00e0 la conqu\u00eate du d\u00e9sert la hache sur l&rsquo;\u00e9paule, n&rsquo;ayant pour pupitre, dans l&rsquo;intervalle de leurs labeurs, que l&rsquo;orme qu&rsquo;ils \u00e9quarissaient. Les Am\u00e9ricains n&rsquo;ont point parcouru les degr\u00e9s de l&rsquo;\u00e2ge des peuples ; ils ont laiss\u00e9 en Europe leur enfance et leur jeunesse ; les paroles na\u00efves du berceau leur ont \u00e9t\u00e9 inconnues ; ils n&rsquo;ont joui des douceurs du foyer qu&rsquo;\u00e0 travers le regret d&rsquo;une patrie qu&rsquo;ils n&rsquo;avaient jamais vue, dont ils pleuraient l&rsquo;\u00e9ternelle absence et le charme qu&rsquo;on leur avait racont\u00e9.<\/p>\n<\/p>\n<p><p>\tIl n&rsquo;y a dans le nouveau continent ni litt\u00e9rature classique, ni litt\u00e9rature romantique, ni litt\u00e9rature indienne : classique, les Am\u00e9ricains n&rsquo;ont point de mod\u00e8les ; romantique, les Am\u00e9ricains n&rsquo;ont point de moyen \u00e2ge ; indienne, les Am\u00e9ricains m\u00e9prisent les sauvages et ont horreur des bois comme d&rsquo;une prison qui leur \u00e9tait destin\u00e9e.<\/p>\n<\/p>\n<p><p>\tAinsi, ce n&rsquo;est donc pas la litt\u00e9rature \u00e0 part, la litt\u00e9rature proprement dite, que l&rsquo;on trouve en Am\u00e9rique c&rsquo;est la litt\u00e9rature appliqu\u00e9e, servant aux divers usages de la soci\u00e9t\u00e9 ; c&rsquo;est la litt\u00e9rature d&rsquo;ouvriers, de n\u00e9gociants, de marins, de laboureurs. Les Am\u00e9ricains ne r\u00e9ussissent gu\u00e8re que dans la m\u00e9canique et dans les sciences, parce que les sciences ont un c\u00f4t\u00e9 mat\u00e9riel : Franklin et Fulton se sont empar\u00e9s de la foudre et de la vapeur au profit des hommes. Il appartenait \u00e0 l&rsquo;Am\u00e9rique de doter le monde de la d\u00e9couverte par laquelle aucun continent ne pourra d\u00e9sormais \u00e9chapper aux recherches du navigateur.<\/p>\n<\/p>\n<p><p>\tLa po\u00e9sie et l&rsquo;imagination, partage d&rsquo;un tr\u00e8s petit nombre de d\u00e9soeuvr\u00e9s, sont regard\u00e9es aux \u00c9tats-Unis comme des pu\u00e9rilit\u00e9s du premier et du dernier \u00e2ge de la vie  : les Am\u00e9ricains n&rsquo;ont point eu d&rsquo;enfance, ils n&rsquo;ont point encore de vieillesse.<\/p>\n<\/p>\n<p><p>\tDe ceci il r\u00e9sulte que les hommes engag\u00e9s dans les \u00e9tudes s\u00e9rieuses ont d\u00fb n\u00e9cessairement appartenir aux affaires de leur pays afin d&rsquo;en acqu\u00e9rir la connaissance, et qu&rsquo;ils ont d\u00fb de m\u00eame se trouver acteurs dans leur r\u00e9volution. Mais une chose triste est \u00e0 remarquer : la d\u00e9g\u00e9n\u00e9ration prompte du talent, depuis les premiers hommes des troubles am\u00e9ricains jusqu&rsquo;aux hommes de ces derniers temps ; et cependant ces hommes se touchent. Les anciens pr\u00e9sidents de la R\u00e9publique ont un caract\u00e8re religieux, simple, \u00e9lev\u00e9, calme, dont on ne trouve aucune trace dans nos fracas sanglants de la R\u00e9publique et de l&rsquo;Empire. La solitude dont les Am\u00e9ricains \u00e9taient environn\u00e9s a r\u00e9agi sur leur nature ; ils ont accompli en silence leur libert\u00e9.<\/p>\n<\/p>\n<p><p>\tLe discours d&rsquo;adieu du g\u00e9n\u00e9ral Washington au peuple des \u00c9tats-Unis pourrait avoir \u00e9t\u00e9 prononc\u00e9 par les personnages les plus graves de l&rsquo;antiquit\u00e9 :<\/p>\n<\/p>\n<p><p>\t\u00ab Les actes publics, dit le g\u00e9n\u00e9ral, prouvent jusqu&rsquo;\u00e0 quel point les principes que je viens de rappeler m&rsquo;ont guid\u00e9 lorsque je me suis acquitt\u00e9 des devoirs de ma place. Ma conscience me dit du moins que je les ai suivis. Bien qu&rsquo;en repassant les actes de mon administration, je n&rsquo;aie connaissance d&rsquo;aucune faute d&rsquo;intention, j&rsquo;ai un sentiment trop profond de mes d\u00e9fauts pour ne pas penser que probablement j&rsquo;ai commis beaucoup de fautes. Quelles qu&rsquo;elles soient, je supplie avec ferveur le Tout-Puissant d&rsquo;\u00e9carter ou de dissiper les maux qu&rsquo;elles pourraient entra\u00eener. J&#8217;emporterai aussi avec moi l&rsquo;espoir que mon pays ne cessera jamais de les consid\u00e9rer avec indulgence, et qu&rsquo;apr\u00e8s quarante-cinq ann\u00e9es de ma vie d\u00e9vou\u00e9es \u00e0 son service avec z\u00e8le et droiture, les torts d&rsquo;un m\u00e9rite insuffisant tomberont dans l&rsquo;oubli, comme je tomberai bient\u00f4t moi-m\u00eame dans la demeure du repos. \u00bb<\/p>\n<\/p>\n<p><p>\tJefferson, dans son habitation de Monticello, \u00e9crit, apr\u00e8s la mort de l&rsquo;un de ses enfants :<\/p>\n<\/p>\n<p><p>\t\u00ab La perte que j&rsquo;ai \u00e9prouv\u00e9e est r\u00e9ellement grande. D&rsquo;autres peuvent perdre ce qu&rsquo;ils ont en abondance ; mais moi, de mon strict n\u00e9cessaire, j&rsquo;ai \u00e0 d\u00e9plorer la moiti\u00e9. Le d\u00e9clin de mes jours ne tient plus que par le faible fil d&rsquo;une vie humaine. Peut-\u00eatre suis-je destin\u00e9 \u00e0 voir rompre ce dernier lien de l&rsquo;affection d&rsquo;un p\u00e8re ! \u00bb<\/p>\n<\/p>\n<p><p>\tLa philosophie, rarement touchante, l&rsquo;est ici au souverain degr\u00e9. Et ce n&rsquo;est pas l\u00e0 la douleur oiseuse d&rsquo;un homme qui ne s&rsquo;\u00e9tait m\u00eal\u00e9 de rien : Jefferson mourut le 4 juillet 1826, dans la quatre-vingt-quatri\u00e8me ann\u00e9e de son \u00e2ge, et la cinquante-quatri\u00e8me de l&rsquo;ind\u00e9pendance de son pays. Ses restes reposent, recouverts d&rsquo;une pierre, n&rsquo;ayant pour \u00e9pitaphe que ces mots : \u00ab <em>THOMAS JEFFERSON, auteur de la D\u00e9claration d&rsquo;ind\u00e9pendance.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tP\u00e9ricl\u00e8s et D\u00e9mosth\u00e8ne avaient prononc\u00e9 l&rsquo;oraison fun\u00e8bre des jeunes Grecs tomb\u00e9s pour un peuple qui disparut bient\u00f4t apr\u00e8s eux : Brackenridge, en 1817, c\u00e9l\u00e9brait la mort des jeunes Am\u00e9ricains dont le sang a fait na\u00eetre un peuple.<\/p>\n<\/p>\n<p><p>\tOn a une galerie nationale des portraits des Am\u00e9ricains distingu\u00e9s, en quatre volumes in-octavo, et ce qu&rsquo;il y a de plus singulier, une biographie contenant la vie de plus de cent principaux chefs indiens. Logan, chef de la Virginie, pronon\u00e7a devant lord Dunmore ces paroles : \u00ab Au printemps dernier, sans provocation aucune, le colonel Crasp \u00e9gorgea tous les parents de Logan  : il ne coule plus une seule goutte de mon sang dans les veines d&rsquo;aucune cr\u00e9ature vivante. C&rsquo;est l\u00e0 ce qui m&rsquo;a appel\u00e9 \u00e0 la vengeance. Je l&rsquo;ai cherch\u00e9e ; j&rsquo;ai tu\u00e9 beaucoup de monde. Est-il quelqu&rsquo;un qui viendrait maintenant pleurer la mort de Logan? Personne. \u00bb<\/p>\n<\/p>\n<p><p>\tSans aimer la nature, les Am\u00e9ricains se sont appliqu\u00e9s \u00e0 l&rsquo;\u00e9tude de l&rsquo;histoire naturelle. Towsend, parti de Philadelphie, a parcouru \u00e0 pied les r\u00e9gions qui s\u00e9parent l&rsquo;Atlantique de l&rsquo;oc\u00e9an Pacifique, en consignant dans son journal ses nombreuses observations. Thomas Say, voyageur dans les Florides et aux montagnes Rocheuses, a donn\u00e9 un ouvrage sur l&rsquo;entomologie am\u00e9ricaine. Wilson, tisserand, devenu auteur, a des peintures assez finies.<\/p>\n<\/p>\n<p><p>\tArriv\u00e9s \u00e0 la litt\u00e9rature proprement dite, quoiqu&rsquo;elle soit peu de chose, il y a pourtant quelques \u00e9crivains \u00e0 citer parmi les romanciers et les po\u00e8tes. Le fils d&rsquo;un quaker, Brown, est l&rsquo;auteur de <em>Wieland<\/em>, lequel <em>Wieland<\/em> est la source et le mod\u00e8le des romans de la nouvelle \u00e9cole. Contrairement \u00e0 ses compatriotes, \u00ab j&rsquo;aime mieux, assurait Brown, errer parmi les for\u00eats que de battre le bl\u00e9 \u00bb. Wieland, le h\u00e9ros du roman, est un puritain \u00e0 qui le ciel a command\u00e9 de tuer sa femme : \u00ab Je t&rsquo;ai amen\u00e9e ici, lui dit-il, pour accomplir les ordres de Dieu : c&rsquo;est par moi que tu dois p\u00e9rir ; et je saisis ses deux bras. Elle poussa plusieurs cris per\u00e7ants et voulut se d\u00e9gager :  Wieland, ne suis-je pas ta femme? et tu veux me tuer ; me tuer, moi, oh! non, oh! gr\u00e2ce! gr\u00e2ce!  tant que sa voix eut un passage, elle cria ainsi gr\u00e2ce et secours. \u00bb Wieland \u00e9trangle sa femme et \u00e9prouve d&rsquo;ineffables d\u00e9lices aupr\u00e8s du cadavre expir\u00e9. L&rsquo;horreur de nos inventions modernes est ici surpass\u00e9e. Brown s&rsquo;\u00e9tait form\u00e9 \u00e0 la lecture de <em>Caleb Williams<\/em>, et il imitait dans <em>Wieland<\/em> une sc\u00e8ne d&rsquo;<em>Othello<\/em>.<\/p>\n<\/p>\n<p><p>\tA cette heure, les romanciers am\u00e9ricains, Cooper, Washington Irving, sont forc\u00e9s de se r\u00e9fugier en Europe, pour y trouver des chroniques et un public. La langue des grands \u00e9crivains de l&rsquo;Angleterre s&rsquo;est <em>cr\u00e9olis\u00e9e, provincialis\u00e9e, barbaris\u00e9e<\/em>, sans avoir rien gagn\u00e9 en \u00e9nergie au milieu de la nature vierge ; on a \u00e9t\u00e9 oblig\u00e9 de dresser des catalogues des expressions am\u00e9ricaines.<\/p>\n<\/p>\n<p><p>\t[Le th\u00e9\u00e2tre (c) est le th\u00e9\u00e2tre anglais : il n&rsquo;offre aux Yankees que le tableau des moeurs \u00e9trang\u00e8res, comme la com\u00e9die et la trag\u00e9die ne pr\u00e9sentaient aux Romains que la peinture de la soci\u00e9t\u00e9 grecque. Lewis, fr\u00e8re de Holfam, associ\u00e9 de Garrick, s&#8217;embarqua en Angleterre en 1752 ; descendu \u00e0 York-Town en Virginie, il obtint des magistrats la permission d&rsquo;y dresser ses tr\u00e9teaux. La premi\u00e8re pi\u00e8ce jou\u00e9e sur ce th\u00e9\u00e2tre forain fut le <em>Marchand de Venise<\/em>. Washington, alors inconnu, assista \u00e0 la prise de possession par Shakespeare de la terre de Christophe Colomb ; un acteur d\u00e9bita un prologue commen\u00e7ant ainsi :<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t<em>To this new world front famed Britannia&rsquo;s shore, Through boist&rsquo;rous seas where foaming billows roar, The Muse who Britons charmed for many an age Now sends her servants forth, to tread your stage.<\/em><\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab A ce nouveau monde, du rivage fameux d&rsquo;Albion, \u00e0 travers les orageuses mers, o\u00f9 r\u00e8gnent des vagues \u00e9cumantes, la Muse qui charma les Bretons pendant plus d&rsquo;un si\u00e8cle envoie maintenant ses serviteurs pour fouler votre sc\u00e8ne. \u00bb<\/p>\n<\/p>\n<p><p>\tLes graves Am\u00e9ricains ont la t\u00eate renvers\u00e9e aujourd&rsquo;hui par une danseuses europ\u00e9enne : c&rsquo;est toujours leur g\u00e9nie industriel ; il les conduit \u00e0 pr\u00e9f\u00e9rer des pirouettes \u00e0 des plaisirs intellectuels.<\/p>\n<\/p>\n<p><p>\tLe plus ancien po\u00e8te des \u00c9tats-Unis est une n\u00e9gresse, Philis Weatley. Quelques-uns de ses vers sont un hommage au g\u00e9n\u00e9ral Washington. Il y a d&rsquo;autres essais de po\u00e9sie africaine : des n\u00e8gres de la Virginie en voulaient au chef de la police de Richemond ; ils avaient compos\u00e9 une ronde qu&rsquo;une jeune po\u00e8te blanche a traduite : \u00ab J&rsquo;\u00e9tais un vieux li\u00e8vre, et je naquis dans la neige, et je fus poursuivi par le cheval noir de Richemond \u00bb ; une autre ronde sur la moisson.]<\/p>\n<\/p>\n<p><p>\tQuant aux po\u00e8tes am\u00e9ricains, leur langage a de l&rsquo;agr\u00e9ment ; mais ils s&rsquo;\u00e9l\u00e8vent peu au-dessus de l&rsquo;ordre commun. Cependant, l&rsquo;<em>Ode \u00e0 la brise du soir, le Lever du soleil sur la montagne, le Torrent<\/em>, et quelques autres po\u00e9sies, m\u00e9ritent d&rsquo;\u00eatre parcourues. Hallek a chant\u00e9 Botzaris expirant, et George Hill a err\u00e9 parmi les ruines de la Gr\u00e8ce : \u00ab O Ath\u00e8nes ! dit-il, c&rsquo;est donc toi, reine solitaire, reine d\u00e9tr\u00f4n\u00e9e! . . . . . .  : Parth\u00e9non, roi des temples, tu as vu les monuments tes contemporains laisser au temps d\u00e9rober leurs pr\u00eatres et leurs dieux. \u00bb<\/p>\n<\/p>\n<p><p>\tIl me pla\u00eet, \u00e0 moi voyageur aux rivages de l&rsquo;Hell\u00e9nie (d) et de l&rsquo;Atlantide, d&rsquo;entendre la voix ind\u00e9pendante d&rsquo;une terre inconnue \u00e0 l&rsquo;antiquit\u00e9 g\u00e9mir sur la libert\u00e9 perdue du vieux monde.<\/p>\n<\/p>\n<p><\/p>\n<h3>11.Dangers pour les \u00c9tats-Unis.<\/h3>\n<\/p>\n<p><p>\tMais l&rsquo;Am\u00e9rique conservera-t-elle la forme de son gouvernement ? Les \u00c9tats ne se diviseront-ils pas? Un d\u00e9put\u00e9 de la Virginie n&rsquo;a-t-il pas d\u00e9j\u00e0 soutenu la th\u00e8se de la libert\u00e9<\/p>\n<\/p>\n<p><p>\tantique avec des esclaves, r\u00e9sultant du paganisme, contre un d\u00e9put\u00e9 du Massachusetts, d\u00e9fendant la cause de la libert\u00e9 moderne sans esclaves, telle que le christianisme l&rsquo;a faite?<\/p>\n<\/p>\n<p><p>\tLes \u00c9tats du nord et du midi ne sont-ils pas oppos\u00e9s d&rsquo;esprit et d&rsquo;int\u00e9r\u00eats? Les \u00c9tats de l&rsquo;ouest, trop \u00e9loign\u00e9s de l&rsquo;Atlantique, ne voudront-ils pas avoir un r\u00e9gime \u00e0 part? D&rsquo;un c\u00f4t\u00e9, le lien f\u00e9d\u00e9ral est-il assez fort pour maintenir l&rsquo;union et contraindre chaque \u00c9tat \u00e0 s&rsquo;y resserrer? D&rsquo;un autre c\u00f4t\u00e9, si l&rsquo;on augmente le pouvoir de la pr\u00e9sidence, le despotisme n&rsquo;arrivera-il pas avec les gardes et les privil\u00e8ges du dictateur?<\/p>\n<\/p>\n<p><p>\t[Le probl\u00e8me de l&rsquo;existence prolong\u00e9e de la r\u00e9publique n&rsquo;est pas encore r\u00e9solu. Quand la r\u00e9publique romaine passa les Alpes et franchit la M\u00e9diterran\u00e9e, elle se transforma en monarchie. Une r\u00e9publique simple et absolue a des principes plus puissants de stabilit\u00e9, une unit\u00e9 d&rsquo;action plus imp\u00e9rieuse qu&rsquo;une r\u00e9publique f\u00e9d\u00e9rative o\u00f9 les volont\u00e9s sont multipli\u00e9es et contradictoires (a).]<\/p>\n<\/p>\n<p><p>\tL&rsquo;isolement des \u00c9tats-Unis leur a permis de na\u00eetre et de grandir : il est douteux qu&rsquo;ils eussent pu vivre et cro\u00eetre en Europe. La Suisse f\u00e9d\u00e9rale subsiste au milieu de nous pourquoi? parce qu&rsquo;elle est petite, pauvre, cantonn\u00e9e au giron des montagnes ; p\u00e9pini\u00e8re de soldats pour les rois, but de promenade pour les voyageurs.<\/p>\n<\/p>\n<p><p>\tS\u00e9par\u00e9e de l&rsquo;ancien monde, la population des \u00c9tats-Unis habite encore la solitude ; ses d\u00e9serts ont \u00e9t\u00e9 sa libert\u00e9 mais d\u00e9j\u00e0 les conditions de son existence s&rsquo;alt\u00e8rent.<\/p>\n<\/p>\n<p><p>\tL&rsquo;existence des d\u00e9mocraties du Mexique, de la Colombie, du P\u00e9rou, du Chili, de Buenos-Ayres, toutes troubl\u00e9es qu&rsquo;elles sont, est un danger. Lorsque les \u00c9tats-Unis n&rsquo;avaient aupr\u00e8s d&rsquo;eux que les colonies d&rsquo;un royaume transatlantique, aucune guerre s\u00e9rieuse n&rsquo;\u00e9tait probable ; maintenant des rivalit\u00e9s ne sont-elles pas \u00e0 craindre? que de part et d&rsquo;autre on coure aux armes, que l&rsquo;esprit militaire s&#8217;empare des enfants de Washington, un grand capitaine pourra surgir au tr\u00f4ne  : la gloire aime les couronnes.<\/p>\n<\/p>\n<p><p>\tJ&rsquo;ai dit que les \u00c9tats du nord, du midi et de l&rsquo;ouest \u00e9taient divis\u00e9s d&rsquo;int\u00e9r\u00eats ; chacun le sait : ces \u00c9tats rompant l&rsquo;union, les r\u00e9duira-t-on par les armes? Alors, quel ferment d&rsquo;inimiti\u00e9s r\u00e9pandu dans le corps social! Les \u00c9tats dissidents maintiendront-ils leur ind\u00e9pendance? Alors, quelles discordes n&rsquo;\u00e9clateront-elles pas parmi ces \u00c9tats \u00e9mancip\u00e9s! Ces r\u00e9publiques d&rsquo;outre-mer, d\u00e9sengren\u00e9es, ne formeraient plus que des unit\u00e9s d\u00e9biles de nul poids dans la balance sociale, ou elles seraient successivement subjugu\u00e9es par l&rsquo;une d&rsquo;entre elles. (Je laisse de c\u00f4t\u00e9 le grave sujet des alliances et des interventions \u00e9trang\u00e8res.) Le Kentucky, peupl\u00e9 d&rsquo;une race d&rsquo;hommes plus rustique, plus hardie et plus militaire, semblerait destin\u00e9 \u00e0 devenir l&rsquo;\u00c9tat conqu\u00e9rant. Dans cet \u00c9tat qui d\u00e9vorerait les autres, le pouvoir d&rsquo;un seul ne tarderait pas \u00e0 s&rsquo;\u00e9lever sur la ruine du pouvoir de tous.<\/p>\n<\/p>\n<p><p>\tJ&rsquo;ai parl\u00e9 du danger de la guerre, je dois rappeler les dangers d&rsquo;une longue paix. Les \u00c9tats-Unis, depuis leur \u00e9mancipation, ont joui, \u00e0 quelques mois pr\u00e8s, de la tranquillit\u00e9 la plus profonde : tandis que cent batailles \u00e9branlaient l&rsquo;Europe, ils cultivaient leurs champs en s\u00fbret\u00e9. De l\u00e0 un d\u00e9bordement de population et de richesses, avec tous les inconv\u00e9nients de la surabondance des richesses et des populations.<\/p>\n<\/p>\n<p><p>\tSi des hostilit\u00e9s survenaient chez un peuple imbelle (b), saurait-on r\u00e9sister? Les fortunes et les moeurs consentiraient-elles \u00e0 des sacrifices ? Comment renoncer aux usances c\u00e2lines, au confort, au bien-\u00eatre indolent de la vie? La Chine et l&rsquo;Inde, endormies dans leur mousseline, ont constamment subi la domination \u00e9trang\u00e8re. Ce qui convient \u00e0 la complexion d&rsquo;une soci\u00e9t\u00e9 libre, c&rsquo;est un \u00e9tat de paix mod\u00e9r\u00e9 par la guerre, et un \u00e9tat de guerre attremp\u00e9 de paix. Les Am\u00e9ricains ont d\u00e9j\u00e0 port\u00e9 trop longtemps de suite la couronne d&rsquo;olivier : l&rsquo;arbre qui la fournit n&rsquo;est pas naturel \u00e0 leur rive.<\/p>\n<\/p>\n<p><p>\tL&rsquo;esprit mercantile commence \u00e0 les envahir ; l&rsquo;int\u00e9r\u00eat devient chez eux le vice national. D\u00e9j\u00e0, le jeu des banques des divers \u00c9tats s&rsquo;entrave, et des banqueroutes menacent la fortune commune. Tant que la libert\u00e9 produit de l&rsquo;or, une r\u00e9publique industrielle fait des prodiges ; mais quand l&rsquo;or est acquis ou \u00e9puis\u00e9, elle perd son amour de l&rsquo;ind\u00e9pendance non fond\u00e9 sur un sentiment moral, mais provenu de la soif du gain et de la passion de l&rsquo;industrie.<\/p>\n<\/p>\n<p><p>\tDe plus, il est difficile de cr\u00e9er une <em>patrie<\/em> parmi des \u00c9tats qui n&rsquo;ont aucune communaut\u00e9 de religion et d&rsquo;int\u00e9r\u00eats, qui, sortis de diverses sources en des temps divers, vivent sur un sol diff\u00e9rent et sous un diff\u00e9rent soleil. Quel rapport y a-t-il entre un Fran\u00e7ais de la Louisiane, un Espagnol des Florides, un Allemand de New-York, un Anglais de la Nouvelle-Angleterre, de la Virginie, de la Caroline, de la G\u00e9orgie, tous r\u00e9put\u00e9s Am\u00e9ricains? Celui-l\u00e0 l\u00e9ger et duelliste ; celui-l\u00e0 catholique, paresseux et superbe ; celui-l\u00e0 luth\u00e9rien, laboureur et sans esclaves ; celui-l\u00e0 anglican et planteur avec des n\u00e8gres ; celui-l\u00e0 puritain et n\u00e9gociant ; combien faudra-t-il de si\u00e8cles pour rendre ces \u00e9l\u00e9ments homog\u00e8nes!<\/p>\n<\/p>\n<p><p>\tUne aristocratie chrysog\u00e8ne est pr\u00eate \u00e0 para\u00eetre avec l&rsquo;amour des distinctions et la passion des titres. On se figure qu&rsquo;il r\u00e8gne un niveau g\u00e9n\u00e9ral aux \u00c9tats-Unis : c&rsquo;est une compl\u00e8te erreur. Il y a des soci\u00e9t\u00e9s qui se d\u00e9daignent et ne se voient point entre elles ; il y a des salons on la morgue des ma\u00eetres surpasse celle d&rsquo;un prince allemand \u00e0 seize quartiers. Ces nobles pl\u00e9b\u00e9iens aspirent \u00e0 la caste, en d\u00e9pit du progr\u00e8s des lumi\u00e8res qui les a faits \u00e9gaux et libres. Quelques-uns d&rsquo;entre eux ne parlent que de leurs a\u00efeux, fiers barons, apparemment b\u00e2tards et compagnons de Guillaume-le-B\u00e2tard. Ils \u00e9talent les blasons de chevalerie de l&rsquo;ancien monde, orn\u00e9s des serpents, des l\u00e9zards et des perruches du monde nouveau. Un cadet de Gascogne abordant avec la cape et le parapluie au rivage r\u00e9publicain, s&rsquo;il a soin de se surnommer <em>marquis<\/em>, est consid\u00e9r\u00e9 sur les bateaux \u00e0 vapeur.<\/p>\n<\/p>\n<p><p>\tL&rsquo;\u00e9norme in\u00e9galit\u00e9 des fortunes menace encore plus s\u00e9rieusement de tuer l&rsquo;esprit d&rsquo;\u00e9galit\u00e9. Tel Am\u00e9ricain poss\u00e8de un ou deux millions de revenu ; aussi, les Yankees de la grande soci\u00e9t\u00e9 ne peuvent-ils d\u00e9j\u00e0 plus vivre comme Franklin : le vrai <em>gentleman<\/em>, d\u00e9go\u00fbt\u00e9 de son pays neuf, vient en Europe chercher du vieux ; on le rencontre dans les auberges, faisant comme les Anglais, avec l&rsquo;extravagance ou le spleen, des <em>tours<\/em> en Italie. Ces r\u00f4deurs de la Caroline ou de la Virginie ach\u00e8tent des ruines d&rsquo;abbayes en France, et plantent, \u00e0 Melun, des jardins anglais avec des arbres am\u00e9ricains. Naples envoie \u00e0 New-York ses chanteurs et ses parfumeurs, Paris ses modes et ses baladins, Londres ses grooms et ses boxeurs : joies exotiques qui ne rendent pas l&rsquo;Union plus gaie. On s&rsquo;y divertit en se jetant dans la cataracte de Niagara, aux applaudissements de cinquante mille planteurs, demi-sauvages que la mort a bien de la peine \u00e0 faire rire.<\/p>\n<\/p>\n<p><p>\tEt ce qu&rsquo;il y a d&rsquo;extraordinaire, c&rsquo;est qu&rsquo;en m\u00eame temps que d\u00e9borde l&rsquo;in\u00e9galit\u00e9 des fortunes et qu&rsquo;une aristocratie commence, la grande impulsion \u00e9galitaire au dehors oblige les possesseurs industriels ou fonciers \u00e0 cacher leur luxe, \u00e0 dissimuler leurs richesses, de crainte d&rsquo;\u00eatre assomm\u00e9s par leurs voisins. On ne reconna\u00eet point la puissance ex\u00e9cutive ; on chasse \u00e0 volont\u00e9 les autorit\u00e9s locales que l&rsquo;on a choisies, et on leur substitue des autorit\u00e9s nouvelles. Cela ne trouble point l&rsquo;ordre ; la d\u00e9mocratie pratique est observ\u00e9e, et l&rsquo;on se rit des lois pos\u00e9es par la m\u00eame d\u00e9mocratie, en th\u00e9orie. L&rsquo;esprit de famille existe peu ; aussit\u00f4t que l&rsquo;enfant est en \u00e9tat de travailler, il faut, comme l&rsquo;oiseau emplum\u00e9, qu&rsquo;il vole de ses propres ailes. De ces g\u00e9n\u00e9rations \u00e9mancip\u00e9es dans un h\u00e2tif orphelinage et des \u00e9migrations qui arrivent de l&rsquo;Europe, il se forme des compagnies nomades qui d\u00e9frichent les terres, creusent des canaux et portent leur industrie partout sans s&rsquo;attacher au sol ; elles commencent des maisons dans le d\u00e9sert o\u00f9 le propri\u00e9taire passager restera \u00e0 peine quelques jours.<\/p>\n<\/p>\n<p><p>\tUn \u00e9go\u00efsme froid et dur r\u00e8gne dans les villes ; piastres et dollars, billets de banque et argent, hausse et baisse des fonds, c&rsquo;est tout l&rsquo;entretien ; on se croirait \u00e0 la Bourse ou au comptoir d&rsquo;une grande boutique. Les journaux, d&rsquo;une dimension immense, sont remplis d&rsquo;expositions d&rsquo;affaires ou de caquets grossiers. Les Am\u00e9ricains subiraient-ils, sans le savoir, la loi d&rsquo;un climat o\u00f9 la nature v\u00e9g\u00e9tale para\u00eet avoir profit\u00e9 aux d\u00e9pens de la nature vivante, loi combattue par des esprits distingu\u00e9s, mais non pas tout \u00e0 fait mise hors d&rsquo;examen par la r\u00e9futation m\u00eame (c) ? On pourrait s&rsquo;enqu\u00e9rir si l&rsquo;Am\u00e9ricain n&rsquo;a pas \u00e9t\u00e9 trop t\u00f4t us\u00e9 dans la libert\u00e9 philosophique, comme le Russe dans le despotisme civilis\u00e9.<\/p>\n<\/p>\n<p><p>\tEn somme, les \u00c9tats-Unis donnent l&rsquo;id\u00e9e d&rsquo;une colonie et non d&rsquo;une patrie-m\u00e8re : ils n&rsquo;ont point de pass\u00e9, les moeurs s&rsquo;y sont faites par les lois. Ces citoyens du Nouveau Monde ont pris rang parmi les nations au moment que les id\u00e9es politiques entraient dans une phase ascendante : cela explique pourquoi ils se transforment avec une rapidit\u00e9 extraordinaire. La soci\u00e9t\u00e9 permanente semble devenir impraticable chez eux, d&rsquo;un c\u00f4t\u00e9 par l&rsquo;extr\u00eame ennui des individus, de l&rsquo;autre par l&rsquo;impossibilit\u00e9 de rester en place, et par la n\u00e9cessit\u00e9 de mouvement qui les domine : car on n&rsquo;est jamais bien fix\u00e9 (d) l\u00e0 o\u00f9 les p\u00e9nates sont errants. Plac\u00e9 sur la route des oc\u00e9ans, \u00e0 la t\u00eate des opinions progressives aussi neuves que son pays, l&rsquo;Am\u00e9ricain semble avoir re\u00e7u de Colomb plut\u00f4t la mission de d\u00e9couvrir d&rsquo;autres univers que de les cr\u00e9er.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Enchanteur nous parle des \u00c9tats-Unis, L&rsquo;Am\u00e9rique dans les M\u00e9moires d&rsquo;outre-tombe &bull; L&rsquo;extrait : En fait, des passages significatifs des M\u00e9moires d&rsquo;outre-tombe, rapportant des jugements du voyageur fran\u00e7ais aux \u00c9tats-Unis, en 1791-93. On y trouve \u00e9galement la confrontation de ces jugements de l&rsquo;explorateur jeune avec des r\u00e9flexions apport\u00e9es plus tard, vingt ou trente ans plus tard,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[11],"tags":[],"class_list":["post-65878","post","type-post","status-publish","format-standard","hentry","category-extraits"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65878"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65878\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}