{"id":65895,"date":"2004-03-14T00:00:00","date_gmt":"2004-03-14T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2004\/03\/14\/vers-le-retour-discret-de-la-conscription-aux-usa\/"},"modified":"2004-03-14T00:00:00","modified_gmt":"2004-03-14T00:00:00","slug":"vers-le-retour-discret-de-la-conscription-aux-usa","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2004\/03\/14\/vers-le-retour-discret-de-la-conscription-aux-usa\/","title":{"rendered":"<strong><em>Vers le retour discret de la conscription aux USA ?<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Vers le retour discret de la conscription aux USA ?<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t14 mars 2004  Si la nouvelle se confirme dans les implications qu&rsquo;on envisage, ce sera l&rsquo;une des plus importantes dans les affaires militaires et politiques aux USA depuis longtemps. <a href=\"http:\/\/sfgate.com\/cgi-bin\/article.cgi?f=\/c\/a\/2004\/03\/13\/MNG905K1BC1.DTL\" class=\"gen\">Le San Francisco Chronicle annonce qu&rsquo;on \u00e9tudie une conscription s\u00e9lective<\/a>, sous la forme du rappel sous les drapeaux de certaines cat\u00e9gories de citoyens am\u00e9ricains,  ceux qui sont sp\u00e9cialis\u00e9s dans le maniement des ordinateurs et ceux qui sont connus pour leurs capacit\u00e9s en langues \u00e9trang\u00e8res.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>The government is taking the first steps toward a targeted military draft of Americans with special skills in computers and foreign languages. The Selective Service System has begun the process of creating the procedures and policies to conduct such a targeted draft in case military officials ask Congress to authorize it and the lawmakers agree to such a request.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>Richard Flahavan, a spokesman for the Selective Service System, said planning for a possible draft of linguists and computer experts had begun last fall after Pentagon personnel officials said the military needed more people with skills in those areas.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>Talking to the manpower folks at the Department of Defense and others, what came up was that nobody foresees a need for a large conventional draft such as we had in Vietnam, Flahavan said. But they thought that if we have any kind of a draft, it will probably be a special skills draft.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tPour l&rsquo;instant, le langage est prudent et se limite volontairement \u00e0 des cat\u00e9gories pr\u00e9cises de personnes. C&rsquo;est toujours de cette fa\u00e7on que la bureaucratie aborde un probl\u00e8me complexe et politiquement tr\u00e8s sensible. Le reste, en g\u00e9n\u00e9ral et une fois que le premier pas est franchi (ce qui devrait \u00eatre fait rapidement tant le Pentagone manque de ces deux cat\u00e9gories de personnes mentionn\u00e9es ici), vient d&rsquo;une fa\u00e7on automatique, selon les pressions de la bureaucratie.<\/p>\n<\/p>\n<p><p>\tD&rsquo;un c\u00f4t\u00e9, on doit observer combien cette \u00e9volution vers une amorce de conscription pourrait bien s&rsquo;ins\u00e9rer dans la campagne \u00e9lectorale, dans la mesure o\u00f9 Kerry lui-m\u00eame a annonc\u00e9 qu&rsquo;il voulait 40.000 hommes de plus pour les forces arm\u00e9es. D&rsquo;une fa\u00e7on diff\u00e9rente et plus pol\u00e9mique, certaines sources, du c\u00f4t\u00e9 d\u00e9mocrate, ont comment\u00e9 ces informations du San Francisco <em>Chronicle<\/em> comme l&rsquo;annonce du d\u00e9veloppement de la conscription apr\u00e8s les \u00e9lections, dans le cas de la r\u00e9\u00e9lection de GW Bush. \u00ab <em>La bureaucratie du Pentagone a d&rsquo;ores et d\u00e9j\u00e0 propos\u00e9 une certaine forme de retour \u00e0 la conscription, <\/em>disent ces sources, <em>mais elle a \u00e9t\u00e9 pri\u00e9e d&rsquo;en rester pour l&rsquo;instant \u00e0 l&rsquo;\u00e9tude de cas tr\u00e8s sp\u00e9cifiques. Au contraire, m\u00eame, cette m\u00e9thode est assez habile : elle coupe les ailes \u00e0 d&rsquo;\u00e9ventuelles fuites sur le travail interne de la bureaucratie, en le limitant \u00e0 des projets de conscription tr\u00e8s r\u00e9duite, mais c&rsquo;est apr\u00e8s la r\u00e9\u00e9lection de Bush, si elle a lieu, qu&rsquo;on verra les vrais plans de l&rsquo;administration pour la conscription.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\tEffectivement, les termes du porte-parole Richard Flahavan sont tr\u00e8s prudents :<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>A targeted registration and draft is is strictly in the planning stage, said Flahavan, adding that the whole thing is driven by what appears to be the more pressing and relevant need today  the deficit in language and computer experts.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>We want to gear up and make sure we are capable of providing (those types of draftees) since that&rsquo;s the more likely need, the spokesman said, adding that it could take about two years to to have all the kinks worked out.<\/em> \u00bb <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tRien n&rsquo;est fait mais tout est possible. Ce qui est remarquable dans cette annonce et les perspectives ainsi ouvertes, c&rsquo;est l&rsquo;implication que l&rsquo;activit\u00e9 militaire et la militarisation de l&rsquo;action antiterroriste am\u00e9ricaine continuent plus que jamais. C&rsquo;est une indication pr\u00e9cieuse ; comme elle est beaucoup plus d&rsquo;ordre structurel et bureaucratique que politique, elle peut \u00eatre tenue pour tr\u00e8s s\u00e9rieuse.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vers le retour discret de la conscription aux USA ? 14 mars 2004 Si la nouvelle se confirme dans les implications qu&rsquo;on envisage, ce sera l&rsquo;une des plus importantes dans les affaires militaires et politiques aux USA depuis longtemps. Le San Francisco Chronicle annonce qu&rsquo;on \u00e9tudie une conscription s\u00e9lective, sous la forme du rappel sous&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-65895","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65895"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65895\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}