{"id":65908,"date":"2004-03-23T00:00:00","date_gmt":"2004-03-23T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2004\/03\/23\/anniversaires-anniversaires-dune-guerre-lautre\/"},"modified":"2004-03-23T00:00:00","modified_gmt":"2004-03-23T00:00:00","slug":"anniversaires-anniversaires-dune-guerre-lautre","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2004\/03\/23\/anniversaires-anniversaires-dune-guerre-lautre\/","title":{"rendered":"<strong><em>Anniversaires, anniversaires, \u2014 d&rsquo;une guerre l&rsquo;autre<\/em><\/strong>"},"content":{"rendered":"<p><p>20,  non, 23 mars 2004 <\/p>\n<\/p>\n<p><p>\tIl y a un an, etc &#8230; Grosse faute de communication. On ne s&rsquo;\u00e9tait pas avis\u00e9, en lan\u00e7ant cette grande guerre de l&rsquo;Irak, que la date de son d\u00e9clenchement la rapprocherait tant de l&rsquo;anniversaire d&rsquo;une autre grande guerre, qui inaugura la s\u00e9rie. (Signe que lorsqu&rsquo;on veut opposer GW \u00e0 Clinton par une rupture, on pousse un peu. Le Kosovo,  c&rsquo;est d&rsquo;elle qu&rsquo;il s&rsquo;agit, commenc\u00e9e le 23 mars 1999  est la premi\u00e8re grande guerre d\u00e9mocratique du simili Empire en qu\u00eate de confirmation. Celle du Golfe-I faisait encore partie de l&rsquo;ancien temps.)<\/p>\n<\/p>\n<p><p>\t[Quant \u00e0 nous, bons princes et fines mouches, c&rsquo;est celle du Kosovo dont nous comm\u00e9morons l&rsquo;anniversaire des d\u00e9buts, prioritairement sur celle de l&rsquo;Irak parce que conform\u00e9ment \u00e0 la chronologie.]<\/p>\n<\/p>\n<p><p>\tPour le temps d&rsquo;aujourd&rsquo;hui et pour l&rsquo;OTAN tout autant (ce sigle invite irr\u00e9sistiblement aux pi\u00e8tres jeux de mots), la premi\u00e8re grande guerre se rappelle \u00e0 notre souvenir. Quelle paix est la plus significative de notre temps ? <a href=\"http:\/\/www.guardian.co.uk\/Kosovo\/Story\/0,2763,1173301,00.html\" class=\"gen\">Celle du Kosovo<\/a>, celle de l&rsquo;Irak ? L&rsquo;on d\u00e9couvre que la source de ces \u00e9v\u00e9nements jaillit dans le mois des fous, que les folies s&rsquo;y d\u00e9cha\u00eenent justement et comme \u00e0 propos. C&rsquo;est bien de folie dont il s&rsquo;agit, dans sa version s\u00e9rieuse, la pathologique.<\/p>\n<\/p>\n<p><p>\tDepuis le 23 mars 1999 o\u00f9 furent lanc\u00e9es les armadas de l&rsquo;OTAN, avec consigne de frapper courageusement mais pas en-dessous de 5.000 m\u00e8tres d&rsquo;altitude, nous sommes entr\u00e9s dans l&rsquo;\u00e8re des guerres \u00e0 la double r\u00e9alit\u00e9. La guerre du Kosovo se d\u00e9roule \u00e0 Evere, au centre de presse de l&rsquo;OTAN, tandis qu&rsquo;Alastair Campbell, qu&rsquo;on retrouvera pour l&rsquo;Irak, charge son \u00e9quipe de mettre en forme des histoires croustillantes qui d\u00e9tourneront l&rsquo;attention. Bient\u00f4t, ces histoires raconteront une guerre du Kosovo \u00e0 c\u00f4t\u00e9 de la r\u00e9elle guerre du Kosovo, celle dont on voit la paix aujourd&rsquo;hui. Bient\u00f4t, on ne se souviendra plus que la premi\u00e8re, <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=35\" class=\"gen\">la premi\u00e8re guerre virtualiste<\/a>.<\/p>\n<\/p>\n<p><p>\tA cause de notre m\u00e9moire si courte, nous avions perdu de vue cet incident de l&rsquo;histoire. La conclusion de cette aventure c&rsquo;\u00e9tait James Rubin, ancien porte-parole du d\u00e9partement d&rsquo;\u00c9tat de Madeleine Albright, qui nous l&rsquo;avait donn\u00e9e, dans une \u00e9mission documentaire (90 minutes, sur Canal +) <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=36\" class=\"gen\">projet\u00e9e au d\u00e9but de 2002<\/a>. Lorsqu&rsquo;on l&rsquo;avait interrog\u00e9 sur toutes les fausses r\u00e9alit\u00e9s (ne parlons pas de mensonges) que les Top Guns de la communication (les hommes de Campbell) nous avaient fait avaler, Rubin avait r\u00e9pondu, tr\u00e8s spontan\u00e9 : \u00ab <strong><em>But it works.<\/em><\/strong> \u00bb C&rsquo;est ce qui s&rsquo;appelle marquer un point.<\/p>\n<\/p>\n<p><p>\tChangement de d\u00e9cor, mais point d&rsquo;esprit.  <\/p>\n<\/p>\n<p><p>\tDepuis le 20 mars 2003, o\u00f9 fut lanc\u00e9e la guerre irakienne apr\u00e8s un impromptu le 19 au soir (tir pr\u00e9cis contre le bunker de Saddam o\u00f9 Saddam ne se trouvait pas), nous sommes comme dans un r\u00eave, mais plut\u00f4t mauvais, qui prendrait \u00e9videmment des allures d&rsquo;un cauchemar. La pire des caricatures que nous envisagions est en-dessous de la  caricature que nous offre la situation du monde. Pas d&rsquo;ADM qui furent la cause de la guerre, <a href=\"http:\/\/www.newsday.com\/news\/nationworld\/world\/ny-woiraq193714003mar19,0,7744865.story?coll=ny-worldnews-headlines\" class=\"gen\">la situation en Irak chaotique<\/a>, la r\u00e9gion d\u00e9stabilis\u00e9e par l&rsquo;apparition de ce foyer du terrorisme, les gouvernements occidentaux qui lanc\u00e8rent la guerre eux-m\u00eames d\u00e9stabilis\u00e9s, le terrorisme hors de la zone relanc\u00e9 comme jamais par l&rsquo;invasion irakienne. C&rsquo;est une qu\u00eate harassante de trouver un peu de bon dans cette pitoyable entreprise, m\u00eame si les moins critiquables s&rsquo;y emploient dans un dernier espoir de se convaincre qu&rsquo;il y a un peu de coh\u00e9rence dans le comportement de ceux qui, aujourd&rsquo;hui, dirigent ce bas monde. (L&rsquo;\u00e9dito de <a href=\"http:\/\/www.guardian.co.uk\/Iraq\/Story\/0,2763,1174660,00.html\" class=\"gen\">The Observer du 21 mars, bien qu&rsquo;on en comprenne l&rsquo;esprit, n&rsquo;ajoute pas beaucoup \u00e0 la gloire de ce journal<\/a>, si honorable en d&rsquo;autres circonstances.) \u00ab <strong><em>La guerre contre l&rsquo;Irak, <\/em><\/strong>dit un expert europ\u00e9en friand de lieux communs, <strong><em>ressemble \u00e0 l&rsquo;\u00e9l\u00e9phant dans le magasin de porcelaines pour son effet sur la stabilit\u00e9 de la r\u00e9gion, elle ressemble au chiffon rouge secou\u00e9 devant les cornes du taureau pour son effet sur le terrorisme.<\/em><\/strong> \u00bb<\/p>\n<\/p>\n<p><p>\tTout cela n&rsquo;est encore rien, si cela est possible. Nous voulons dire que ce n&rsquo;est pas le principal. A c\u00f4t\u00e9, il y a cet \u00e9norme ph\u00e9nom\u00e8ne, cette monstrueuse a-r\u00e9alit\u00e9 du monde, la r\u00e9alit\u00e9 d&rsquo;a c\u00f4t\u00e9 de la r\u00e9alit\u00e9, ce que nous d\u00e9signons dans notre jargon comme le virtualisme. La fa\u00e7on dont les responsables de cette universelle d\u00e9gradation continuent \u00e0 plastronner, sans le moindre doute s\u00e9rieux ni fondamental sur la justesse irr\u00e9futable de leur action, voil\u00e0 qui n&rsquo;est pas courant et nous fait mesurer combien nous sommes dans une \u00e9poque diff\u00e9rant radicalement de tout ce qui a pr\u00e9c\u00e9d\u00e9, mais qui \u00e9tait bien pr\u00e9par\u00e9e par la guerre du Kosovo.<\/p>\n<\/p>\n<p><p>\tQuand, apr\u00e8s avoir d\u00e9velopp\u00e9 votre critique, vous appuyant sur des t\u00e9moignages, d&rsquo;autres analyses, le courant d&rsquo;appr\u00e9ciation g\u00e9n\u00e9ral, en un mot l&rsquo;\u00e9vidence, vous voyez un George W. Bush monter \u00e0 la tribune et que vous l&rsquo;entendez lancer que la guerre contre l&rsquo;Irak <a href=\"http:\/\/story.news.yahoo.com\/news?tmpl=story&#038;cid=564&#038;ncid=564&#038;e=5&#038;u=\/nm\/20040319\/ts_nm\/iraq_dc_69\" class=\"gen\">fut a boost for Middle East stability<\/a>, vous vous demandez de quoi l&rsquo;on parle et qui dit quoi. Puis vous vous rappelez Jamie Rubin, le Kosovo, l&rsquo;OTAN \u00e0 Evere et la bande \u00e0 Campbell,  et vous y \u00eates,  nous y sommes.<\/p>\n<\/p>\n<p><p>\tEntre temps, entre Kosovo et Irak, s&rsquo;est gliss\u00e9e une autre trouvaille : <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=266\" class=\"gen\">la guerre contre la terreur<\/a>. Mener les deux \u00e0 la fois, celle contre la terreur et celle contre l&rsquo;Irak, faire de la guerre contre l&rsquo;Irak la guerre contre la terreur et vice-versa, et ainsi de suite, m\u00e9langer les r\u00e9alit\u00e9s virtualistes, les arguments, les ADM et tout le toutim, c&rsquo;est une t\u00e2che difficile. Ils ont fini par se prendre les pieds.<\/p>\n<\/p>\n<p><p>\tIl y a d\u00e9j\u00e0 eu pas mal d&rsquo;anicroches (les avatars de Blair, l&rsquo;ing\u00e9nuit\u00e9 de David Kay et des ADM introuvables, etc). <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1030\" class=\"gen\">L&rsquo;incident espagnol est le dernier du genre et le plus s\u00e9rieux<\/a>, parce qu&rsquo;il plonge bien des gens, en Europe et aux USA, dans le plus complet embarras. L&rsquo;incident espagnol c\u00e9l\u00e8bre \u00e0 sa fa\u00e7on l&rsquo;anniversaire de la guerre qui a men\u00e9 \u00e0 son terme la r\u00e9volution virtualiste, en la pla\u00e7ant devant le plus redoutable ennemi qu&rsquo;un commandant en chef postmoderne puisse redouter : la r\u00e9alit\u00e9. L&rsquo;histoire, plut\u00f4t que le diable, en rit d\u00e9j\u00e0.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>20, non, 23 mars 2004 Il y a un an, etc &#8230; Grosse faute de communication. On ne s&rsquo;\u00e9tait pas avis\u00e9, en lan\u00e7ant cette grande guerre de l&rsquo;Irak, que la date de son d\u00e9clenchement la rapprocherait tant de l&rsquo;anniversaire d&rsquo;une autre grande guerre, qui inaugura la s\u00e9rie. (Signe que lorsqu&rsquo;on veut opposer GW \u00e0 Clinton&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[9],"tags":[],"class_list":["post-65908","post","type-post","status-publish","format-standard","hentry","category-messagerie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65908"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65908\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}