{"id":65942,"date":"2004-04-21T00:00:00","date_gmt":"2004-04-21T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2004\/04\/21\/comment-blair-est-en-train-de-briser-les-special-relationships\/"},"modified":"2004-04-21T00:00:00","modified_gmt":"2004-04-21T00:00:00","slug":"comment-blair-est-en-train-de-briser-les-special-relationships","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2004\/04\/21\/comment-blair-est-en-train-de-briser-les-special-relationships\/","title":{"rendered":"<strong><em>Comment Blair est en train de briser les \u201cspecial relationships\u201d<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Comment Blair est en train de briser les special relationships<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t21 avril 2004  L&rsquo;article de Richard Norton-Taylor, <a href=\"http:\/\/www.guardian.co.uk\/comment\/story\/0,3604,1195569,00.html\" class=\"gen\">dans le Guardian du 21 avril<\/a>, est important. Fait inhabituel, qui accentue ce jugement, il est pr\u00e9sent\u00e9 sous forme de commentaire (<em>Comment<\/em>), alors que Norton-Taylor, sp\u00e9cialiste des affaires de s\u00e9curit\u00e9 au <em>Guardian<\/em>, \u00e9crit d&rsquo;habitude sous la forme informative des articles normaux de journalistes.<\/p>\n<\/p>\n<p><p>\tL&rsquo;article est un r\u00e9quisitoire, \u00e0 la fois contre la politique militaire et la politique suivie par les Am\u00e9ricains en Irak et dans la guerre contre le terrorisme, \u00e0 la fois contre la politique de Blair qui aligne compl\u00e8tement les int\u00e9r\u00eats et les actions du Royaume-Uni sur les Am\u00e9ricains dans ces mati\u00e8res. L&rsquo;occasion en est le sommet Bush-Blair, dont les partisans du Premier ministre avaient officieusement annonc\u00e9,  une fois de plus, comme avant chaque rencontre avec Bush,  qu&rsquo;on verrait l&rsquo;influence britannique sur les Am\u00e9ricains, et qu&rsquo;on trouverait alors justifi\u00e9e la politique des <em>special relationships<\/em>.<\/p>\n<\/p>\n<p><p>\tNorton-Taylor termine son article de cette fa\u00e7on :<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>The fact remains that Whitehall officials, spooks, military chiefs and even some diplomats have for well over a year been deeply unhappy  privately seething  over the policies and rhetoric of the Bush administration.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>For understandable reasons they do not want to be publicly identified. Have they privately told their political masters? Or have they not dared to, just as they didn&rsquo;t object to the government&rsquo;s highly misleading Iraqi weapons dossier?<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb <em>Blair will claim he has succeeded in getting the UN to play a bigger role in Iraq. Yet that is something the Bush administration itself now desperately wants. Since Blair has failed to persuade Bush to change his calamitous policies towards Iraq, the Middle East, and beyond, what really is the value of the special relationship? It is a question being asked increasingly in Whitehall, let alone the outside world.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tPubli\u00e9 et \u00e9crit sous cette forme, l&rsquo;article de Norton-Taylor est significatif. Il n&rsquo;a pas \u00e9t\u00e9 \u00e9crit sans consultations avec certaines sources militaires du journaliste. Il met en \u00e9vidence le malaise, surtout chez les militaires, avec cette mise en cause fondamentale des relations avec les USA (\u00ab <em>and beyond, what really is the value of the special relationship? It is a question being asked increasingly in Whitehall, let alone the outside world<\/em> \u00bb). \u00c9crire cela \u00e0 propos des militaires britanniques, en g\u00e9n\u00e9ral les plus fid\u00e8les \u00e0 l&rsquo;alliance am\u00e9ricaine, est un point d&rsquo;une r\u00e9elle importance. Il marque les d\u00e9g\u00e2ts en train d&rsquo;\u00eatre caus\u00e9s aux rapports anglo-am\u00e9ricains par l&rsquo;actuelle politique.<\/p>\n<\/p>\n<p><p>\tOn notera que l&rsquo;article de Norton-Taylor, bien s\u00fbr, n&rsquo;est pas isol\u00e9. Le journaliste cite des courriers adress\u00e9s r\u00e9guli\u00e8rement par des militaires aux journaux britanniques (et pas seulement au <em>Guardian<\/em>, et Norton-Taylor cite le <em>Times<\/em>). Surtout, le ton de l&rsquo;article rencontre les constats que font nombre de diplomates et militaires europ\u00e9ens, notamment fran\u00e7ais, dans leurs contacts avec les militaires britanniques. Cette \u00e9volution se fait notamment, \u00e0 la britannique, de fa\u00e7on indirecte,  notamment par le d\u00e9sint\u00e9r\u00eat, voire l&rsquo;oubli (voulu) complet des Britanniques de toute r\u00e9f\u00e9rence \u00e0 l&rsquo;OTAN dans les conversations sur les questions de s\u00e9curit\u00e9 europ\u00e9enne. Certaines orientations nouvelles, allant vers des formules avec une compl\u00e8te autonomie europ\u00e9enne, sont en train d&rsquo;\u00eatre d\u00e9velopp\u00e9es.<\/p>\n<\/p>\n<p><p>\tCurieuse situation Le paradoxe est de constater que Blair ne s&rsquo;y serait pas pris autrement s&rsquo;il avait voulu conduire les <em>special relationships<\/em> \u00e0 un point de rupture. <\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comment Blair est en train de briser les special relationships 21 avril 2004 L&rsquo;article de Richard Norton-Taylor, dans le Guardian du 21 avril, est important. Fait inhabituel, qui accentue ce jugement, il est pr\u00e9sent\u00e9 sous forme de commentaire (Comment), alors que Norton-Taylor, sp\u00e9cialiste des affaires de s\u00e9curit\u00e9 au Guardian, \u00e9crit d&rsquo;habitude sous la forme informative&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-65942","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65942"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65942\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}