{"id":65978,"date":"2004-05-23T00:00:00","date_gmt":"2004-05-23T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2004\/05\/23\/une-palme-dor-freudienne-mais-le-contraire-dun-lapsus\/"},"modified":"2004-05-23T00:00:00","modified_gmt":"2004-05-23T00:00:00","slug":"une-palme-dor-freudienne-mais-le-contraire-dun-lapsus","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2004\/05\/23\/une-palme-dor-freudienne-mais-le-contraire-dun-lapsus\/","title":{"rendered":"<strong><em>Une Palme d&rsquo;Or freudienne, mais le contraire d&rsquo;un lapsus<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Une Palme d&rsquo;Or freudienne, mais le contraire d&rsquo;un lapsus<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t23 mai 2004  Michael Moore est un personnage controvers\u00e9 autant qu&rsquo;original. Il est habile par ailleurs, d\u00e9vastateur, efficace. On dit qu&rsquo;il est autoritaire et dictatorial et qu&rsquo;il a un sens de l&rsquo;argent au-del\u00e0 du commun, m\u00eame am\u00e9ricain. Il faut lire la chronique am\u00e8re et m\u00eame acari\u00e2tre de <a href=\"http:\/\/observer.guardian.co.uk\/review\/story\/0,6903,1222496,00.html\" class=\"gen\">notre ami Andrew Anthony, de l&rsquo;Observer<\/a>,  vrai morceau de choix britannique, lorsque les Britanniques sont mal dans leur peau, parce qu&rsquo;ils ratent tout, parce qu&rsquo;ils sont pris \u00e0 la gorge et au pi\u00e8ge de leur habilet\u00e9 l\u00e9gendaire et diabolique. (Lorsque les Britanniques sont Tony Blair, ce plus fabuleux ratage de l&rsquo;histoire politique occidentale, compl\u00e8tement le miroir de son pays aujourd&rsquo;hui.) L&rsquo;article taille des croupi\u00e8res \u00e0 Moore (et aux Fran\u00e7ais, en m\u00eame temps, qui sont toujours \u00e0 l&rsquo;aise quand les Anglais vont mal, qui ont trouv\u00e9 le truc, tiens : \u00ab <em>and for the French, well, there is nothing the French love more than an American criticising America<\/em> \u00bb).<\/p>\n<\/p>\n<p><p>\tCertes, Andrew n&rsquo;a pas tort,  sauf qu&rsquo;il n&rsquo;est pas question de Moore, ni du cinoche, ni de Cannes ni des Fran\u00e7ais finalement, mais qu&rsquo;il est question de GW, de l&rsquo;Am\u00e9rique et de toute cette sorte de choses. Jamais une Palme d&rsquo;Or n&rsquo;aura \u00e9t\u00e9 plus directement ancr\u00e9e dans l&rsquo;actualit\u00e9, dans la psychologie du moment, dans la politique la plus horriblement br\u00fblante, jamais le cin\u00e9ma n&rsquo;aura \u00e9t\u00e9 aussi compl\u00e8tement utilis\u00e9 comme une arme politique, manipul\u00e9, tordu pour devenir un br\u00fblot. (En ce sens, les Fran\u00e7ais, \u00e0 la grande d\u00e9tresse d&rsquo;Andrew Anthony sans doute, donnent une le\u00e7on \u00e0 Hollywood, dont on croyait jusqu&rsquo;ici qu&rsquo;il avait le monopole de cette sorte de manipulation.) Alors, on comprend bien : Moore ou Tartempion Pourvu que le sujet soit notre actualit\u00e9.<\/p>\n<\/p>\n<p><p>\tTout dans ce choix et dans ce qui l&rsquo;a accompagn\u00e9, contribue \u00e0 le rendre exceptionnel. De ce jury pr\u00e9sid\u00e9 par un Am\u00e9ricain, le plus talentueux parmi les jeunes rebelles, rentr\u00e9 dans le syst\u00e8me sans perdre compl\u00e8tement son \u00e2me (Quentin Tarentino, lequel se paye le luxe de dire que le choix du jury n&rsquo;est pas politique) ; les formidables ovations qui ont accompagn\u00e9 la projection du film et l&rsquo;attribution de la palme d&rsquo;Or, 14 et 9 minutes \u00e0 une semaine d&rsquo;intervalle. (Toujours selon l&rsquo;acari\u00e2tre Anthony, mais tout de m\u00eame pas mal trouv\u00e9 : \u00ab <em> a Cannes record, and possibly unmatched since Stalin&rsquo;s audiences used to continue clapping for mortal fear of being the first person to stop<\/em> \u00bb)<\/p>\n<\/p>\n<p><p>\tTentons de tirer une morale sommaire de cette histoire.<\/p>\n<\/p>\n<p><p>\t&bull; Certains diront que le cin\u00e9ma est d\u00e9tourn\u00e9 de sa voie v\u00e9ritable, surtout le cin\u00e9ma \u00e0 la fran\u00e7aise, qui refuse de tenir compte des int\u00e9r\u00eats divers, commerciaux, politiques, etc. Mais tant pis : \u00e0 situation exceptionnelle, conduite exceptionnelle. Encore une fois, ce n&rsquo;est pas le cin\u00e9ma qui est en cause, mais la politique \u00e9trang\u00e8re des \u00c9tats-Unis. Il est sans doute plus pr\u00e9occupant de voir une puissance de la force des \u00c9tats-Unis lancer une guerre d&rsquo;agression de son seul droit, s&rsquo;installer dans un pays ind\u00e9pendant comme elle le fait, traiter des prisonniers comme elle le fait, etc, que de voir le r\u00f4le du cin\u00e9ma et les coutumes du Festival de Cannes transform\u00e9s.<\/p>\n<\/p>\n<p><p>\t&bull; Cannes a permis \u00e0 l&rsquo;opinion fran\u00e7aise et, derri\u00e8re elle, \u00e0 l&rsquo;opinion internationale (et \u00e0 l&rsquo;opinion dissidente US) de s&rsquo;exprimer d&rsquo;une fa\u00e7on officielle. Les <em>standing ovations<\/em> ont balay\u00e9 tous les d\u00e9comptes d&rsquo;apothicaire des gardiens vigilants de la morale sur les soup\u00e7ons d&rsquo;anti-am\u00e9ricanisme qui planent en permanence. Ce type de d\u00e9cision (la Palme d&rsquo;Or \u00e0 Moore) a l&rsquo;avantage de faire jaillir en pleine lumi\u00e8re un sentiment sous-jacent, qu&rsquo;on s&rsquo;interdit d&rsquo;exprimer par conformisme, qui est enferm\u00e9 dans l&rsquo;inconscient (Freud serait satisfait de le voir lib\u00e9r\u00e9). Cannes, les conditions d&rsquo;attribution de la Palme, la d\u00e9cision, l&rsquo;accueil du public qui repr\u00e9sente un milieu en g\u00e9n\u00e9ral tr\u00e8s peu suspect d&rsquo;anti-am\u00e9ricanisme (contrairement aux fables qui courent sur le cin\u00e9ma fran\u00e7ais, le milieu cin\u00e9matographique fran\u00e7ais actuel, dans tous les cas jusqu&rsquo;au 11 septembre 2001, est tr\u00e8s peu anti-am\u00e9ricain),  tout cela permet de mesurer l&rsquo;effondrement du prestige moral et politique des \u00c9tats-Unis.<\/p>\n<\/p>\n<p><p>\t&bull; Cannes 2004 a confirm\u00e9 la puissance formidable des techniques et arts de communication et culturels dans la bataille politique. Rien que de tr\u00e8s normal depuis que triomphe le virtualisme, lui-m\u00eame fond\u00e9 sur la communication et les manipulations de type culturel : pour l&rsquo;attaquer, il faut une arme du m\u00eame domaine. Cannes 2004 a \u00e9galement montr\u00e9 qu&rsquo;en mati\u00e8re de manipulation politique, les Fran\u00e7ais (les Europ\u00e9ens) pouvaient se montrer plus audacieux que et sup\u00e9rieurs au ma\u00eetre en la mati\u00e8re, le cin\u00e9ma am\u00e9ricain. <\/p>\n<\/p>\n<p><p>\t&bull; Enfin, le moment du choix, en pleine pr\u00e9sidentielle, au cur des scandales de l&rsquo;occupation en Irak, etc. Dans ce sens qui est celui des circonstances, la d\u00e9cision \u00e0 Cannes 2004 appara\u00eet presque naturelle et fond\u00e9e.<\/p>\n<\/p>\n<p><p>\tEn effet, nous sommes \u00e0 un moment d\u00e9licat du drame, comme l&rsquo;\u00e9crit Robert G. Kaiser, <a href=\"http:\/\/www.washingtonpost.com\/wp-dyn\/articles\/A47244-2004May22_3.html\" class=\"gen\">dans un article, le 23 mai dans le Post<\/a>, d&rsquo;une extraordinaire violence dans sa pr\u00e9cision et l&rsquo;implacabilit\u00e9 un rien m\u00e9prisante du r\u00e9quisitoire (le titre, d\u00e9j\u00e0, \u00e9voquant le ch\u00e2teau de cartes : \u00ab <em>A Foreign Policy, Falling Apart <\/em> \u00bb).<\/p>\n<\/p>\n<p><p>\tCe que d\u00e9crit Kaiser, on s&rsquo;en doute, est le contraire de Cannes acclamant Michael Moore. C&rsquo;est Washington \u00e0 l&rsquo;or\u00e9e du mois fatal, juin 2004 qui doit nous conduire au processus lib\u00e9rateur de l&rsquo;Irak :<\/p>\n<\/p>\n<p><\/p>\n<p><p>\t\u00ab <em>We have come to a delicate moment in an absorbing drama. The actors seem unsure of their roles. The audience is becoming restless with the confusion on stage. But the scriptwriters keep trying to convince the crowd that the ending they imagined can still, somehow, come to pass.<\/em> \u00bb<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une Palme d&rsquo;Or freudienne, mais le contraire d&rsquo;un lapsus 23 mai 2004 Michael Moore est un personnage controvers\u00e9 autant qu&rsquo;original. Il est habile par ailleurs, d\u00e9vastateur, efficace. On dit qu&rsquo;il est autoritaire et dictatorial et qu&rsquo;il a un sens de l&rsquo;argent au-del\u00e0 du commun, m\u00eame am\u00e9ricain. Il faut lire la chronique am\u00e8re et m\u00eame acari\u00e2tre&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[915],"class_list":["post-65978","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-moore"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=65978"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/65978\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=65978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=65978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=65978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}